{"id":5676,"date":"2021-10-20T09:15:00","date_gmt":"2021-10-20T09:15:00","guid":{"rendered":"http:\/\/informatepy.com\/2022\/2021\/10\/20\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\/"},"modified":"2022-09-27T23:54:18","modified_gmt":"2022-09-27T23:54:18","slug":"el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2022\/2021\/10\/20\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\/","title":{"rendered":"El senado brasilero busca derrocar a Bolsonaro acus\u00e1ndolo de homicidio en masa"},"content":{"rendered":"\n<p>La comisi\u00f3n especial instalada en el<strong>&nbsp;Senado de Brasil&nbsp;<\/strong>para investigar los \u00abposibles delitos\u00bb cometidos por el Gobierno de&nbsp;Jair Bolsonaro&nbsp;en la gesti\u00f3n de la pandemia&nbsp;<strong>acusar\u00e1 al presidente de 11 delitos<\/strong>, entre ellos el de homicidio por omisi\u00f3n. El senador&nbsp;<strong>Renan Calheiros<\/strong>, relator del informe, presentar\u00e1 hoy un texto, pero ya adelant\u00f3 que las acusaciones ser\u00e1n de peso.<\/p>\n\n\n\n<p>Seg\u00fan \u00e9l, Bolsonaro, muchos de sus ministros y otros integrantes del Gobierno<strong>&nbsp;actuaron para que el covid-19 se propagase lo m\u00e1s r\u00e1pido posible<\/strong>. \u00abCon este comportamiento, el Gobierno, que ten\u00eda el deber legal de actuar, consinti\u00f3 la muerte de brasile\u00f1as y brasile\u00f1os\u00bb, apunt\u00f3. M\u00e1s de&nbsp;<strong>600.000 personas perdieron la vida<\/strong>&nbsp;en el pa\u00eds, y los senadores creen que la pol\u00edtica negacionista del Gobierno tuvo un papel clave en ese tr\u00e1gico resultado.<\/p>\n\n\n\n<p>El informe comprueba la existencia del llamado&nbsp;<strong>&#8216;gabinete paralelo&#8217;<\/strong>, compuesto por m\u00e9dicos, pol\u00edticos y empresarios que asesoraban a Bolsonaro \u00abcon la intenci\u00f3n de inmunizar a la poblaci\u00f3n por medio de la contaminaci\u00f3n natural\u00bb, priorizando el tratamiento precoz con medicamentos sin eficacia probada y estimulando el incumplimiento de medidas no farmacol\u00f3gicas, como el distanciamiento social. Adem\u00e1s, recuerda que hubo un&nbsp;<strong>\u00abdeliberado atraso\u00bb en la compra de vacunas<\/strong>, lo que acab\u00f3 costando miles de vidas.<\/p>\n\n\n\n<p>Despu\u00e9s de cinco meses de interrogatorios p\u00fablicos que llenaron horas de telediarios y contribuyeron a desgastar a\u00fan m\u00e1s la popularidad del presidente, el Senado termin\u00f3 su trabajo. La comisi\u00f3n recopil\u00f3 pruebas importantes a trav\u00e9s de las audiencias y ahora el informe se entregar\u00e1 a<strong>&nbsp;la Fiscal\u00eda, que decidir\u00e1 si imputa o no a Bolsonaro y al resto de acusados<\/strong>. Se prev\u00e9 acusar a 70 personas y a dos empresas, por un total de 24 delitos. La mayor\u00eda tienen que ver con la defensa de medicamentos ineficaces para tratar el covid-19.<\/p>\n\n\n\n<p>Previsiblemente, Bolsonaro ser\u00e1 acusado de 11 delitos, en base al C\u00f3digo Penal, la Constituci\u00f3n y el Estatuto de Roma: delito por epidemia con resultado de muerte, infracci\u00f3n a medidas sanitarias preventivas, uso irregular de fondos p\u00fablicos, incitaci\u00f3n al delito, falsificaci\u00f3n de documentos, charlatanismo, prevaricaci\u00f3n, genocidio de ind\u00edgenas, crimen de responsabilidad, crimen contra la humanidad y homicidio por omisi\u00f3n.<\/p>\n\n\n\n<p>En los \u00faltimos d\u00edas hubo fuertes tensiones entre los senadores, sobre todo porque algunos no ve\u00edan clara la base legal para acusar a Bolsonaro de genocidio (dado que habr\u00eda que comprobar una intenci\u00f3n deliberada de provocar la muerte) o de homicidio doloso, ni para incluir a sus hijos en las acusaciones.&nbsp;<strong>La redacci\u00f3n final del informe se conocer\u00e1 a partir del mi\u00e9rcoles<\/strong>&nbsp;, cuando se haga la lectura oficial, y se votar\u00e1 la semana que viene, aunque se prev\u00e9 que se apruebe sin problemas. Despu\u00e9s, la pelota estar\u00e1 en el tejado de la Fiscal\u00eda.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Con informaci\u00f3n de El Mundo (Espa\u00f1a)<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La comisi\u00f3n especial instalada en el&nbsp;Senado de Brasil&nbsp;para investigar los \u00abposibles delitos\u00bb cometidos por el Gobierno de&nbsp;Jair Bolsonaro&nbsp;en la gesti\u00f3n de la pandemia&nbsp;acusar\u00e1 al presidente de 11 delitos, entre ellos el de homicidio por omisi\u00f3n. El senador&nbsp;Renan Calheiros, relator del informe, presentar\u00e1 hoy un texto, pero ya adelant\u00f3 que las acusaciones ser\u00e1n de peso. Seg\u00fan [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5677,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[14],"tags":[387,328,871,494],"ppma_author":[],"class_list":{"0":"post-5676","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mundo","8":"tag-bolsonaro","9":"tag-brasil","10":"tag-destacada","11":"tag-jair-bolsonaro"},"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El senado brasilero busca derrocar a Bolsonaro acus\u00e1ndolo de homicidio en masa - Informatepy.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2022\/2021\/10\/20\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El senado brasilero busca derrocar a Bolsonaro acus\u00e1ndolo de homicidio en masa - Informatepy.com\" \/>\n<meta property=\"og:description\" content=\"La comisi\u00f3n especial instalada en el&nbsp;Senado de Brasil&nbsp;para investigar los \u00abposibles delitos\u00bb cometidos por el Gobierno de&nbsp;Jair Bolsonaro&nbsp;en la gesti\u00f3n de la pandemia&nbsp;acusar\u00e1 al presidente de 11 delitos, entre ellos el de homicidio por omisi\u00f3n. El senador&nbsp;Renan Calheiros, relator del informe, presentar\u00e1 hoy un texto, pero ya adelant\u00f3 que las acusaciones ser\u00e1n de peso. Seg\u00fan [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2022\/2021\/10\/20\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-20T09:15:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-27T23:54:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/10\/bolsonaro-riendo.jpeg?fit=954%2C550&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"954\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:site\" content=\"@InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/10\\\/20\\\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/10\\\/20\\\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/e7c5b605ddfb77041eeddff4d93b26af\"},\"headline\":\"El senado brasilero busca derrocar a Bolsonaro acus\u00e1ndolo de homicidio en masa\",\"datePublished\":\"2021-10-20T09:15:00+00:00\",\"dateModified\":\"2022-09-27T23:54:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/10\\\/20\\\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\\\/\"},\"wordCount\":521,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/10\\\/20\\\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/bolsonaro-riendo.jpeg?fit=954%2C550&ssl=1\",\"keywords\":[\"bolsonaro\",\"brasil\",\"destacada\",\"jair bolsonaro\"],\"articleSection\":[\"Mundo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/10\\\/20\\\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/10\\\/20\\\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/10\\\/20\\\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\\\/\",\"name\":\"El senado brasilero busca derrocar a Bolsonaro acus\u00e1ndolo de homicidio en masa - Informatepy.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/10\\\/20\\\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/10\\\/20\\\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/bolsonaro-riendo.jpeg?fit=954%2C550&ssl=1\",\"datePublished\":\"2021-10-20T09:15:00+00:00\",\"dateModified\":\"2022-09-27T23:54:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/10\\\/20\\\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/10\\\/20\\\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/10\\\/20\\\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/bolsonaro-riendo.jpeg?fit=954%2C550&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/bolsonaro-riendo.jpeg?fit=954%2C550&ssl=1\",\"width\":954,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/10\\\/20\\\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El senado brasilero busca derrocar a Bolsonaro acus\u00e1ndolo de homicidio en masa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"name\":\"Informatepy.com\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\",\"name\":\"Informatepy.com\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"width\":589,\"height\":150,\"caption\":\"Informatepy.com\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/InformatePy1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/e7c5b605ddfb77041eeddff4d93b26af\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.pngce0c1b6da06ae20abaff417c2cdeea83\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El senado brasilero busca derrocar a Bolsonaro acus\u00e1ndolo de homicidio en masa - Informatepy.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2022\/2021\/10\/20\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\/","og_locale":"es_ES","og_type":"article","og_title":"El senado brasilero busca derrocar a Bolsonaro acus\u00e1ndolo de homicidio en masa - Informatepy.com","og_description":"La comisi\u00f3n especial instalada en el&nbsp;Senado de Brasil&nbsp;para investigar los \u00abposibles delitos\u00bb cometidos por el Gobierno de&nbsp;Jair Bolsonaro&nbsp;en la gesti\u00f3n de la pandemia&nbsp;acusar\u00e1 al presidente de 11 delitos, entre ellos el de homicidio por omisi\u00f3n. El senador&nbsp;Renan Calheiros, relator del informe, presentar\u00e1 hoy un texto, pero ya adelant\u00f3 que las acusaciones ser\u00e1n de peso. Seg\u00fan [&hellip;]","og_url":"https:\/\/informatepy.com\/2022\/2021\/10\/20\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\/","og_site_name":"Informatepy.com","article_publisher":"https:\/\/www.facebook.com\/InformatePyCom","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2021-10-20T09:15:00+00:00","article_modified_time":"2022-09-27T23:54:18+00:00","og_image":[{"width":954,"height":550,"url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/10\/bolsonaro-riendo.jpeg?fit=954%2C550&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_site":"@InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2022\/2021\/10\/20\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/2021\/10\/20\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/e7c5b605ddfb77041eeddff4d93b26af"},"headline":"El senado brasilero busca derrocar a Bolsonaro acus\u00e1ndolo de homicidio en masa","datePublished":"2021-10-20T09:15:00+00:00","dateModified":"2022-09-27T23:54:18+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2021\/10\/20\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\/"},"wordCount":521,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2021\/10\/20\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/10\/bolsonaro-riendo.jpeg?fit=954%2C550&ssl=1","keywords":["bolsonaro","brasil","destacada","jair bolsonaro"],"articleSection":["Mundo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2022\/2021\/10\/20\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2022\/2021\/10\/20\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\/","url":"https:\/\/informatepy.com\/2022\/2021\/10\/20\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\/","name":"El senado brasilero busca derrocar a Bolsonaro acus\u00e1ndolo de homicidio en masa - Informatepy.com","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2021\/10\/20\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2021\/10\/20\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/10\/bolsonaro-riendo.jpeg?fit=954%2C550&ssl=1","datePublished":"2021-10-20T09:15:00+00:00","dateModified":"2022-09-27T23:54:18+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2022\/2021\/10\/20\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2022\/2021\/10\/20\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/2021\/10\/20\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/10\/bolsonaro-riendo.jpeg?fit=954%2C550&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/10\/bolsonaro-riendo.jpeg?fit=954%2C550&ssl=1","width":954,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2022\/2021\/10\/20\/el-senado-brasilero-busca-derrocar-a-bolsonaro-acusandolo-de-homicidio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2022\/"},{"@type":"ListItem","position":2,"name":"El senado brasilero busca derrocar a Bolsonaro acus\u00e1ndolo de homicidio en masa"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2022\/#website","url":"https:\/\/informatepy.com\/2022\/","name":"Informatepy.com","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2022\/#organization","name":"Informatepy.com","url":"https:\/\/informatepy.com\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","width":589,"height":150,"caption":"Informatepy.com"},"image":{"@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/InformatePy1"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/e7c5b605ddfb77041eeddff4d93b26af","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.pngce0c1b6da06ae20abaff417c2cdeea83","url":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2022\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/10\/bolsonaro-riendo.jpeg?fit=954%2C550&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"authors":[{"term_id":1037,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/5676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/comments?post=5676"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/5676\/revisions"}],"predecessor-version":[{"id":13192,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/5676\/revisions\/13192"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media\/5677"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media?parent=5676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/categories?post=5676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/tags?post=5676"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/ppma_author?post=5676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}