{"id":5054,"date":"2021-08-26T18:46:31","date_gmt":"2021-08-26T18:46:31","guid":{"rendered":"http:\/\/informatepy.com\/2022\/2021\/08\/26\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\/"},"modified":"2022-09-27T23:43:23","modified_gmt":"2022-09-27T23:43:23","slug":"cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2022\/2021\/08\/26\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\/","title":{"rendered":"Cristiano Ronaldo lleg\u00f3 a un acuerdo con el Manchester City"},"content":{"rendered":"\n<p>El mercado de transferencias est\u00e1 viviendo unos intensos \u00faltimos d\u00edas antes de que se baje la cortina de negociaciones. Mientras que en\u00a0Par\u00eds definen qu\u00e9 pasar\u00e1 con Kylian Mbapp\u00e9, a 775 kil\u00f3metros de distancia se define otra de las grandes novelas de este a\u00f1o:\u00a0<strong>Cristiano Ronaldo<\/strong>\u00a0busca marcharse de Tur\u00edn.<\/p>\n\n\n\n<p>El diario espa\u00f1ol\u00a0<em>AS<\/em>\u00a0asegur\u00f3 en las \u00faltimas horas que el\u00a0<strong>futbolista portugu\u00e9s<\/strong>\u00a0<strong>lleg\u00f3 a un acuerdo contractual con el Manchester City<\/strong>, pero ahora las trabas est\u00e1n del lado de la\u00a0<strong>Juventus<\/strong>. El periodista Mirko Calemme de ese peri\u00f3dico detall\u00f3 que CR7 podr\u00eda\u00a0<strong>firmar hasta 2023 con un salario de 15 millones de euros<\/strong>\u00a0netos.<\/p>\n\n\n\n<p>Frente a ese tablero, este jueves se llev\u00f3 a cabo una reuni\u00f3n clave entre los dirigentes de la\u00a0<em>Vecchia Signora<\/em>\u00a0y el medi\u00e1tico representante del luso Jorge M\u00e9ndes. Seg\u00fan inform\u00f3 la<em>\u00a0Gazzetta dello Sport<\/em>, la c\u00fapula del club de Tur\u00edn le\u00a0<strong>asegur\u00f3 que no quer\u00edan seguir dilatando las tratativas<\/strong>\u00a0y pusieron sobre las mesas las condiciones para dejarlo partir al f\u00fatbol ingl\u00e9s.<\/p>\n\n\n\n<p>El problema ser\u00eda que el due\u00f1o de los&nbsp;<em>citizens,&nbsp;<\/em>Sheikh Mansour, no estar\u00eda dispuesto a invertir dinero en su contrato y&nbsp;<strong>pretende fichar a la estrella portuguesa de forma gratuita<\/strong>, seg\u00fan aclar\u00f3 el&nbsp;<em>Corriere dello Sport<\/em>.<\/p>\n\n\n\n<p>La Juventus, sin embargo, se habr\u00eda negado a cumplir con los deseos del jeque \u00e1rabe:\u00a0<strong>buscan recibir entre 28 y 30 millones de euros<\/strong>\u00a0para dejar marchar a su m\u00e1ximo referente, por el que desembolsaron\u00a0<strong>100 millones<\/strong>\u00a0en 2018. \u00bfLa perilla que podr\u00eda destrabar las tratativas?\u00a0<strong>Un intercambio de futbolistas<\/strong>.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Con informaci\u00f3n de Infobae<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Desde Espa\u00f1a afirman que el portugu\u00e9s tiene encaminado su contrato con la entidad inglesa, pero la gran traba radica en las pretensiones de la Vecchia Signora<\/p>\n","protected":false},"author":3,"featured_media":2082,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[24],"tags":[843,751,845,248],"ppma_author":[998],"class_list":{"0":"post-5054","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deportes","8":"tag-cristiano-ronaldo","9":"tag-futbol-europeo","10":"tag-juventus","11":"tag-manchester-city"},"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cristiano Ronaldo lleg\u00f3 a un acuerdo con el Manchester City - Informatepy.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2022\/2021\/08\/26\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cristiano Ronaldo lleg\u00f3 a un acuerdo con el Manchester City - Informatepy.com\" \/>\n<meta property=\"og:description\" content=\"Desde Espa\u00f1a afirman que el portugu\u00e9s tiene encaminado su contrato con la entidad inglesa, pero la gran traba radica en las pretensiones de la Vecchia Signora\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2022\/2021\/08\/26\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-26T18:46:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-27T23:43:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/01\/cristiano-ronaldo.jpg?fit=660%2C371&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"371\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:site\" content=\"@InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/08\\\/26\\\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/08\\\/26\\\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/e7c5b605ddfb77041eeddff4d93b26af\"},\"headline\":\"Cristiano Ronaldo lleg\u00f3 a un acuerdo con el Manchester City\",\"datePublished\":\"2021-08-26T18:46:31+00:00\",\"dateModified\":\"2022-09-27T23:43:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/08\\\/26\\\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\\\/\"},\"wordCount\":291,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/08\\\/26\\\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/cristiano-ronaldo.jpg?fit=660%2C371&ssl=1\",\"keywords\":[\"cristiano ronaldo\",\"futbol europeo\",\"juventus\",\"manchester city\"],\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/08\\\/26\\\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/08\\\/26\\\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/08\\\/26\\\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\\\/\",\"name\":\"Cristiano Ronaldo lleg\u00f3 a un acuerdo con el Manchester City - Informatepy.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/08\\\/26\\\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/08\\\/26\\\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/cristiano-ronaldo.jpg?fit=660%2C371&ssl=1\",\"datePublished\":\"2021-08-26T18:46:31+00:00\",\"dateModified\":\"2022-09-27T23:43:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/08\\\/26\\\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/08\\\/26\\\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/08\\\/26\\\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/cristiano-ronaldo.jpg?fit=660%2C371&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/cristiano-ronaldo.jpg?fit=660%2C371&ssl=1\",\"width\":660,\"height\":371},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/08\\\/26\\\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cristiano Ronaldo lleg\u00f3 a un acuerdo con el Manchester City\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"name\":\"Informatepy.com\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\",\"name\":\"Informatepy.com\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"width\":589,\"height\":150,\"caption\":\"Informatepy.com\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/InformatePy1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/e7c5b605ddfb77041eeddff4d93b26af\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.pngce0c1b6da06ae20abaff417c2cdeea83\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cristiano Ronaldo lleg\u00f3 a un acuerdo con el Manchester City - Informatepy.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2022\/2021\/08\/26\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\/","og_locale":"es_ES","og_type":"article","og_title":"Cristiano Ronaldo lleg\u00f3 a un acuerdo con el Manchester City - Informatepy.com","og_description":"Desde Espa\u00f1a afirman que el portugu\u00e9s tiene encaminado su contrato con la entidad inglesa, pero la gran traba radica en las pretensiones de la Vecchia Signora","og_url":"https:\/\/informatepy.com\/2022\/2021\/08\/26\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\/","og_site_name":"Informatepy.com","article_publisher":"https:\/\/www.facebook.com\/InformatePyCom","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2021-08-26T18:46:31+00:00","article_modified_time":"2022-09-27T23:43:23+00:00","og_image":[{"width":660,"height":371,"url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/01\/cristiano-ronaldo.jpg?fit=660%2C371&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_site":"@InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2022\/2021\/08\/26\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/2021\/08\/26\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/e7c5b605ddfb77041eeddff4d93b26af"},"headline":"Cristiano Ronaldo lleg\u00f3 a un acuerdo con el Manchester City","datePublished":"2021-08-26T18:46:31+00:00","dateModified":"2022-09-27T23:43:23+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2021\/08\/26\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\/"},"wordCount":291,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2021\/08\/26\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/01\/cristiano-ronaldo.jpg?fit=660%2C371&ssl=1","keywords":["cristiano ronaldo","futbol europeo","juventus","manchester city"],"articleSection":["Deportes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2022\/2021\/08\/26\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2022\/2021\/08\/26\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\/","url":"https:\/\/informatepy.com\/2022\/2021\/08\/26\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\/","name":"Cristiano Ronaldo lleg\u00f3 a un acuerdo con el Manchester City - Informatepy.com","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2021\/08\/26\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2021\/08\/26\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/01\/cristiano-ronaldo.jpg?fit=660%2C371&ssl=1","datePublished":"2021-08-26T18:46:31+00:00","dateModified":"2022-09-27T23:43:23+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2022\/2021\/08\/26\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2022\/2021\/08\/26\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/2021\/08\/26\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/01\/cristiano-ronaldo.jpg?fit=660%2C371&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/01\/cristiano-ronaldo.jpg?fit=660%2C371&ssl=1","width":660,"height":371},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2022\/2021\/08\/26\/cristiano-ronaldo-llego-a-un-acuerdo-con-el-manchester-city\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2022\/"},{"@type":"ListItem","position":2,"name":"Cristiano Ronaldo lleg\u00f3 a un acuerdo con el Manchester City"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2022\/#website","url":"https:\/\/informatepy.com\/2022\/","name":"Informatepy.com","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2022\/#organization","name":"Informatepy.com","url":"https:\/\/informatepy.com\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","width":589,"height":150,"caption":"Informatepy.com"},"image":{"@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/InformatePy1"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/e7c5b605ddfb77041eeddff4d93b26af","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.pngce0c1b6da06ae20abaff417c2cdeea83","url":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2022\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/01\/cristiano-ronaldo.jpg?fit=660%2C371&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"authors":[{"term_id":998,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/5054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/comments?post=5054"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/5054\/revisions"}],"predecessor-version":[{"id":12887,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/5054\/revisions\/12887"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media\/2082"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media?parent=5054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/categories?post=5054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/tags?post=5054"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/ppma_author?post=5054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}