{"id":4769,"date":"2021-08-09T21:07:34","date_gmt":"2021-08-09T21:07:34","guid":{"rendered":"http:\/\/informatepy.com\/2022\/2021\/08\/09\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\/"},"modified":"2022-09-27T23:38:20","modified_gmt":"2022-09-27T23:38:20","slug":"la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2022\/2021\/08\/09\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\/","title":{"rendered":"La nueva Ley de Educaci\u00f3n en Espa\u00f1a propone el \u201cdescubrimiento de la sexualidad\u201d en alumnos de 0 a 6 a\u00f1os"},"content":{"rendered":"\n<p>Descubrir la&nbsp;<strong>sexualidad en las aulas antes de los 6 a\u00f1os<\/strong>, dar un&nbsp;<strong>enfoque socioemocional a la ense\u00f1anza de Matem\u00e1ticas<\/strong>, facilitar la construcci\u00f3n de g\u00e9nero sobre valores de igualdad en la educaci\u00f3n Primaria\u2026 La oposici\u00f3n al Gobierno de Pedro S\u00e1nchez ha reaccionado con contundencia al contenido de los decretos que deben desarrollar la nueva Ley de Educaci\u00f3n, la conocida como&nbsp;<em>Ley Cela\u00e1<\/em>.<\/p>\n\n\n\n<p>Dos aspectos revelados en las \u00faltimas horas han centrado las&nbsp;<strong>cr\u00edticas Partido Popular, Vox y Ciudadanos<\/strong>. Por un lado,<strong>&nbsp;la educaci\u00f3n sexual en el ciclo Educaci\u00f3n Infantil, de 0 a 6 a\u00f1os. Por otro, el enfoque \u201csocioemocional\u201d que se quiere imprimir a la ense\u00f1anza de matem\u00e1ticas en el ciclo de Primaria (de 6 a 12 a\u00f1os).<\/strong><\/p>\n\n\n\n<p>Los borradores de los decretos que desarrollan la Ley de educaci\u00f3n, parte de cuyo contenido publican este 9 de agosto&nbsp;<em>Abc<\/em>&nbsp;y&nbsp;<em>El Mundo<\/em>, han sido remitidos a las Consejer\u00edas de Educaci\u00f3n de las Comunidades Aut\u00f3nomas \u2013que tienen transferidas las competencias en la materia- para que presenten alegaciones.<\/p>\n\n\n\n<p>\u00bfQu\u00e9 dicen estos textos? \u201cEn esta etapa\u201d, explican en relaci\u00f3n a la Educaci\u00f3n Infantil, \u201c<strong>se inicia la construcci\u00f3n sexual y de g\u00e9nero, sin distinci\u00f3n entre ambas. La intervenci\u00f3n educativa debe favorecer el descubrimiento personal de la sexualidad y la construcci\u00f3n de g\u00e9nero a trav\u00e9s de valores de igualdad y modelos no estereotipados\u00bb.<\/strong><\/p>\n\n\n\n<p>La\u00a0<em>Ley Cela\u00e1<\/em>\u00a0\u2013llamada as\u00ed por la anterior titular del Ministerio, Isabel Cela\u00e1, que sali\u00f3 del Ejecutivo en la crisis de Gobierno realizada por Pedro S\u00e1nchez el pasado 11 de julio-, propone como ideas generales que a los alumnos se les explique, entre otras cuestiones, \u201cla funci\u00f3n social de los impuestos y lajusticia fiscal\u201d, la \u201cigualdad de mujeres y hombres\u201d y \u201cel valor del respeto a la diversidad, fomentando el esp\u00edritu cr\u00edtico, la cultura de paz y no violencia y el respeto por el entorno y los animales\u201d.<\/p>\n\n\n\n<h6 class=\"has-text-align-center wp-block-heading\"><img loading=\"lazy\" decoding=\"async\" height=\"2576\" width=\"3872\" alt=\"La ex ministra de Educaci\u00f3n Isabel Cela\u00e1.\n\" src=\"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/EF65F2MK6RA5TMBBEBO2RTSOIY.jpg%20420w\">La ex ministra de Educaci\u00f3n Isabel Cela\u00e1.<\/h6>\n\n\n\n<p>Los pol\u00e9micos borradores conocidos ahora se\u00f1alan que en el \u00e1mbito escolar se debe facilitar \u201cel contexto adecuado y el acompa\u00f1amiento necesario, bajo una mirada atenta, paciente y respetuosa,&nbsp;<strong>para que los beb\u00e9s puedan descubrir el placer que les proporciona la actividad por iniciativa propia<\/strong>, que es su principal necesidad en relaci\u00f3n con su entorno, en un ambiente estimulante de seguridad, calma y tranquilidad\u201d.<\/p>\n\n\n\n<p>A\u00f1ade el decreto que esto permitir\u00e1 a<strong>&nbsp;los escolares de 0 a 6 a\u00f1os ir conociendo \u201csu cuerpo global y parcialmente\u201d<\/strong>, as\u00ed como&nbsp;<strong>\u201csus posibilidades perceptivas y de acci\u00f3n, expresi\u00f3n y movimiento, as\u00ed como sus limitaciones, siendo capaces de identificar las sensaciones que experimenta, disfrutar con ellas y servirse de las posibilidades expresivas del cuerpo para manifestarlas\u00bb<\/strong><\/p>\n\n\n\n<p>Esto ha sido interpretado por la oposici\u00f3n como una intromisi\u00f3n en el derecho de los menores. Ana Pastor, vicesecretaria de Pol\u00edtica Social del partido Popular y ex ministra de Sanidad y ex presidenta del Congreso de los Diputados, ha criticado al Gobierno, lo ha acusado de lanzar \u201c<strong>serpientes de verano\u201d<\/strong>&nbsp;y ha afirmado que el contenido de los decretos que desarrollan la ley de educaci\u00f3n \u201c<strong>son una solemne bobada\u201d.<\/strong><\/p>\n\n\n\n<p>En referencia al \u201csentido socioemocional\u201d que se debe dar a la ense\u00f1anza de Matem\u00e1ticas en Primaria, ha afirmado. \u201cEn vez de estar preocupados por que las ni\u00f1as y los ni\u00f1os tengan una educaci\u00f3n de calidad, porque haya evaluaci\u00f3n [de sus aprendizaje], porque la EBAU [prueba de acceso a la Universidad] sea nacional, o porque no haya fracaso escolar, nos encontramos con estas matem\u00e1ticas socioemocionales. Si lo hicieran a prop\u00f3sito no lo har\u00edan peor\u201d.<\/p>\n\n\n\n<p>La exministra Pastor ha a\u00f1adido: \u201cAlguien ha perdido el norte. Lo importante es aprender Matem\u00e1ticas, Lengua, todas las \u00e1reas del conocimiento.\u00a0<strong>Le pedimos al gobierno que en ese real decreto retire estas cosas que no aportan nada al conocimiento<\/strong>\u00a0y se preocupe de la evaluaci\u00f3n de los ni\u00f1os.\u00a0<strong>Las bobadas no le interesan nada a los espa\u00f1oles<\/strong>\u201d.<\/p>\n\n\n\n<h6 class=\"has-text-align-center wp-block-heading\"><img loading=\"lazy\" decoding=\"async\" height=\"3499\" width=\"4895\" alt=\"El l\u00edder de Vox, Santiago Abascal, en una reciente intervenci\u00f3n en el Congreso de los Diputados.\" src=\"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/7DIVCP3P6NCFLB22H42LUGWMEI.jpg%20420w\">El l\u00edder de Vox, Santiago Abascal, en una reciente intervenci\u00f3n en el Congreso de los Diputados.<\/h6>\n\n\n\n<p>El l\u00edder de Vox, Santiago Abascal, por su lado, ha sido escueto y categ\u00f3rico: \u201c<strong>\u00a1Apartad vuestras manos de nuestros hijos, chusma totalitaria<\/strong>\u201d.<\/p>\n\n\n\n<p>En esta l\u00ednea se pronunci\u00f3 el responsable de la formaci\u00f3n en el Congreso, Joaqu\u00edn Robles, en conversaci\u00f3n con Infobae: \u201cEsta propuesta -que es un borrador y no se puede descartar que el Gobierno d\u00e9 marcha atr\u00e1s-&nbsp;<strong>choca con la Constituci\u00f3n<\/strong>. El art\u00edculo 27.3 dice que los padres tienen la \u00faltima palabra sobre la educaci\u00f3n moral de sus hijos\u201d dentro del sentido com\u00fan y la legalidad.<\/p>\n\n\n\n<p>Robles sostiene que se trata de una nueva \u201cinjerencia del Gobierno\u201d que \u201ccada vez que toca poder pretende transmitir e imponer su ideolog\u00eda a trav\u00e9s de las instituciones que son p\u00fablicas\u201d.<\/p>\n\n\n\n<p>Por su lado, el vicesecretario general de Ciudadanos y portavoz adjunto en el Congreso, Edmundo Bal, ha explicado a Infobae que esta ley es producto \u201cdel sectarismo y la demagogia; de la ideolog\u00eda que se impone sobre la raz\u00f3n\u201d. Recuerda Bal que su formaci\u00f3n se opuso a la Ley Cela\u00e1, que pidi\u00f3 que se tramitara con m\u00e1s cautela y que, sobre todo, se tuviera en cuenta a los expertos. \u201cHemos pedido siempre un pacto de Estado\u201d sobre Educaci\u00f3n. \u201c<strong>No puede ser que haya una ley del PP, otra del PSOE\u2026 Este es el fracaso de nuestro sistema: aportar ideolog\u00eda a la educaci\u00f3n<\/strong>\u201d.<\/p>\n\n\n\n<p>El portavoz de la los liberales considera un \u201cdisparate\u201d la ense\u00f1anza socioemocional de las Matem\u00e1ticas, igual que introducir educaci\u00f3n sexual en las aulas de 0 a 6 a\u00f1os. \u201c<strong>\u00a1De qu\u00e9 estamos hablando! El desarrollo sexual aparece mucho m\u00e1s y tarde<\/strong>\u201d, dice.<\/p>\n\n\n\n<p>La Ley Cela\u00e1 se aprob\u00f3 con el apoyo fundamental de Esquerra Republicana de Catalunya (ERC), \u201ca cambio de introducir el catal\u00e1n como lengua vehicular\u201d en la ense\u00f1anza, desplazando al castellano, recuerda Ciudadanos.<\/p>\n\n\n\n<p>Bal recuerda que algo pasa en el sistema cuando Espa\u00f1a sale en las \u00faltimas posiciones de los informes internacionales sobre niveles educativos. Desde la reinstauraci\u00f3n de la democracia, en 1977, Espa\u00f1a ha aprobado ocho leyes de Educaci\u00f3n diferentes.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Fernando Mas Paradiso &#8211; Infobae<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Desde la oposici\u00f3n, han arreciado las cr\u00edticas por parte del PP, Ciudadanos y Vox<\/p>\n","protected":false},"author":3,"featured_media":4770,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[14],"tags":[1096,823],"ppma_author":[998],"class_list":{"0":"post-4769","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","8":"tag-espana","9":"tag-vox"},"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La nueva Ley de Educaci\u00f3n en Espa\u00f1a propone el \u201cdescubrimiento de la sexualidad\u201d en alumnos de 0 a 6 a\u00f1os - Informatepy.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2022\/2021\/08\/09\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La nueva Ley de Educaci\u00f3n en Espa\u00f1a propone el \u201cdescubrimiento de la sexualidad\u201d en alumnos de 0 a 6 a\u00f1os - Informatepy.com\" \/>\n<meta property=\"og:description\" content=\"Desde la oposici\u00f3n, han arreciado las cr\u00edticas por parte del PP, Ciudadanos y Vox\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2022\/2021\/08\/09\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-09T21:07:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-27T23:38:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/08\/pedro-snchez-espana.jpg?fit=1200%2C675&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:site\" content=\"@InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/08\\\/09\\\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/08\\\/09\\\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/e7c5b605ddfb77041eeddff4d93b26af\"},\"headline\":\"La nueva Ley de Educaci\u00f3n en Espa\u00f1a propone el \u201cdescubrimiento de la sexualidad\u201d en alumnos de 0 a 6 a\u00f1os\",\"datePublished\":\"2021-08-09T21:07:34+00:00\",\"dateModified\":\"2022-09-27T23:38:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/08\\\/09\\\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\\\/\"},\"wordCount\":1100,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/08\\\/09\\\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/pedro-snchez-espana.jpg?fit=1200%2C675&ssl=1\",\"keywords\":[\"espa\u00f1a\",\"vox\"],\"articleSection\":[\"Mundo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/08\\\/09\\\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/08\\\/09\\\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/08\\\/09\\\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\\\/\",\"name\":\"La nueva Ley de Educaci\u00f3n en Espa\u00f1a propone el \u201cdescubrimiento de la sexualidad\u201d en alumnos de 0 a 6 a\u00f1os - Informatepy.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/08\\\/09\\\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/08\\\/09\\\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/pedro-snchez-espana.jpg?fit=1200%2C675&ssl=1\",\"datePublished\":\"2021-08-09T21:07:34+00:00\",\"dateModified\":\"2022-09-27T23:38:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/08\\\/09\\\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/08\\\/09\\\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/08\\\/09\\\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/pedro-snchez-espana.jpg?fit=1200%2C675&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/pedro-snchez-espana.jpg?fit=1200%2C675&ssl=1\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/08\\\/09\\\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La nueva Ley de Educaci\u00f3n en Espa\u00f1a propone el \u201cdescubrimiento de la sexualidad\u201d en alumnos de 0 a 6 a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"name\":\"Informatepy.com\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\",\"name\":\"Informatepy.com\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"width\":589,\"height\":150,\"caption\":\"Informatepy.com\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/InformatePy1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/e7c5b605ddfb77041eeddff4d93b26af\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.pngce0c1b6da06ae20abaff417c2cdeea83\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La nueva Ley de Educaci\u00f3n en Espa\u00f1a propone el \u201cdescubrimiento de la sexualidad\u201d en alumnos de 0 a 6 a\u00f1os - Informatepy.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2022\/2021\/08\/09\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\/","og_locale":"es_ES","og_type":"article","og_title":"La nueva Ley de Educaci\u00f3n en Espa\u00f1a propone el \u201cdescubrimiento de la sexualidad\u201d en alumnos de 0 a 6 a\u00f1os - Informatepy.com","og_description":"Desde la oposici\u00f3n, han arreciado las cr\u00edticas por parte del PP, Ciudadanos y Vox","og_url":"https:\/\/informatepy.com\/2022\/2021\/08\/09\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\/","og_site_name":"Informatepy.com","article_publisher":"https:\/\/www.facebook.com\/InformatePyCom","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2021-08-09T21:07:34+00:00","article_modified_time":"2022-09-27T23:38:20+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/08\/pedro-snchez-espana.jpg?fit=1200%2C675&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_site":"@InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2022\/2021\/08\/09\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/2021\/08\/09\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/e7c5b605ddfb77041eeddff4d93b26af"},"headline":"La nueva Ley de Educaci\u00f3n en Espa\u00f1a propone el \u201cdescubrimiento de la sexualidad\u201d en alumnos de 0 a 6 a\u00f1os","datePublished":"2021-08-09T21:07:34+00:00","dateModified":"2022-09-27T23:38:20+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2021\/08\/09\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\/"},"wordCount":1100,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2021\/08\/09\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/08\/pedro-snchez-espana.jpg?fit=1200%2C675&ssl=1","keywords":["espa\u00f1a","vox"],"articleSection":["Mundo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2022\/2021\/08\/09\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2022\/2021\/08\/09\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\/","url":"https:\/\/informatepy.com\/2022\/2021\/08\/09\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\/","name":"La nueva Ley de Educaci\u00f3n en Espa\u00f1a propone el \u201cdescubrimiento de la sexualidad\u201d en alumnos de 0 a 6 a\u00f1os - Informatepy.com","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2021\/08\/09\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2021\/08\/09\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/08\/pedro-snchez-espana.jpg?fit=1200%2C675&ssl=1","datePublished":"2021-08-09T21:07:34+00:00","dateModified":"2022-09-27T23:38:20+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2022\/2021\/08\/09\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2022\/2021\/08\/09\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/2021\/08\/09\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/08\/pedro-snchez-espana.jpg?fit=1200%2C675&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/08\/pedro-snchez-espana.jpg?fit=1200%2C675&ssl=1","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2022\/2021\/08\/09\/la-nueva-ley-de-educacion-en-espana-propone-el-descubrimiento-de-la-sexualidad-entre-alumnos-de-0-a-6-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2022\/"},{"@type":"ListItem","position":2,"name":"La nueva Ley de Educaci\u00f3n en Espa\u00f1a propone el \u201cdescubrimiento de la sexualidad\u201d en alumnos de 0 a 6 a\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2022\/#website","url":"https:\/\/informatepy.com\/2022\/","name":"Informatepy.com","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2022\/#organization","name":"Informatepy.com","url":"https:\/\/informatepy.com\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","width":589,"height":150,"caption":"Informatepy.com"},"image":{"@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/InformatePy1"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/e7c5b605ddfb77041eeddff4d93b26af","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.pngce0c1b6da06ae20abaff417c2cdeea83","url":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2022\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/08\/pedro-snchez-espana.jpg?fit=1200%2C675&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"authors":[{"term_id":998,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/4769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/comments?post=4769"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/4769\/revisions"}],"predecessor-version":[{"id":12789,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/4769\/revisions\/12789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media\/4770"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media?parent=4769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/categories?post=4769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/tags?post=4769"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/ppma_author?post=4769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}