{"id":2730,"date":"2021-04-17T16:17:05","date_gmt":"2021-04-17T16:17:05","guid":{"rendered":"http:\/\/informatepy.com\/2022\/2021\/04\/17\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\/"},"modified":"2022-09-27T23:18:22","modified_gmt":"2022-09-27T23:18:22","slug":"neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2022\/2021\/04\/17\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\/","title":{"rendered":"Neymar mantiene los 142 puestos de trabajo de su instituto, cerrado desde hace un a\u00f1o por la pandemia"},"content":{"rendered":"\n<p><strong>Neymar Junior no es ajeno a la pandemia que est\u00e1 asolando al planeta y golpeando con fuerza a Brasil.&nbsp;<\/strong>El Instituto Neymar Jr, que ha atendido a unos 3.000 ni\u00f1os y adolescentes necesitados en Praia Grande y que es gestionado por la familia de la estrella del PSG, lleva cerrado desde marzo de 2020 por el coronavirus. Sin embargo, ninguno de sus trabajadores se ha quedado atr\u00e1s.<\/p>\n\n\n\n<p><strong>Y es que Neymar ha mantenido los puestos de trabajo de las 142 personas que trabajan en su instituto.&nbsp;<\/strong>El brasile\u00f1o est\u00e1 pagando \u00edntegramente el salario y manteniendo la cobertura sanitaria de sus empleados y colaboradores, con un coste de 600.000 reales mensuales. La idea es mantener su estructura hasta que termine la crisis sanitaria y poder despu\u00e9s retomar su actividad como antes de la pandemia.<\/p>\n\n\n\n<p>\u00abEl Instituto ha cumplido un a\u00f1o cerrado por la crisis de la Covid-19. Mi familia y yo estamos manteniendo toda la estructura, con 142 empleados, que est\u00e1n recibiendo sus salarios y beneficios en su totalidad. Lo hemos hecho con nuestros propios recursos\u00bb, asegur\u00f3 el padre de Neymar, que&nbsp;<strong>hace un a\u00f1o puso el Instituto a disposici\u00f3n de las autoridades brasile\u00f1as<\/strong>.<\/p>\n\n\n\n<p><strong><em>\u00abLos empleos y los salarios de las personas que trabajan en nuestro Instituto est\u00e1n asegurados independientemente de lo que dure la pandemia. Adem\u00e1s, pongo a disposici\u00f3n de las autoridades, si fuera necesario, las instalaciones de nuestro instituto. Pido a todo el mundo que reforcemos nuestros compromisos y nos quedemos en casa para combatir al coronavius\u00bb<\/em><\/strong>, asegur\u00f3 Neymar Pai entonces.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Revista Marca<\/h6>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Instituto Neymar Jr. atendi\u00f3 a unos 3.000 ni\u00f1os y adolescentes necesitados en Praia Grande<\/p>\n","protected":false},"author":3,"featured_media":1123,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[24],"tags":[440],"ppma_author":[998],"class_list":{"0":"post-2730","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deportes","8":"tag-neymar"},"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neymar mantiene los 142 puestos de trabajo de su instituto, cerrado desde hace un a\u00f1o por la pandemia - Informatepy.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2022\/2021\/04\/17\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neymar mantiene los 142 puestos de trabajo de su instituto, cerrado desde hace un a\u00f1o por la pandemia - Informatepy.com\" \/>\n<meta property=\"og:description\" content=\"El Instituto Neymar Jr. atendi\u00f3 a unos 3.000 ni\u00f1os y adolescentes necesitados en Praia Grande\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2022\/2021\/04\/17\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-17T16:17:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-27T23:18:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/02\/Neymar-PSG1.jpg?fit=750%2C422&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:site\" content=\"@InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/04\\\/17\\\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/04\\\/17\\\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/e7c5b605ddfb77041eeddff4d93b26af\"},\"headline\":\"Neymar mantiene los 142 puestos de trabajo de su instituto, cerrado desde hace un a\u00f1o por la pandemia\",\"datePublished\":\"2021-04-17T16:17:05+00:00\",\"dateModified\":\"2022-09-27T23:18:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/04\\\/17\\\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\\\/\"},\"wordCount\":282,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/04\\\/17\\\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Neymar-PSG1.jpg?fit=750%2C422&ssl=1\",\"keywords\":[\"neymar\"],\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/04\\\/17\\\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/04\\\/17\\\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/04\\\/17\\\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\\\/\",\"name\":\"Neymar mantiene los 142 puestos de trabajo de su instituto, cerrado desde hace un a\u00f1o por la pandemia - Informatepy.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/04\\\/17\\\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/04\\\/17\\\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Neymar-PSG1.jpg?fit=750%2C422&ssl=1\",\"datePublished\":\"2021-04-17T16:17:05+00:00\",\"dateModified\":\"2022-09-27T23:18:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/04\\\/17\\\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/04\\\/17\\\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/04\\\/17\\\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Neymar-PSG1.jpg?fit=750%2C422&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Neymar-PSG1.jpg?fit=750%2C422&ssl=1\",\"width\":750,\"height\":422},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/04\\\/17\\\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neymar mantiene los 142 puestos de trabajo de su instituto, cerrado desde hace un a\u00f1o por la pandemia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"name\":\"Informatepy.com\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\",\"name\":\"Informatepy.com\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"width\":589,\"height\":150,\"caption\":\"Informatepy.com\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/InformatePy1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/e7c5b605ddfb77041eeddff4d93b26af\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.pngce0c1b6da06ae20abaff417c2cdeea83\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neymar mantiene los 142 puestos de trabajo de su instituto, cerrado desde hace un a\u00f1o por la pandemia - Informatepy.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2022\/2021\/04\/17\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\/","og_locale":"es_ES","og_type":"article","og_title":"Neymar mantiene los 142 puestos de trabajo de su instituto, cerrado desde hace un a\u00f1o por la pandemia - Informatepy.com","og_description":"El Instituto Neymar Jr. atendi\u00f3 a unos 3.000 ni\u00f1os y adolescentes necesitados en Praia Grande","og_url":"https:\/\/informatepy.com\/2022\/2021\/04\/17\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\/","og_site_name":"Informatepy.com","article_publisher":"https:\/\/www.facebook.com\/InformatePyCom","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2021-04-17T16:17:05+00:00","article_modified_time":"2022-09-27T23:18:22+00:00","og_image":[{"width":750,"height":422,"url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/02\/Neymar-PSG1.jpg?fit=750%2C422&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_site":"@InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2022\/2021\/04\/17\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/2021\/04\/17\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/e7c5b605ddfb77041eeddff4d93b26af"},"headline":"Neymar mantiene los 142 puestos de trabajo de su instituto, cerrado desde hace un a\u00f1o por la pandemia","datePublished":"2021-04-17T16:17:05+00:00","dateModified":"2022-09-27T23:18:22+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2021\/04\/17\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\/"},"wordCount":282,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2021\/04\/17\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/02\/Neymar-PSG1.jpg?fit=750%2C422&ssl=1","keywords":["neymar"],"articleSection":["Deportes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2022\/2021\/04\/17\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2022\/2021\/04\/17\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\/","url":"https:\/\/informatepy.com\/2022\/2021\/04\/17\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\/","name":"Neymar mantiene los 142 puestos de trabajo de su instituto, cerrado desde hace un a\u00f1o por la pandemia - Informatepy.com","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2021\/04\/17\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2021\/04\/17\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/02\/Neymar-PSG1.jpg?fit=750%2C422&ssl=1","datePublished":"2021-04-17T16:17:05+00:00","dateModified":"2022-09-27T23:18:22+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2022\/2021\/04\/17\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2022\/2021\/04\/17\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/2021\/04\/17\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/02\/Neymar-PSG1.jpg?fit=750%2C422&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/02\/Neymar-PSG1.jpg?fit=750%2C422&ssl=1","width":750,"height":422},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2022\/2021\/04\/17\/neymar-mantiene-los-142-puestos-de-trabajo-de-su-instituto-cerrado-desde-hace-un-ano-por-la-pandemia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2022\/"},{"@type":"ListItem","position":2,"name":"Neymar mantiene los 142 puestos de trabajo de su instituto, cerrado desde hace un a\u00f1o por la pandemia"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2022\/#website","url":"https:\/\/informatepy.com\/2022\/","name":"Informatepy.com","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2022\/#organization","name":"Informatepy.com","url":"https:\/\/informatepy.com\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","width":589,"height":150,"caption":"Informatepy.com"},"image":{"@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/InformatePy1"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/e7c5b605ddfb77041eeddff4d93b26af","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.pngce0c1b6da06ae20abaff417c2cdeea83","url":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2022\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/02\/Neymar-PSG1.jpg?fit=750%2C422&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"authors":[{"term_id":998,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/2730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/comments?post=2730"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/2730\/revisions"}],"predecessor-version":[{"id":3799,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/2730\/revisions\/3799"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media\/1123"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media?parent=2730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/categories?post=2730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/tags?post=2730"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/ppma_author?post=2730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}