{"id":23601,"date":"2024-02-21T03:53:00","date_gmt":"2024-02-21T06:53:00","guid":{"rendered":"https:\/\/informatepy.com\/2022\/?p=23601"},"modified":"2024-02-20T18:04:40","modified_gmt":"2024-02-20T21:04:40","slug":"putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2022\/2024\/02\/21\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\/","title":{"rendered":"Putin: En Rusia hay bastante tolerancia con la homosexualidad, pero, \u00aben cuanto a los ni\u00f1os, no los toquen\u00bb"},"content":{"rendered":"\n<p class=\"has-text-align-justify\">El presidente de Rusia, <strong>Vladimir Putin<\/strong>, ha asegurado este martes que existe <em><strong>\u00abbastante\u00bb<\/strong><\/em> tolerancia en el pa\u00eds con los homosexuales, aunque no la consideran una orientaci\u00f3n correcta.<\/p>\n\n\n\n<p class=\"has-text-align-justify\"><strong><em>\u00abSomos bastante tolerantes con las personas de orientaci\u00f3n sexual no tradicional. Simplemente no insistimos y no creemos que sea correcto hacerlo\u00bb<\/em><\/strong>, afirm\u00f3 el mandatario ruso.<\/p>\n\n\n\n<p class=\"has-text-align-justify\"><strong><em>\u00abQue cada uno viva como quiera. Nadie los limita en nada, pero, en cuanto a los ni\u00f1os, no los toquen\u00bb <\/em><\/strong>agreg\u00f3 Putin.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Rusia, Vladimir Putin, ha asegurado este martes que existe \u00abbastante\u00bb tolerancia en el pa\u00eds con los homosexuales, aunque no la consideran una orientaci\u00f3n correcta. \u00abSomos bastante tolerantes con las personas de orientaci\u00f3n sexual no tradicional. Simplemente no insistimos y no creemos que sea correcto hacerlo\u00bb, afirm\u00f3 el mandatario ruso. \u00abQue cada uno [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2138,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":false,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[14],"tags":[871,1043,990,183,516],"ppma_author":[1037],"class_list":{"0":"post-23601","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mundo","8":"tag-destacada","9":"tag-lgbt","10":"tag-putin","11":"tag-rusia","12":"tag-vladimir-putin"},"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Putin: En Rusia hay bastante tolerancia con la homosexualidad, pero, &quot;en cuanto a los ni\u00f1os, no los toquen&quot; - Informatepy.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2022\/2024\/02\/21\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Putin: En Rusia hay bastante tolerancia con la homosexualidad, pero, &quot;en cuanto a los ni\u00f1os, no los toquen&quot; - Informatepy.com\" \/>\n<meta property=\"og:description\" content=\"El presidente de Rusia, Vladimir Putin, ha asegurado este martes que existe \u00abbastante\u00bb tolerancia en el pa\u00eds con los homosexuales, aunque no la consideran una orientaci\u00f3n correcta. \u00abSomos bastante tolerantes con las personas de orientaci\u00f3n sexual no tradicional. Simplemente no insistimos y no creemos que sea correcto hacerlo\u00bb, afirm\u00f3 el mandatario ruso. \u00abQue cada uno [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2022\/2024\/02\/21\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-21T06:53:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/01\/vladimir-putin.jpg?fit=1000%2C541&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"541\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:site\" content=\"@InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2024\\\/02\\\/21\\\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2024\\\/02\\\/21\\\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/e7c5b605ddfb77041eeddff4d93b26af\"},\"headline\":\"Putin: En Rusia hay bastante tolerancia con la homosexualidad, pero, \u00aben cuanto a los ni\u00f1os, no los toquen\u00bb\",\"datePublished\":\"2024-02-21T06:53:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2024\\\/02\\\/21\\\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\\\/\"},\"wordCount\":97,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2024\\\/02\\\/21\\\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/vladimir-putin.jpg?fit=1000%2C541&ssl=1\",\"keywords\":[\"destacada\",\"lgbt\",\"putin\",\"rusia\",\"vladimir putin\"],\"articleSection\":[\"Mundo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2024\\\/02\\\/21\\\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2024\\\/02\\\/21\\\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2024\\\/02\\\/21\\\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\\\/\",\"name\":\"Putin: En Rusia hay bastante tolerancia con la homosexualidad, pero, \\\"en cuanto a los ni\u00f1os, no los toquen\\\" - Informatepy.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2024\\\/02\\\/21\\\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2024\\\/02\\\/21\\\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/vladimir-putin.jpg?fit=1000%2C541&ssl=1\",\"datePublished\":\"2024-02-21T06:53:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2024\\\/02\\\/21\\\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2024\\\/02\\\/21\\\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2024\\\/02\\\/21\\\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/vladimir-putin.jpg?fit=1000%2C541&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/vladimir-putin.jpg?fit=1000%2C541&ssl=1\",\"width\":1000,\"height\":541},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2024\\\/02\\\/21\\\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Putin: En Rusia hay bastante tolerancia con la homosexualidad, pero, \u00aben cuanto a los ni\u00f1os, no los toquen\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"name\":\"Informatepy.com\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\",\"name\":\"Informatepy.com\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"width\":589,\"height\":150,\"caption\":\"Informatepy.com\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/InformatePy1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/e7c5b605ddfb77041eeddff4d93b26af\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.pngce0c1b6da06ae20abaff417c2cdeea83\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Putin: En Rusia hay bastante tolerancia con la homosexualidad, pero, \"en cuanto a los ni\u00f1os, no los toquen\" - Informatepy.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2022\/2024\/02\/21\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\/","og_locale":"es_ES","og_type":"article","og_title":"Putin: En Rusia hay bastante tolerancia con la homosexualidad, pero, \"en cuanto a los ni\u00f1os, no los toquen\" - Informatepy.com","og_description":"El presidente de Rusia, Vladimir Putin, ha asegurado este martes que existe \u00abbastante\u00bb tolerancia en el pa\u00eds con los homosexuales, aunque no la consideran una orientaci\u00f3n correcta. \u00abSomos bastante tolerantes con las personas de orientaci\u00f3n sexual no tradicional. Simplemente no insistimos y no creemos que sea correcto hacerlo\u00bb, afirm\u00f3 el mandatario ruso. \u00abQue cada uno [&hellip;]","og_url":"https:\/\/informatepy.com\/2022\/2024\/02\/21\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\/","og_site_name":"Informatepy.com","article_publisher":"https:\/\/www.facebook.com\/InformatePyCom","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2024-02-21T06:53:00+00:00","og_image":[{"width":1000,"height":541,"url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/01\/vladimir-putin.jpg?fit=1000%2C541&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_site":"@InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2022\/2024\/02\/21\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/2024\/02\/21\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/e7c5b605ddfb77041eeddff4d93b26af"},"headline":"Putin: En Rusia hay bastante tolerancia con la homosexualidad, pero, \u00aben cuanto a los ni\u00f1os, no los toquen\u00bb","datePublished":"2024-02-21T06:53:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2024\/02\/21\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\/"},"wordCount":97,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2024\/02\/21\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/01\/vladimir-putin.jpg?fit=1000%2C541&ssl=1","keywords":["destacada","lgbt","putin","rusia","vladimir putin"],"articleSection":["Mundo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2022\/2024\/02\/21\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2022\/2024\/02\/21\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\/","url":"https:\/\/informatepy.com\/2022\/2024\/02\/21\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\/","name":"Putin: En Rusia hay bastante tolerancia con la homosexualidad, pero, \"en cuanto a los ni\u00f1os, no los toquen\" - Informatepy.com","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2024\/02\/21\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2024\/02\/21\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/01\/vladimir-putin.jpg?fit=1000%2C541&ssl=1","datePublished":"2024-02-21T06:53:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2022\/2024\/02\/21\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2022\/2024\/02\/21\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/2024\/02\/21\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/01\/vladimir-putin.jpg?fit=1000%2C541&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/01\/vladimir-putin.jpg?fit=1000%2C541&ssl=1","width":1000,"height":541},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2022\/2024\/02\/21\/putin-en-rusia-hay-bastante-tolerancia-con-la-homosexualidad-pero-en-cuanto-a-los-ninos-no-los-toquen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2022\/"},{"@type":"ListItem","position":2,"name":"Putin: En Rusia hay bastante tolerancia con la homosexualidad, pero, \u00aben cuanto a los ni\u00f1os, no los toquen\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2022\/#website","url":"https:\/\/informatepy.com\/2022\/","name":"Informatepy.com","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2022\/#organization","name":"Informatepy.com","url":"https:\/\/informatepy.com\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","width":589,"height":150,"caption":"Informatepy.com"},"image":{"@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/InformatePy1"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/e7c5b605ddfb77041eeddff4d93b26af","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.pngce0c1b6da06ae20abaff417c2cdeea83","url":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2022\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/01\/vladimir-putin.jpg?fit=1000%2C541&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"authors":[{"term_id":1037,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/23601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/comments?post=23601"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/23601\/revisions"}],"predecessor-version":[{"id":23602,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/23601\/revisions\/23602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media\/2138"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media?parent=23601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/categories?post=23601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/tags?post=23601"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/ppma_author?post=23601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}