{"id":23528,"date":"2024-02-15T04:33:00","date_gmt":"2024-02-15T07:33:00","guid":{"rendered":"https:\/\/informatepy.com\/2022\/?p=23528"},"modified":"2024-02-15T07:11:31","modified_gmt":"2024-02-15T10:11:31","slug":"opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2022\/2024\/02\/15\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\/","title":{"rendered":"Opositores prometen unirse luego de la destituci\u00f3n de Kattya Gonz\u00e1lez"},"content":{"rendered":"\n<p class=\"has-text-align-justify\">Finalizada la sesi\u00f3n extraordinaria de la C\u00e1mara de Senadores y ya con Kattya Gonz\u00e1lez destituida, los parlamentarios opositores al gobierno afirmaron que es tiempo de dejar de lado sus diferencias y unirse.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">La senadora Celeste Amarilla afirm\u00f3 frente a los medios de comunicaci\u00f3n, que la situaci\u00f3n les hizo ver <strong><em>\u00abla necesidad de dejar de lado el vedetismo, estrellitas, etc, me incluyo, comienzo por m\u00ed y de cuidarnos entre los que hacemos oposici\u00f3n\u00bb<\/em><\/strong>.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Adem\u00e1s, la senadora liberal agreg\u00f3 que <strong><em>\u00abEstamos conformando, estamos con la voluntad de fortalecer el bloque opositor de diputados, senadores, los dos gobernadores del Partido Liberal y el centenar de intendentes que tenemos esparcidos en toda la Rep\u00fablica, y de decirle al gobierno estos somos\u00bb<\/em><\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfKattya Gonz\u00e1lez candidata a presidente?<\/h3>\n\n\n\n<p class=\"has-text-align-justify\">En una entrevista con Radio \u00d1anduti, el diputado <strong>Ra\u00fal Ben\u00edtez<\/strong>, en referencia a la p\u00e9rdida de investidura de la senadora Kattya Gonz\u00e1lez, sostuvo que la democracia est\u00e1 en peligro, aunque puntualiz\u00f3 que esta maniobra del Partido Colorado podr\u00eda beneficiar el futuro pol\u00edtico de la senadora. <strong><em>\u00abYo creo que a Kattya Gonz\u00e1lez la acaban de hacer candidata a presidenta de la Rep\u00fablica para el 2028\u201d<\/em><\/strong>, asegur\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finalizada la sesi\u00f3n extraordinaria de la C\u00e1mara de Senadores y ya con Kattya Gonz\u00e1lez destituida, los parlamentarios opositores al gobierno afirmaron que es tiempo de dejar de lado sus diferencias y unirse. La senadora Celeste Amarilla afirm\u00f3 frente a los medios de comunicaci\u00f3n, que la situaci\u00f3n les hizo ver \u00abla necesidad de dejar de lado [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":23531,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":false,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[18],"tags":[422,871,585,2097],"ppma_author":[1037],"class_list":{"0":"post-23528","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nacionales","8":"tag-celeste-amarilla","9":"tag-destacada","10":"tag-kattya-gonzalez","11":"tag-raul-benitez"},"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Opositores prometen unirse luego de la destituci\u00f3n de Kattya Gonz\u00e1lez - Informatepy.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2022\/2024\/02\/15\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Opositores prometen unirse luego de la destituci\u00f3n de Kattya Gonz\u00e1lez - Informatepy.com\" \/>\n<meta property=\"og:description\" content=\"Finalizada la sesi\u00f3n extraordinaria de la C\u00e1mara de Senadores y ya con Kattya Gonz\u00e1lez destituida, los parlamentarios opositores al gobierno afirmaron que es tiempo de dejar de lado sus diferencias y unirse. La senadora Celeste Amarilla afirm\u00f3 frente a los medios de comunicaci\u00f3n, que la situaci\u00f3n les hizo ver \u00abla necesidad de dejar de lado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2022\/2024\/02\/15\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-15T07:33:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-15T10:11:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2024\/02\/legisladores-oposicion.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"802\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:site\" content=\"@InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2024\\\/02\\\/15\\\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2024\\\/02\\\/15\\\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/e7c5b605ddfb77041eeddff4d93b26af\"},\"headline\":\"Opositores prometen unirse luego de la destituci\u00f3n de Kattya Gonz\u00e1lez\",\"datePublished\":\"2024-02-15T07:33:00+00:00\",\"dateModified\":\"2024-02-15T10:11:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2024\\\/02\\\/15\\\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\\\/\"},\"wordCount\":215,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2024\\\/02\\\/15\\\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/legisladores-oposicion.jpg?fit=1280%2C802&ssl=1\",\"keywords\":[\"celeste amarilla\",\"destacada\",\"kattya gonzalez\",\"raul benitez\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2024\\\/02\\\/15\\\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2024\\\/02\\\/15\\\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2024\\\/02\\\/15\\\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\\\/\",\"name\":\"Opositores prometen unirse luego de la destituci\u00f3n de Kattya Gonz\u00e1lez - Informatepy.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2024\\\/02\\\/15\\\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2024\\\/02\\\/15\\\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/legisladores-oposicion.jpg?fit=1280%2C802&ssl=1\",\"datePublished\":\"2024-02-15T07:33:00+00:00\",\"dateModified\":\"2024-02-15T10:11:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2024\\\/02\\\/15\\\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2024\\\/02\\\/15\\\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2024\\\/02\\\/15\\\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/legisladores-oposicion.jpg?fit=1280%2C802&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/legisladores-oposicion.jpg?fit=1280%2C802&ssl=1\",\"width\":1280,\"height\":802,\"caption\":\"Foto de archivo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2024\\\/02\\\/15\\\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Opositores prometen unirse luego de la destituci\u00f3n de Kattya Gonz\u00e1lez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"name\":\"Informatepy.com\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\",\"name\":\"Informatepy.com\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"width\":589,\"height\":150,\"caption\":\"Informatepy.com\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/InformatePy1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/e7c5b605ddfb77041eeddff4d93b26af\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.pngce0c1b6da06ae20abaff417c2cdeea83\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Opositores prometen unirse luego de la destituci\u00f3n de Kattya Gonz\u00e1lez - Informatepy.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2022\/2024\/02\/15\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\/","og_locale":"es_ES","og_type":"article","og_title":"Opositores prometen unirse luego de la destituci\u00f3n de Kattya Gonz\u00e1lez - Informatepy.com","og_description":"Finalizada la sesi\u00f3n extraordinaria de la C\u00e1mara de Senadores y ya con Kattya Gonz\u00e1lez destituida, los parlamentarios opositores al gobierno afirmaron que es tiempo de dejar de lado sus diferencias y unirse. La senadora Celeste Amarilla afirm\u00f3 frente a los medios de comunicaci\u00f3n, que la situaci\u00f3n les hizo ver \u00abla necesidad de dejar de lado [&hellip;]","og_url":"https:\/\/informatepy.com\/2022\/2024\/02\/15\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\/","og_site_name":"Informatepy.com","article_publisher":"https:\/\/www.facebook.com\/InformatePyCom","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2024-02-15T07:33:00+00:00","article_modified_time":"2024-02-15T10:11:31+00:00","og_image":[{"width":1280,"height":802,"url":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2024\/02\/legisladores-oposicion.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_site":"@InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2022\/2024\/02\/15\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/2024\/02\/15\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/e7c5b605ddfb77041eeddff4d93b26af"},"headline":"Opositores prometen unirse luego de la destituci\u00f3n de Kattya Gonz\u00e1lez","datePublished":"2024-02-15T07:33:00+00:00","dateModified":"2024-02-15T10:11:31+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2024\/02\/15\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\/"},"wordCount":215,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2024\/02\/15\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2024\/02\/legisladores-oposicion.jpg?fit=1280%2C802&ssl=1","keywords":["celeste amarilla","destacada","kattya gonzalez","raul benitez"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2022\/2024\/02\/15\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2022\/2024\/02\/15\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\/","url":"https:\/\/informatepy.com\/2022\/2024\/02\/15\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\/","name":"Opositores prometen unirse luego de la destituci\u00f3n de Kattya Gonz\u00e1lez - Informatepy.com","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2024\/02\/15\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2024\/02\/15\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2024\/02\/legisladores-oposicion.jpg?fit=1280%2C802&ssl=1","datePublished":"2024-02-15T07:33:00+00:00","dateModified":"2024-02-15T10:11:31+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2022\/2024\/02\/15\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2022\/2024\/02\/15\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/2024\/02\/15\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2024\/02\/legisladores-oposicion.jpg?fit=1280%2C802&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2024\/02\/legisladores-oposicion.jpg?fit=1280%2C802&ssl=1","width":1280,"height":802,"caption":"Foto de archivo"},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2022\/2024\/02\/15\/opositores-prometen-unirse-luego-de-la-destitucion-de-kattya-gonzalez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2022\/"},{"@type":"ListItem","position":2,"name":"Opositores prometen unirse luego de la destituci\u00f3n de Kattya Gonz\u00e1lez"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2022\/#website","url":"https:\/\/informatepy.com\/2022\/","name":"Informatepy.com","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2022\/#organization","name":"Informatepy.com","url":"https:\/\/informatepy.com\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","width":589,"height":150,"caption":"Informatepy.com"},"image":{"@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/InformatePy1"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/e7c5b605ddfb77041eeddff4d93b26af","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.pngce0c1b6da06ae20abaff417c2cdeea83","url":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2022\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2024\/02\/legisladores-oposicion.jpg?fit=1280%2C802&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"authors":[{"term_id":1037,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/23528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/comments?post=23528"}],"version-history":[{"count":2,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/23528\/revisions"}],"predecessor-version":[{"id":23530,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/23528\/revisions\/23530"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media\/23531"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media?parent=23528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/categories?post=23528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/tags?post=23528"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/ppma_author?post=23528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}