{"id":22334,"date":"2023-11-26T04:04:00","date_gmt":"2023-11-26T07:04:00","guid":{"rendered":"https:\/\/informatepy.com\/2022\/?p=22334"},"modified":"2023-11-26T08:43:16","modified_gmt":"2023-11-26T11:43:16","slug":"todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2022\/2023\/11\/26\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\/","title":{"rendered":"Todo es vanidad, hasta que llega la hora de la verdad"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">Mi finado amigo y muy le\u00eddo Dr. Henry Cueppens me dijo hace a\u00f1os que Nicol\u00e1s de Maquiavelo se inspir\u00f3 en el libro b\u00edblico de Eclesiast\u00e9s para escribir su c\u00e9lebre obra <em>\u201cEl Pr\u00edncipe\u201d.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Me sorprend\u00ed, aunque luego pens\u00e9 que no ser\u00eda raro debido a que el primero lo escribi\u00f3 nada m\u00e1s y nada menos que el rey m\u00e1s sabio de la historia: Salom\u00f3n.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Confieso que este texto es mi preferido del Antiguo Testamento mientras que la ep\u00edstola a los Romanos de Pablo ap\u00f3stol del Nuevo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y ustedes no saben nada.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Vanidad de vanidades, dijo el Predicador, vanidad de vanidades, todo es vanidad<\/p><\/blockquote><\/figure>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Me van a disculpar, pero esto me recuerda a lo que me repet\u00eda una y mil veces Edgardo Villalba Vichini cuando nos cruz\u00e1bamos todos los d\u00edas en el estudio de canal 9: <em><strong>\u201cHola Ra\u00fal, todo es bola, no te olvides, todo es bola, desde la ra\u00edz, todo bola\u201d.<\/strong><\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Pongamos la situaci\u00f3n de la bolaterapia en el contexto de la conducta humana en general, porque los edificios que se construyen en ciudad capital, por ejemplo, son de verdad, los podemos ver, palpar y usufructuar por m\u00e1s que la mayor\u00eda sean gigantes mausoleos inhabitados. No obstante, a la filosof\u00eda criolla de Villalba Vichini sumo la universal de Frederick Nietzsche: <strong><em>\u201cLa mentira m\u00e1s com\u00fan es aquella con la que las personas se enga\u00f1an a s\u00ed mismas\u201d.<\/em><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">En el libro de Eclesiast\u00e9s se lee tambi\u00e9n, en el cap\u00edtulo tres, que todo tiene su tiempo y todo lo que se quiere debajo del cielo tiene su hora.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Creo que estamos viviendo un tiempo fabuloso en el cual toda vanidad comienza a resquebrajarse gracias al soplo muy potente de un viento que ech\u00f3 m\u00e1scaras y disfraces de casi toda la humanidad para que se vea de qu\u00e9 est\u00e1 hecha. No solo la gente com\u00fan, tambi\u00e9n las instituciones que nos rigen a nivel nacional e internacional han quedado al desnudo mostrando sus rostros horrorosos y cuerpos de bestia.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">La gran iron\u00eda es que este viento arrasador fue generado por la <em>plandemia <\/em>genocida primeramente y ahora por la guerra en Israel.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Es realmente sorprendente c\u00f3mo estos hechos pusieron y ponen a prueba a casi todo el mundo en cuanto al uso de la raz\u00f3n y manifestaci\u00f3n de sus verdaderos sentimientos disimulados por la hipocres\u00eda en el traj\u00edn diario de la vida sobre el escenario de lo cotidiano.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Se puede colegir entonces que, mediante estos episodios de trascendencia mundial, estamos viviendo en tiempos del purete y viendo el verdadero entramado de las cosas, los aut\u00e9nticos sentimientos de los seres humanos, son situaciones que rompieron moldes usuales y tradicionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estamos al desnudo y mi pene est\u00e1 circuncidado.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Ahora podemos notar con toda claridad el verdadero odio que existe en el mundo, t\u00e9rmino tan cacareado por sodomitas y su coro de progresistas, incluso por empresas trasnacionales como Burger King y Starbucks, militantes a nivel nacional de la repugnante causa colorinche.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Tambi\u00e9n se puede ver en todo el planeta la verdadera fobia, t\u00e9rmino muy utilizado nuevamente por homosexuales y aliades para victimizarse y pretender que su degenero sea tomado como una simple opci\u00f3n sexual cuando que son unos anormales y crueles asesinos en potencia.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Evidentemente esto no es nuevo en el mundo, la historia nos ense\u00f1a que han estado presente entre la gente desde siempre, no solo los putos, si no el odio y las fobias.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Por su parte, est\u00e1n las desgraciadas, falsas, rid\u00edculas, pat\u00e9ticas, mediocres, cobardes y est\u00fapidas autodenominadas \u201cempoderadas\u201d. Para colmo, como si no bastase, la mayor\u00eda de ellas ni siquiera son atractivas, menos a\u00fan femeninas y en muchos casos repulsivas.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Sin duda el feminismo y el machismo son la misma mierda con distintos sexos, pero el primero no tiene nada de femenino, al contrario, y el feminismo de g\u00e9nero es una fuerza envidiosa y destructora de la femineidad. Sus militantes destilan un odio brutal porque nadie las quiere coger, pero no las vamos a coger igual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En lenguaje com\u00fan y corriente son una partida de mal cogidas por incogibles.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">La plandemia, hoy harto descubierta en su verdadera naturaleza diab\u00f3lica, genocida y criminal, de lesa humanidad, demostr\u00f3 el esp\u00edritu borrego y cobarde de la mayor\u00eda de los habitantes de la Tierra, una humanidad llena de dioses falsos que a la hora de la verdad no sirvieron para un carajo. Se not\u00f3 lo que dijo Albert Einstein de la gente, que su estupidez es permanente y por m\u00e1s t\u00edtulos acad\u00e9micos que tengas pod\u00e9s ser un perfecto idiota. Hoy v\u00e9anse los vacunados que est\u00e1n muriendo a diestra y siniestra. Vivir en negaci\u00f3n no salvar\u00e1 sus vidas, todo lo contrario, pueden morir ma\u00f1ana.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">La atroz, cobarde y bestial masacre del 7\/10\/23 por parte de excrementos humanos organizados como grupo terrorista, electos por el tan victimizado mal llamado pueblo palestino, Hamas, hizo flotar el esti\u00e9rcol humano en casi todo el planeta mediante manifestaciones multitudinarias de verdadero odio y fobia a los jud\u00edos, nada nuevo, nada raro, solo que esta vez, este mundo de mierda lleno de odio irracional al pueblo elegido va a pagar las consecuencias, no ser\u00e1 gratis como cuando hicieron la vista gorda con el Holocausto, cr\u00e9anme gente, este es el purete y m\u00e1s vale ubicarse del lado correcto porque estar contra Israel es oponerse y enfrentarse al Dios verdadero, Jehov\u00e1 de los Ej\u00e9rcitos.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">El sesgo y la negaci\u00f3n sobre la barbaridad de los musulmanes como la negaci\u00f3n de la plandemia terminar\u00e1 por acabarlos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No se debe tolerar la intolerancia porque si no esto es lo que suceder\u00e1;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Primero vinieron por los comunistas, y guard\u00e9 silencio porque no era comunista. Luego vinieron por los sindicalistas, y no habl\u00e9 porque no era sindicalista. Luego vinieron por los jud\u00edos, y no dije nada porque no era jud\u00edo. Luego vinieron por m\u00ed, y para entonces ya no quedaba nadie que hablara en mi nombre<\/p><cite>Pastor luterano alem\u00e1n Martin Niem\u00f6ller sobre el r\u00e9gimen nazi.<\/cite><\/blockquote><\/figure>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Por \u00faltimo, un toque sensual entre tanta tragedia, se trata de verdaderas empoderadas, bellas, atractivas, esbeltas, valientes, con armas de guerra en mano y vestidas en sus respectivos uniformes de combate yendo a la guerra, las soldados israel\u00edes, quienes despertaron la admiraci\u00f3n y el deseo de todo aqu\u00e9l que se precie de ser var\u00f3n.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Hasta aqu\u00ed mis tibios olivos silvestres, procuren ser injertados en el tronco de las ramas naturales y s\u00e1lvense, porque la salvaci\u00f3n no viene de las vacunas, mal que les pese, escrito est\u00e1, viene de los jud\u00edos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Te amo Israel, por siempre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mi finado amigo y muy le\u00eddo Dr. Henry Cueppens me dijo hace a\u00f1os que Nicol\u00e1s de Maquiavelo se inspir\u00f3 en el libro b\u00edblico de Eclesiast\u00e9s para escribir su c\u00e9lebre obra \u201cEl Pr\u00edncipe\u201d. Me sorprend\u00ed, aunque luego pens\u00e9 que no ser\u00eda raro debido a que el primero lo escribi\u00f3 nada m\u00e1s y nada menos que el [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":22335,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":false,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[92],"tags":[871,480,567,789],"ppma_author":[1039],"class_list":["post-22334","post","type-post","status-publish","format-standard","has-post-thumbnail","category-analisis","tag-destacada","tag-palestina","tag-terrorismo","tag-terrorismo-islamico"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Todo es vanidad, hasta que llega la hora de la verdad - Informatepy.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2022\/2023\/11\/26\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Todo es vanidad, hasta que llega la hora de la verdad - Informatepy.com\" \/>\n<meta property=\"og:description\" content=\"Mi finado amigo y muy le\u00eddo Dr. Henry Cueppens me dijo hace a\u00f1os que Nicol\u00e1s de Maquiavelo se inspir\u00f3 en el libro b\u00edblico de Eclesiast\u00e9s para escribir su c\u00e9lebre obra \u201cEl Pr\u00edncipe\u201d. Me sorprend\u00ed, aunque luego pens\u00e9 que no ser\u00eda raro debido a que el primero lo escribi\u00f3 nada m\u00e1s y nada menos que el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2022\/2023\/11\/26\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-26T07:04:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-26T11:43:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/11\/cerebro-vacio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"839\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ra\u00fal Melamed\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/raulmelamed\" \/>\n<meta name=\"twitter:site\" content=\"@InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ra\u00fal Melamed\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/11\\\/26\\\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/11\\\/26\\\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\\\/\"},\"author\":{\"name\":\"Ra\u00fal Melamed\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/627c6994f0a2a49b5d3a7e40abc4232f\"},\"headline\":\"Todo es vanidad, hasta que llega la hora de la verdad\",\"datePublished\":\"2023-11-26T07:04:00+00:00\",\"dateModified\":\"2023-11-26T11:43:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/11\\\/26\\\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\\\/\"},\"wordCount\":1154,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/11\\\/26\\\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cerebro-vacio.jpg?fit=1280%2C839&ssl=1\",\"keywords\":[\"destacada\",\"palestina\",\"terrorismo\",\"terrorismo islamico\"],\"articleSection\":[\"Analisis\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/11\\\/26\\\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/11\\\/26\\\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/11\\\/26\\\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\\\/\",\"name\":\"Todo es vanidad, hasta que llega la hora de la verdad - Informatepy.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/11\\\/26\\\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/11\\\/26\\\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cerebro-vacio.jpg?fit=1280%2C839&ssl=1\",\"datePublished\":\"2023-11-26T07:04:00+00:00\",\"dateModified\":\"2023-11-26T11:43:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/11\\\/26\\\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/11\\\/26\\\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/11\\\/26\\\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cerebro-vacio.jpg?fit=1280%2C839&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cerebro-vacio.jpg?fit=1280%2C839&ssl=1\",\"width\":1280,\"height\":839},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/11\\\/26\\\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Todo es vanidad, hasta que llega la hora de la verdad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"name\":\"Informatepy.com\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\",\"name\":\"Informatepy.com\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"width\":589,\"height\":150,\"caption\":\"Informatepy.com\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/InformatePy1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/627c6994f0a2a49b5d3a7e40abc4232f\",\"name\":\"Ra\u00fal Melamed\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/taiwanesa.jpg?fit=96%2C64&ssl=1a34c985e380342d96a0dc9fff0a6b5a9\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/taiwanesa.jpg?fit=96%2C64&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/taiwanesa.jpg?fit=96%2C64&ssl=1\",\"caption\":\"Ra\u00fal Melamed\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/raulmelamed\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/author\\\/raulmelamed\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Todo es vanidad, hasta que llega la hora de la verdad - Informatepy.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2022\/2023\/11\/26\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\/","og_locale":"es_ES","og_type":"article","og_title":"Todo es vanidad, hasta que llega la hora de la verdad - Informatepy.com","og_description":"Mi finado amigo y muy le\u00eddo Dr. Henry Cueppens me dijo hace a\u00f1os que Nicol\u00e1s de Maquiavelo se inspir\u00f3 en el libro b\u00edblico de Eclesiast\u00e9s para escribir su c\u00e9lebre obra \u201cEl Pr\u00edncipe\u201d. Me sorprend\u00ed, aunque luego pens\u00e9 que no ser\u00eda raro debido a que el primero lo escribi\u00f3 nada m\u00e1s y nada menos que el [&hellip;]","og_url":"https:\/\/informatepy.com\/2022\/2023\/11\/26\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\/","og_site_name":"Informatepy.com","article_publisher":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2023-11-26T07:04:00+00:00","article_modified_time":"2023-11-26T11:43:16+00:00","og_image":[{"width":1280,"height":839,"url":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/11\/cerebro-vacio.jpg","type":"image\/jpeg"}],"author":"Ra\u00fal Melamed","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/raulmelamed","twitter_site":"@InformatePy1","twitter_misc":{"Escrito por":"Ra\u00fal Melamed","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2022\/2023\/11\/26\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/2023\/11\/26\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\/"},"author":{"name":"Ra\u00fal Melamed","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/627c6994f0a2a49b5d3a7e40abc4232f"},"headline":"Todo es vanidad, hasta que llega la hora de la verdad","datePublished":"2023-11-26T07:04:00+00:00","dateModified":"2023-11-26T11:43:16+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2023\/11\/26\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\/"},"wordCount":1154,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2023\/11\/26\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2023\/11\/cerebro-vacio.jpg?fit=1280%2C839&ssl=1","keywords":["destacada","palestina","terrorismo","terrorismo islamico"],"articleSection":["Analisis"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2022\/2023\/11\/26\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2022\/2023\/11\/26\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\/","url":"https:\/\/informatepy.com\/2022\/2023\/11\/26\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\/","name":"Todo es vanidad, hasta que llega la hora de la verdad - Informatepy.com","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2023\/11\/26\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2023\/11\/26\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2023\/11\/cerebro-vacio.jpg?fit=1280%2C839&ssl=1","datePublished":"2023-11-26T07:04:00+00:00","dateModified":"2023-11-26T11:43:16+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2022\/2023\/11\/26\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2022\/2023\/11\/26\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/2023\/11\/26\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2023\/11\/cerebro-vacio.jpg?fit=1280%2C839&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2023\/11\/cerebro-vacio.jpg?fit=1280%2C839&ssl=1","width":1280,"height":839},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2022\/2023\/11\/26\/todo-es-vanidad-hasta-que-llega-la-hora-de-la-verdad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2022\/"},{"@type":"ListItem","position":2,"name":"Todo es vanidad, hasta que llega la hora de la verdad"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2022\/#website","url":"https:\/\/informatepy.com\/2022\/","name":"Informatepy.com","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2022\/#organization","name":"Informatepy.com","url":"https:\/\/informatepy.com\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","width":589,"height":150,"caption":"Informatepy.com"},"image":{"@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/InformatePy1"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/627c6994f0a2a49b5d3a7e40abc4232f","name":"Ra\u00fal Melamed","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/04\/taiwanesa.jpg?fit=96%2C64&ssl=1a34c985e380342d96a0dc9fff0a6b5a9","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/04\/taiwanesa.jpg?fit=96%2C64&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/04\/taiwanesa.jpg?fit=96%2C64&ssl=1","caption":"Ra\u00fal Melamed"},"sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/raulmelamed"],"url":"https:\/\/informatepy.com\/2022\/author\/raulmelamed\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2023\/11\/cerebro-vacio.jpg?fit=1280%2C839&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"authors":[{"term_id":1039,"user_id":5,"is_guest":0,"slug":"raulmelamed","display_name":"Ra\u00fal Melamed","avatar_url":{"url":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2022\/10\/melamed.jpg","url2x":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2022\/10\/melamed.jpg"},"author_category":"","user_url":"","last_name":"Melamed","first_name":"Ra\u00fal","job_title":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/22334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/comments?post=22334"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/22334\/revisions"}],"predecessor-version":[{"id":22336,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/22334\/revisions\/22336"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media\/22335"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media?parent=22334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/categories?post=22334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/tags?post=22334"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/ppma_author?post=22334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}