{"id":2184,"date":"2021-02-10T15:28:21","date_gmt":"2021-02-10T15:28:21","guid":{"rendered":"http:\/\/informatepy.com\/2022\/2021\/02\/10\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\/"},"modified":"2022-09-27T23:03:39","modified_gmt":"2022-09-27T23:03:39","slug":"no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2022\/2021\/02\/10\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\/","title":{"rendered":"No prospera pedido para tratar conformaci\u00f3n de mesa receptora de denuncias ciudadanas"},"content":{"rendered":"\n<p><em><strong>La Comisi\u00f3n Permanente del Congreso Nacional, presidida por el diputado Ra\u00fal Latorre, sesion\u00f3 de forma ordinaria este mi\u00e9rcoles, para el tratamiento de tres puntos contemplados en el orden del d\u00eda.<\/strong><\/em><\/p>\n\n\n\n<p>El punto tres contemplaba el an\u00e1lisis del Proyecto de Resoluci\u00f3n <em><strong>\u201cQue conforma la mesa receptora de denuncias ciudadanas por abuso de poder, mal desempe\u00f1o de funciones, prevaricato y hechos punibles comunes cometidos por los integrantes del Ministerio P\u00fablico y el Poder Judicial, en especial, en lo que hace al mandato constitucional ejercido por la Sra. Fiscal General del Estado Sandra Qui\u00f1\u00f3nez: que funcionar\u00e1 bajo la coordinaci\u00f3n del Frente Parlamentario contra la Corrupci\u00f3n e Impunidad y la designaci\u00f3n de nueve diputados\u201d<\/strong><\/em>.\u00a0<\/p>\n\n\n\n<p>A pesar del rimbombante nombre elegido por la diputada Kattya Gonz\u00e1lez y luego de un amplio debate sobre este punto, los legisladores llevaron a votaci\u00f3n y el tema obtuvo cuatro votos a favor, por lo que fue rechazada la propuesta legislativa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Comisi\u00f3n Permanente del Congreso Nacional, presidida por el diputado Ra\u00fal Latorre, sesion\u00f3 de forma ordinaria este mi\u00e9rcoles, para el tratamiento de tres puntos contemplados en el orden del d\u00eda. El punto tres contemplaba el an\u00e1lisis del Proyecto de Resoluci\u00f3n \u201cQue conforma la mesa receptora de denuncias ciudadanas por abuso de poder, mal desempe\u00f1o de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12317,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[18],"tags":[274,701,283,585,285],"ppma_author":[],"class_list":{"0":"post-2184","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nacionales","8":"tag-camara-de-diputados","9":"tag-fiscalia","10":"tag-fiscalia-general","11":"tag-kattya-gonzalez","12":"tag-sandra-quinonez"},"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>No prospera pedido para tratar conformaci\u00f3n de mesa receptora de denuncias ciudadanas - Informatepy.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2022\/2021\/02\/10\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"No prospera pedido para tratar conformaci\u00f3n de mesa receptora de denuncias ciudadanas - Informatepy.com\" \/>\n<meta property=\"og:description\" content=\"La Comisi\u00f3n Permanente del Congreso Nacional, presidida por el diputado Ra\u00fal Latorre, sesion\u00f3 de forma ordinaria este mi\u00e9rcoles, para el tratamiento de tres puntos contemplados en el orden del d\u00eda. El punto tres contemplaba el an\u00e1lisis del Proyecto de Resoluci\u00f3n \u201cQue conforma la mesa receptora de denuncias ciudadanas por abuso de poder, mal desempe\u00f1o de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2022\/2021\/02\/10\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-10T15:28:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-27T23:03:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/02\/kattya-gonzalez.jpeg?fit=860%2C573&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"860\" \/>\n\t<meta property=\"og:image:height\" content=\"573\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@InformatePy1\" \/>\n<meta name=\"twitter:site\" content=\"@InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/02\\\/10\\\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/02\\\/10\\\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/51a66e4894ad41947ebb945804418db8\"},\"headline\":\"No prospera pedido para tratar conformaci\u00f3n de mesa receptora de denuncias ciudadanas\",\"datePublished\":\"2021-02-10T15:28:21+00:00\",\"dateModified\":\"2022-09-27T23:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/02\\\/10\\\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\\\/\"},\"wordCount\":178,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/02\\\/10\\\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/kattya-gonzalez.jpeg?fit=860%2C573&ssl=1\",\"keywords\":[\"c\u00e1mara de diputados\",\"fiscalia\",\"fiscal\u00eda general\",\"kattya gonzalez\",\"sandra qui\u00f1onez\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/02\\\/10\\\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/02\\\/10\\\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/02\\\/10\\\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\\\/\",\"name\":\"No prospera pedido para tratar conformaci\u00f3n de mesa receptora de denuncias ciudadanas - Informatepy.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/02\\\/10\\\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/02\\\/10\\\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/kattya-gonzalez.jpeg?fit=860%2C573&ssl=1\",\"datePublished\":\"2021-02-10T15:28:21+00:00\",\"dateModified\":\"2022-09-27T23:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/02\\\/10\\\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/02\\\/10\\\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/02\\\/10\\\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/kattya-gonzalez.jpeg?fit=860%2C573&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/kattya-gonzalez.jpeg?fit=860%2C573&ssl=1\",\"width\":860,\"height\":573},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2021\\\/02\\\/10\\\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"No prospera pedido para tratar conformaci\u00f3n de mesa receptora de denuncias ciudadanas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"name\":\"Informatepy.com\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\",\"name\":\"Informatepy.com\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"width\":589,\"height\":150,\"caption\":\"Informatepy.com\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/InformatePy1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/51a66e4894ad41947ebb945804418db8\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g276449386956a98e04614ff4c246c7b8\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2022\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"No prospera pedido para tratar conformaci\u00f3n de mesa receptora de denuncias ciudadanas - Informatepy.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2022\/2021\/02\/10\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\/","og_locale":"es_ES","og_type":"article","og_title":"No prospera pedido para tratar conformaci\u00f3n de mesa receptora de denuncias ciudadanas - Informatepy.com","og_description":"La Comisi\u00f3n Permanente del Congreso Nacional, presidida por el diputado Ra\u00fal Latorre, sesion\u00f3 de forma ordinaria este mi\u00e9rcoles, para el tratamiento de tres puntos contemplados en el orden del d\u00eda. El punto tres contemplaba el an\u00e1lisis del Proyecto de Resoluci\u00f3n \u201cQue conforma la mesa receptora de denuncias ciudadanas por abuso de poder, mal desempe\u00f1o de [&hellip;]","og_url":"https:\/\/informatepy.com\/2022\/2021\/02\/10\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\/","og_site_name":"Informatepy.com","article_publisher":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2021-02-10T15:28:21+00:00","article_modified_time":"2022-09-27T23:03:39+00:00","og_image":[{"width":860,"height":573,"url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/02\/kattya-gonzalez.jpeg?fit=860%2C573&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@InformatePy1","twitter_site":"@InformatePy1","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2022\/2021\/02\/10\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/2021\/02\/10\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/51a66e4894ad41947ebb945804418db8"},"headline":"No prospera pedido para tratar conformaci\u00f3n de mesa receptora de denuncias ciudadanas","datePublished":"2021-02-10T15:28:21+00:00","dateModified":"2022-09-27T23:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2021\/02\/10\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\/"},"wordCount":178,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2021\/02\/10\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/02\/kattya-gonzalez.jpeg?fit=860%2C573&ssl=1","keywords":["c\u00e1mara de diputados","fiscalia","fiscal\u00eda general","kattya gonzalez","sandra qui\u00f1onez"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2022\/2021\/02\/10\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2022\/2021\/02\/10\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\/","url":"https:\/\/informatepy.com\/2022\/2021\/02\/10\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\/","name":"No prospera pedido para tratar conformaci\u00f3n de mesa receptora de denuncias ciudadanas - Informatepy.com","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2021\/02\/10\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2021\/02\/10\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/02\/kattya-gonzalez.jpeg?fit=860%2C573&ssl=1","datePublished":"2021-02-10T15:28:21+00:00","dateModified":"2022-09-27T23:03:39+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2022\/2021\/02\/10\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2022\/2021\/02\/10\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/2021\/02\/10\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/02\/kattya-gonzalez.jpeg?fit=860%2C573&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/02\/kattya-gonzalez.jpeg?fit=860%2C573&ssl=1","width":860,"height":573},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2022\/2021\/02\/10\/no-prospera-pedido-para-tratar-conformacion-de-mesa-receptora-de-denuncias-ciudadanas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2022\/"},{"@type":"ListItem","position":2,"name":"No prospera pedido para tratar conformaci\u00f3n de mesa receptora de denuncias ciudadanas"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2022\/#website","url":"https:\/\/informatepy.com\/2022\/","name":"Informatepy.com","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2022\/#organization","name":"Informatepy.com","url":"https:\/\/informatepy.com\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","width":589,"height":150,"caption":"Informatepy.com"},"image":{"@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/InformatePy1"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/51a66e4894ad41947ebb945804418db8","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g276449386956a98e04614ff4c246c7b8","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/informatepy.com\/2022"],"url":"https:\/\/informatepy.com\/2022\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/02\/kattya-gonzalez.jpeg?fit=860%2C573&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"authors":[{"term_id":998,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/2184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/comments?post=2184"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/2184\/revisions"}],"predecessor-version":[{"id":3570,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/2184\/revisions\/3570"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media\/12317"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media?parent=2184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/categories?post=2184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/tags?post=2184"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/ppma_author?post=2184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}