{"id":20648,"date":"2023-08-28T09:56:10","date_gmt":"2023-08-28T12:56:10","guid":{"rendered":"https:\/\/informatepy.com\/2022\/?p=20648"},"modified":"2023-08-28T09:57:06","modified_gmt":"2023-08-28T12:57:06","slug":"presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2022\/2023\/08\/28\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\/","title":{"rendered":"Presidente de un comit\u00e9 de la OTAN pide desmembrar Brasil, Rusia, China y los Emiratos \u00c1rabes para acabar con el BRICS"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">El presidente del <strong>Comit\u00e9 de Desarrollo Europeo de la OTAN<\/strong>, <strong>G\u00fcnther Fehlinger<\/strong>, otro loco neocolonialista, tras finalizar la cumbre de los BRICS, en Johannesburgo, amenaz\u00f3 con que la alianza <strong>\u201cdesmantelar\u00eda\u201d<\/strong> a <strong>Brasil <\/strong>en cinco estados separados, si ese pa\u00eds segu\u00eda apoyando a Rusia.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Esta amenaza la hizo en su p\u00e1gina de la red social X (Twitter), donde escribi\u00f3: <strong><em>\u201cPido la liberaci\u00f3n del pueblo de Brasil mediante el desmantelamiento de Rusia, &lt;\u2026> en cinco estados nuevos y m\u00e1s libres que puedan unirse a la OTAN\u201d<\/em><\/strong>, escribi\u00f3 Fehlinger.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Prometi\u00f3<strong> \u201cdesmantelar\u201d <\/strong>Brasil si el presidente <strong>Luiz In\u00e1cio \u00abLula\u00bb da Silva<\/strong> contin\u00faa apoyando a <strong>Rusia, China<\/strong> e <strong>Ir\u00e1n<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">I call to free the people of Brazil \ud83c\udde7\ud83c\uddf7 by dismantling the Socialist Genocidal BRICS Ally of Russia \ud83c\uddf7\ud83c\uddfa misled by <a href=\"https:\/\/twitter.com\/LulaOficial?ref_src=twsrc%5Etfw\">@LulaOficial<\/a> into 5 new better free states who can join <a href=\"https:\/\/twitter.com\/NATO?ref_src=twsrc%5Etfw\">@nato<\/a> <a href=\"https:\/\/twitter.com\/OECD?ref_src=twsrc%5Etfw\">@OECD<\/a> a d <a href=\"https:\/\/twitter.com\/mercosur?ref_src=twsrc%5Etfw\">@mercosur<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/ExBrazil?src=hash&amp;ref_src=twsrc%5Etfw\">#ExBrazil<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/FehlingerDoctrine?src=hash&amp;ref_src=twsrc%5Etfw\">#FehlingerDoctrine<\/a> <a href=\"https:\/\/t.co\/MEY5qzReiW\">pic.twitter.com\/MEY5qzReiW<\/a><\/p>&mdash; Gunther Fehlinger (@GunterFehlinger) <a href=\"https:\/\/twitter.com\/GunterFehlinger\/status\/1695161912361668791?ref_src=twsrc%5Etfw\">August 25, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Del mismo modo, G\u00fcnther Fehlinger, quiere desmantelar Rusia, China y los Emiratos \u00c1rabes Unidos. En el caso del pa\u00eds \u00e1rabe, la amenaza del funcionario de la OTAN fue directa: <strong><em>\u00abPuse en aviso a UAE. Solicitar\u00e9 el desmantelamiento de los Emiratos \u00c1rabes Unidos si realmente se unen al BRICS 2024 Es mi \u00faltima advertencia, Se\u00f1or Sheikh el UAE es muy f\u00e1cil de desmantelar\u2026\u00bb<\/em><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">I call to dismantle Russia and China <a href=\"https:\/\/twitter.com\/hashtag\/BRICS?src=hash&amp;ref_src=twsrc%5Etfw\">#BRICS<\/a> will be gone in seconds once the \ud83d\udcb0 from Russia and China dries up<a href=\"https:\/\/twitter.com\/hashtag\/exRussia?src=hash&amp;ref_src=twsrc%5Etfw\">#exRussia<\/a> and <a href=\"https:\/\/twitter.com\/hashtag\/ExChina?src=hash&amp;ref_src=twsrc%5Etfw\">#ExChina<\/a> = <a href=\"https:\/\/twitter.com\/hashtag\/ExBRICS?src=hash&amp;ref_src=twsrc%5Etfw\">#ExBRICS<\/a> <a href=\"https:\/\/t.co\/N0BSXJFZ2n\">pic.twitter.com\/N0BSXJFZ2n<\/a><\/p>&mdash; Gunther Fehlinger (@GunterFehlinger) <a href=\"https:\/\/twitter.com\/GunterFehlinger\/status\/1696007900190122384?ref_src=twsrc%5Etfw\">August 28, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">I put UAE \ud83c\udde6\ud83c\uddea on notice <br>I will call for UAE dismantling if you really join <a href=\"https:\/\/twitter.com\/hashtag\/BRICS?src=hash&amp;ref_src=twsrc%5Etfw\">#BRICS<\/a> 2024 <br>It is my last warning \u26a0\ufe0f Mr Sheikh <br>You UAE is very easy to dismantle \u2026 <a href=\"https:\/\/t.co\/XZVnrZuSfS\">https:\/\/t.co\/XZVnrZuSfS<\/a><\/p>&mdash; Gunther Fehlinger (@GunterFehlinger) <a href=\"https:\/\/twitter.com\/GunterFehlinger\/status\/1696051600517632462?ref_src=twsrc%5Etfw\">August 28, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El presidente del Comit\u00e9 de Desarrollo Europeo de la OTAN, G\u00fcnther Fehlinger, otro loco neocolonialista, tras finalizar la cumbre de los BRICS, en Johannesburgo, amenaz\u00f3 con que la alianza \u201cdesmantelar\u00eda\u201d a Brasil en cinco estados separados, si ese pa\u00eds segu\u00eda apoyando a Rusia. Esta amenaza la hizo en su p\u00e1gina de la red social X [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":20649,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":false,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[14],"tags":[328,181,871,1940,1181,183],"ppma_author":[1037],"class_list":["post-20648","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mundo","tag-brasil","tag-china","tag-destacada","tag-emiratos-arabes","tag-otan","tag-rusia"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presidente de un comit\u00e9 de la OTAN pide desmembrar Brasil, Rusia, China y los Emiratos \u00c1rabes para acabar con el BRICS - Informatepy.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2022\/2023\/08\/28\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presidente de un comit\u00e9 de la OTAN pide desmembrar Brasil, Rusia, China y los Emiratos \u00c1rabes para acabar con el BRICS - Informatepy.com\" \/>\n<meta property=\"og:description\" content=\"El presidente del Comit\u00e9 de Desarrollo Europeo de la OTAN, G\u00fcnther Fehlinger, otro loco neocolonialista, tras finalizar la cumbre de los BRICS, en Johannesburgo, amenaz\u00f3 con que la alianza \u201cdesmantelar\u00eda\u201d a Brasil en cinco estados separados, si ese pa\u00eds segu\u00eda apoyando a Rusia. Esta amenaza la hizo en su p\u00e1gina de la red social X [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2022\/2023\/08\/28\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-28T12:56:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-28T12:57:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/08\/gunter-fehlinger.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:site\" content=\"@InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/08\\\/28\\\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/08\\\/28\\\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/e7c5b605ddfb77041eeddff4d93b26af\"},\"headline\":\"Presidente de un comit\u00e9 de la OTAN pide desmembrar Brasil, Rusia, China y los Emiratos \u00c1rabes para acabar con el BRICS\",\"datePublished\":\"2023-08-28T12:56:10+00:00\",\"dateModified\":\"2023-08-28T12:57:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/08\\\/28\\\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\\\/\"},\"wordCount\":215,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/08\\\/28\\\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/gunter-fehlinger.jpg?fit=1280%2C960&ssl=1\",\"keywords\":[\"brasil\",\"china\",\"destacada\",\"emiratos arabes\",\"otan\",\"rusia\"],\"articleSection\":[\"Mundo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/08\\\/28\\\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/08\\\/28\\\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/08\\\/28\\\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\\\/\",\"name\":\"Presidente de un comit\u00e9 de la OTAN pide desmembrar Brasil, Rusia, China y los Emiratos \u00c1rabes para acabar con el BRICS - Informatepy.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/08\\\/28\\\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/08\\\/28\\\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/gunter-fehlinger.jpg?fit=1280%2C960&ssl=1\",\"datePublished\":\"2023-08-28T12:56:10+00:00\",\"dateModified\":\"2023-08-28T12:57:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/08\\\/28\\\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/08\\\/28\\\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/08\\\/28\\\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/gunter-fehlinger.jpg?fit=1280%2C960&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/gunter-fehlinger.jpg?fit=1280%2C960&ssl=1\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/08\\\/28\\\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presidente de un comit\u00e9 de la OTAN pide desmembrar Brasil, Rusia, China y los Emiratos \u00c1rabes para acabar con el BRICS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"name\":\"Informatepy.com\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\",\"name\":\"Informatepy.com\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"width\":589,\"height\":150,\"caption\":\"Informatepy.com\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/InformatePy1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/e7c5b605ddfb77041eeddff4d93b26af\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.pngce0c1b6da06ae20abaff417c2cdeea83\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presidente de un comit\u00e9 de la OTAN pide desmembrar Brasil, Rusia, China y los Emiratos \u00c1rabes para acabar con el BRICS - Informatepy.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2022\/2023\/08\/28\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\/","og_locale":"es_ES","og_type":"article","og_title":"Presidente de un comit\u00e9 de la OTAN pide desmembrar Brasil, Rusia, China y los Emiratos \u00c1rabes para acabar con el BRICS - Informatepy.com","og_description":"El presidente del Comit\u00e9 de Desarrollo Europeo de la OTAN, G\u00fcnther Fehlinger, otro loco neocolonialista, tras finalizar la cumbre de los BRICS, en Johannesburgo, amenaz\u00f3 con que la alianza \u201cdesmantelar\u00eda\u201d a Brasil en cinco estados separados, si ese pa\u00eds segu\u00eda apoyando a Rusia. Esta amenaza la hizo en su p\u00e1gina de la red social X [&hellip;]","og_url":"https:\/\/informatepy.com\/2022\/2023\/08\/28\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\/","og_site_name":"Informatepy.com","article_publisher":"https:\/\/www.facebook.com\/InformatePyCom","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2023-08-28T12:56:10+00:00","article_modified_time":"2023-08-28T12:57:06+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/08\/gunter-fehlinger.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_site":"@InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2022\/2023\/08\/28\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/2023\/08\/28\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/e7c5b605ddfb77041eeddff4d93b26af"},"headline":"Presidente de un comit\u00e9 de la OTAN pide desmembrar Brasil, Rusia, China y los Emiratos \u00c1rabes para acabar con el BRICS","datePublished":"2023-08-28T12:56:10+00:00","dateModified":"2023-08-28T12:57:06+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2023\/08\/28\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\/"},"wordCount":215,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2023\/08\/28\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2023\/08\/gunter-fehlinger.jpg?fit=1280%2C960&ssl=1","keywords":["brasil","china","destacada","emiratos arabes","otan","rusia"],"articleSection":["Mundo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2022\/2023\/08\/28\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2022\/2023\/08\/28\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\/","url":"https:\/\/informatepy.com\/2022\/2023\/08\/28\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\/","name":"Presidente de un comit\u00e9 de la OTAN pide desmembrar Brasil, Rusia, China y los Emiratos \u00c1rabes para acabar con el BRICS - Informatepy.com","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2023\/08\/28\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2023\/08\/28\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2023\/08\/gunter-fehlinger.jpg?fit=1280%2C960&ssl=1","datePublished":"2023-08-28T12:56:10+00:00","dateModified":"2023-08-28T12:57:06+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2022\/2023\/08\/28\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2022\/2023\/08\/28\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/2023\/08\/28\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2023\/08\/gunter-fehlinger.jpg?fit=1280%2C960&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2023\/08\/gunter-fehlinger.jpg?fit=1280%2C960&ssl=1","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2022\/2023\/08\/28\/presidente-del-comite-austriaco-para-la-otan-pide-desmantelar-brasil-rusia-china-y-los-emiratos-arabes-para-acabar-con-el-brics\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2022\/"},{"@type":"ListItem","position":2,"name":"Presidente de un comit\u00e9 de la OTAN pide desmembrar Brasil, Rusia, China y los Emiratos \u00c1rabes para acabar con el BRICS"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2022\/#website","url":"https:\/\/informatepy.com\/2022\/","name":"Informatepy.com","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2022\/#organization","name":"Informatepy.com","url":"https:\/\/informatepy.com\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","width":589,"height":150,"caption":"Informatepy.com"},"image":{"@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/InformatePy1"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/e7c5b605ddfb77041eeddff4d93b26af","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.pngce0c1b6da06ae20abaff417c2cdeea83","url":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2022\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2023\/08\/gunter-fehlinger.jpg?fit=1280%2C960&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"authors":[{"term_id":1037,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png"},"author_category":"","user_url":"","last_name":"","first_name":"Redacci\u00f3n","job_title":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/20648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/comments?post=20648"}],"version-history":[{"count":4,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/20648\/revisions"}],"predecessor-version":[{"id":20654,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/20648\/revisions\/20654"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media\/20649"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media?parent=20648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/categories?post=20648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/tags?post=20648"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/ppma_author?post=20648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}