{"id":20287,"date":"2023-08-07T06:53:00","date_gmt":"2023-08-07T09:53:00","guid":{"rendered":"https:\/\/informatepy.com\/2022\/?p=20287"},"modified":"2023-08-06T19:08:39","modified_gmt":"2023-08-06T22:08:39","slug":"feminismo-radical-hijas-de-marx-de-rousseau-y-foucault","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2022\/2023\/08\/07\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\/","title":{"rendered":"Feminismo radical: hijas de Marx, Rousseau y Foucault"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">A menudo somos incapaces de prever las consecuencias \u00faltimas de las ideas que abrazamos en nuestra vida personal. Esa incapacidad es tanto m\u00e1s notoria cuando hablamos de las ideas predominantes en la vida en com\u00fan. Las consecuencias l\u00f3gicas de las ideas predominantes nos conducen a derroteros insospechados. En definitiva, siendo que es imposible que la acci\u00f3n humana suceda en el vac\u00edo ideol\u00f3gico, debemos reconocer que las ideas hegem\u00f3nicas determinan en gran medida la evoluci\u00f3n social.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Las feministas son un caso que ilustra con claridad el punto anterior. Dicen condenar la violencia contra la mujer, sin embargo, reclaman aborto legal, un acto quir\u00fargico de profunda violencia f\u00edsica y psicol\u00f3gica instrumentado bajo la enga\u00f1osa apariencia de la benevolencia. El aborto legal que exigen es violencia dirigida sistem\u00e1ticamente hacia la mujer, violencia institucionalizada. Por otro lado, no deja de ser llamativa la defensa que las mismas realizan de los violadores y ped\u00f3filos.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Intentar\u00e9 explicar este punto, la defensa feminista de violadores y ped\u00f3filos, intentando integrar una razonable <em>genealog\u00eda de las ideas<\/em>, como dir\u00eda Lord Acton. Este es un proceso tedioso, pero necesario, si el deseo es contribuir arrojando un poco de luz te\u00f3rica sobre este desagradable asunto.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Las feministas defienden a los violadores y ped\u00f3filos porque son hijas de Marx.<\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Primero, es relevante mencionar que este feminismo radical fue perge\u00f1ado a la luz del marxismo. No es el feminismo burgu\u00e9s que exig\u00eda igualdad ante la ley, sino que, como digno engendro te\u00f3rico del marxismo alega <em>desigualdades estructurales<\/em>, invisibles, por cierto, que no se pueden abordar mediante el instrumento de la igualdad jur\u00eddica, y que demandan la completa demolici\u00f3n del edificio social: destruir la infraestructura para que caiga la superestructura. No es por ello extra\u00f1o que en todas las marchas feministas de marras se encuentren carteles que ordenen la destrucci\u00f3n del sistema capitalista.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Son hijas de Karl Marx por ello, principalmente, y eso explica porque hablan de que <em><strong>\u201cla lucha es colectiva\u201d<\/strong><\/em> y usan ese lenguaje tan <strong>\u00ab<em>estructuralista<\/em>\u00ab<\/strong>. Valga decir que Frederic Engels en su libro <em>\u00abEl origen de la familia, la propiedad privada y el Estado\u00bb<\/em> hab\u00eda adelantado argumentos para un marxismo cultural: <strong><em>\u00abEn la familia el var\u00f3n es el burgu\u00e9s y la mujer el proletario\u00bb<\/em>,<\/strong> trasladando la lucha de clases a una lucha de sexos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u00bfPor qu\u00e9 defender\u00edan entonces a los violadores siendo hijas de Marx?<\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Para Marx y Engels toda la cultura burguesa est\u00e1 basada en los modos de producci\u00f3n. En otras palabras, la cultura est\u00e1 basada en las relaciones sociales y estas se fundamentan en las relaciones de producci\u00f3n.<strong> <em>\u00abLa cultura de la violaci\u00f3n\u00bb<\/em><\/strong> que denuncian a boca de jarro ser\u00eda solamente una funci\u00f3n del capitalismo explotador, exonerando as\u00ed de culpas individuales a los violadores. La doctrina marxista es tan perniciosa, en \u00faltima instancia, porque deteriora y, con el tiempo, elimina la responsabilidad individual. Ese materialismo desbocado, en el cual se nutre el marxismo cl\u00e1sico, no solo justifica la defensa de violadores, sino que sustenta te\u00f3ricamente el filicidio intrauterino, o aborto: \u00bfqu\u00e9 puede ser m\u00e1s materialista que decir que un ser humano en gestaci\u00f3n <strong>\u00abes solamente un conjunto de c\u00e9lulas\u00bb<\/strong>?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antes de la tragedia, siempre la estupidez.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Las feministas defienden a los violadores y ped\u00f3filos porque son hijas de Rousseau.<\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Son hijas de Jean Jacques Rousseau porque se abrazan fervientemente <em>el mito del buen salvaje<\/em>, hasta el punto de que algunas feministas sostienen que, si se redujera la poblaci\u00f3n masculina al 20% y se mandara a los hombres a campos de concentraci\u00f3n, las mujeres volver\u00edan a un estado id\u00edlico, de bondad absoluta entre ellas, el que fue perdido debido a la intervenci\u00f3n masculina en sus vidas. Rousseau dec\u00eda que los seres humanos nacen buenos pero la sociedad los corrompe. Otro tanto dicen las feministas: las mujeres nacen buenas, se corrompen bajo el patriarcado. Sin patriarcado la humanidad ser\u00eda perfecta. De ah\u00ed que procuren introducir en la educaci\u00f3n estatal manuales para <em>\u00ab<strong>nuevas masculinidades\u00bb<\/strong><\/em> o <strong><em>\u201ccontra la masculinidad t\u00f3xica\u00bb<\/em>.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u00bfQu\u00e9 tiene que ver esto con la defensa feminista de violadores y ped\u00f3filos? Todo.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Una vez m\u00e1s si el hombre nace bueno, pero la sociedad patriarcal lo corrompe, entonces \u00bfno ser\u00eda una injusticia encarcelar a una persona por algo que es responsabilidad de todos? Nuevamente las feministas, con un discurso colectivista, esta vez devenido de Rousseau, deben llegar a la \u00faltima consecuencia l\u00f3gica de sus postulados: defender violadores y ped\u00f3filos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Las feministas defienden a los violadores y ped\u00f3filos porque son hijas de Foucault.<\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><em><u>Michel Foucault<\/u><\/em> llev\u00f3 al extremo ambas teor\u00edas, tanto la de Rousseau como la de Marx, y no es extra\u00f1o que, por lo tanto, sea considerado <em>\u201cpadre de la teor\u00eda queer\u201d<\/em>.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">El sistema dominante, la infraestructura econ\u00f3mica, habr\u00eda generado instancias de control social en la superestructura: el sistema penitenciario.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Pero es precisamente la infraestructura, con su colonialismo, capitalismo y sistema jur\u00eddico basado en el individualismo, el que seg\u00fan Foucault causa el crimen, el robo, el asesinato. Si cambiamos el sistema, por ejemplo, de propiedad individual a propiedad comunal, el robo deja de existir, no hace falta punirlo y las c\u00e1rceles terminan siendo innecesarias.\u00a0 Con la violaci\u00f3n es otro tanto. Las hijas de Foucault, las feministas, argumentan que encerrar a los violadores no resuelve el problema de la violaci\u00f3n y apuntan a que <em><strong>\u00abel sistema reproduce las violaciones\u00bb<\/strong><\/em>. Dicen ellas que <em><strong>\u00ablos mecanismos punitivos no resuelven el problema\u00bb<\/strong><\/em> e incluso ensayan el alegato de que, si encerrar a los ladrones eliminaba el robo, el robo ya no existir\u00eda \u00bfNo se percatan de que no existen soluciones perfectas en una realidad imperfecta?<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Una vez m\u00e1s, al no asignar responsabilidades individuales, el colectivismo diluye la posibilidad de civilizaci\u00f3n en el solvente de la moral de la tribu.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">En todas sus variantes, el hilo conductor de este totalitarismo moderno denominado feminismo radical es el colectivismo. Sin embargo, hay tambi\u00e9n otro asunto, no menos importante. Estas personas, las feministas, los socialistas y comunistas parten de un punto de partida espurio, previo a la experiencia, que se resume en la frase <em><strong>\u00abel mundo no es lo que debe ser\u00bb, \u00abel mundo est\u00e1 mal\u00bb.<\/strong><\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Partir de la premisa a priori de que el mundo est\u00e1 mal y que, por lo tanto, te debe algo es causa eficiente y garant\u00eda suficiente para convertirse en un peligroso tirano que duerme con la conciencia tranquila.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A menudo somos incapaces de prever las consecuencias \u00faltimas de las ideas que abrazamos en nuestra vida personal. Esa incapacidad es tanto m\u00e1s notoria cuando hablamos de las ideas predominantes en la vida en com\u00fan. Las consecuencias l\u00f3gicas de las ideas predominantes nos conducen a derroteros insospechados. En definitiva, siendo que es imposible que la [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":20288,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":false,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[92],"tags":[798,871,298,512],"ppma_author":[1020],"class_list":["post-20287","post","type-post","status-publish","format-standard","has-post-thumbnail","category-analisis","tag-aborto","tag-destacada","tag-feminismo","tag-feminismo-radical"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Feminismo radical: hijas de Marx, Rousseau y Foucault - Informatepy.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2022\/2023\/08\/07\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Feminismo radical: hijas de Marx, Rousseau y Foucault - Informatepy.com\" \/>\n<meta property=\"og:description\" content=\"A menudo somos incapaces de prever las consecuencias \u00faltimas de las ideas que abrazamos en nuestra vida personal. Esa incapacidad es tanto m\u00e1s notoria cuando hablamos de las ideas predominantes en la vida en com\u00fan. Las consecuencias l\u00f3gicas de las ideas predominantes nos conducen a derroteros insospechados. En definitiva, siendo que es imposible que la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2022\/2023\/08\/07\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-07T09:53:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2023\/08\/feminismo-aborto.jpg?fit=1280%2C907&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"907\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"H\u00e9ctor Acu\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/hectoracunat\" \/>\n<meta name=\"twitter:site\" content=\"@InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"H\u00e9ctor Acu\u00f1a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/08\\\/07\\\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/08\\\/07\\\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\\\/\"},\"author\":{\"name\":\"H\u00e9ctor Acu\u00f1a\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/9428158c026f5e5d919ea2151ecbe79f\"},\"headline\":\"Feminismo radical: hijas de Marx, Rousseau y Foucault\",\"datePublished\":\"2023-08-07T09:53:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/08\\\/07\\\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\\\/\"},\"wordCount\":1115,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/08\\\/07\\\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/feminismo-aborto.jpg?fit=1280%2C907&ssl=1\",\"keywords\":[\"aborto\",\"destacada\",\"feminismo\",\"feminismo radical\"],\"articleSection\":[\"Analisis\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/08\\\/07\\\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/08\\\/07\\\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/08\\\/07\\\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\\\/\",\"name\":\"Feminismo radical: hijas de Marx, Rousseau y Foucault - Informatepy.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/08\\\/07\\\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/08\\\/07\\\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/feminismo-aborto.jpg?fit=1280%2C907&ssl=1\",\"datePublished\":\"2023-08-07T09:53:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/08\\\/07\\\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/08\\\/07\\\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/08\\\/07\\\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/feminismo-aborto.jpg?fit=1280%2C907&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/feminismo-aborto.jpg?fit=1280%2C907&ssl=1\",\"width\":1280,\"height\":907},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/08\\\/07\\\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Feminismo radical: hijas de Marx, Rousseau y Foucault\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"name\":\"Informatepy.com\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\",\"name\":\"Informatepy.com\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"width\":589,\"height\":150,\"caption\":\"Informatepy.com\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/InformatePy1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/9428158c026f5e5d919ea2151ecbe79f\",\"name\":\"H\u00e9ctor Acu\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/hector-acuna1.png?fit=96%2C96&ssl=1c01f50187caa50b7cb145201e0e27d1a\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/hector-acuna1.png?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/hector-acuna1.png?fit=96%2C96&ssl=1\",\"caption\":\"H\u00e9ctor Acu\u00f1a\"},\"description\":\"Director Editorial de InformatePy\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/hectoracunat\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/author\\\/hacuna\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Feminismo radical: hijas de Marx, Rousseau y Foucault - Informatepy.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2022\/2023\/08\/07\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\/","og_locale":"es_ES","og_type":"article","og_title":"Feminismo radical: hijas de Marx, Rousseau y Foucault - Informatepy.com","og_description":"A menudo somos incapaces de prever las consecuencias \u00faltimas de las ideas que abrazamos en nuestra vida personal. Esa incapacidad es tanto m\u00e1s notoria cuando hablamos de las ideas predominantes en la vida en com\u00fan. Las consecuencias l\u00f3gicas de las ideas predominantes nos conducen a derroteros insospechados. En definitiva, siendo que es imposible que la [&hellip;]","og_url":"https:\/\/informatepy.com\/2022\/2023\/08\/07\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\/","og_site_name":"Informatepy.com","article_publisher":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2023-08-07T09:53:00+00:00","og_image":[{"width":1280,"height":907,"url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2023\/08\/feminismo-aborto.jpg?fit=1280%2C907&ssl=1","type":"image\/jpeg"}],"author":"H\u00e9ctor Acu\u00f1a","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/hectoracunat","twitter_site":"@InformatePy1","twitter_misc":{"Escrito por":"H\u00e9ctor Acu\u00f1a","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2022\/2023\/08\/07\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/2023\/08\/07\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\/"},"author":{"name":"H\u00e9ctor Acu\u00f1a","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/9428158c026f5e5d919ea2151ecbe79f"},"headline":"Feminismo radical: hijas de Marx, Rousseau y Foucault","datePublished":"2023-08-07T09:53:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2023\/08\/07\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\/"},"wordCount":1115,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2023\/08\/07\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2023\/08\/feminismo-aborto.jpg?fit=1280%2C907&ssl=1","keywords":["aborto","destacada","feminismo","feminismo radical"],"articleSection":["Analisis"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2022\/2023\/08\/07\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2022\/2023\/08\/07\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\/","url":"https:\/\/informatepy.com\/2022\/2023\/08\/07\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\/","name":"Feminismo radical: hijas de Marx, Rousseau y Foucault - Informatepy.com","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2023\/08\/07\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2023\/08\/07\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2023\/08\/feminismo-aborto.jpg?fit=1280%2C907&ssl=1","datePublished":"2023-08-07T09:53:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2022\/2023\/08\/07\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2022\/2023\/08\/07\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/2023\/08\/07\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2023\/08\/feminismo-aborto.jpg?fit=1280%2C907&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2023\/08\/feminismo-aborto.jpg?fit=1280%2C907&ssl=1","width":1280,"height":907},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2022\/2023\/08\/07\/feminismo-radical-hijas-de-marx-de-rousseau-y-foucault\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2022\/"},{"@type":"ListItem","position":2,"name":"Feminismo radical: hijas de Marx, Rousseau y Foucault"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2022\/#website","url":"https:\/\/informatepy.com\/2022\/","name":"Informatepy.com","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2022\/#organization","name":"Informatepy.com","url":"https:\/\/informatepy.com\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","width":589,"height":150,"caption":"Informatepy.com"},"image":{"@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/InformatePy1"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/9428158c026f5e5d919ea2151ecbe79f","name":"H\u00e9ctor Acu\u00f1a","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/10\/hector-acuna1.png?fit=96%2C96&ssl=1c01f50187caa50b7cb145201e0e27d1a","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/10\/hector-acuna1.png?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/10\/hector-acuna1.png?fit=96%2C96&ssl=1","caption":"H\u00e9ctor Acu\u00f1a"},"description":"Director Editorial de InformatePy","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/hectoracunat"],"url":"https:\/\/informatepy.com\/2022\/author\/hacuna\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2023\/08\/feminismo-aborto.jpg?fit=1280%2C907&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"authors":[{"term_id":1020,"user_id":36,"is_guest":0,"slug":"hacuna","display_name":"H\u00e9ctor Acu\u00f1a","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/10\/hector-acuna1.png?fit=96%2C96&ssl=1","author_category":"","user_url":"","last_name":"Acu\u00f1a","first_name":"H\u00e9ctor","job_title":"","description":"Director Editorial de InformatePy"}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/20287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/comments?post=20287"}],"version-history":[{"count":2,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/20287\/revisions"}],"predecessor-version":[{"id":20290,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/20287\/revisions\/20290"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media\/20288"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media?parent=20287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/categories?post=20287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/tags?post=20287"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/ppma_author?post=20287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}