{"id":19833,"date":"2023-07-08T11:08:23","date_gmt":"2023-07-08T14:08:23","guid":{"rendered":"https:\/\/informatepy.com\/2022\/?p=19833"},"modified":"2023-07-08T11:08:29","modified_gmt":"2023-07-08T14:08:29","slug":"estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2022\/2023\/07\/08\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\/","title":{"rendered":"Estados Unidos enviar\u00e1 a Ucrania bombas de racimo, prohibidas en 127 pa\u00edses"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">El gobierno de\u00a0<strong>Joe Biden<\/strong>\u00a0confirm\u00f3 el env\u00edo de\u00a0<strong>municiones de racimo<\/strong>\u00a0a\u00a0<strong>Ucrania<\/strong>, para ayudar a su ej\u00e9rcito a\u00a0<strong>hacer retroceder a las tropas rusas atrincheradas<\/strong>, ya que est\u00e1n experimentando\u00a0<strong>dificultades para avanzar en la\u00a0contraofensiva<\/strong>.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Las municiones de racimo, tambi\u00e9n conocidas como\u00a0<strong>bombas de racimo<\/strong>, son proyectiles que tienen, en su interior,\u00a0<strong>decenas de bombas m\u00e1s peque\u00f1as<\/strong>, conocidas como submuniciones. Dependiendo del objetivo del que se trate, y a una altura preestablecida,\u00a0<strong>los proyectiles se abren, para que las bombas en su interior se esparzan<\/strong>.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Estados Unidos hab\u00eda tomado la decisi\u00f3n de\u00a0<strong>comenzar a eliminar gradualmente<\/strong>\u00a0a estas municiones a partir del 2016, extremadamente\u00a0<strong>controvertidas<\/strong>\u00a0ya que, como las submuniciones caen en \u00e1reas amplias,\u00a0<strong>pueden poner en peligro a un gran n\u00famero de no combatientes<\/strong>. Como hasta un 40% de ellas fallan, seg\u00fan el Comit\u00e9 Internacional de la Cruz Roja, las bombas sin explotar tienen la capacidad de ser detonadas con posterioridad por la autoridad civil. \u201c<em>Las municiones de racimo siguen siendo una de las armas m\u00e1s traicioneras del mundo.\u00a0<strong>Matan y mutilan indiscriminadamente y causan sufrimiento humano generalizado<\/strong><\/em>\u201d, dijo el vicepresidente del Comit\u00e9, Gilles Carbonnier, el a\u00f1o pasado.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Es por ello que gran parte del mundo ha\u00a0<strong>prohibido el uso de estas armas<\/strong>: 123 Estados, incluyendo\u00a0<strong>gran parte de los aliados de Estados Unidos en Europa Occidental<\/strong>, firmaron la\u00a0<strong>Convenci\u00f3n sobre Municiones de Racimo<\/strong>\u00a0(CCM) en 2008, que proh\u00edbe el uso de estas bombas, pero tambi\u00e9n su desarrollo, producci\u00f3n y transferencia. Cabe destacar que, entre los 74 pa\u00edses que no se han unido a la Convenci\u00f3n, se encuentran\u00a0<strong>Estados Unidos<\/strong>,\u00a0<strong>Ucrania<\/strong>\u00a0y\u00a0<strong>Rusia<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"youtube-embed\" data-video_id=\"Es1A1XoM5ZE\"><iframe loading=\"lazy\" title=\"How do cluster bombs work?\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/Es1A1XoM5ZE?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El gobierno de\u00a0Joe Biden\u00a0confirm\u00f3 el env\u00edo de\u00a0municiones de racimo\u00a0a\u00a0Ucrania, para ayudar a su ej\u00e9rcito a\u00a0hacer retroceder a las tropas rusas atrincheradas, ya que est\u00e1n experimentando\u00a0dificultades para avanzar en la\u00a0contraofensiva. Las municiones de racimo, tambi\u00e9n conocidas como\u00a0bombas de racimo, son proyectiles que tienen, en su interior,\u00a0decenas de bombas m\u00e1s peque\u00f1as, conocidas como submuniciones. Dependiendo del objetivo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":19834,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":false,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[14],"tags":[871,660,183,1501],"ppma_author":[1037],"class_list":["post-19833","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mundo","tag-destacada","tag-estados-unidos","tag-rusia","tag-ucrania"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estados Unidos enviar\u00e1 a Ucrania bombas de racimo, prohibidas en 127 pa\u00edses - Informatepy.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2022\/2023\/07\/08\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estados Unidos enviar\u00e1 a Ucrania bombas de racimo, prohibidas en 127 pa\u00edses - Informatepy.com\" \/>\n<meta property=\"og:description\" content=\"El gobierno de\u00a0Joe Biden\u00a0confirm\u00f3 el env\u00edo de\u00a0municiones de racimo\u00a0a\u00a0Ucrania, para ayudar a su ej\u00e9rcito a\u00a0hacer retroceder a las tropas rusas atrincheradas, ya que est\u00e1n experimentando\u00a0dificultades para avanzar en la\u00a0contraofensiva. Las municiones de racimo, tambi\u00e9n conocidas como\u00a0bombas de racimo, son proyectiles que tienen, en su interior,\u00a0decenas de bombas m\u00e1s peque\u00f1as, conocidas como submuniciones. Dependiendo del objetivo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2022\/2023\/07\/08\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-08T14:08:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-08T14:08:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/07\/bombas-de-racimo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:site\" content=\"@InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/07\\\/08\\\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/07\\\/08\\\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/e7c5b605ddfb77041eeddff4d93b26af\"},\"headline\":\"Estados Unidos enviar\u00e1 a Ucrania bombas de racimo, prohibidas en 127 pa\u00edses\",\"datePublished\":\"2023-07-08T14:08:23+00:00\",\"dateModified\":\"2023-07-08T14:08:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/07\\\/08\\\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\\\/\"},\"wordCount\":301,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/07\\\/08\\\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/bombas-de-racimo.jpg?fit=1280%2C720&ssl=1\",\"keywords\":[\"destacada\",\"estados unidos\",\"rusia\",\"ucrania\"],\"articleSection\":[\"Mundo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/07\\\/08\\\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/07\\\/08\\\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/07\\\/08\\\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\\\/\",\"name\":\"Estados Unidos enviar\u00e1 a Ucrania bombas de racimo, prohibidas en 127 pa\u00edses - Informatepy.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/07\\\/08\\\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/07\\\/08\\\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/bombas-de-racimo.jpg?fit=1280%2C720&ssl=1\",\"datePublished\":\"2023-07-08T14:08:23+00:00\",\"dateModified\":\"2023-07-08T14:08:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/07\\\/08\\\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/07\\\/08\\\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/07\\\/08\\\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/bombas-de-racimo.jpg?fit=1280%2C720&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/bombas-de-racimo.jpg?fit=1280%2C720&ssl=1\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/07\\\/08\\\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estados Unidos enviar\u00e1 a Ucrania bombas de racimo, prohibidas en 127 pa\u00edses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"name\":\"Informatepy.com\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\",\"name\":\"Informatepy.com\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"width\":589,\"height\":150,\"caption\":\"Informatepy.com\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/InformatePy1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/e7c5b605ddfb77041eeddff4d93b26af\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.pngce0c1b6da06ae20abaff417c2cdeea83\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estados Unidos enviar\u00e1 a Ucrania bombas de racimo, prohibidas en 127 pa\u00edses - Informatepy.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2022\/2023\/07\/08\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\/","og_locale":"es_ES","og_type":"article","og_title":"Estados Unidos enviar\u00e1 a Ucrania bombas de racimo, prohibidas en 127 pa\u00edses - Informatepy.com","og_description":"El gobierno de\u00a0Joe Biden\u00a0confirm\u00f3 el env\u00edo de\u00a0municiones de racimo\u00a0a\u00a0Ucrania, para ayudar a su ej\u00e9rcito a\u00a0hacer retroceder a las tropas rusas atrincheradas, ya que est\u00e1n experimentando\u00a0dificultades para avanzar en la\u00a0contraofensiva. Las municiones de racimo, tambi\u00e9n conocidas como\u00a0bombas de racimo, son proyectiles que tienen, en su interior,\u00a0decenas de bombas m\u00e1s peque\u00f1as, conocidas como submuniciones. Dependiendo del objetivo [&hellip;]","og_url":"https:\/\/informatepy.com\/2022\/2023\/07\/08\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\/","og_site_name":"Informatepy.com","article_publisher":"https:\/\/www.facebook.com\/InformatePyCom","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2023-07-08T14:08:23+00:00","article_modified_time":"2023-07-08T14:08:29+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/07\/bombas-de-racimo.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_site":"@InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2022\/2023\/07\/08\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/2023\/07\/08\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/e7c5b605ddfb77041eeddff4d93b26af"},"headline":"Estados Unidos enviar\u00e1 a Ucrania bombas de racimo, prohibidas en 127 pa\u00edses","datePublished":"2023-07-08T14:08:23+00:00","dateModified":"2023-07-08T14:08:29+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2023\/07\/08\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\/"},"wordCount":301,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2023\/07\/08\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2023\/07\/bombas-de-racimo.jpg?fit=1280%2C720&ssl=1","keywords":["destacada","estados unidos","rusia","ucrania"],"articleSection":["Mundo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2022\/2023\/07\/08\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2022\/2023\/07\/08\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\/","url":"https:\/\/informatepy.com\/2022\/2023\/07\/08\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\/","name":"Estados Unidos enviar\u00e1 a Ucrania bombas de racimo, prohibidas en 127 pa\u00edses - Informatepy.com","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2023\/07\/08\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2023\/07\/08\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2023\/07\/bombas-de-racimo.jpg?fit=1280%2C720&ssl=1","datePublished":"2023-07-08T14:08:23+00:00","dateModified":"2023-07-08T14:08:29+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2022\/2023\/07\/08\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2022\/2023\/07\/08\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/2023\/07\/08\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2023\/07\/bombas-de-racimo.jpg?fit=1280%2C720&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2023\/07\/bombas-de-racimo.jpg?fit=1280%2C720&ssl=1","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2022\/2023\/07\/08\/estados-unidos-enviara-a-ucrania-bombas-de-racimo-prohibidas-en-127-paises\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2022\/"},{"@type":"ListItem","position":2,"name":"Estados Unidos enviar\u00e1 a Ucrania bombas de racimo, prohibidas en 127 pa\u00edses"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2022\/#website","url":"https:\/\/informatepy.com\/2022\/","name":"Informatepy.com","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2022\/#organization","name":"Informatepy.com","url":"https:\/\/informatepy.com\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","width":589,"height":150,"caption":"Informatepy.com"},"image":{"@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/InformatePy1"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/e7c5b605ddfb77041eeddff4d93b26af","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.pngce0c1b6da06ae20abaff417c2cdeea83","url":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2022\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2023\/07\/bombas-de-racimo.jpg?fit=1280%2C720&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"authors":[{"term_id":1037,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png"},"author_category":"","user_url":"","last_name":"","first_name":"Redacci\u00f3n","job_title":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/19833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/comments?post=19833"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/19833\/revisions"}],"predecessor-version":[{"id":19835,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/19833\/revisions\/19835"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media\/19834"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media?parent=19833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/categories?post=19833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/tags?post=19833"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/ppma_author?post=19833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}