{"id":1697,"date":"2020-07-04T20:20:00","date_gmt":"2020-07-04T20:20:00","guid":{"rendered":"http:\/\/informatepy.com\/2022\/2020\/07\/04\/la-omerta-kirchnerista\/"},"modified":"2022-09-27T22:53:55","modified_gmt":"2022-09-27T22:53:55","slug":"la-omerta-kirchnerista","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2022\/2020\/07\/04\/la-omerta-kirchnerista\/","title":{"rendered":"La Omert\u00e1 Kirchnerista"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La \u00abOmert\u00e1\u00bb, es el c\u00f3digo de honor de la Mafia, la ley de leyes. Es la ley del silencio. Esta ley, dice que est\u00e1 terminantemente prohibido \u00absoplar\u00bb a los compa\u00f1eros ante la justicia o colaborar con las autoridades bajo ning\u00fan concepto. Obviamente, el quebrantamiento de esta ley de la Mafia se paga con la vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta ma\u00f1ana, Fabi\u00e1n Guti\u00e9rrez, ex secretario privado de Cristina Kirchner que estaba desaparecido desde el jueves, fue hallado muerto en una de las viviendas allanadas en Calafate, en el marco de la investigaci\u00f3n del caso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El hallazgo se produjo luego de que tres de los detenidos por el caso le confesaran al juez Carlos Narvarte que lo hab\u00edan matado. De acuerdo con los primeros datos de la investigaci\u00f3n, y seg\u00fan fuentes judiciales, se tratar\u00eda de un crimen \u201cpasional-extorsivo\u201d. El cuerpo de Guti\u00e9rrez se encontraba maniatado con precintos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta aqu\u00ed, todo \u00abnormal\u00bb podr\u00edamos decir, aunque no es menor el dato que Guti\u00e9rrez hab\u00eda declarado en contra de su antigua Jefa y Ex Presidente Argentina, Cristina Fern\u00e1ndez de Kirchner, en el marco de la causa donde se investigaba el lavado de dinero durante su gobierno, conocida como \u00abla ruta del dinero K\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Leer tambi\u00e9n: <a href=\"http:\/\/informatepy.com\/2020\/06\/14\/ex-mossad-vincula-a-cristina-fernandez-con-el-terrorismo-irani\/\">Ex Mossad vincula a Cristina Fern\u00e1ndez con el terrorismo iran\u00ed<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otro dato curioso, es que la fiscal del caso es la Abogada Natalia Mercado, hija de la gobernadora de Santa Cruz, Alicia Kirchner y, por ende, sobrina de la ex mandataria. Tambi\u00e9n, en el mes de febrero de este a\u00f1o, el actual presidente argentino, Alberto Fern\u00e1ndez, derog\u00f3 decreto de testigos protegidos sancionada durante el gobierno de Mauricio Macri; Fabi\u00e1n Guti\u00e9rrez, se hab\u00eda acogida a este decreto para declarar en contra de Cristina Kirchner.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/02\/testigos-protegidos.jpg?w=696&#038;ssl=1\" alt=\"\" class=\"wp-image-2830\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Este sistema, el de la omert\u00e1, es empleado por los K desde su tiempo al mando de la provincia de Santa Cruz y, obviamente, al alcanzar el poder a nivel nacional continu\u00f3 e, incluso, se hizo m\u00e1s grosero debido a la impunidad. Aqu\u00ed una lista de los casos mas resonantes:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Ra\u00fal Espinosa denunci\u00f3 la cercan\u00eda de N\u00e9stor Kirchner con el narcotr\u00e1fico. Asesinado en 2003.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Vittorio Gotti, competidor de L\u00e1zaro B\u00e1ez (Testaferro de N\u00e9stor Kirchner). Muerto en un extra\u00f1o accidente en 2004.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Forza, Bina y Ferr\u00f3n, asesinados en el triple crimen de Gral. Rodr\u00edguez, proveedores de efedrina al momento de estallar el esc\u00e1ndalo de la mafia de los medicamentos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Iv\u00e1n Heyn, camporista asesinado en Uruguay.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Juan Castro, periodista que iba a publicar fotos comprometedoras del supuesto romance entre Cristina Fern\u00e1ndes y el entonces Senador Augusto Alasino. \u00abSuicidado\u00bb en 2004. Varios de los testigos de este \u00abSuicidio\u00bb murieron en extra\u00f1as circunstancias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Familia Pomar, que aparecieron muertos tras darse a la fuga, luego de ser relacionados con la mafia de los medicamentos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Abel Beroiz, tesorero de Camioneros, asesinado en la ciudad de Rosario luego de denunciar negocios entre los K y Hugo Moyano, titular del gremio de camioneros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Carlos Soria, ex gobernador de R\u00edo Negro, muerto en aparente focejeo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Rodolfo Mora\u00f1a, de camioneros, \u00absuicidado\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Alberto Nisman, \u00absuicidado\u00bb en 2015, 24 horas antes de declarar ante el congreso argentino en la causa contra Cristina Kirchner por traic\u00f3n a la patria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Fabi\u00e1n Guti\u00e9rrez, desaparecido en julio del 2020.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n, actualmente uno de los custodios de Cristina Kirchner se encuentra desaparecido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si esta no es una pr\u00e1ctica habitual, los Kirchner, tanto N\u00e9stor como Cristina, tienen mucha, pero mucha mala suerte para las coincidencias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La \u00abOmert\u00e1\u00bb, es el c\u00f3digo de honor de la Mafia, la ley de leyes. Es la ley del silencio. Esta ley, dice que est\u00e1 terminantemente prohibido \u00absoplar\u00bb a los compa\u00f1eros ante la justicia o colaborar con las autoridades bajo ning\u00fan concepto. Obviamente, el quebrantamiento de esta ley de la Mafia se paga con la vida. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1698,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[14],"tags":[502,716,721],"ppma_author":[998],"class_list":["post-1697","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mundo","tag-argentina","tag-cristina-kirchner","tag-omerta"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Omert\u00e1 Kirchnerista - Informatepy.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2022\/2020\/07\/04\/la-omerta-kirchnerista\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Omert\u00e1 Kirchnerista - Informatepy.com\" \/>\n<meta property=\"og:description\" content=\"La \u00abOmert\u00e1\u00bb, es el c\u00f3digo de honor de la Mafia, la ley de leyes. Es la ley del silencio. Esta ley, dice que est\u00e1 terminantemente prohibido \u00absoplar\u00bb a los compa\u00f1eros ante la justicia o colaborar con las autoridades bajo ning\u00fan concepto. Obviamente, el quebrantamiento de esta ley de la Mafia se paga con la vida. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2022\/2020\/07\/04\/la-omerta-kirchnerista\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-04T20:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-27T22:53:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/07\/cristina-kirchner-pide-silecio.jpg?fit=1920%2C1079&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1079\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@InformatePy1\" \/>\n<meta name=\"twitter:site\" content=\"@InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2020\\\/07\\\/04\\\/la-omerta-kirchnerista\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2020\\\/07\\\/04\\\/la-omerta-kirchnerista\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/51a66e4894ad41947ebb945804418db8\"},\"headline\":\"La Omert\u00e1 Kirchnerista\",\"datePublished\":\"2020-07-04T20:20:00+00:00\",\"dateModified\":\"2022-09-27T22:53:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2020\\\/07\\\/04\\\/la-omerta-kirchnerista\\\/\"},\"wordCount\":612,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2020\\\/07\\\/04\\\/la-omerta-kirchnerista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cristina-kirchner-pide-silecio.jpg?fit=1920%2C1079&ssl=1\",\"keywords\":[\"argentina\",\"cristina kirchner\",\"omerta\"],\"articleSection\":[\"Mundo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2020\\\/07\\\/04\\\/la-omerta-kirchnerista\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2020\\\/07\\\/04\\\/la-omerta-kirchnerista\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2020\\\/07\\\/04\\\/la-omerta-kirchnerista\\\/\",\"name\":\"La Omert\u00e1 Kirchnerista - Informatepy.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2020\\\/07\\\/04\\\/la-omerta-kirchnerista\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2020\\\/07\\\/04\\\/la-omerta-kirchnerista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cristina-kirchner-pide-silecio.jpg?fit=1920%2C1079&ssl=1\",\"datePublished\":\"2020-07-04T20:20:00+00:00\",\"dateModified\":\"2022-09-27T22:53:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2020\\\/07\\\/04\\\/la-omerta-kirchnerista\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2020\\\/07\\\/04\\\/la-omerta-kirchnerista\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2020\\\/07\\\/04\\\/la-omerta-kirchnerista\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cristina-kirchner-pide-silecio.jpg?fit=1920%2C1079&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/cristina-kirchner-pide-silecio.jpg?fit=1920%2C1079&ssl=1\",\"width\":1920,\"height\":1079},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2020\\\/07\\\/04\\\/la-omerta-kirchnerista\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Omert\u00e1 Kirchnerista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"name\":\"Informatepy.com\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\",\"name\":\"Informatepy.com\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"width\":589,\"height\":150,\"caption\":\"Informatepy.com\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/InformatePy1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/51a66e4894ad41947ebb945804418db8\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g276449386956a98e04614ff4c246c7b8\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2022\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Omert\u00e1 Kirchnerista - Informatepy.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2022\/2020\/07\/04\/la-omerta-kirchnerista\/","og_locale":"es_ES","og_type":"article","og_title":"La Omert\u00e1 Kirchnerista - Informatepy.com","og_description":"La \u00abOmert\u00e1\u00bb, es el c\u00f3digo de honor de la Mafia, la ley de leyes. Es la ley del silencio. Esta ley, dice que est\u00e1 terminantemente prohibido \u00absoplar\u00bb a los compa\u00f1eros ante la justicia o colaborar con las autoridades bajo ning\u00fan concepto. Obviamente, el quebrantamiento de esta ley de la Mafia se paga con la vida. [&hellip;]","og_url":"https:\/\/informatepy.com\/2022\/2020\/07\/04\/la-omerta-kirchnerista\/","og_site_name":"Informatepy.com","article_publisher":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2020-07-04T20:20:00+00:00","article_modified_time":"2022-09-27T22:53:55+00:00","og_image":[{"width":1920,"height":1079,"url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/07\/cristina-kirchner-pide-silecio.jpg?fit=1920%2C1079&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@InformatePy1","twitter_site":"@InformatePy1","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2022\/2020\/07\/04\/la-omerta-kirchnerista\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/2020\/07\/04\/la-omerta-kirchnerista\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/51a66e4894ad41947ebb945804418db8"},"headline":"La Omert\u00e1 Kirchnerista","datePublished":"2020-07-04T20:20:00+00:00","dateModified":"2022-09-27T22:53:55+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2020\/07\/04\/la-omerta-kirchnerista\/"},"wordCount":612,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2020\/07\/04\/la-omerta-kirchnerista\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/07\/cristina-kirchner-pide-silecio.jpg?fit=1920%2C1079&ssl=1","keywords":["argentina","cristina kirchner","omerta"],"articleSection":["Mundo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2022\/2020\/07\/04\/la-omerta-kirchnerista\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2022\/2020\/07\/04\/la-omerta-kirchnerista\/","url":"https:\/\/informatepy.com\/2022\/2020\/07\/04\/la-omerta-kirchnerista\/","name":"La Omert\u00e1 Kirchnerista - Informatepy.com","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2020\/07\/04\/la-omerta-kirchnerista\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2020\/07\/04\/la-omerta-kirchnerista\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/07\/cristina-kirchner-pide-silecio.jpg?fit=1920%2C1079&ssl=1","datePublished":"2020-07-04T20:20:00+00:00","dateModified":"2022-09-27T22:53:55+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2022\/2020\/07\/04\/la-omerta-kirchnerista\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2022\/2020\/07\/04\/la-omerta-kirchnerista\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/2020\/07\/04\/la-omerta-kirchnerista\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/07\/cristina-kirchner-pide-silecio.jpg?fit=1920%2C1079&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/07\/cristina-kirchner-pide-silecio.jpg?fit=1920%2C1079&ssl=1","width":1920,"height":1079},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2022\/2020\/07\/04\/la-omerta-kirchnerista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2022\/"},{"@type":"ListItem","position":2,"name":"La Omert\u00e1 Kirchnerista"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2022\/#website","url":"https:\/\/informatepy.com\/2022\/","name":"Informatepy.com","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2022\/#organization","name":"Informatepy.com","url":"https:\/\/informatepy.com\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","width":589,"height":150,"caption":"Informatepy.com"},"image":{"@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/InformatePy1"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/51a66e4894ad41947ebb945804418db8","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g276449386956a98e04614ff4c246c7b8","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/informatepy.com\/2022"],"url":"https:\/\/informatepy.com\/2022\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/07\/cristina-kirchner-pide-silecio.jpg?fit=1920%2C1079&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"authors":[{"term_id":998,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","author_category":"","user_url":"http:\/\/informatepy.com\/2022","last_name":"","first_name":"","job_title":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/1697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/comments?post=1697"}],"version-history":[{"count":2,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/1697\/revisions"}],"predecessor-version":[{"id":12296,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/1697\/revisions\/12296"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media\/1698"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media?parent=1697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/categories?post=1697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/tags?post=1697"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/ppma_author?post=1697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}