{"id":16727,"date":"2023-01-02T07:35:00","date_gmt":"2023-01-02T10:35:00","guid":{"rendered":"https:\/\/informatepy.com\/2022\/?p=16727"},"modified":"2023-01-01T20:02:20","modified_gmt":"2023-01-01T23:02:20","slug":"bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2022\/2023\/01\/02\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\/","title":{"rendered":"Bolivia 2023: Devaluaci\u00f3n, Gasolinazo y Terrorismo de Estado"},"content":{"rendered":"\n<p class=\"has-text-align-justify\">Mientras la ciudadan\u00eda se preparaba para despedir el a\u00f1o 2022, el r\u00e9gimen boliviano secuestraba a <strong>Luis Fernando Camacho<\/strong>, gobernador del departamento de Santa Cruz.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Hay varias especulaciones sobre las motivaciones que tuvo el gobierno para volver a enfrentarse con la regi\u00f3n m\u00e1s pr\u00f3spera de Bolivia. Se habla hasta de un regalo navide\u00f1o de <strong>Luis Arce Catacora <\/strong>a <strong>Evo Morales<\/strong>. Pero todo parece indicar que los motivos son m\u00e1s serios que una simple reconciliaci\u00f3n entre el bur\u00f3crata y el cocalero.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Primero, la fuerte inflaci\u00f3n internacional y la alta probabilidad de recesi\u00f3n global amenazan con elevar la cotizaci\u00f3n del precio del petr\u00f3leo. Sin embargo, a diferencia del pasado, este no ser\u00eda un factor a favor de Bolivia, sino de preocupaci\u00f3n. Pues la capacidad de producci\u00f3n de Yacimientos Petrol\u00edferos Fiscales Bolivianos (YPFB) es cada vez menor, por ende, la necesidad de importar combustibles es cada vez mayor.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Segundo, como agravante de la situaci\u00f3n anterior, las divisas, la parte m\u00e1s l\u00edquida de las Reservas Internacionales, apenas alcanzan a $us 758 millones. Tenemos que comprar una gasolina m\u00e1s cara, pero nosotros tenemos menos dinero. Adem\u00e1s, con tan poco nivel de liquidez, las presiones sobre el tipo de cambio son cada vez mayores. Es decir, que estamos con un alto riesgo de devaluaci\u00f3n.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/04\/vir-banner.png?resize=522%2C123&#038;ssl=1\" alt=\"\" class=\"wp-image-10087\" width=\"522\" height=\"123\"\/><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-justify\">Para enfrentar este complicado escenario, <strong>Arce Catacora<\/strong> est\u00e1 apostando por el incremento, de la ya elevada, deuda p\u00fablica. Al respecto, <strong>Luisa Nayar<\/strong>, diputada de oposici\u00f3n, el 22 de diciembre pasado en una entrevista al peri\u00f3dico <em>P\u00e1gina Siete<\/em>, expres\u00f3 lo siguiente:<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Est\u00e1n cada vez gestando m\u00e1s pr\u00e9stamos internacionales y clar\u00edsimo es el ejemplo porque ma\u00f1ana tenemos una sesi\u00f3n en la Comisi\u00f3n de Planificaci\u00f3n donde se va a tratar un proyecto de ley de un pr\u00e9stamo con el BID de $us 100 millones, de un pr\u00e9stamo con el Instituto de Cr\u00e9dito Fiscal de $us 30 millones, un cr\u00e9dito de la Agencia Francesa para el Desarrollo de 200 millones de euros, de un cr\u00e9dito con el Banco Mundial de $us 300 millones.<\/p><\/blockquote><\/figure>\n\n\n\n<p class=\"has-text-align-justify\">Note la paradoja, esos que, en teor\u00eda, gobiernan obedeciendo al pueblo, est\u00e1n hipotecando el futuro del pa\u00eds para, tan solo, intentar sostener su fracasado modelo.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Pero si la apuesta por el endeudamiento no sale bien \u2015peor si consideramos que la calificadora Standard &amp; Poor\u2019s decidi\u00f3 rebajar la calificaci\u00f3n de riesgo de Bolivia\u2015, la dictadura va a recurrir al otro elemento de la franquicia castrochavista: <em>el terrorismo de Estado.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify\">Se entiende el Terrorismo de Estado como los cr\u00edmenes ejercidos desde el gobierno sobre una poblaci\u00f3n civil y desarmada. Las dictaduras utilizan esta metodolog\u00eda para obligar a la ciudadan\u00eda a aceptar cosas que en condiciones normales jam\u00e1s lo har\u00eda, por ejemplo, cupos de racionamiento de combustible o tarjetas de alimentos. La idea es que nadie se queje o proteste si el dictador ordena que todos nos muramos de hambre, menos \u00e9l, obviamente.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/04\/balderrama-zermat.png?resize=525%2C146&#038;ssl=1\" alt=\"\" class=\"wp-image-10351\" width=\"525\" height=\"146\"\/><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-justify\">Entonces, todo parece indicar que \u2015especialmente, luego de la reuni\u00f3n entre <strong>Luis Arce Catacora<\/strong> y <strong>Miguel Diaz Canel<\/strong>\u2015 la dictadura boliviana est\u00e1 dispuesta a avanzar en la agenda totalitaria del Socialismo del Siglo 21. Al final, la supuesta divisi\u00f3n del MAS no es nada m\u00e1s que un detalle, porque para el Castrochavismo lo importante es cumplir sus objetivos, los t\u00edteres son reemplazables.<\/p>\n\n\n\n<p>Me gustar\u00eda desearle un pr\u00f3spero 2023, pero ser\u00eda una burla, \u00a1pobre Bolivia!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mientras la ciudadan\u00eda se preparaba para despedir el a\u00f1o 2022, el r\u00e9gimen boliviano secuestraba a Luis Fernando Camacho, gobernador del departamento de Santa Cruz. Hay varias especulaciones sobre las motivaciones que tuvo el gobierno para volver a enfrentarse con la regi\u00f3n m\u00e1s pr\u00f3spera de Bolivia. Se habla hasta de un regalo navide\u00f1o de Luis Arce [&hellip;]<\/p>\n","protected":false},"author":31,"featured_media":6071,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[92],"tags":[553,871,407],"ppma_author":[1021],"class_list":{"0":"post-16727","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-analisis","8":"tag-bolivia","9":"tag-destacada","10":"tag-inflacion"},"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bolivia 2023: Devaluaci\u00f3n, Gasolinazo y Terrorismo de Estado - Informatepy.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2022\/2023\/01\/02\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolivia 2023: Devaluaci\u00f3n, Gasolinazo y Terrorismo de Estado - Informatepy.com\" \/>\n<meta property=\"og:description\" content=\"Mientras la ciudadan\u00eda se preparaba para despedir el a\u00f1o 2022, el r\u00e9gimen boliviano secuestraba a Luis Fernando Camacho, gobernador del departamento de Santa Cruz. Hay varias especulaciones sobre las motivaciones que tuvo el gobierno para volver a enfrentarse con la regi\u00f3n m\u00e1s pr\u00f3spera de Bolivia. Se habla hasta de un regalo navide\u00f1o de Luis Arce [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2022\/2023\/01\/02\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-02T10:35:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/11\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hugo Marcelo Balderrama\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/hugobalderrama\" \/>\n<meta name=\"twitter:site\" content=\"@InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hugo Marcelo Balderrama\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/01\\\/02\\\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/01\\\/02\\\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\\\/\"},\"author\":{\"name\":\"Hugo Marcelo Balderrama\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/2afd2fb41a32854dba0b74368813f3fe\"},\"headline\":\"Bolivia 2023: Devaluaci\u00f3n, Gasolinazo y Terrorismo de Estado\",\"datePublished\":\"2023-01-02T10:35:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/01\\\/02\\\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\\\/\"},\"wordCount\":598,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/01\\\/02\\\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1\",\"keywords\":[\"Bolivia\",\"destacada\",\"inflacion\"],\"articleSection\":[\"Analisis\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/01\\\/02\\\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/01\\\/02\\\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/01\\\/02\\\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\\\/\",\"name\":\"Bolivia 2023: Devaluaci\u00f3n, Gasolinazo y Terrorismo de Estado - Informatepy.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/01\\\/02\\\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/01\\\/02\\\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1\",\"datePublished\":\"2023-01-02T10:35:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/01\\\/02\\\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/01\\\/02\\\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/01\\\/02\\\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1\",\"width\":1280,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2023\\\/01\\\/02\\\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bolivia 2023: Devaluaci\u00f3n, Gasolinazo y Terrorismo de Estado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"name\":\"Informatepy.com\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\",\"name\":\"Informatepy.com\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"width\":589,\"height\":150,\"caption\":\"Informatepy.com\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/InformatePy1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/2afd2fb41a32854dba0b74368813f3fe\",\"name\":\"Hugo Marcelo Balderrama\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/balderrama.jpg2b64d5f06afe56832edf09c51cec9b87\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/balderrama.jpg\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/balderrama.jpg\",\"caption\":\"Hugo Marcelo Balderrama\"},\"description\":\"Economista, Docente, Periodista y Consultor Pol\u00edtico. Comprometido con la defensa de la vida, la propiedad y la libertad.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/hugobalderrama\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/author\\\/hbalderrama\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bolivia 2023: Devaluaci\u00f3n, Gasolinazo y Terrorismo de Estado - Informatepy.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2022\/2023\/01\/02\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\/","og_locale":"es_ES","og_type":"article","og_title":"Bolivia 2023: Devaluaci\u00f3n, Gasolinazo y Terrorismo de Estado - Informatepy.com","og_description":"Mientras la ciudadan\u00eda se preparaba para despedir el a\u00f1o 2022, el r\u00e9gimen boliviano secuestraba a Luis Fernando Camacho, gobernador del departamento de Santa Cruz. Hay varias especulaciones sobre las motivaciones que tuvo el gobierno para volver a enfrentarse con la regi\u00f3n m\u00e1s pr\u00f3spera de Bolivia. Se habla hasta de un regalo navide\u00f1o de Luis Arce [&hellip;]","og_url":"https:\/\/informatepy.com\/2022\/2023\/01\/02\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\/","og_site_name":"Informatepy.com","article_publisher":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2023-01-02T10:35:00+00:00","og_image":[{"width":1280,"height":700,"url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/11\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1","type":"image\/jpeg"}],"author":"Hugo Marcelo Balderrama","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/hugobalderrama","twitter_site":"@InformatePy1","twitter_misc":{"Escrito por":"Hugo Marcelo Balderrama","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2022\/2023\/01\/02\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/2023\/01\/02\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\/"},"author":{"name":"Hugo Marcelo Balderrama","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/2afd2fb41a32854dba0b74368813f3fe"},"headline":"Bolivia 2023: Devaluaci\u00f3n, Gasolinazo y Terrorismo de Estado","datePublished":"2023-01-02T10:35:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2023\/01\/02\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\/"},"wordCount":598,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2023\/01\/02\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/11\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1","keywords":["Bolivia","destacada","inflacion"],"articleSection":["Analisis"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2022\/2023\/01\/02\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2022\/2023\/01\/02\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\/","url":"https:\/\/informatepy.com\/2022\/2023\/01\/02\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\/","name":"Bolivia 2023: Devaluaci\u00f3n, Gasolinazo y Terrorismo de Estado - Informatepy.com","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2023\/01\/02\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2023\/01\/02\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/11\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1","datePublished":"2023-01-02T10:35:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2022\/2023\/01\/02\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2022\/2023\/01\/02\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/2023\/01\/02\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/11\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/11\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1","width":1280,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2022\/2023\/01\/02\/bolivia-2023-devaluacion-gasolinazo-y-terrorismo-de-estado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2022\/"},{"@type":"ListItem","position":2,"name":"Bolivia 2023: Devaluaci\u00f3n, Gasolinazo y Terrorismo de Estado"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2022\/#website","url":"https:\/\/informatepy.com\/2022\/","name":"Informatepy.com","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2022\/#organization","name":"Informatepy.com","url":"https:\/\/informatepy.com\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","width":589,"height":150,"caption":"Informatepy.com"},"image":{"@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/InformatePy1"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/2afd2fb41a32854dba0b74368813f3fe","name":"Hugo Marcelo Balderrama","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2022\/10\/balderrama.jpg2b64d5f06afe56832edf09c51cec9b87","url":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2022\/10\/balderrama.jpg","contentUrl":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2022\/10\/balderrama.jpg","caption":"Hugo Marcelo Balderrama"},"description":"Economista, Docente, Periodista y Consultor Pol\u00edtico. Comprometido con la defensa de la vida, la propiedad y la libertad.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/hugobalderrama"],"url":"https:\/\/informatepy.com\/2022\/author\/hbalderrama\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/11\/HUGO-BALDERRAMA-COLUMNISTA.jpg?fit=1280%2C700&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"authors":[{"term_id":1021,"user_id":31,"is_guest":0,"slug":"hbalderrama","display_name":"Hugo Marcelo Balderrama","avatar_url":{"url":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2022\/10\/balderrama.jpg","url2x":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2022\/10\/balderrama.jpg"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/16727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/comments?post=16727"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/16727\/revisions"}],"predecessor-version":[{"id":16728,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/16727\/revisions\/16728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media\/6071"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media?parent=16727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/categories?post=16727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/tags?post=16727"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/ppma_author?post=16727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}