{"id":11707,"date":"2022-08-17T18:51:19","date_gmt":"2022-08-17T18:51:19","guid":{"rendered":"http:\/\/informatepy.com\/2022\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/"},"modified":"2022-09-28T00:53:44","modified_gmt":"2022-09-28T00:53:44","slug":"el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2022\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/","title":{"rendered":"El TEP de la ANR ya neg\u00f3 una sustituci\u00f3n por renuncia a la lista de Petta"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">En horas de la tarde, el ex ministro de educaci\u00f3n, <strong>Eduardo Petta<\/strong>, mencion\u00f3 que el Tribunal Electoral Partidario (TEP) del Partido Colorado, le neg\u00f3 a su movimiento <strong>\u00abEducaci\u00f3n Primero\u00bb<\/strong>, la sustituci\u00f3n de un candidato al senado por renuncia.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">En la comunicaci\u00f3n del TEP, le comunicaron a Petta que resolvieron <strong>NO HACER LUGAR<\/strong> a su pedido por ser \u00e9ste <strong>EXTEMPOR\u00c1NEO<\/strong> y, para solucionar la situaci\u00f3n, <strong>debi\u00f3 reposicionar a sus candidatos para cubrir los espacios.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">En pocas palabras, los antecedentes del propio TEP de la ANR indicar\u00edan que, si actuaran conforme a derecho, a la ley; <strong>para hacer lugar a la renuncia de Hugo Vel\u00e1zquez, el movimiento Fuerza Republicana deber\u00eda reposicionar sus candidatos, <\/strong>dejando como \u00fanica dupla viable a<strong> Juan Manuel Brunetti Presidente, Derlis Ozorio Vicepresidente .<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">El Movimiento Educaci\u00f3n Primero ( MEP-ANR ) hizo sustituci\u00f3n por RENUNCIA en la lista senado . El TEP resolvi\u00f3 \ud83d\udc46\ud83c\udffc \u201cRECHAZAR por EXTEMPOR\u00c1NEO\u201d y tuve que plantear REPOSICI\u00d3N. <a href=\"https:\/\/t.co\/hzGhrhDjd4\">pic.twitter.com\/hzGhrhDjd4<\/a><\/p>&mdash; Eduardo Petta (@petta08) <a href=\"https:\/\/twitter.com\/petta08\/status\/1559930434238222343?ref_src=twsrc%5Etfw\">August 17, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>En horas de la tarde, el ex ministro de educaci\u00f3n, Eduardo Petta, mencion\u00f3 que el Tribunal Electoral Partidario (TEP) del Partido Colorado, le neg\u00f3 a su movimiento \u00abEducaci\u00f3n Primero\u00bb, la sustituci\u00f3n de un candidato al senado por renuncia. En la comunicaci\u00f3n del TEP, le comunicaron a Petta que resolvieron NO HACER LUGAR a su pedido [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":601,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[18],"tags":[111,871,200,1417,260],"ppma_author":[1037],"class_list":["post-11707","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales","tag-anr","tag-destacada","tag-eduardo-petta","tag-elecciones-2023","tag-partido-colorado"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El TEP de la ANR ya neg\u00f3 una sustituci\u00f3n por renuncia a la lista de Petta - Informatepy.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2022\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El TEP de la ANR ya neg\u00f3 una sustituci\u00f3n por renuncia a la lista de Petta - Informatepy.com\" \/>\n<meta property=\"og:description\" content=\"En horas de la tarde, el ex ministro de educaci\u00f3n, Eduardo Petta, mencion\u00f3 que el Tribunal Electoral Partidario (TEP) del Partido Colorado, le neg\u00f3 a su movimiento \u00abEducaci\u00f3n Primero\u00bb, la sustituci\u00f3n de un candidato al senado por renuncia. En la comunicaci\u00f3n del TEP, le comunicaron a Petta que resolvieron NO HACER LUGAR a su pedido [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2022\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-17T18:51:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-28T00:53:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/03\/eduardo-petta.jpg?fit=760%2C420&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:site\" content=\"@InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2022\\\/08\\\/17\\\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2022\\\/08\\\/17\\\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/e7c5b605ddfb77041eeddff4d93b26af\"},\"headline\":\"El TEP de la ANR ya neg\u00f3 una sustituci\u00f3n por renuncia a la lista de Petta\",\"datePublished\":\"2022-08-17T18:51:19+00:00\",\"dateModified\":\"2022-09-28T00:53:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2022\\\/08\\\/17\\\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\\\/\"},\"wordCount\":155,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2022\\\/08\\\/17\\\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/eduardo-petta.jpg?fit=760%2C420&ssl=1\",\"keywords\":[\"anr\",\"destacada\",\"eduardo petta\",\"elecciones 2023\",\"partido colorado\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2022\\\/08\\\/17\\\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2022\\\/08\\\/17\\\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2022\\\/08\\\/17\\\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\\\/\",\"name\":\"El TEP de la ANR ya neg\u00f3 una sustituci\u00f3n por renuncia a la lista de Petta - Informatepy.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2022\\\/08\\\/17\\\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2022\\\/08\\\/17\\\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/eduardo-petta.jpg?fit=760%2C420&ssl=1\",\"datePublished\":\"2022-08-17T18:51:19+00:00\",\"dateModified\":\"2022-09-28T00:53:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2022\\\/08\\\/17\\\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2022\\\/2022\\\/08\\\/17\\\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2022\\\/08\\\/17\\\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/eduardo-petta.jpg?fit=760%2C420&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/eduardo-petta.jpg?fit=760%2C420&ssl=1\",\"width\":760,\"height\":420,\"caption\":\"Eduardo Petta, titular del MEC. Foto: La Naci\u00f3n.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/2022\\\/08\\\/17\\\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El TEP de la ANR ya neg\u00f3 una sustituci\u00f3n por renuncia a la lista de Petta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"name\":\"Informatepy.com\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#organization\",\"name\":\"Informatepy.com\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/informatepy150-2.png?fit=589%2C150\",\"width\":589,\"height\":150,\"caption\":\"Informatepy.com\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/InformatePy1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/#\\\/schema\\\/person\\\/e7c5b605ddfb77041eeddff4d93b26af\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.pngce0c1b6da06ae20abaff417c2cdeea83\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Isologo-sin-fondo.png\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2022\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El TEP de la ANR ya neg\u00f3 una sustituci\u00f3n por renuncia a la lista de Petta - Informatepy.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2022\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/","og_locale":"es_ES","og_type":"article","og_title":"El TEP de la ANR ya neg\u00f3 una sustituci\u00f3n por renuncia a la lista de Petta - Informatepy.com","og_description":"En horas de la tarde, el ex ministro de educaci\u00f3n, Eduardo Petta, mencion\u00f3 que el Tribunal Electoral Partidario (TEP) del Partido Colorado, le neg\u00f3 a su movimiento \u00abEducaci\u00f3n Primero\u00bb, la sustituci\u00f3n de un candidato al senado por renuncia. En la comunicaci\u00f3n del TEP, le comunicaron a Petta que resolvieron NO HACER LUGAR a su pedido [&hellip;]","og_url":"https:\/\/informatepy.com\/2022\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/","og_site_name":"Informatepy.com","article_publisher":"https:\/\/www.facebook.com\/InformatePyCom","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-08-17T18:51:19+00:00","article_modified_time":"2022-09-28T00:53:44+00:00","og_image":[{"width":760,"height":420,"url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/03\/eduardo-petta.jpg?fit=760%2C420&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_site":"@InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2022\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/e7c5b605ddfb77041eeddff4d93b26af"},"headline":"El TEP de la ANR ya neg\u00f3 una sustituci\u00f3n por renuncia a la lista de Petta","datePublished":"2022-08-17T18:51:19+00:00","dateModified":"2022-09-28T00:53:44+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/"},"wordCount":155,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/03\/eduardo-petta.jpg?fit=760%2C420&ssl=1","keywords":["anr","destacada","eduardo petta","elecciones 2023","partido colorado"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2022\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2022\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/","url":"https:\/\/informatepy.com\/2022\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/","name":"El TEP de la ANR ya neg\u00f3 una sustituci\u00f3n por renuncia a la lista de Petta - Informatepy.com","isPartOf":{"@id":"https:\/\/informatepy.com\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2022\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2022\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/03\/eduardo-petta.jpg?fit=760%2C420&ssl=1","datePublished":"2022-08-17T18:51:19+00:00","dateModified":"2022-09-28T00:53:44+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2022\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2022\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/03\/eduardo-petta.jpg?fit=760%2C420&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/03\/eduardo-petta.jpg?fit=760%2C420&ssl=1","width":760,"height":420,"caption":"Eduardo Petta, titular del MEC. Foto: La Naci\u00f3n."},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2022\/2022\/08\/17\/el-tep-de-la-anr-ya-nego-una-sustitucion-por-renuncia-a-la-lista-de-petta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2022\/"},{"@type":"ListItem","position":2,"name":"El TEP de la ANR ya neg\u00f3 una sustituci\u00f3n por renuncia a la lista de Petta"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2022\/#website","url":"https:\/\/informatepy.com\/2022\/","name":"Informatepy.com","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/informatepy.com\/2022\/#organization","name":"Informatepy.com","url":"https:\/\/informatepy.com\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2022\/09\/informatepy150-2.png?fit=589%2C150","width":589,"height":150,"caption":"Informatepy.com"},"image":{"@id":"https:\/\/informatepy.com\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/InformatePy1"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2022\/#\/schema\/person\/e7c5b605ddfb77041eeddff4d93b26af","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.pngce0c1b6da06ae20abaff417c2cdeea83","url":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","contentUrl":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2022\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2022\/wp-content\/uploads\/2021\/03\/eduardo-petta.jpg?fit=760%2C420&ssl=1","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"authors":[{"term_id":1037,"user_id":3,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":{"url":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png","url2x":"https:\/\/informatepy.com\/2022\/wp-content\/uploads\/2023\/04\/Isologo-sin-fondo.png"},"author_category":"","user_url":"","last_name":"","first_name":"Redacci\u00f3n","job_title":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/11707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/comments?post=11707"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/11707\/revisions"}],"predecessor-version":[{"id":14209,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/posts\/11707\/revisions\/14209"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media\/601"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/media?parent=11707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/categories?post=11707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/tags?post=11707"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2022\/wp-json\/wp\/v2\/ppma_author?post=11707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}