{"id":9979,"date":"2022-02-05T12:42:44","date_gmt":"2022-02-05T15:42:44","guid":{"rendered":"https:\/\/informatepy.com\/2021\/?p=9979"},"modified":"2022-02-05T12:45:37","modified_gmt":"2022-02-05T15:45:37","slug":"gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2022\/02\/05\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\/","title":{"rendered":"GoFundMe suspende por segunda vez la campa\u00f1a de recaudaci\u00f3n en apoyo a los camioneros canadienses tras acumularse m\u00e1s de 10 millones de d\u00f3lares"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">El servicio de recaudaci\u00f3n de fondos virtual <strong>GoFundMe\u00a0<\/strong>suspendi\u00f3\u00a0una campa\u00f1a en apoyo a los camioneros canadienses del denominado &#8216;convoy de la libertad&#8217; que acapar\u00f3 estos d\u00edas los titulares con su protestas contra la vacunaci\u00f3n obligatoria para los transportistas. La interrupci\u00f3n se produjo cuando ya se acumularon m\u00e1s de 10 millones de d\u00f3lares.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">\u00abEsta recaudaci\u00f3n de fondos est\u00e1 actualmente&nbsp;<strong>en pausa<\/strong>&nbsp;y bajo revisi\u00f3n para asegurar que cumple con nuestros t\u00e9rminos de servicio y las leyes y regulaciones aplicables. Nuestro equipo est\u00e1 trabajando 24\/7 y haciendo todo lo posible para proteger tanto a los organizadores como a los donantes\u00bb, cita&nbsp;<a href=\"https:\/\/www.ctvnews.ca\/canada\/trucker-convoy-gofundme-suspended-after-reaching-10-1-million-1.5765794\" target=\"_blank\" rel=\"noreferrer noopener\">CTV News<\/a>&nbsp;el mensaje de la plataforma.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"a-donde-va-el-dinero\">\u00bfA d\u00f3nde va el dinero?<\/h3>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Es la segunda vez que la campa\u00f1a se pone en pausa. A mediados de enero el servicio congel\u00f3 los fondos recaudados (4,5 millones),&nbsp;esgrimiendo tambi\u00e9n la necesidad de&nbsp;<strong>comprobar<\/strong>&nbsp;c\u00f3mo van a distribuirse. El jueves pasado el primer tramo de un mill\u00f3n fue entregado a los organizadores de la iniciativa tras recibir GoFundMe el plan para repartir el dinero entre los transportistas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se trata de la segunda vez que el servicio pone en pausa la iniciativa para comprobar c\u00f3mo se distribuir\u00e1n los fondos recaudados.<\/p>\n","protected":false},"author":4,"featured_media":9982,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[197],"tags":[1391,1036,1668],"ppma_author":[1051],"class_list":["post-9979","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnologia","tag-canada","tag-destacada","tag-gofundme"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GoFundMe suspende por segunda vez la campa\u00f1a de recaudaci\u00f3n en apoyo a los camioneros canadienses tras acumularse m\u00e1s de 10 millones de d\u00f3lares - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2022\/02\/05\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GoFundMe suspende por segunda vez la campa\u00f1a de recaudaci\u00f3n en apoyo a los camioneros canadienses tras acumularse m\u00e1s de 10 millones de d\u00f3lares - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Se trata de la segunda vez que el servicio pone en pausa la iniciativa para comprobar c\u00f3mo se distribuir\u00e1n los fondos recaudados.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2022\/02\/05\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-05T15:42:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-05T15:45:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/gofundme.png\" \/>\n\t<meta property=\"og:image:width\" content=\"712\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/05\\\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/05\\\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\"},\"headline\":\"GoFundMe suspende por segunda vez la campa\u00f1a de recaudaci\u00f3n en apoyo a los camioneros canadienses tras acumularse m\u00e1s de 10 millones de d\u00f3lares\",\"datePublished\":\"2022-02-05T15:42:44+00:00\",\"dateModified\":\"2022-02-05T15:45:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/05\\\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\\\/\"},\"wordCount\":219,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/05\\\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/gofundme.png?fit=712%2C400&ssl=1\",\"keywords\":[\"canada\",\"destacada\",\"gofundme\"],\"articleSection\":[\"Ciencia y Tecnolog\u00eda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/05\\\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/05\\\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/05\\\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\\\/\",\"name\":\"GoFundMe suspende por segunda vez la campa\u00f1a de recaudaci\u00f3n en apoyo a los camioneros canadienses tras acumularse m\u00e1s de 10 millones de d\u00f3lares - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/05\\\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/05\\\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/gofundme.png?fit=712%2C400&ssl=1\",\"datePublished\":\"2022-02-05T15:42:44+00:00\",\"dateModified\":\"2022-02-05T15:45:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/05\\\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/05\\\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/05\\\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/gofundme.png?fit=712%2C400&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/gofundme.png?fit=712%2C400&ssl=1\",\"width\":712,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/05\\\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GoFundMe suspende por segunda vez la campa\u00f1a de recaudaci\u00f3n en apoyo a los camioneros canadienses tras acumularse m\u00e1s de 10 millones de d\u00f3lares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GoFundMe suspende por segunda vez la campa\u00f1a de recaudaci\u00f3n en apoyo a los camioneros canadienses tras acumularse m\u00e1s de 10 millones de d\u00f3lares - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2022\/02\/05\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\/","og_locale":"es_ES","og_type":"article","og_title":"GoFundMe suspende por segunda vez la campa\u00f1a de recaudaci\u00f3n en apoyo a los camioneros canadienses tras acumularse m\u00e1s de 10 millones de d\u00f3lares - Informatepy","og_description":"Se trata de la segunda vez que el servicio pone en pausa la iniciativa para comprobar c\u00f3mo se distribuir\u00e1n los fondos recaudados.","og_url":"https:\/\/informatepy.com\/2021\/2022\/02\/05\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\/","og_site_name":"Informatepy","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-02-05T15:42:44+00:00","article_modified_time":"2022-02-05T15:45:37+00:00","og_image":[{"width":712,"height":400,"url":"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/gofundme.png","type":"image\/png"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2022\/02\/05\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2022\/02\/05\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b"},"headline":"GoFundMe suspende por segunda vez la campa\u00f1a de recaudaci\u00f3n en apoyo a los camioneros canadienses tras acumularse m\u00e1s de 10 millones de d\u00f3lares","datePublished":"2022-02-05T15:42:44+00:00","dateModified":"2022-02-05T15:45:37+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/02\/05\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\/"},"wordCount":219,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/02\/05\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/gofundme.png?fit=712%2C400&ssl=1","keywords":["canada","destacada","gofundme"],"articleSection":["Ciencia y Tecnolog\u00eda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2022\/02\/05\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2022\/02\/05\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\/","url":"https:\/\/informatepy.com\/2021\/2022\/02\/05\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\/","name":"GoFundMe suspende por segunda vez la campa\u00f1a de recaudaci\u00f3n en apoyo a los camioneros canadienses tras acumularse m\u00e1s de 10 millones de d\u00f3lares - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/02\/05\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/02\/05\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/gofundme.png?fit=712%2C400&ssl=1","datePublished":"2022-02-05T15:42:44+00:00","dateModified":"2022-02-05T15:45:37+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2022\/02\/05\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2022\/02\/05\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2022\/02\/05\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/gofundme.png?fit=712%2C400&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/gofundme.png?fit=712%2C400&ssl=1","width":712,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2022\/02\/05\/gofundme-suspende-por-segunda-vez-la-campana-de-recaudacion-en-apoyo-a-los-camioneros-canadienses-tras-acumularse-mas-de-10-millones-de-dolares\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"GoFundMe suspende por segunda vez la campa\u00f1a de recaudaci\u00f3n en apoyo a los camioneros canadienses tras acumularse m\u00e1s de 10 millones de d\u00f3lares"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2021\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/gofundme.png?fit=712%2C400&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":9810,"url":"https:\/\/informatepy.com\/2021\/2022\/01\/28\/facebook-elimino-el-grupo-del-convoy-de-camioneros-canadienses-y-gofundme-retiene-los-fondos-recolectados-en-apoyo-de-la-protesta\/","url_meta":{"origin":9979,"position":0},"title":"Facebook elimin\u00f3 el grupo del convoy de camioneros canadienses y GoFundMe retiene los fondos recolectados en apoyo de la protesta","date":"28 de enero de 2022","format":false,"excerpt":"Los organizadores de la protesta en Canad\u00e1 contras los mandatos de vacunaci\u00f3n ordenados por el gobierno de Justin Trudeau, denunciaron que el grupo de Facebook, \"Canada Truckers For Freedom\", donde actualizaban la informaci\u00f3n de la marcha ha sido eliminado por la red social. El grupo, al momento de ser eliminado,\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/fuck-trudeau.jpg?fit=700%2C394&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10347,"url":"https:\/\/informatepy.com\/2021\/2022\/02\/28\/gofundme-quiso-robar-los-fondos-del-convoy-por-la-libertad\/","url_meta":{"origin":9979,"position":1},"title":"GoFundMe quiso robar los fondos del \u00abConvoy por la libertad\u00bb","date":"28 de febrero de 2022","format":false,"excerpt":"Luego de retener los casi 9 millones de d\u00f3lares recaudados por los organizadores del \"Convoy por la libertad\", la plataforma GoFundMe anunci\u00f3 que redirigir\u00eda esas donaciones a una serie de ONG\u00b4s, obviamente cercanas a su ideolog\u00eda, y no a sus verdaderos destinatarios, los camioneros canadienses. Jim Watson, Alcalde de Ottawa,\u00a0se\u2026","rel":"","context":"En \u00abCiencia y Tecnolog\u00eda\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/gofundme.png?fit=712%2C400&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10006,"url":"https:\/\/informatepy.com\/2021\/2022\/02\/07\/gofundme-considera-el-periodismo-una-conducta-prohibida\/","url_meta":{"origin":9979,"position":2},"title":"GoFundMe considera el periodismo como una \u00abConducta Prohibida\u00bb","date":"7 de febrero de 2022","format":false,"excerpt":"Una periodista canadiense que se encontraba cubriendo las multitudinarias manifestaciones contra el gobierno de Justin Trudeau en la ciudad canadiense de Ottawa, recibi\u00f3 un mensaje de cancelaci\u00f3n de la plataforma GoFundMe. A la periodista conocida en redes sociales con el nombre de usuario de @CarymaRules (Twitter), la plataforma le cancel\u00f3\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/caryma-periodista.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9817,"url":"https:\/\/informatepy.com\/2021\/2022\/01\/29\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\/","url_meta":{"origin":9979,"position":3},"title":"Elon Musk tuitea en apoyo a los camioneros canadienses","date":"29 de enero de 2022","format":false,"excerpt":"El multimillonario Elon Musk ha tuiteado su apoyo a los camioneros canadienses y, dado el momento, parece ser un visto bueno para los camioneros que protestan por los mandatos de vacunas para los conductores transfronterizos y otras restricciones de cierre. Musk, due\u00f1o de Tesla y SpaceX y nunca tiene miedo\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/01\/elon-musk.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10344,"url":"https:\/\/informatepy.com\/2021\/2022\/02\/27\/donald-trump-no-olvida-a-los-camioneros-canadienses\/","url_meta":{"origin":9979,"position":4},"title":"Donald Trump no olvida a los camioneros canadienses","date":"27 de febrero de 2022","format":false,"excerpt":"En el marco de la Conferencia de Acci\u00f3n Pol\u00edtica Conservadora (CPAC - por sus siglas en Ingl\u00e9s), el expresidente Donald Trump, record\u00f3 la falta de libertad y la brutal represi\u00f3n sufrida por los ciudadanos canadienses del \"Convoy por la Libertad\". En su discurso afirm\u00f3 que \u201cSi quieren luchar por las\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/trump-cpac-2022.jpg?fit=1024%2C682&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9846,"url":"https:\/\/informatepy.com\/2021\/2022\/01\/29\/canada-justin-trudeau-y-su-familia-se-mudan-a-un-lugar-secreto-por-temor-a-las-protestas-de-los-camioneros\/","url_meta":{"origin":9979,"position":5},"title":"Canad\u00e1: Justin Trudeau y su familia se mudan a un lugar secreto por temor a las protestas de los camioneros","date":"29 de enero de 2022","format":false,"excerpt":"CBC inform\u00f3 que el primer ministro canadiense,\u00a0Justin Trudeau, y su familia abandonaron su casa en Ottawa para ir a un lugar secreto, en medio de preocupaciones de seguridad debido a que miles de personas llegaron a la capital canadiense el s\u00e1bado en convoyes de camiones para protestar por los mandatos\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/justin-trudeau.jpg?fit=710%2C399&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1051,"user_id":4,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/9979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=9979"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/9979\/revisions"}],"predecessor-version":[{"id":9981,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/9979\/revisions\/9981"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/9982"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=9979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=9979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=9979"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=9979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}