{"id":9949,"date":"2022-02-04T08:46:02","date_gmt":"2022-02-04T11:46:02","guid":{"rendered":"https:\/\/informatepy.com\/2021\/?p=9949"},"modified":"2022-02-04T08:46:04","modified_gmt":"2022-02-04T11:46:04","slug":"camioneros-anuncian-paro-desde-el-lunes","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2022\/02\/04\/camioneros-anuncian-paro-desde-el-lunes\/","title":{"rendered":"Camioneros anuncian paro desde el lunes"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">El gremio de camioneros ir\u00eda a un paro a partir del lunes por el aumento del precio del combustible, la reducci\u00f3n de a tarifa del flete, la suba del peaje y la falta de cumplimiento del compromiso con el sector por parte del gobierno, seg\u00fan anunci\u00f3 <strong>\u00c1ngel Zaracho<\/strong>, presidente de la Federaci\u00f3n de Camioneros.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">El trabajador manifest\u00f3 que ma\u00f1ana s\u00e1bado mantendr\u00e1n una reuni\u00f3n en Coronel Oviedo y Villarrica, para luego realizar el anuncio oficial del cese de las actividades. <strong><em>\u201cCreo que el 90% de los camioneros se sumar\u00edan al paro, son unos 36.000\u201d,<\/em><\/strong> indic\u00f3, en comunicaci\u00f3n con Tempran\u00edsimo por Canal GEN y la emisora Universo 970 AM.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><em><strong>\u201cTodo apunta a que no nos queda otra m\u00e1s que parar, porque con el aumento del combustible, los agroexportadores bajaron los precios del flete en un 30 %, una barbaridad subi\u00f3 el peaje, que est\u00e1n alzando de 20.000 a 36.000 guaran\u00edes; el IVA que el gobierno se hab\u00eda comprometido en bajar en enero y no lo hizo. Cinco meses hace que estamos sentados en el comit\u00e9 t\u00e9cnico y no encontramos una soluci\u00f3n\u201d<\/strong><\/em>, cuestion\u00f3 Zaracho.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Se comprometi\u00f3, como en otras ocasiones, en no cerrar las rutas. <em><strong>\u201cS\u00ed vamos a dejar de trabajar y eso va a producir la falta de todo tipo de mercader\u00edas\u201d<\/strong><\/em>, refiri\u00f3.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><em><strong>\u201cLos compa\u00f1eros del lado brasile\u00f1o igualmente nos est\u00e1n llamando, porque tambi\u00e9n tenemos problemas en la frontera. Los federales est\u00e1n de brazos ca\u00eddos y el tr\u00e1nsito est\u00e1 muy lento. Tenemos a compa\u00f1eros que hace tres d\u00edas est\u00e1n ah\u00ed en el asfalto caliente y todo eso influye en el \u00e1nimo de los camioneros para que podamos buscar una soluci\u00f3n a estos problemas\u201d<\/strong><\/em>, se\u00f1al\u00f3 el gremialista.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Manifest\u00f3 que <em><strong>\u201cahora nos quieren meter en el problema diciendo que la situaci\u00f3n est\u00e1 fea y que vamos a ganar menos. No funciona as\u00ed la econom\u00eda. Ac\u00e1 no es una cuesti\u00f3n pol\u00edtica, es econ\u00f3mica, estamos hablando gente que lleva la divisa\u201d.<\/strong><\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Destac\u00f3 que los trabajadores del sector tienen muchas deudas. <strong><em>\u201cHemos comprado cubiertas, repuestos, pero no tenemos ninguna soluci\u00f3n\u201d<\/em><\/strong>, subray\u00f3.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"adn-digital\" style=\"font-style:normal;font-weight:100\">ADN Digital<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El gremio de camioneros ir\u00eda a un paro a partir del lunes por el aumento del precio del combustible, la reducci\u00f3n de a tarifa del flete, la suba del peaje y la falta de cumplimiento del compromiso con el sector por parte del gobierno, seg\u00fan anunci\u00f3 \u00c1ngel Zaracho, presidente de la Federaci\u00f3n de Camioneros. El [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":6209,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[177],"tags":[1036,1308],"ppma_author":[1051],"class_list":["post-9949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-destacada","tag-gremio-de-camioneros"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Camioneros anuncian paro desde el lunes - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2022\/02\/04\/camioneros-anuncian-paro-desde-el-lunes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Camioneros anuncian paro desde el lunes - Informatepy\" \/>\n<meta property=\"og:description\" content=\"El gremio de camioneros ir\u00eda a un paro a partir del lunes por el aumento del precio del combustible, la reducci\u00f3n de a tarifa del flete, la suba del peaje y la falta de cumplimiento del compromiso con el sector por parte del gobierno, seg\u00fan anunci\u00f3 \u00c1ngel Zaracho, presidente de la Federaci\u00f3n de Camioneros. El [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2022\/02\/04\/camioneros-anuncian-paro-desde-el-lunes\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-04T11:46:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-04T11:46:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/camioneros-rutas-paraguay.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/04\\\/camioneros-anuncian-paro-desde-el-lunes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/04\\\/camioneros-anuncian-paro-desde-el-lunes\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\"},\"headline\":\"Camioneros anuncian paro desde el lunes\",\"datePublished\":\"2022-02-04T11:46:02+00:00\",\"dateModified\":\"2022-02-04T11:46:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/04\\\/camioneros-anuncian-paro-desde-el-lunes\\\/\"},\"wordCount\":371,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/04\\\/camioneros-anuncian-paro-desde-el-lunes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/camioneros-rutas-paraguay.jpg?fit=1200%2C675&ssl=1\",\"keywords\":[\"destacada\",\"gremio de camioneros\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/04\\\/camioneros-anuncian-paro-desde-el-lunes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/04\\\/camioneros-anuncian-paro-desde-el-lunes\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/04\\\/camioneros-anuncian-paro-desde-el-lunes\\\/\",\"name\":\"Camioneros anuncian paro desde el lunes - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/04\\\/camioneros-anuncian-paro-desde-el-lunes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/04\\\/camioneros-anuncian-paro-desde-el-lunes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/camioneros-rutas-paraguay.jpg?fit=1200%2C675&ssl=1\",\"datePublished\":\"2022-02-04T11:46:02+00:00\",\"dateModified\":\"2022-02-04T11:46:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/04\\\/camioneros-anuncian-paro-desde-el-lunes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/04\\\/camioneros-anuncian-paro-desde-el-lunes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/04\\\/camioneros-anuncian-paro-desde-el-lunes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/camioneros-rutas-paraguay.jpg?fit=1200%2C675&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/camioneros-rutas-paraguay.jpg?fit=1200%2C675&ssl=1\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/02\\\/04\\\/camioneros-anuncian-paro-desde-el-lunes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Camioneros anuncian paro desde el lunes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Camioneros anuncian paro desde el lunes - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2022\/02\/04\/camioneros-anuncian-paro-desde-el-lunes\/","og_locale":"es_ES","og_type":"article","og_title":"Camioneros anuncian paro desde el lunes - Informatepy","og_description":"El gremio de camioneros ir\u00eda a un paro a partir del lunes por el aumento del precio del combustible, la reducci\u00f3n de a tarifa del flete, la suba del peaje y la falta de cumplimiento del compromiso con el sector por parte del gobierno, seg\u00fan anunci\u00f3 \u00c1ngel Zaracho, presidente de la Federaci\u00f3n de Camioneros. El [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2022\/02\/04\/camioneros-anuncian-paro-desde-el-lunes\/","og_site_name":"Informatepy","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-02-04T11:46:02+00:00","article_modified_time":"2022-02-04T11:46:04+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/camioneros-rutas-paraguay.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2022\/02\/04\/camioneros-anuncian-paro-desde-el-lunes\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2022\/02\/04\/camioneros-anuncian-paro-desde-el-lunes\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b"},"headline":"Camioneros anuncian paro desde el lunes","datePublished":"2022-02-04T11:46:02+00:00","dateModified":"2022-02-04T11:46:04+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/02\/04\/camioneros-anuncian-paro-desde-el-lunes\/"},"wordCount":371,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/02\/04\/camioneros-anuncian-paro-desde-el-lunes\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/camioneros-rutas-paraguay.jpg?fit=1200%2C675&ssl=1","keywords":["destacada","gremio de camioneros"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2022\/02\/04\/camioneros-anuncian-paro-desde-el-lunes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2022\/02\/04\/camioneros-anuncian-paro-desde-el-lunes\/","url":"https:\/\/informatepy.com\/2021\/2022\/02\/04\/camioneros-anuncian-paro-desde-el-lunes\/","name":"Camioneros anuncian paro desde el lunes - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/02\/04\/camioneros-anuncian-paro-desde-el-lunes\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/02\/04\/camioneros-anuncian-paro-desde-el-lunes\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/camioneros-rutas-paraguay.jpg?fit=1200%2C675&ssl=1","datePublished":"2022-02-04T11:46:02+00:00","dateModified":"2022-02-04T11:46:04+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2022\/02\/04\/camioneros-anuncian-paro-desde-el-lunes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2022\/02\/04\/camioneros-anuncian-paro-desde-el-lunes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2022\/02\/04\/camioneros-anuncian-paro-desde-el-lunes\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/camioneros-rutas-paraguay.jpg?fit=1200%2C675&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/camioneros-rutas-paraguay.jpg?fit=1200%2C675&ssl=1","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2022\/02\/04\/camioneros-anuncian-paro-desde-el-lunes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Camioneros anuncian paro desde el lunes"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2021\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/camioneros-rutas-paraguay.jpg?fit=1200%2C675&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":9993,"url":"https:\/\/informatepy.com\/2021\/2022\/02\/06\/camioneros-suspenden-el-paro-anunciado-para-este-lunes\/","url_meta":{"origin":9949,"position":0},"title":"Camioneros suspenden el paro anunciado para este lunes","date":"6 de febrero de 2022","format":false,"excerpt":"Tras un acuerdo con las autoridades, miembros de la Federaci\u00f3n de Camioneros del Paraguay no ir\u00e1n a paro este lunes 7 de febrero como estaba previsto. La medida de fuerza fue hecha a ra\u00edz de la suba del precio del combustible, entre otros. \u00d3scar Oru\u00e9, titular de la Subsecretar\u00eda de\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/oscar-orue-set-y-camioneros1.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13765,"url":"https:\/\/informatepy.com\/2021\/2022\/09\/06\/gremio-de-camioneros-anuncia-medidas-drasticas\/","url_meta":{"origin":9949,"position":1},"title":"Gremio de Camioneros anuncia medidas \u00abdr\u00e1sticas\u00bb","date":"6 de septiembre de 2022","format":false,"excerpt":"Dar\u00edo To\u00f1\u00e1nez del gremio de camioneros, anunci\u00f3 que tomar\u00e1n medidas dr\u00e1sticas, \"Basta de ser tibios, evidentemente con este gobierno no funciona\" manifest\u00f3 en comunicaci\u00f3n radial con Radio \u00d1andut\u00ed. El d\u00eda de ayer levantaron la medida que los manten\u00eda en las puertas de Petropar, pero anunciaron que en los pr\u00f3ximos d\u00edas\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/camioneros-rutas-paraguay.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12868,"url":"https:\/\/informatepy.com\/2021\/2022\/07\/26\/camioneros-van-al-paro-desde-la-madrugada\/","url_meta":{"origin":9949,"position":2},"title":"Camioneros van al paro desde la madrugada","date":"26 de julio de 2022","format":false,"excerpt":"Juan Villalba, de la Federaci\u00f3n Nacional de Camioneros, explic\u00f3 que todos los gremios est\u00e1n de acuerdo con la movilizaci\u00f3n, debido a que ya no dan m\u00e1s con los precios actuales del combustible, la falta de respuestas del gobierno y a\u00f1adi\u00f3 en que \u201chicimos un pedido en com\u00fan, el precio del\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/camioneros-rutas-paraguay.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11184,"url":"https:\/\/informatepy.com\/2021\/2022\/04\/16\/este-lunes-los-camioneros-se-movilizaran-contra-subas-y-exigiran-pruebas-en-caso-de-extorsion\/","url_meta":{"origin":9949,"position":3},"title":"Este lunes los camioneros se movilizar\u00e1n contra subas y exigir\u00e1n pruebas en caso de extorsi\u00f3n","date":"16 de abril de 2022","format":false,"excerpt":"Al t\u00e9rmino de la reuni\u00f3n realizada en la ciudad de Caacup\u00e9, los camioneros dieron el anuncio que retomar\u00e1n las movilizaciones en diferentes puntos del pa\u00eds con el objetivo de exigir una soluci\u00f3n definitiva a la suba del combustible. La movilizaci\u00f3n y los cierres de rutas est\u00e1n previstos para este lunes\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/gremio-camioneros.jpg?fit=660%2C330&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11645,"url":"https:\/\/informatepy.com\/2021\/2022\/05\/16\/gremio-de-camioneros-amenaza-con-volver-a-cerrar-las-rutas-del-pais\/","url_meta":{"origin":9949,"position":4},"title":"Gremio de camioneros amenaza con volver a cerrar las rutas del pa\u00eds","date":"16 de mayo de 2022","format":false,"excerpt":"L\u00edderes camioneros anunciaron una reuni\u00f3n para este lunes, a fin de definir el d\u00eda y los lugares donde volver\u00e1n a cerrar rutas para exigir pago justo por los fletes. Tambi\u00e9n, reclaman por el alto costo del combustible y por la situaci\u00f3n de sus compa\u00f1eros, presos por supuestamente extorsionar al Gobierno.\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/camioneros-cortes.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6578,"url":"https:\/\/informatepy.com\/2021\/2021\/08\/19\/aplaudan-pero-con-terroristas-no-se-negocia\/","url_meta":{"origin":9949,"position":5},"title":"Aplaudan\u2026 pero con terroristas no se negocia","date":"19 de agosto de 2021","format":false,"excerpt":"\u00bfExagerado? Tal vez, tal vez no tanto, porque que sembraron terror lo sembraron. Industrias paradas, fletes parados, camioneros y sus familias violentadas, animales hambrientos, empresarios y productores desesperados, aumento de precios, desabastecimiento, etc. D\u00edganme que no es un escenario terror\u00edfico. Por un lado, el viceministro de tributaci\u00f3n festej\u00f3, como si\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/oscar-orue-set-y-camioneros.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1051,"user_id":4,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/9949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=9949"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/9949\/revisions"}],"predecessor-version":[{"id":9950,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/9949\/revisions\/9950"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/6209"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=9949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=9949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=9949"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=9949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}