{"id":984,"date":"2019-04-02T20:19:00","date_gmt":"2019-04-02T20:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=984"},"modified":"2021-02-10T14:20:20","modified_gmt":"2021-02-10T14:20:20","slug":"anuncian-nuevas-tomas-de-colegios","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/04\/02\/anuncian-nuevas-tomas-de-colegios\/","title":{"rendered":"Anuncian nuevas tomas de colegios"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Tamara Cabello, coordinadora Ejecutiva de la Federaci\u00f3n Nacional de Estudiantes Secundarios (Fenaes), detall\u00f3 que hace dos meses unos 40.000 alumnos est\u00e1n a la deriva, sin dar clases, a causa de la falta de docentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En charla con la 970 AM, la joven estudiante mencion\u00f3 que se agotaron todas las instancias y que este martes el gremio estudiantil convoc\u00f3 a asamblea general en todo el pa\u00eds para ver las medidas a tomar en cada instituci\u00f3n. \u201cPor supuesto habr\u00e1 compa\u00f1eros que tomar\u00e1n sus colegios porque no podemos darnos el lujo de seguir perdiendo clases\u201d, acot\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabello mencion\u00f3 que la propuesta del sector estudiantil, al igual que los directores de los colegios, es que el MEC contrate de manera interina a los docentes para suplir los cargos vacantes, hasta tanto concrete el concurso. Sin embargo, Petta no escucha y se empecina en su postura de no hacerlo, seg\u00fan critic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cQueremos saber por qu\u00e9 antes no trataron de solucionar esta situaci\u00f3n\u201d, cuestion\u00f3 la coordinadora de Fenaes, atendiendo que existen estudios de a\u00f1os anteriores que advert\u00edan que miles de docentes estaban pr\u00f3ximos a jubilarse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo la estudiante mencion\u00f3 que el sector no se re\u00fane con Petta, sino que solo lo hizo en puntuales ocasiones con el viceministro Roberto Cano. \u201cPocas veces vimos e interactuamos con el ministro\u201d, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ayer el gremio de los directores tambi\u00e9n reclam\u00f3 que el ministro Petta ningunea a ese grupo y que no da la cara. En tanto que la exviceministra Nancy Ovelar asegur\u00f3 que al titular del MEC no le gusta reunirse y que \u201cgobierna con el Twitter\u201d para contentar a la grader\u00eda y generar titulares en los medios de prensa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tamara Cabello, coordinadora Ejecutiva de la Federaci\u00f3n Nacional de Estudiantes Secundarios (Fenaes), detall\u00f3 que hace dos meses unos 40.000 alumnos est\u00e1n a la deriva, sin dar clases, a causa de la falta de docentes. En charla con la 970 AM, la joven estudiante mencion\u00f3 que se agotaron todas las instancias y que este martes el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":985,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[177],"tags":[360,482,528],"ppma_author":[1039],"class_list":["post-984","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-eduardo-petta","tag-ministerio-de-educacion","tag-toma-de-colegios"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anuncian nuevas tomas de colegios - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/04\/02\/anuncian-nuevas-tomas-de-colegios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anuncian nuevas tomas de colegios - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Tamara Cabello, coordinadora Ejecutiva de la Federaci\u00f3n Nacional de Estudiantes Secundarios (Fenaes), detall\u00f3 que hace dos meses unos 40.000 alumnos est\u00e1n a la deriva, sin dar clases, a causa de la falta de docentes. En charla con la 970 AM, la joven estudiante mencion\u00f3 que se agotaron todas las instancias y que este martes el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/04\/02\/anuncian-nuevas-tomas-de-colegios\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-02T20:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-10T14:20:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/toma-de-colegios.jpg?fit=760%2C420&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/02\\\/anuncian-nuevas-tomas-de-colegios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/02\\\/anuncian-nuevas-tomas-de-colegios\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"Anuncian nuevas tomas de colegios\",\"datePublished\":\"2019-04-02T20:19:00+00:00\",\"dateModified\":\"2021-02-10T14:20:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/02\\\/anuncian-nuevas-tomas-de-colegios\\\/\"},\"wordCount\":289,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/02\\\/anuncian-nuevas-tomas-de-colegios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/toma-de-colegios.jpg?fit=760%2C420&ssl=1\",\"keywords\":[\"eduardo petta\",\"ministerio de educaci\u00f3n\",\"toma de colegios\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/02\\\/anuncian-nuevas-tomas-de-colegios\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/02\\\/anuncian-nuevas-tomas-de-colegios\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/02\\\/anuncian-nuevas-tomas-de-colegios\\\/\",\"name\":\"Anuncian nuevas tomas de colegios - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/02\\\/anuncian-nuevas-tomas-de-colegios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/02\\\/anuncian-nuevas-tomas-de-colegios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/toma-de-colegios.jpg?fit=760%2C420&ssl=1\",\"datePublished\":\"2019-04-02T20:19:00+00:00\",\"dateModified\":\"2021-02-10T14:20:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/02\\\/anuncian-nuevas-tomas-de-colegios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/02\\\/anuncian-nuevas-tomas-de-colegios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/02\\\/anuncian-nuevas-tomas-de-colegios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/toma-de-colegios.jpg?fit=760%2C420&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/toma-de-colegios.jpg?fit=760%2C420&ssl=1\",\"width\":760,\"height\":420,\"caption\":\"En el 2017 se registraron varias tomas de colegios. Foto: archivo.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/04\\\/02\\\/anuncian-nuevas-tomas-de-colegios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anuncian nuevas tomas de colegios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anuncian nuevas tomas de colegios - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/04\/02\/anuncian-nuevas-tomas-de-colegios\/","og_locale":"es_ES","og_type":"article","og_title":"Anuncian nuevas tomas de colegios - Informatepy","og_description":"Tamara Cabello, coordinadora Ejecutiva de la Federaci\u00f3n Nacional de Estudiantes Secundarios (Fenaes), detall\u00f3 que hace dos meses unos 40.000 alumnos est\u00e1n a la deriva, sin dar clases, a causa de la falta de docentes. En charla con la 970 AM, la joven estudiante mencion\u00f3 que se agotaron todas las instancias y que este martes el [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2019\/04\/02\/anuncian-nuevas-tomas-de-colegios\/","og_site_name":"Informatepy","article_published_time":"2019-04-02T20:19:00+00:00","article_modified_time":"2021-02-10T14:20:20+00:00","og_image":[{"width":760,"height":420,"url":"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/toma-de-colegios.jpg?fit=760%2C420&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/04\/02\/anuncian-nuevas-tomas-de-colegios\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/02\/anuncian-nuevas-tomas-de-colegios\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"Anuncian nuevas tomas de colegios","datePublished":"2019-04-02T20:19:00+00:00","dateModified":"2021-02-10T14:20:20+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/02\/anuncian-nuevas-tomas-de-colegios\/"},"wordCount":289,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/02\/anuncian-nuevas-tomas-de-colegios\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/toma-de-colegios.jpg?fit=760%2C420&ssl=1","keywords":["eduardo petta","ministerio de educaci\u00f3n","toma de colegios"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/04\/02\/anuncian-nuevas-tomas-de-colegios\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/04\/02\/anuncian-nuevas-tomas-de-colegios\/","url":"https:\/\/informatepy.com\/2021\/2019\/04\/02\/anuncian-nuevas-tomas-de-colegios\/","name":"Anuncian nuevas tomas de colegios - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/02\/anuncian-nuevas-tomas-de-colegios\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/02\/anuncian-nuevas-tomas-de-colegios\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/toma-de-colegios.jpg?fit=760%2C420&ssl=1","datePublished":"2019-04-02T20:19:00+00:00","dateModified":"2021-02-10T14:20:20+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/04\/02\/anuncian-nuevas-tomas-de-colegios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/04\/02\/anuncian-nuevas-tomas-de-colegios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/04\/02\/anuncian-nuevas-tomas-de-colegios\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/toma-de-colegios.jpg?fit=760%2C420&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/toma-de-colegios.jpg?fit=760%2C420&ssl=1","width":760,"height":420,"caption":"En el 2017 se registraron varias tomas de colegios. Foto: archivo."},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/04\/02\/anuncian-nuevas-tomas-de-colegios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Anuncian nuevas tomas de colegios"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/toma-de-colegios.jpg?fit=760%2C420&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1890,"url":"https:\/\/informatepy.com\/2021\/2020\/04\/19\/desastrekoeducacionvirtual-estudiantes-iran-a-paro-desde-el-lunes\/","url_meta":{"origin":984,"position":0},"title":"#DesastreKoEducaci\u00f3nVirtual: estudiantes ir\u00e1n a paro desde el lunes","date":"19 de abril de 2020","format":false,"excerpt":"La Organizaci\u00f3n Nacional Estudiantil (ONE), la Coalici\u00f3n Nacional Estudiantil, el Consejo Estudiantil Nacional, la Alianza de Centros Regionales Estudiantiles del Paraguay (Acrep) y los Colegios Independientes realizaron un comunicado mediante el cual llaman a la emergencia nacional educativa contra la media provisoria del Gobierno de fomentar la educaci\u00f3n virtual ante\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/educacion.png?fit=512%2C263&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13608,"url":"https:\/\/informatepy.com\/2021\/2022\/08\/26\/abuso-sexual-en-el-sek-colegio-avisa-a-padres-que-protestaron-que-sus-hijos-ya-no-seran-admitidos-en-el-2023\/","url_meta":{"origin":984,"position":1},"title":"Abuso sexual en el SEK: colegio avisa a padres que protestaron que sus hijos ya no ser\u00e1n admitidos en el 2023","date":"26 de agosto de 2022","format":false,"excerpt":"Varios padres fueron notificados de que sus hijos ya no ser\u00e1n admitidos en el Colegio SEK, de la ciudad de Lambar\u00e9, para el a\u00f1o lectivo 2023, \u201cdebido a conductas de agresividad e irrespeto mostradas hacia el colegio\u201d, seg\u00fan se desprende del comunicado que recibieron a trav\u00e9s de los correos. Se\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/sek.jpg?fit=660%2C330&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11554,"url":"https:\/\/informatepy.com\/2021\/2022\/05\/10\/padres-de-colegio-sek-conformaran-asociacion-con-ayuda-del-mec\/","url_meta":{"origin":984,"position":2},"title":"Padres de colegio SEK conformar\u00e1n asociaci\u00f3n con ayuda del MEC","date":"10 de mayo de 2022","format":false,"excerpt":"Padres del colegio SEK, donde se registraron varios casos de abuso sexual, y autoridades del Ministerio de Educaci\u00f3n y Ciencias (MEC), se reunieron para planificar la conformaci\u00f3n de una asociaci\u00f3n con apoyo de la cartera educativa. Anunciaron que en todo momento apoyar\u00e1n a los interventores que tomaron la instituci\u00f3n este\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/05\/sek.png?fit=770%2C464&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1876,"url":"https:\/\/informatepy.com\/2021\/2020\/04\/16\/el-diputado-hugo-ramirez-presento-un-proyecto-de-ley-para-exonerar-50-de-las-cuotas-de-colegios-privados\/","url_meta":{"origin":984,"position":3},"title":"El Diputado Hugo Ram\u00edrez present\u00f3 un proyecto de ley para exonerar parte de las cuotas de colegios privados","date":"16 de abril de 2020","format":false,"excerpt":"El Diputado Nacional por la ANR, Hugo Ram\u00edrez, present\u00f3 un proyecto de Ley a la c\u00e1mara de Diputados donde propone la exenci\u00f3n de hasta un 70% de las cuotas de los colegios privados, en el marco de la pandemia de Covid-19. El proyecto intenta establecer la exoneraci\u00f3n parcial y extraordinaria\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/hugo-ramirez.jpeg?fit=730%2C486&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11226,"url":"https:\/\/informatepy.com\/2021\/2022\/04\/19\/en-los-estadios-no-pero-en-las-aulas-si-colegios-siguen-exigiendo-uso-de-tapabocas-a-los-ninos\/","url_meta":{"origin":984,"position":4},"title":"En los estadios no, pero en las aulas si. Colegios siguen exigiendo uso de tapabocas a los ni\u00f1os","date":"19 de abril de 2022","format":false,"excerpt":"Ayer, tras el levantamiento de la emergencia sanitaria por el Covid-19 por parte del Poder Ejecutivo, que a su vez levanta la obligatoriedad del uso de tapabocas, el Ministerio de Educaci\u00f3n y Ciencias (MEC) sac\u00f3 un nuevo protocolo de bioseguridad para entornos escolares, que regir\u00e1 en instituciones oficiales, privadas y\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/tapaboca-aula-estadio.png?fit=1200%2C633&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11510,"url":"https:\/\/informatepy.com\/2021\/2022\/05\/06\/denuncian-presunto-caso-de-abuso-sexual-de-un-nene-de-6-anos-en-el-colegio-sek\/","url_meta":{"origin":984,"position":5},"title":"Denuncian presunto caso de abuso sexual de un nene de 6 a\u00f1os en el Colegio SEK","date":"6 de mayo de 2022","format":false,"excerpt":"Padres de alumnos del Colegio SEK de Lambar\u00e9 denunciaron un supuesto caso de abuso sexual. El supuesto autor ser\u00eda un adolescente de 15 a\u00f1os y la v\u00edctima un ni\u00f1o de 6 a\u00f1os. El hecho habr\u00eda ocurrido el pasado 26 de abril en el ba\u00f1o de la instituci\u00f3n.","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/05\/sek.png?fit=770%2C464&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=984"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/984\/revisions"}],"predecessor-version":[{"id":3157,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/984\/revisions\/3157"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/985"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=984"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}