{"id":9817,"date":"2022-01-29T09:06:50","date_gmt":"2022-01-29T12:06:50","guid":{"rendered":"https:\/\/informatepy.com\/2021\/?p=9817"},"modified":"2022-01-29T09:06:52","modified_gmt":"2022-01-29T12:06:52","slug":"elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2022\/01\/29\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\/","title":{"rendered":"Elon Musk tuitea en apoyo a los camioneros canadienses"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">El multimillonario Elon Musk ha tuiteado su apoyo a los camioneros canadienses y, dado el momento, parece ser un visto bueno para los camioneros que protestan por los mandatos de vacunas para los conductores transfronterizos y otras restricciones de cierre.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Musk, due\u00f1o de Tesla y SpaceX y nunca tiene miedo de decir lo que piensa, tuite\u00f3 el jueves: <em><strong>\u201cGobiernan los camioneros canadienses\u201d.<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Canadian truckers rule<\/p>&mdash; Elon Musk (@elonmusk) <a href=\"https:\/\/twitter.com\/elonmusk\/status\/1486772334635536395?ref_src=twsrc%5Etfw\">January 27, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El multimillonario Elon Musk ha tuiteado su apoyo a los camioneros canadienses y, dado el momento, parece ser un visto bueno para los camioneros que protestan por los mandatos de vacunas para los conductores transfronterizos y otras restricciones de cierre. Musk, due\u00f1o de Tesla y SpaceX y nunca tiene miedo de decir lo que piensa, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":2476,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[173],"tags":[1391,1026],"ppma_author":[1051],"class_list":["post-9817","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","tag-canada","tag-elon-musk"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elon Musk tuitea en apoyo a los camioneros canadienses - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2022\/01\/29\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elon Musk tuitea en apoyo a los camioneros canadienses - Informatepy\" \/>\n<meta property=\"og:description\" content=\"El multimillonario Elon Musk ha tuiteado su apoyo a los camioneros canadienses y, dado el momento, parece ser un visto bueno para los camioneros que protestan por los mandatos de vacunas para los conductores transfronterizos y otras restricciones de cierre. Musk, due\u00f1o de Tesla y SpaceX y nunca tiene miedo de decir lo que piensa, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2022\/01\/29\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-29T12:06:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-29T12:06:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2021\/01\/elon-musk.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/01\\\/29\\\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/01\\\/29\\\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\"},\"headline\":\"Elon Musk tuitea en apoyo a los camioneros canadienses\",\"datePublished\":\"2022-01-29T12:06:50+00:00\",\"dateModified\":\"2022-01-29T12:06:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/01\\\/29\\\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\\\/\"},\"wordCount\":77,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/01\\\/29\\\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/elon-musk.jpg?fit=1200%2C630&ssl=1\",\"keywords\":[\"canada\",\"elon musk\"],\"articleSection\":[\"Mundo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/01\\\/29\\\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/01\\\/29\\\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/01\\\/29\\\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\\\/\",\"name\":\"Elon Musk tuitea en apoyo a los camioneros canadienses - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/01\\\/29\\\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/01\\\/29\\\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/elon-musk.jpg?fit=1200%2C630&ssl=1\",\"datePublished\":\"2022-01-29T12:06:50+00:00\",\"dateModified\":\"2022-01-29T12:06:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/01\\\/29\\\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/01\\\/29\\\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/01\\\/29\\\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/elon-musk.jpg?fit=1200%2C630&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/elon-musk.jpg?fit=1200%2C630&ssl=1\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/01\\\/29\\\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elon Musk tuitea en apoyo a los camioneros canadienses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elon Musk tuitea en apoyo a los camioneros canadienses - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2022\/01\/29\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\/","og_locale":"es_ES","og_type":"article","og_title":"Elon Musk tuitea en apoyo a los camioneros canadienses - Informatepy","og_description":"El multimillonario Elon Musk ha tuiteado su apoyo a los camioneros canadienses y, dado el momento, parece ser un visto bueno para los camioneros que protestan por los mandatos de vacunas para los conductores transfronterizos y otras restricciones de cierre. Musk, due\u00f1o de Tesla y SpaceX y nunca tiene miedo de decir lo que piensa, [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2022\/01\/29\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\/","og_site_name":"Informatepy","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-01-29T12:06:50+00:00","article_modified_time":"2022-01-29T12:06:52+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2021\/01\/elon-musk.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2022\/01\/29\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2022\/01\/29\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b"},"headline":"Elon Musk tuitea en apoyo a los camioneros canadienses","datePublished":"2022-01-29T12:06:50+00:00","dateModified":"2022-01-29T12:06:52+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/01\/29\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\/"},"wordCount":77,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/01\/29\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/01\/elon-musk.jpg?fit=1200%2C630&ssl=1","keywords":["canada","elon musk"],"articleSection":["Mundo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2022\/01\/29\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2022\/01\/29\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\/","url":"https:\/\/informatepy.com\/2021\/2022\/01\/29\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\/","name":"Elon Musk tuitea en apoyo a los camioneros canadienses - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/01\/29\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/01\/29\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/01\/elon-musk.jpg?fit=1200%2C630&ssl=1","datePublished":"2022-01-29T12:06:50+00:00","dateModified":"2022-01-29T12:06:52+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2022\/01\/29\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2022\/01\/29\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2022\/01\/29\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/01\/elon-musk.jpg?fit=1200%2C630&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/01\/elon-musk.jpg?fit=1200%2C630&ssl=1","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2022\/01\/29\/elon-musk-tuitea-en-apoyo-a-los-camioneros-canadienses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Elon Musk tuitea en apoyo a los camioneros canadienses"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2021\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/01\/elon-musk.jpg?fit=1200%2C630&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":12952,"url":"https:\/\/informatepy.com\/2021\/2022\/07\/30\/elon-musk-contrademanda-a-twitter-por-el-acuerdo-fallido\/","url_meta":{"origin":9817,"position":0},"title":"Elon Musk contrademanda a Twitter por el acuerdo fallido","date":"30 de julio de 2022","format":false,"excerpt":"Tras la ca\u00edda del acuerdo por la compra de la red social Twitter, donde Elon Musk se compromet\u00eda a pagar 44.000 millones por la misma, la red social demand\u00f3 el empresario para obligarlo a cumplir el acuerdo. En la demanda, Twitter alega que Elon Musk no puede, sencillamente, retractarse de\u2026","rel":"","context":"En \u00abCiencia y Tecnolog\u00eda\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/elon-musk-twitter.jpg?fit=1200%2C600&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11761,"url":"https:\/\/informatepy.com\/2021\/2022\/05\/24\/elon-musk-dice-que-votara-a-los-republicanos-y-comienzan-las-denuncias-de-acoso-sexual-en-su-contra\/","url_meta":{"origin":9817,"position":1},"title":"Elon Musk dice que votar\u00e1 a los republicanos y comienzan las denuncias de acoso sexual en su contra","date":"24 de mayo de 2022","format":false,"excerpt":"Seg\u00fan un informe de la prensa estadounidense, SpaceX, la empresa aeroespacial fundada por Musk, pag\u00f3 a una azafata USD 250.000 para resolver una demanda por conducta sexual inapropiada contra Musk en 2018.\u00a0Musk neg\u00f3 los cargos y los atribuy\u00f3 al impacto pol\u00edtico que gener\u00f3 su agresiva maniobra de compra hostil de\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/01\/elon-musk.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10844,"url":"https:\/\/informatepy.com\/2021\/2022\/03\/28\/elon-musk-confirma-que-esta-pensando-seriamente-en-construir-una-alternativa-a-twitter\/","url_meta":{"origin":9817,"position":2},"title":"Elon Musk confirma que est\u00e1 \u00abpensando seriamente\u00bb en construir una alternativa a Twitter","date":"28 de marzo de 2022","format":false,"excerpt":"El jefe de Telsa y SpaceX, Elon Musk, confirm\u00f3 el s\u00e1bado por la noche que est\u00e1 \"pensando seriamente\" en construir una alternativa amigable a la libertad de expresi\u00f3n a Twitter. https:\/\/twitter.com\/PPathole\/status\/1507780749629730817 El viernes, Musk encuest\u00f3 a su audiencia de Twitter y pregunt\u00f3 si los usuarios de la plataforma cre\u00edan que\u2026","rel":"","context":"En \u00abCiencia y Tecnolog\u00eda\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/elon-musk-twitter.jpg?fit=1200%2C600&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10459,"url":"https:\/\/informatepy.com\/2021\/2022\/03\/05\/elon-musk-contra-la-censura-a-rusia\/","url_meta":{"origin":9817,"position":3},"title":"Elon Musk contra la censura a Rusia","date":"5 de marzo de 2022","format":false,"excerpt":"Mientras las \"Big Tech\" censuran noticias desde y hacia Rusia, el hombre m\u00e1s rico del mundo, Elon Musk, manifest\u00f3 a trav\u00e9s de su cuenta de Twitter, que no est\u00e1 dispuesto a sumarse a esa \"tendencia\". \"Algunos gobiernos (no Ucrania) le han dicho a Starlink que bloquee las fuentes de noticias\u2026","rel":"","context":"En \u00abCiencia y Tecnolog\u00eda\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/elon-musk.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12297,"url":"https:\/\/informatepy.com\/2021\/2022\/06\/22\/la-junta-directiva-de-twitter-aprobo-la-oferta-de-44-000-millones-de-dolares-de-elon-musk\/","url_meta":{"origin":9817,"position":4},"title":"La junta directiva de Twitter aprob\u00f3 la oferta de 44.000 millones de d\u00f3lares de Elon Musk","date":"22 de junio de 2022","format":false,"excerpt":"Elon Musk se acerc\u00f3 un paso m\u00e1s a completar su adquisici\u00f3n de Twitter por 44.000 millones de d\u00f3lares el martes cuando la junta directiva de la compa\u00f1\u00eda aprob\u00f3 por unanimidad su oferta de compra, seg\u00fan una presentaci\u00f3n de la SEC. Las acciones de Twitter subieron poco menos del 1% en\u2026","rel":"","context":"En \u00abCiencia y Tecnolog\u00eda\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/elon-musk-twitter.jpg?fit=976%2C549&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11372,"url":"https:\/\/informatepy.com\/2021\/2022\/04\/27\/amnistia-human-rights-watch-y-la-aclu-denunciaran-a-elon-musk-por-ser-un-absolutista-de-la-libertad-de-expresion\/","url_meta":{"origin":9817,"position":5},"title":"Amnist\u00eda, Human Rights Watch y la ACLU denunciar\u00e1n a Elon Musk por ser un \u201cabsolutista de la libertad de expresi\u00f3n\u201d","date":"27 de abril de 2022","format":false,"excerpt":"A menos de 24 horas de que\u00a0Elon Musk\u00a0se alzara con el 100% de las acciones de\u00a0Twitter, varias de las organizaciones autodenominadas de \u201cderechos humanos\u201d anunciaron que\u00a0denunciar\u00e1n a Musk por querer imponer la libertad de expresi\u00f3n absoluta en la plataforma porque, seg\u00fan su criterio, \u201chabilita discursos de odio\u201c. Musk\u00a0se ha descrito\u2026","rel":"","context":"En \u00abCiencia y Tecnolog\u00eda\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/elon-musk-twitter.jpg?fit=1200%2C600&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1051,"user_id":4,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/9817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=9817"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/9817\/revisions"}],"predecessor-version":[{"id":9818,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/9817\/revisions\/9818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/2476"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=9817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=9817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=9817"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=9817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}