{"id":962,"date":"2019-03-27T20:19:00","date_gmt":"2019-03-27T20:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=962"},"modified":"2021-02-10T14:44:50","modified_gmt":"2021-02-10T14:44:50","slug":"sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/03\/27\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\/","title":{"rendered":"Sobreviviente del accidente de Chapecoense fallece en Brasil"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Henzel fue uno de los seis supervivientes de la tragedia a\u00e9rea ocurrida en noviembre de 2016, cuando el avi\u00f3n en el que viajaba el&nbsp;Chapecoense&nbsp;se estrell\u00f3 a 17 kil\u00f3metros de llegar al aeropuerto Jos\u00e9 Mar\u00eda C\u00f3rdova, cerca de Medell\u00edn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El equipo se dirig\u00eda a Colombia para jugar ante el Atl\u00e9tico Nacional la final de la Copa Sudamericana 2016 y Henzel viajaba en el avi\u00f3n junto con la plantilla para retransmitir el hist\u00f3rico partido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la tragedia murieron 71 de las 77 personas que se encontraban en la aeronave de la aerol\u00ednea boliviana Lamia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Chapecoense record\u00f3 en un mensaje en Twitter la \u00abbrillante carrera\u00bb del periodista, quien \u00abnarr\u00f3, de forma excepcional, la historia\u00bb del club.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abSe convirti\u00f3 en un s\u00edmbolo de la reconstrucci\u00f3n del club y, en las p\u00e1ginas verdes y blancas de esta instituci\u00f3n, siempre habr\u00e1 un recuerdo de su ejemplo de superaci\u00f3n y de todo lo que hizo, con amor, por el equipo, por la ciudad de Chapec\u00f3 y por todos los aficionados del f\u00fatbol\u00bb, agreg\u00f3 el Chapecoense.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Henzel fue uno de los seis supervivientes de la tragedia a\u00e9rea ocurrida en noviembre de 2016, cuando el avi\u00f3n en el que viajaba el&nbsp;Chapecoense&nbsp;se estrell\u00f3 a 17 kil\u00f3metros de llegar al aeropuerto Jos\u00e9 Mar\u00eda C\u00f3rdova, cerca de Medell\u00edn. El equipo se dirig\u00eda a Colombia para jugar ante el Atl\u00e9tico Nacional la final de la Copa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":963,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[183],"tags":[517],"ppma_author":[1039],"class_list":["post-962","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-chapecoense"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sobreviviente del accidente de Chapecoense fallece en Brasil - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/03\/27\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sobreviviente del accidente de Chapecoense fallece en Brasil - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Henzel fue uno de los seis supervivientes de la tragedia a\u00e9rea ocurrida en noviembre de 2016, cuando el avi\u00f3n en el que viajaba el&nbsp;Chapecoense&nbsp;se estrell\u00f3 a 17 kil\u00f3metros de llegar al aeropuerto Jos\u00e9 Mar\u00eda C\u00f3rdova, cerca de Medell\u00edn. El equipo se dirig\u00eda a Colombia para jugar ante el Atl\u00e9tico Nacional la final de la Copa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/03\/27\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-27T20:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-10T14:44:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/sobrevivientes-chapecoense.jpg?fit=730%2C410&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"730\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/27\\\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/27\\\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"Sobreviviente del accidente de Chapecoense fallece en Brasil\",\"datePublished\":\"2019-03-27T20:19:00+00:00\",\"dateModified\":\"2021-02-10T14:44:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/27\\\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\\\/\"},\"wordCount\":193,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/27\\\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/sobrevivientes-chapecoense.jpg?fit=730%2C410&ssl=1\",\"keywords\":[\"chapecoense\"],\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/27\\\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/27\\\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/27\\\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\\\/\",\"name\":\"Sobreviviente del accidente de Chapecoense fallece en Brasil - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/27\\\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/27\\\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/sobrevivientes-chapecoense.jpg?fit=730%2C410&ssl=1\",\"datePublished\":\"2019-03-27T20:19:00+00:00\",\"dateModified\":\"2021-02-10T14:44:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/27\\\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/27\\\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/27\\\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/sobrevivientes-chapecoense.jpg?fit=730%2C410&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/sobrevivientes-chapecoense.jpg?fit=730%2C410&ssl=1\",\"width\":730,\"height\":410,\"caption\":\"Henzel (der) muri\u00f3 este martes mientras jugaba f\u00fatbol. Foto: @TycSports\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/27\\\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sobreviviente del accidente de Chapecoense fallece en Brasil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sobreviviente del accidente de Chapecoense fallece en Brasil - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/03\/27\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\/","og_locale":"es_ES","og_type":"article","og_title":"Sobreviviente del accidente de Chapecoense fallece en Brasil - Informatepy","og_description":"Henzel fue uno de los seis supervivientes de la tragedia a\u00e9rea ocurrida en noviembre de 2016, cuando el avi\u00f3n en el que viajaba el&nbsp;Chapecoense&nbsp;se estrell\u00f3 a 17 kil\u00f3metros de llegar al aeropuerto Jos\u00e9 Mar\u00eda C\u00f3rdova, cerca de Medell\u00edn. El equipo se dirig\u00eda a Colombia para jugar ante el Atl\u00e9tico Nacional la final de la Copa [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2019\/03\/27\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\/","og_site_name":"Informatepy","article_published_time":"2019-03-27T20:19:00+00:00","article_modified_time":"2021-02-10T14:44:50+00:00","og_image":[{"width":730,"height":410,"url":"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/sobrevivientes-chapecoense.jpg?fit=730%2C410&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/03\/27\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/27\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"Sobreviviente del accidente de Chapecoense fallece en Brasil","datePublished":"2019-03-27T20:19:00+00:00","dateModified":"2021-02-10T14:44:50+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/27\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\/"},"wordCount":193,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/27\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/sobrevivientes-chapecoense.jpg?fit=730%2C410&ssl=1","keywords":["chapecoense"],"articleSection":["Deportes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/03\/27\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/03\/27\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\/","url":"https:\/\/informatepy.com\/2021\/2019\/03\/27\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\/","name":"Sobreviviente del accidente de Chapecoense fallece en Brasil - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/27\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/27\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/sobrevivientes-chapecoense.jpg?fit=730%2C410&ssl=1","datePublished":"2019-03-27T20:19:00+00:00","dateModified":"2021-02-10T14:44:50+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/27\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/03\/27\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/03\/27\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/sobrevivientes-chapecoense.jpg?fit=730%2C410&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/sobrevivientes-chapecoense.jpg?fit=730%2C410&ssl=1","width":730,"height":410,"caption":"Henzel (der) muri\u00f3 este martes mientras jugaba f\u00fatbol. Foto: @TycSports"},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/03\/27\/sobreviviente-del-accidente-de-chapecoense-fallece-en-brasil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Sobreviviente del accidente de Chapecoense fallece en Brasil"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/sobrevivientes-chapecoense.jpg?fit=730%2C410&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":9019,"url":"https:\/\/informatepy.com\/2021\/2021\/12\/25\/un-futbolista-de-23-anos-muere-tras-sufrir-un-ataque-cardiaco-en-el-entrenamiento\/","url_meta":{"origin":962,"position":0},"title":"Un futbolista croata de 23 a\u00f1os muere tras sufrir un ataque card\u00edaco en el entrenamiento","date":"25 de diciembre de 2021","format":false,"excerpt":"El jugador del NK Nehaj croata estaba en coma y los m\u00e9dicos no pudieron hacer nada por \u00e9l","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/marin-cacic.jpg?fit=958%2C596&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2431,"url":"https:\/\/informatepy.com\/2021\/2021\/01\/20\/cristiano-ronaldo-grito-campeon-con-la-juventus-y-quedo-mas-cerca-que-nunca-de-lionel-messi-en-la-carrera-historica-de-titulos\/","url_meta":{"origin":962,"position":1},"title":"Cristiano Ronaldo grit\u00f3 campe\u00f3n con la Juventus y qued\u00f3 m\u00e1s cerca que nunca de Lionel Messi en la carrera hist\u00f3rica de t\u00edtulos","date":"20 de enero de 2021","format":false,"excerpt":"La carrera entre Cristiano Ronaldo y Lionel Messi por ser el mejor futbolista\u00a0de la era actual sum\u00f3 un nuevo cap\u00edtulo con la consagraci\u00f3n de Juventus en la Supercopa de Italia.\u00a0La Vecchia Signora venci\u00f3 por la m\u00ednima al Napoli\u00a0y\u00a0CR7 celebr\u00f3 el primer t\u00edtulo en el 2021, el cuarto personal en el\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/01\/cristiano-ronaldo.jpg?fit=660%2C371&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11976,"url":"https:\/\/informatepy.com\/2021\/2022\/06\/06\/avion-de-combate-chino-intercepto-y-ataco-a-un-avion-australiano-sobre-aguas-internacionales\/","url_meta":{"origin":962,"position":2},"title":"Avi\u00f3n de combate chino intercept\u00f3 y atac\u00f3 a un avi\u00f3n australiano sobre aguas internacionales","date":"6 de junio de 2022","format":false,"excerpt":"De acuerdo a las declaraciones del gobierno australiano, un avi\u00f3n de combate chino realiz\u00f3 una maniobra peligrosa cerca de una de sus aeronave en aguas internacionales del Mar de China Meridional. Camberra asegura que la aeronave china, un\u00a0jet de combate J-16, lanz\u00f3 bengalas y cerr\u00f3 el paso de manera riesgosa\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/avion-chino-j16.jpg?fit=800%2C445&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2495,"url":"https:\/\/informatepy.com\/2021\/2021\/02\/02\/el-gran-reseteo-de-davos-se-adelanta-y-concluye-con-el-fin-del-capitalismo\/","url_meta":{"origin":962,"position":3},"title":"&#8216;El Gran Reseteo&#8217; de Davos se adelanta y concluye con el fin del capitalismo","date":"2 de febrero de 2021","format":false,"excerpt":"Jefes de Estado, gobiernos, CEO de empresas, medios de comunicaci\u00f3n globales y l\u00edderes izquierdistas de la sociedad civil han coincidido en que la\u00a0Agenda 2030\u00a0debe adelantarse. Es la conclusi\u00f3n final sustra\u00edda del\u00a0Foro Econ\u00f3mico Mundial\u00a0que ha finalizado este pasado fin de semana de enero. La excusa para adelantar este proyecto colectivista, que\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/Foro-Economico-mundial.jpg?fit=1182%2C800&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":7302,"url":"https:\/\/informatepy.com\/2021\/2021\/09\/24\/taiwan-denuncio-que-24-aviones-de-combate-del-regimen-chino-violaron-nuevamente-su-espacio-aereo\/","url_meta":{"origin":962,"position":4},"title":"Taiw\u00e1n denunci\u00f3 que 24 aviones de combate del r\u00e9gimen chino violaron nuevamente su espacio a\u00e9reo","date":"24 de septiembre de 2021","format":false,"excerpt":"La acci\u00f3n de Beijing es considerada como un amedrentamiento por parte de la isla tras la formalizaci\u00f3n de su incorporaci\u00f3n al Acuerdo Progresivo e Integral para la Asociaci\u00f3n Transpac\u00edfica","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/china-taiwan-aviones.jpg?fit=768%2C512&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8579,"url":"https:\/\/informatepy.com\/2021\/2021\/11\/30\/taiwan-envio-aviones-de-combate-para-repeler-una-nueva-incursion-de-27-naves-chinas-en-su-zona-de-defensa-aerea\/","url_meta":{"origin":962,"position":5},"title":"Taiw\u00e1n envi\u00f3 aviones de combate para repeler una nueva incursi\u00f3n de 27 naves chinas en su zona de defensa a\u00e9rea","date":"30 de noviembre de 2021","format":false,"excerpt":"La nueva provocaci\u00f3n del r\u00e9gimen de Xi Jinping incluy\u00f3 18 cazas y cinco bombarderos H-6 con capacidad nuclear, as\u00ed como un avi\u00f3n de reabastecimiento a\u00e9reo Y-20","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/cazas-taiwan.jpg?fit=768%2C432&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=962"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/962\/revisions"}],"predecessor-version":[{"id":3177,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/962\/revisions\/3177"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/963"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=962"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}