{"id":947,"date":"2019-03-25T20:19:00","date_gmt":"2019-03-25T20:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=947"},"modified":"2021-02-13T12:00:44","modified_gmt":"2021-02-13T12:00:44","slug":"cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/03\/25\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\/","title":{"rendered":"CDE: candidato de A\u00f1etete logra victoria en internas de la ANR"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Con el total de mesas escrutadas, el Tribunal Electoral Partidario (TEP) del Partido Colorado confirm\u00f3 a Wilberto Caba\u00f1as como ganador de las internas partidarias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El candidato de Colorado A\u00f1etete (Lista 3) logr\u00f3 hacerse con un total de 19.127 votos (49,67%), superando por un margen de casi 10% a su rival del movimiento Colorados CDE (Lista 4), Lilian Gonz\u00e1lez de Aguinagalde, quien obtuvo 15.131 votos (39,27%).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El nivel de participaci\u00f3n registrado en las internas coloradas fue del 32,54% con un total de 38.531 votos, de acuerdo a los datos del Sistema de Transmisi\u00f3n de Resultados Electorales Preliminares (TREP).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De esta manera, Caba\u00f1as representar\u00e1 al Partido Colorado en las elecciones municipales que se celebrar\u00e1n el pr\u00f3ximo 5 de mayo en Ciudad del Este para elegir a un nuevo intendente que se encargar\u00e1 de completar el periodo 2015-2020.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un total de 12 precandidatos se presentaron para las elecciones internas en la capital departamental, siete de ellos de la ANR. En el caso de las dem\u00e1s nucleaciones pol\u00edticas (incluyendo al PLRA), se presentaron listas \u00fanicas de consenso que fueron oficializadas a trav\u00e9s de estos comicios.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/D2dROrBX0AA2za3.jpg?w=740&#038;ssl=1\" alt=\"\" data-recalc-dims=\"1\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Con el total de mesas escrutadas, el Tribunal Electoral Partidario (TEP) del Partido Colorado confirm\u00f3 a Wilberto Caba\u00f1as como ganador de las internas partidarias. El candidato de Colorado A\u00f1etete (Lista 3) logr\u00f3 hacerse con un total de 19.127 votos (49,67%), superando por un margen de casi 10% a su rival del movimiento Colorados CDE (Lista [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":949,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[483],"tags":[267,290,313,492],"ppma_author":[1039],"class_list":["post-947","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipales","tag-anr","tag-cde","tag-colorado-anetete","tag-elecciones-2019"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CDE: candidato de A\u00f1etete logra victoria en internas de la ANR - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/03\/25\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CDE: candidato de A\u00f1etete logra victoria en internas de la ANR - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Con el total de mesas escrutadas, el Tribunal Electoral Partidario (TEP) del Partido Colorado confirm\u00f3 a Wilberto Caba\u00f1as como ganador de las internas partidarias. El candidato de Colorado A\u00f1etete (Lista 3) logr\u00f3 hacerse con un total de 19.127 votos (49,67%), superando por un margen de casi 10% a su rival del movimiento Colorados CDE (Lista [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/03\/25\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-25T20:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-13T12:00:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/Wilberto-CabaC3B1as-AC3B1etete-CDE.jpg?fit=760%2C420&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/25\\\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/25\\\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"CDE: candidato de A\u00f1etete logra victoria en internas de la ANR\",\"datePublished\":\"2019-03-25T20:19:00+00:00\",\"dateModified\":\"2021-02-13T12:00:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/25\\\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\\\/\"},\"wordCount\":193,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/25\\\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Wilberto-CabaC3B1as-AC3B1etete-CDE.jpg?fit=760%2C420&ssl=1\",\"keywords\":[\"anr\",\"CDE\",\"colorado a\u00f1etete\",\"elecciones 2019\"],\"articleSection\":[\"Municipales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/25\\\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/25\\\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/25\\\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\\\/\",\"name\":\"CDE: candidato de A\u00f1etete logra victoria en internas de la ANR - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/25\\\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/25\\\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Wilberto-CabaC3B1as-AC3B1etete-CDE.jpg?fit=760%2C420&ssl=1\",\"datePublished\":\"2019-03-25T20:19:00+00:00\",\"dateModified\":\"2021-02-13T12:00:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/25\\\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/25\\\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/25\\\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Wilberto-CabaC3B1as-AC3B1etete-CDE.jpg?fit=760%2C420&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Wilberto-CabaC3B1as-AC3B1etete-CDE.jpg?fit=760%2C420&ssl=1\",\"width\":760,\"height\":420,\"caption\":\"Wilberto Caba\u00f1as result\u00f3 ganador de las internas partidaria de la ANR en Ciudad del Este. Foto: Twitter @DaniCenturionpy.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/25\\\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CDE: candidato de A\u00f1etete logra victoria en internas de la ANR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CDE: candidato de A\u00f1etete logra victoria en internas de la ANR - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/03\/25\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\/","og_locale":"es_ES","og_type":"article","og_title":"CDE: candidato de A\u00f1etete logra victoria en internas de la ANR - Informatepy","og_description":"Con el total de mesas escrutadas, el Tribunal Electoral Partidario (TEP) del Partido Colorado confirm\u00f3 a Wilberto Caba\u00f1as como ganador de las internas partidarias. El candidato de Colorado A\u00f1etete (Lista 3) logr\u00f3 hacerse con un total de 19.127 votos (49,67%), superando por un margen de casi 10% a su rival del movimiento Colorados CDE (Lista [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2019\/03\/25\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\/","og_site_name":"Informatepy","article_published_time":"2019-03-25T20:19:00+00:00","article_modified_time":"2021-02-13T12:00:44+00:00","og_image":[{"width":760,"height":420,"url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/Wilberto-CabaC3B1as-AC3B1etete-CDE.jpg?fit=760%2C420&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/03\/25\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/25\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"CDE: candidato de A\u00f1etete logra victoria en internas de la ANR","datePublished":"2019-03-25T20:19:00+00:00","dateModified":"2021-02-13T12:00:44+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/25\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\/"},"wordCount":193,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/25\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/Wilberto-CabaC3B1as-AC3B1etete-CDE.jpg?fit=760%2C420&ssl=1","keywords":["anr","CDE","colorado a\u00f1etete","elecciones 2019"],"articleSection":["Municipales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/03\/25\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/03\/25\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\/","url":"https:\/\/informatepy.com\/2021\/2019\/03\/25\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\/","name":"CDE: candidato de A\u00f1etete logra victoria en internas de la ANR - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/25\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/25\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/Wilberto-CabaC3B1as-AC3B1etete-CDE.jpg?fit=760%2C420&ssl=1","datePublished":"2019-03-25T20:19:00+00:00","dateModified":"2021-02-13T12:00:44+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/25\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/03\/25\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/03\/25\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/Wilberto-CabaC3B1as-AC3B1etete-CDE.jpg?fit=760%2C420&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/Wilberto-CabaC3B1as-AC3B1etete-CDE.jpg?fit=760%2C420&ssl=1","width":760,"height":420,"caption":"Wilberto Caba\u00f1as result\u00f3 ganador de las internas partidaria de la ANR en Ciudad del Este. Foto: Twitter @DaniCenturionpy."},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/03\/25\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"CDE: candidato de A\u00f1etete logra victoria en internas de la ANR"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/Wilberto-CabaC3B1as-AC3B1etete-CDE.jpg?fit=760%2C420&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":950,"url":"https:\/\/informatepy.com\/2021\/2019\/03\/25\/cde-candidato-de-anetete-logra-victoria-en-internas-de-la-anr-2\/","url_meta":{"origin":947,"position":0},"title":"CDE: candidato de A\u00f1etete logra victoria en internas de la ANR","date":"25 de marzo de 2019","format":false,"excerpt":"Con el total de mesas escrutadas, el Tribunal Electoral Partidario (TEP) del Partido Colorado confirm\u00f3 a Wilberto Caba\u00f1as como ganador de las internas partidarias. El candidato de Colorado A\u00f1etete (Lista 3) logr\u00f3 hacerse con un total de 19.127 votos (49,67%), superando por un margen de casi 10% a su rival\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/Wilberto-CabaC3B1as-AC3B1etete-CDE.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":900,"url":"https:\/\/informatepy.com\/2021\/2019\/03\/19\/anr-tiene-todo-organizado-para-elecciones-internas-en-cde\/","url_meta":{"origin":947,"position":1},"title":"La ANR tiene todo organizado para elecciones internas en CDE","date":"19 de marzo de 2019","format":false,"excerpt":"El Tribunal Electoral de la Asociaci\u00f3n Nacional Republicana (ANR), expuso en conferencia de prensa, todos los detalles que conlleva la organizaci\u00f3n de las elecciones internas del partido colorado para elegir al candidato a intendente que los representar\u00e1 en los comicios de Ciudad del Este. Santiago Brizuela, miembro titular, y el\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/tribunal-electoral-cde-colorados.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1138,"url":"https:\/\/informatepy.com\/2021\/2019\/05\/11\/colorado-anetete-rechaza-la-eleccion-interna-de-las-damas-coloradas\/","url_meta":{"origin":947,"position":2},"title":"Colorado A\u00f1etete rechaza la elecci\u00f3n interna de las Damas Coloradas","date":"11 de mayo de 2019","format":false,"excerpt":"A pesar del incesante trabajo del Presidente de la ANR, el Diputado Pedro Alliana para llevar adelante las elecciones de la Juventud y las Damas Coloradas, el Tribunal Electoral Partidario, con mayor\u00eda \u201cA\u00f1etet\u00e9\u201d, habr\u00eda bajado el pulgar a las elecciones de las Damas. De acuerdo a las versiones que circulan\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/Mario-Abdo-BenC3ADtez.jpg?fit=1000%2C541&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1232,"url":"https:\/\/informatepy.com\/2021\/2019\/06\/02\/se-definieron-las-listas-en-la-juventud-colorada\/","url_meta":{"origin":947,"position":3},"title":"Se definieron las listas en la Juventud Colorada","date":"2 de junio de 2019","format":false,"excerpt":"Luego de largos 17 a\u00f1os de espera, finalmente la Juventud Colorada va a elecciones internas. En el d\u00eda de ayer venc\u00eda el plazo establecido para la inscripci\u00f3n de las listas, un total de 16 movi\u00admientos fueron ins\u00adcriptos en el Tri\u00adbunal Electoral Partidario (TEP) de la Asociaci\u00f3n Nacio\u00adnal Republicana (ANR) para\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/edificio-anr.jpg?fit=1200%2C731&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1121,"url":"https:\/\/informatepy.com\/2021\/2019\/05\/06\/cde-cae-un-bastion-colorado\/","url_meta":{"origin":947,"position":4},"title":"CDE: Cae un basti\u00f3n colorado","date":"6 de mayo de 2019","format":false,"excerpt":"Con la publicaci\u00f3n de los primeros datos preliminares por parte del Tribunal Electoral, Miguel Prieto recibi\u00f3 el 44 % de los votos de los electores, superando a su principal contrincante Wilberto Caba\u00f1as (ANR), quien, pese a contar con el aparato estatal, obtuvo el 39 %, quedando as\u00ed en segundo lugar\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/Wilberto-cabaC3B1as-mario-abdo.jpg?fit=1200%2C890&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1320,"url":"https:\/\/informatepy.com\/2021\/2019\/07\/09\/recta-final-en-las-elecciones-de-la-juventud-de-la-anr\/","url_meta":{"origin":947,"position":5},"title":"Recta final en las elecciones de la Juventud de la ANR","date":"9 de julio de 2019","format":false,"excerpt":"Las elecciones de la juventud de la ANR est\u00e1n llegando a la etapa de definici\u00f3n, en donde se deber\u00e1n inscribir las listas de candidatos. Contra todos los pron\u00f3sticos, los j\u00f3venes cerraron la etapa autorizada para sumar nuevos afiliados al partido, con una convocatoria de casi 60.000 nuevos afiliados al Partido\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/balmori-kike-cabrera-scaled.jpg?fit=1200%2C600&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=947"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/947\/revisions"}],"predecessor-version":[{"id":3255,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/947\/revisions\/3255"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/949"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=947"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}