{"id":9233,"date":"2022-01-06T17:21:00","date_gmt":"2022-01-06T21:21:00","guid":{"rendered":"https:\/\/informatepy.com\/2021\/?p=9233"},"modified":"2022-01-06T17:30:18","modified_gmt":"2022-01-06T21:30:18","slug":"salimos-mejores","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2022\/01\/06\/salimos-mejores\/","title":{"rendered":"Salimos mejores"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">Aunque parezca mentira,<strong>&nbsp;la subjetividad humana es tan amplia como para que existan personas que recuerdan con cierto cari\u00f1o los comienzos de la pandemia<\/strong>. Eso de conseguir provisiones y meterse en casa con los seres queridos a esperar la victoria contra el \u201cenemigo invisible\u201d mentado por algunos&nbsp;<strong>gobernantes era algo similar a la aventura.&nbsp;<\/strong>Una aventura que, por supuesto, s\u00f3lo puede calificarse as\u00ed desde la perspectiva de la clase media, cautiva desde hace tiempo de \u00e9picas casi exclusivamente discursivas y tal vez atra\u00edda por la posibilidad de quebrar la vida atomizada y repetitiva que el advenimiento de una peste supone. Una aventura que pod\u00eda transitarse inm\u00f3vil y en piyama, con las pantallas como \u00fanica ventana y fuente de informaci\u00f3n, cual sue\u00f1o h\u00famedo de&nbsp;Mark Zuckerberg.&nbsp;Como nunca antes,<strong>&nbsp;la noci\u00f3n de la humanidad como un colectivo posicionado frente a algo que ha venido a destruirla pareci\u00f3 posible.<\/strong>&nbsp;Aquello que en el pasado fue objeto de ficciones en la que extraterrestres o fuerzas ocultas van llegando para deshacerse de nosotros parec\u00eda consumarse en la vida real y era inevitable sentirse protagonista de un momento \u00fanico e irrepetible en el que, por fin, todos asist\u00edamos a la coronaci\u00f3n de un enemigo com\u00fan. Frente a ese enemigo, los otros parec\u00edan perder potencia. Los problemas que defin\u00edan y diferenciaban a los diversos pa\u00edses, comunidades y clases sociales deb\u00edan dejar paso al problema mayor, al problema m\u00e1s democr\u00e1tico de todos, pues a todos puede afectarnos. En ese caldo de cultivo&nbsp;<strong>la frase \u201cde esta salimos mejores\u201d comenz\u00f3 a copar las redes sociales y los medios, junto a otras ideas&nbsp;<\/strong>del mismo tenor como \u201cel planeta respira porque los humanos no lo est\u00e1n destruyendo\u201d y un sinf\u00edn de etc\u00e9teras.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Para quienes no ve\u00edan nada rom\u00e1ntico, ni \u00e9pico, ni mucho menos seguro en el&nbsp;encierro global&nbsp;y en la consecuente acumulaci\u00f3n de nuevas atribuciones por parte de los que tienen la manija de las cosas, el \u201csalimos mejores\u201d representaba m\u00e1s bien lo contrario. \u00bfC\u00f3mo pod\u00eda resultar bien un estado de cosas en el que lo que se entiende como \u201cpueblo\u201d queda completamente subordinado a los poderes de turno, sin capacidad de r\u00e9plica? \u00bfC\u00f3mo no sentirse desvalido al carecer de la sapiencia necesaria para comprender y discutir el discurso cientificista que se present\u00f3 y se presenta como pretexto para medidas que el mismo discurso desestima, permuta u olvida? \u00bfQu\u00e9 pod\u00eda haber de prometedor en un un futuro a\u00fan m\u00e1s farmacodependiente e hipercontrolado por fuerzas de seguridad y sofisticados mecanismos de seguimiento ciudadano?&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><strong>Entre zooms,&nbsp;vivos de Instagram y shows online destinados a sobrellevar las cuarentenas<\/strong>, los sectores medios de todo el mundo compraron acr\u00edticamente ciertas nociones que hoy se confirman como funcionales a intereses que nada tienen que ver con la salud de las personas. Sin demasiada oposici\u00f3n, el discurso oficial de la pandemia instal\u00f3 de entrada que las fronteras suponen un riesgo may\u00fasculo, pero nunca focaliz\u00f3 en las grandes aglomeraciones<strong>&nbsp;de personas que viven sin agua potable en tantos pa\u00edses como el nuestro<\/strong>. Era \u2013y es- menos oneroso acordar entre gobiernos y entidades trasnacionales ir limitando cada vez m\u00e1s los movimientos ciudadanos que enfrentar el problema de la pobreza global en serio y hacerse cargo de empezar a resolverla mancomunadamente.&nbsp;<strong>El discurso oficial de la pandemia instal\u00f3, desde el vamos, una din\u00e1mica peligrosa en la que no tener&nbsp;covid&nbsp;parec\u00eda m\u00e1s importante que no tener&nbsp;cualquier otra enfermedad.&nbsp;<\/strong>Pacientes oncol\u00f3gicos o card\u00edacos sufr\u00edan demoras en sus tratamientos porque el sistema de salud deb\u00eda enfocarse en la urgencia del momento. Todo ocurr\u00eda en el marco de una falsa excepcionalidad (equivalente a aquella que, en 2001, bajo el pretexto de controlar el terrorismo luego del atentado a las Torres Gemelas, habilit\u00f3 a Google leer nuestros correos \u201cdurante un tiempo\u201d que ya lleva 20 a\u00f1os) y r\u00e1pidamente se blanque\u00f3 que est\u00e1bamos ante una \u201cnueva normalidad\u201d, un \u201creseteo\u201d y ese tipo de cosas sobre las que aman perorar millonarios tipo Bill Gates, masivamente aceptados como pitonisas contempor\u00e1neas.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Lejos de verificarse, aunque sea parcialmente,<strong>&nbsp;el \u201csalimos mejores\u201d mostr\u00f3 y muestra su reverso en un mundo que, a dos a\u00f1os de la bajada de bandera pandemial,&nbsp;est\u00e1 m\u00e1s empobrecido&nbsp;<\/strong>y contabiliza a\u00fan m\u00e1s muertos que antes por enfermedades y accidentes relacionados a la crisis general. Un mundo en el que la mayor apuesta de gobiernos y organismos transnacionales pasa por empoderar todo tipo de fuerzas represivas en desmedro de la gesti\u00f3n de lazos entre sectores que deber\u00edan poder dialogar. Un mundo en el que se va consolidando a\u00fan con m\u00e1s vigor<strong>&nbsp;la idea de que el enemigo puede ser el vecino<\/strong>, el compa\u00f1ero de trabajo o el chofer del taxi, pero casi nunca el tipo que realmente tiene poder de decisi\u00f3n sobre las mayor\u00edas. A\u00fan m\u00e1s blindadas que dos a\u00f1os atr\u00e1s, las \u00e9lites que deciden sobre nosotros siguen sin ser masivamente interpeladas. Salvo excepciones, se las cuestiona superficialmente o desde lugares que rozan el rid\u00edculo. A\u00fan m\u00e1s omnipresentes que dos a\u00f1os atr\u00e1s, las pantallas dicen \u2013y se contradicen- sobre los pasos a seguir para derrotar a un virus que, en el colmo del absurdo, cuenta con detractores, defensores y promotores. Un virus elevado a diversas categor\u00edas que nada tienen que ver con lo verdaderamente sanitario, un virus que es actor social, negocio millonario o excusa para el conspirativismo m\u00e1s alocado.&nbsp;<strong>Un virus que, en definitiva, parece poder mutar tambi\u00e9n en el orden simb\u00f3lico, pues cada quien le adjudica algo que va m\u00e1s all\u00e1 de su condici\u00f3n.&nbsp;<\/strong>Dos a\u00f1os despu\u00e9s del inicio de la pandemia y, aunque que no hayamos salido de ning\u00fan lugar, estamos en condiciones de asegurar que, de mejores, no tenemos nada. &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">Nancy Giampaolo &#8211; Diario Perfil<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Aunque parezca mentira,&nbsp;la subjetividad humana es tan amplia como para que existan personas que recuerdan con cierto cari\u00f1o los comienzos de la pandemia. Eso de conseguir provisiones y meterse en casa con los seres queridos a esperar la victoria contra el \u201cenemigo invisible\u201d mentado por algunos&nbsp;gobernantes era algo similar a la aventura.&nbsp;Una aventura que, por [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":9234,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[248],"tags":[808,804],"ppma_author":[1051],"class_list":["post-9233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis","tag-cuarentena","tag-pandemia"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salimos mejores - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2022\/01\/06\/salimos-mejores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salimos mejores - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Aunque parezca mentira,&nbsp;la subjetividad humana es tan amplia como para que existan personas que recuerdan con cierto cari\u00f1o los comienzos de la pandemia. Eso de conseguir provisiones y meterse en casa con los seres queridos a esperar la victoria contra el \u201cenemigo invisible\u201d mentado por algunos&nbsp;gobernantes era algo similar a la aventura.&nbsp;Una aventura que, por [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2022\/01\/06\/salimos-mejores\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-06T21:21:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-06T21:30:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/cuarentena.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"983\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/01\\\/06\\\/salimos-mejores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/01\\\/06\\\/salimos-mejores\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\"},\"headline\":\"Salimos mejores\",\"datePublished\":\"2022-01-06T21:21:00+00:00\",\"dateModified\":\"2022-01-06T21:30:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/01\\\/06\\\/salimos-mejores\\\/\"},\"wordCount\":1050,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/01\\\/06\\\/salimos-mejores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cuarentena.jpg?fit=1600%2C983&ssl=1\",\"keywords\":[\"cuarentena\",\"pandemia\"],\"articleSection\":[\"Analisis\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/01\\\/06\\\/salimos-mejores\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/01\\\/06\\\/salimos-mejores\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/01\\\/06\\\/salimos-mejores\\\/\",\"name\":\"Salimos mejores - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/01\\\/06\\\/salimos-mejores\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/01\\\/06\\\/salimos-mejores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cuarentena.jpg?fit=1600%2C983&ssl=1\",\"datePublished\":\"2022-01-06T21:21:00+00:00\",\"dateModified\":\"2022-01-06T21:30:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/01\\\/06\\\/salimos-mejores\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/01\\\/06\\\/salimos-mejores\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/01\\\/06\\\/salimos-mejores\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cuarentena.jpg?fit=1600%2C983&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cuarentena.jpg?fit=1600%2C983&ssl=1\",\"width\":1600,\"height\":983},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/01\\\/06\\\/salimos-mejores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salimos mejores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salimos mejores - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2022\/01\/06\/salimos-mejores\/","og_locale":"es_ES","og_type":"article","og_title":"Salimos mejores - Informatepy","og_description":"Aunque parezca mentira,&nbsp;la subjetividad humana es tan amplia como para que existan personas que recuerdan con cierto cari\u00f1o los comienzos de la pandemia. Eso de conseguir provisiones y meterse en casa con los seres queridos a esperar la victoria contra el \u201cenemigo invisible\u201d mentado por algunos&nbsp;gobernantes era algo similar a la aventura.&nbsp;Una aventura que, por [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2022\/01\/06\/salimos-mejores\/","og_site_name":"Informatepy","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-01-06T21:21:00+00:00","article_modified_time":"2022-01-06T21:30:18+00:00","og_image":[{"width":1600,"height":983,"url":"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/cuarentena.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2022\/01\/06\/salimos-mejores\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2022\/01\/06\/salimos-mejores\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b"},"headline":"Salimos mejores","datePublished":"2022-01-06T21:21:00+00:00","dateModified":"2022-01-06T21:30:18+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/01\/06\/salimos-mejores\/"},"wordCount":1050,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/01\/06\/salimos-mejores\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/cuarentena.jpg?fit=1600%2C983&ssl=1","keywords":["cuarentena","pandemia"],"articleSection":["Analisis"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2022\/01\/06\/salimos-mejores\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2022\/01\/06\/salimos-mejores\/","url":"https:\/\/informatepy.com\/2021\/2022\/01\/06\/salimos-mejores\/","name":"Salimos mejores - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/01\/06\/salimos-mejores\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/01\/06\/salimos-mejores\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/cuarentena.jpg?fit=1600%2C983&ssl=1","datePublished":"2022-01-06T21:21:00+00:00","dateModified":"2022-01-06T21:30:18+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2022\/01\/06\/salimos-mejores\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2022\/01\/06\/salimos-mejores\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2022\/01\/06\/salimos-mejores\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/cuarentena.jpg?fit=1600%2C983&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/cuarentena.jpg?fit=1600%2C983&ssl=1","width":1600,"height":983},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2022\/01\/06\/salimos-mejores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Salimos mejores"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2021\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/cuarentena.jpg?fit=1600%2C983&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":2366,"url":"https:\/\/informatepy.com\/2021\/2020\/12\/27\/estan-avisados-el-coronavirus-no-sera-la-ultima-pandemia\/","url_meta":{"origin":9233,"position":0},"title":"ESTAN AVISADOS: el coronavirus no ser\u00e1 la \u00faltima pandemia","date":"27 de diciembre de 2020","format":false,"excerpt":"La Organizaci\u00f3n Mundial de la Salud (OMS) advirti\u00f3 este s\u00e1bado que la del coronavirus no ser\u00e1 la \u00faltima pandemia y subray\u00f3 que los avances sanitarios resultar\u00e1n insuficientes si no hay\u00a0cambios con respecto al calentamiento global y el bienestar animal. El director general de la OMS, Tedros Adhanom Ghebreyesus, alert\u00f3 ante\u00a0\"el\u2026","rel":"","context":"En \u00abSalud\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/ovejas-al-matadero.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":7119,"url":"https:\/\/informatepy.com\/2021\/2021\/09\/14\/taiwan-reclama-el-lugar-que-le-corresponde-en-la-onu\/","url_meta":{"origin":9233,"position":1},"title":"Taiw\u00e1n reclama el lugar que le corresponde en la ONU","date":"14 de septiembre de 2021","format":false,"excerpt":"Hoy se inicia la 76\u00ba Asamblea General de las Naciones Unidas y, una vez m\u00e1s, 23.5 millones de personas se quedan sin voz","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/09\/dale-una-voz-a-taiwan.jpg?fit=1200%2C681&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4981,"url":"https:\/\/informatepy.com\/2021\/2021\/05\/22\/volver-a-volar-en-medio-de-la-pandemia\/","url_meta":{"origin":9233,"position":2},"title":"Volver a volar en medio de la pandemia","date":"22 de mayo de 2021","format":false,"excerpt":"Clarita Mart\u00ednez, periodista de Canal 13, relat\u00f3 a trav\u00e9s de sus redes sociales su experiencia durante la pandemia. Sus miedos, sus angustias y el camino que pudo encontrar para superarlas y que podr\u00eda, tambi\u00e9n, ayudar a otros. La pandemia que atraviesa el mundo trajo mucho m\u00e1s que un virus, pero\u2026","rel":"","context":"En \u00abSalud\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/clarita-martinez.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8957,"url":"https:\/\/informatepy.com\/2021\/2021\/12\/22\/la-ultima-vez-que-las-farmaceuticas-crecieron-tanto-fue-durante-la-pandemia-de-vih\/","url_meta":{"origin":9233,"position":3},"title":"La \u00faltima vez que las farmac\u00e9uticas crecieron tanto fue durante la \u201cpandemia\u201d de VIH","date":"22 de diciembre de 2021","format":false,"excerpt":"De acuerdo a las estimaciones de las propias farmac\u00e9uticas (Pfizer, BioNTech, Moderna, AstraZeneca y Johnson & Johnson), proyectan cerrar el 2021 con una facturaci\u00f3n conjunta, solo en concepto de vacunas covid, de 74.000 millones de d\u00f3lares. En otras palabras, un poco m\u00e1s del doble de lo facturado por todo el\u2026","rel":"","context":"En \u00abCiencia y Tecnolog\u00eda\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/dolar-avion-nubes.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2314,"url":"https:\/\/informatepy.com\/2021\/2020\/12\/04\/asi-terminan-las-aventuras-ideologicas-de-genero\/","url_meta":{"origin":9233,"position":4},"title":"As\u00ed terminan las aventuras ideol\u00f3gicas de g\u00e9nero","date":"4 de diciembre de 2020","format":false,"excerpt":"Una ni\u00f1a de 4 a\u00f1os que fue\u00a0adoptada cuando ten\u00eda 2 meses de vida por una familia de la ciudad misionera de El dorado (Argentina) fue repentinamente arrebata de su seno por decisi\u00f3n de la jueza de familia Corina Jones y entregada a una pareja de mujeres polic\u00edas de la ciudad\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/familia-encadenada.jpg?fit=689%2C525&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4434,"url":"https:\/\/informatepy.com\/2021\/2021\/04\/10\/que-pasa-cuando-el-hombre-mas-rico-del-mundo-postea-un-mensaje-como-este\/","url_meta":{"origin":9233,"position":5},"title":"\u00bfQu\u00e9 pasa cuando el hombre m\u00e1s rico del mundo postea un mensaje como este?","date":"10 de abril de 2021","format":false,"excerpt":"Muchas cosas podr\u00edamos decir de este muchacho, \u00bfC\u00f3mo es que se llama? Si, un tal Elon Musk, \u00bfLo ubicas? De a ratos es el hombre m\u00e1s rico del planeta tierra, de a ratos manda un auto al espacio y excentricidades de ese tipo. Lo que no podemos decir de \u00e9l,\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/musk3.jpg?fit=1200%2C1180&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1051,"user_id":4,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/9233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=9233"}],"version-history":[{"count":2,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/9233\/revisions"}],"predecessor-version":[{"id":9242,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/9233\/revisions\/9242"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/9234"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=9233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=9233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=9233"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=9233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}