{"id":836,"date":"2019-03-12T20:19:00","date_gmt":"2019-03-13T00:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=836"},"modified":"2021-02-26T17:56:45","modified_gmt":"2021-02-26T21:56:45","slug":"diputado-rejala-denuncia-presiones","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/03\/12\/diputado-rejala-denuncia-presiones\/","title":{"rendered":"Diputado Rejala denuncia presiones"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El diputado sanlorenzano del Partido Hagamos, Carlos Rejala, denunci\u00f3 en su redes sociales, que luego de haber puesto a disposici\u00f3n de la ciudadan\u00eda las irregularidades en las \u00abBecas Itaip\u00fa\u00bb, comenz\u00f3 a recibir presiones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el texto, el diputado manifest\u00f3 que: \u00bb Cuando te metes contra los pol\u00edticos poderosos, ndi! preparate! Van a empezar a decir, por todos los medios, que te drogas, que robaste, que tu familia es ladrona, que hiciste copiat\u00edn en primer grado, que le mataste a alguien, nambr\u00e9, de todo! Para destruirte, para vengarse, porque de eso est\u00e1n hechos algunos pol\u00edticos, de odio\u00bb. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, agreg\u00f3 que, m\u00e1s all\u00e1 de las denuncias realizadas respecto del programa de becas, la corporaci\u00f3n pol\u00edtica no acepta que nuevos exponentes tomen visibilidad, manifestando que:  \u00absuena un nombre joven para Presidente de la C\u00e1mara de Diputados  y hay que bajarle pues a todos esos nuevos que pueden llegar a ser\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/denuncia-carlos-rejala-1.jpg?w=740&#038;ssl=1\" alt=\"\" class=\"wp-image-937\" data-recalc-dims=\"1\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El diputado sanlorenzano del Partido Hagamos, Carlos Rejala, denunci\u00f3 en su redes sociales, que luego de haber puesto a disposici\u00f3n de la ciudadan\u00eda las irregularidades en las \u00abBecas Itaip\u00fa\u00bb, comenz\u00f3 a recibir presiones. En el texto, el diputado manifest\u00f3 que: \u00bb Cuando te metes contra los pol\u00edticos poderosos, ndi! preparate! Van a empezar a decir, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":837,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[177],"tags":[449,469],"ppma_author":[1039],"class_list":["post-836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-becas-itaipu","tag-carlos-rejala"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diputado Rejala denuncia presiones - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/03\/12\/diputado-rejala-denuncia-presiones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diputado Rejala denuncia presiones - Informatepy\" \/>\n<meta property=\"og:description\" content=\"El diputado sanlorenzano del Partido Hagamos, Carlos Rejala, denunci\u00f3 en su redes sociales, que luego de haber puesto a disposici\u00f3n de la ciudadan\u00eda las irregularidades en las \u00abBecas Itaip\u00fa\u00bb, comenz\u00f3 a recibir presiones. En el texto, el diputado manifest\u00f3 que: \u00bb Cuando te metes contra los pol\u00edticos poderosos, ndi! preparate! Van a empezar a decir, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/03\/12\/diputado-rejala-denuncia-presiones\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-13T00:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-26T21:56:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/Carlos-Rejala-diputado-hagamos.jpg?fit=650%2C469&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"469\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/12\\\/diputado-rejala-denuncia-presiones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/12\\\/diputado-rejala-denuncia-presiones\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"Diputado Rejala denuncia presiones\",\"datePublished\":\"2019-03-13T00:19:00+00:00\",\"dateModified\":\"2021-02-26T21:56:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/12\\\/diputado-rejala-denuncia-presiones\\\/\"},\"wordCount\":161,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/12\\\/diputado-rejala-denuncia-presiones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Carlos-Rejala-diputado-hagamos.jpg?fit=650%2C469&ssl=1\",\"keywords\":[\"becas itaipu\",\"carlos rejala\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/12\\\/diputado-rejala-denuncia-presiones\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/12\\\/diputado-rejala-denuncia-presiones\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/12\\\/diputado-rejala-denuncia-presiones\\\/\",\"name\":\"Diputado Rejala denuncia presiones - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/12\\\/diputado-rejala-denuncia-presiones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/12\\\/diputado-rejala-denuncia-presiones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Carlos-Rejala-diputado-hagamos.jpg?fit=650%2C469&ssl=1\",\"datePublished\":\"2019-03-13T00:19:00+00:00\",\"dateModified\":\"2021-02-26T21:56:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/12\\\/diputado-rejala-denuncia-presiones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/12\\\/diputado-rejala-denuncia-presiones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/12\\\/diputado-rejala-denuncia-presiones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Carlos-Rejala-diputado-hagamos.jpg?fit=650%2C469&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Carlos-Rejala-diputado-hagamos.jpg?fit=650%2C469&ssl=1\",\"width\":650,\"height\":469,\"caption\":\"Diputado Carlos Rejala - Hagamos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/12\\\/diputado-rejala-denuncia-presiones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diputado Rejala denuncia presiones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diputado Rejala denuncia presiones - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/03\/12\/diputado-rejala-denuncia-presiones\/","og_locale":"es_ES","og_type":"article","og_title":"Diputado Rejala denuncia presiones - Informatepy","og_description":"El diputado sanlorenzano del Partido Hagamos, Carlos Rejala, denunci\u00f3 en su redes sociales, que luego de haber puesto a disposici\u00f3n de la ciudadan\u00eda las irregularidades en las \u00abBecas Itaip\u00fa\u00bb, comenz\u00f3 a recibir presiones. En el texto, el diputado manifest\u00f3 que: \u00bb Cuando te metes contra los pol\u00edticos poderosos, ndi! preparate! Van a empezar a decir, [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2019\/03\/12\/diputado-rejala-denuncia-presiones\/","og_site_name":"Informatepy","article_published_time":"2019-03-13T00:19:00+00:00","article_modified_time":"2021-02-26T21:56:45+00:00","og_image":[{"width":650,"height":469,"url":"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/Carlos-Rejala-diputado-hagamos.jpg?fit=650%2C469&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/03\/12\/diputado-rejala-denuncia-presiones\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/12\/diputado-rejala-denuncia-presiones\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"Diputado Rejala denuncia presiones","datePublished":"2019-03-13T00:19:00+00:00","dateModified":"2021-02-26T21:56:45+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/12\/diputado-rejala-denuncia-presiones\/"},"wordCount":161,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/12\/diputado-rejala-denuncia-presiones\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/Carlos-Rejala-diputado-hagamos.jpg?fit=650%2C469&ssl=1","keywords":["becas itaipu","carlos rejala"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/03\/12\/diputado-rejala-denuncia-presiones\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/03\/12\/diputado-rejala-denuncia-presiones\/","url":"https:\/\/informatepy.com\/2021\/2019\/03\/12\/diputado-rejala-denuncia-presiones\/","name":"Diputado Rejala denuncia presiones - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/12\/diputado-rejala-denuncia-presiones\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/12\/diputado-rejala-denuncia-presiones\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/Carlos-Rejala-diputado-hagamos.jpg?fit=650%2C469&ssl=1","datePublished":"2019-03-13T00:19:00+00:00","dateModified":"2021-02-26T21:56:45+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/12\/diputado-rejala-denuncia-presiones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/03\/12\/diputado-rejala-denuncia-presiones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/03\/12\/diputado-rejala-denuncia-presiones\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/Carlos-Rejala-diputado-hagamos.jpg?fit=650%2C469&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/Carlos-Rejala-diputado-hagamos.jpg?fit=650%2C469&ssl=1","width":650,"height":469,"caption":"Diputado Carlos Rejala - Hagamos"},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/03\/12\/diputado-rejala-denuncia-presiones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Diputado Rejala denuncia presiones"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/Carlos-Rejala-diputado-hagamos.jpg?fit=650%2C469&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":10665,"url":"https:\/\/informatepy.com\/2021\/2022\/03\/16\/el-diputado-carlos-rejala-manifesto-haberse-sentido-utilizado-por-kattya-gonzalez\/","url_meta":{"origin":836,"position":0},"title":"El diputado Carlos Rejala manifest\u00f3 haberse sentido utilizado por Kattya Gonz\u00e1lez","date":"16 de marzo de 2022","format":false,"excerpt":"En declaraciones a radio Monumental, el diputado Carlos Rejala en referencia al fallido juicio pol\u00edtico a la Fiscal General del Estado, Sandra Qui\u00f1onez, manifest\u00f3 haberse sentido utilizado por la diputada Gonz\u00e1lez. \"Me utilizaron, me sent\u00ed as\u00ed. Hace tiempo vengo asumiendo que hay que enfrentar el juicio y en este caso\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/carlos-rejala.jpg?fit=902%2C601&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11090,"url":"https:\/\/informatepy.com\/2021\/2022\/04\/08\/diputado-rejala-pedira-por-ley-la-reduccion-de-la-tarifa-de-la-ande\/","url_meta":{"origin":836,"position":1},"title":"Diputado Rejala pedir\u00e1 por ley la reducci\u00f3n de la tarifa de la ANDE","date":"8 de abril de 2022","format":false,"excerpt":"A trav\u00e9s de su redes sociales y en declaraciones a medios radiales, el diputado Carlos Rejala inform\u00f3 que presentar\u00e1 sobre tablas, un proyecto de ley para solicitar la disminuci\u00f3n de la tarifa de la ANDE. \"Este lunes presentar\u00e9 sobre tablas un proyecto para la REDUCCI\u00d3N INMEDIATA de la Tarifa de\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/carlos-rejala.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9550,"url":"https:\/\/informatepy.com\/2021\/2022\/01\/20\/diputado-rejala-en-paraguay-no-deben-haber-quiebres-sociales-o-politicos\/","url_meta":{"origin":836,"position":2},"title":"Diputado Rejala: \u00abEn Paraguay no deben haber quiebres sociales o pol\u00edticos\u00bb","date":"20 de enero de 2022","format":false,"excerpt":"En una entrevista con Radio \u00d1andut\u00ed, el diputado y pre candidato a presidente Carlos Rejala, manifest\u00f3 que pretende liderar la concertaci\u00f3n de partidos opositores, teniendo en cuenta a las mejores personas de cada agrupaci\u00f3n. Expuso que \"Debemos anteponer por sobre todo a nuestro pa\u00eds, pensar que nuestro pa\u00eds no puede\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/carlos-rejala.jpg?fit=902%2C601&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12898,"url":"https:\/\/informatepy.com\/2021\/2022\/07\/27\/nueva-violacion-constitucional-en-diputados-jura-suplente-de-rejala\/","url_meta":{"origin":836,"position":3},"title":"Nueva violaci\u00f3n constitucional en Diputados: Jura suplente de Rejala","date":"27 de julio de 2022","format":false,"excerpt":"La mayor\u00eda se impuso y logr\u00f3 que jure como diputado Renato Dami\u00e1n Ibarrola, quien reemplazar\u00e1 por 60 d\u00edas a Carlos Rejala, quien pidi\u00f3 permiso por cuestiones familiares a trav\u00e9s de una nota sin firma, ya que el mismo no se encontrar\u00eda en el pa\u00eds. La bancada de Honor Colorado se\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/07\/renato-damian-ibarrola.jpg?fit=660%2C330&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1899,"url":"https:\/\/informatepy.com\/2021\/2020\/04\/20\/nano-galaverna-con-los-tapones-de-punta-contra-rejala\/","url_meta":{"origin":836,"position":4},"title":"\u00abNano\u00bb Galaverna con los tapones de punta contra Rejala","date":"20 de abril de 2020","format":false,"excerpt":"En un posteo de Facebook, el Diputado Galaverna atac\u00f3 fuertemente a su colega Carlos Rejala. Adem\u00e1s de referirse de manera socarrona al diputado como el \"Bukele paraguayo\", acus\u00f3 al diputado de haber vivido de la pirater\u00eda y de provenir de una \"familia de criminales\". En un pasaje de su denuncia\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/rejala-galaverna-scaled-1.jpg?fit=1200%2C851&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9616,"url":"https:\/\/informatepy.com\/2021\/2022\/01\/22\/el-diputado-rejala-sortea-su-salario-por-el-periodo-de-vacaciones\/","url_meta":{"origin":836,"position":5},"title":"El diputado Rejala sortea su salario por el per\u00edodo de vacaciones","date":"22 de enero de 2022","format":false,"excerpt":"El diputado Carlos Rejala anunci\u00f3 en sus redes sociales que sortear\u00e1 su salario correspondiente al per\u00edodo de vacaciones. El monto de 40.000.000 de guaran\u00edes ser\u00e1 distribuido entre 4 participantes. \"Por mi trabajo como legislador quiero retribuirles a ustedes estos d\u00edas de receso parlamentario, en los que no estamos cumpliendo con\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/sorteo-rejala.jpg?fit=1200%2C1200&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=836"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/836\/revisions"}],"predecessor-version":[{"id":3674,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/836\/revisions\/3674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/837"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=836"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}