{"id":778,"date":"2019-03-02T20:19:00","date_gmt":"2019-03-03T00:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=778"},"modified":"2021-02-26T17:43:23","modified_gmt":"2021-02-26T21:43:23","slug":"juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\/","title":{"rendered":"Juntando latitas y vendiendo diarios, joven encarnaceno logr\u00f3 graduarse de la universidad"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Jorge Enmanuel Cabral tiene 23 a\u00f1os y para muchos es considerado un ejemplo de lucha y perseverancia. No le teme a las adversidades y asegura que pas\u00f3 muchas situaciones dif\u00edciles que le ayudaron a valorar de una manera distinta la vida y, por sobre todo, a lograr sus objetivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A los 7 a\u00f1os comenz\u00f3 a trabajar juntando latitas para ayudar con algunos gastos. Luego, a los 11 a\u00f1os lleg\u00f3 al Alto Paran\u00e1 desde Encarnaci\u00f3n con su madre, hermanas y padrastro, en busca de mejores condiciones de vida Se instalaron en Presidente Franco y trabajaron en otro rubro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEra vendedor ambulante. Recorr\u00eda caminando con mercader\u00edas no perecederas en las manos y vend\u00eda lo que pod\u00eda en mi barrio. As\u00ed trabaj\u00e9 hasta los 15 a\u00f1os. Despu\u00e9s me dediqu\u00e9 a cuidar autos y antes de terminar el colegio comenc\u00e9 a vender diarios\u201d, relat\u00f3 el joven.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la venta de diarios vio que pod\u00eda seguir estudiando una carrera universitaria, pese a que eso demandaba una inversi\u00f3n extra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCuando era peque\u00f1o quer\u00eda ser polic\u00eda, pero ya de grande percib\u00ed que la carrera de criminal\u00edstica era lo que me gustaba\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jorge Cabral coment\u00f3 que no fue f\u00e1cil seguir sus estudios en la universidad y que con mucho empe\u00f1o y dedicaci\u00f3n logr\u00f3 culminar su carrera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Actualmente vive con su pareja pero a\u00fan no tienen hijos. Sigue con proyectos de estudiar, ahora optando por did\u00e1ctica universitaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El nuevo licenciado pidi\u00f3 a las autoridades \u201cdespolitizar\u201d los cargos p\u00fablicos. Muchos j\u00f3venes buenos profesionales no tiene ocupaci\u00f3n porque los puestos son acaparados por recomendados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cQuiero trabajar en el Ministerio P\u00fablico pero se debe dar oportunidad a los dem\u00e1s j\u00f3venes, no solamente a hijos de pol\u00edticos y recomendados\u201d, destac\u00f3 el joven profesional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: Vanguardia\n\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jorge Enmanuel Cabral tiene 23 a\u00f1os y para muchos es considerado un ejemplo de lucha y perseverancia. No le teme a las adversidades y asegura que pas\u00f3 muchas situaciones dif\u00edciles que le ayudaron a valorar de una manera distinta la vida y, por sobre todo, a lograr sus objetivos. A los 7 a\u00f1os comenz\u00f3 a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":779,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[302],"tags":[442,443],"ppma_author":[1039],"class_list":["post-778","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacados","tag-fuerza-de-voluntad","tag-progreso"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Juntando latitas y vendiendo diarios, joven encarnaceno logr\u00f3 graduarse de la universidad - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/03\/02\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Juntando latitas y vendiendo diarios, joven encarnaceno logr\u00f3 graduarse de la universidad - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Jorge Enmanuel Cabral tiene 23 a\u00f1os y para muchos es considerado un ejemplo de lucha y perseverancia. No le teme a las adversidades y asegura que pas\u00f3 muchas situaciones dif\u00edciles que le ayudaron a valorar de una manera distinta la vida y, por sobre todo, a lograr sus objetivos. A los 7 a\u00f1os comenz\u00f3 a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/03\/02\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-03T00:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-26T21:43:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/lic-jorge-emanuel-cabral.jpg?fit=500%2C294&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"294\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/02\\\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/02\\\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"Juntando latitas y vendiendo diarios, joven encarnaceno logr\u00f3 graduarse de la universidad\",\"datePublished\":\"2019-03-03T00:19:00+00:00\",\"dateModified\":\"2021-02-26T21:43:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/02\\\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\\\/\"},\"wordCount\":321,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/02\\\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/lic-jorge-emanuel-cabral.jpg?fit=500%2C294&ssl=1\",\"keywords\":[\"fuerza de voluntad\",\"progreso\"],\"articleSection\":[\"Destacados\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/02\\\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/02\\\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/02\\\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\\\/\",\"name\":\"Juntando latitas y vendiendo diarios, joven encarnaceno logr\u00f3 graduarse de la universidad - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/02\\\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/02\\\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/lic-jorge-emanuel-cabral.jpg?fit=500%2C294&ssl=1\",\"datePublished\":\"2019-03-03T00:19:00+00:00\",\"dateModified\":\"2021-02-26T21:43:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/02\\\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/02\\\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/02\\\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/lic-jorge-emanuel-cabral.jpg?fit=500%2C294&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/lic-jorge-emanuel-cabral.jpg?fit=500%2C294&ssl=1\",\"width\":500,\"height\":294,\"caption\":\"Licenciado Jorge Emanuel Cabral\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/02\\\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Juntando latitas y vendiendo diarios, joven encarnaceno logr\u00f3 graduarse de la universidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Juntando latitas y vendiendo diarios, joven encarnaceno logr\u00f3 graduarse de la universidad - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\/","og_locale":"es_ES","og_type":"article","og_title":"Juntando latitas y vendiendo diarios, joven encarnaceno logr\u00f3 graduarse de la universidad - Informatepy","og_description":"Jorge Enmanuel Cabral tiene 23 a\u00f1os y para muchos es considerado un ejemplo de lucha y perseverancia. No le teme a las adversidades y asegura que pas\u00f3 muchas situaciones dif\u00edciles que le ayudaron a valorar de una manera distinta la vida y, por sobre todo, a lograr sus objetivos. A los 7 a\u00f1os comenz\u00f3 a [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\/","og_site_name":"Informatepy","article_published_time":"2019-03-03T00:19:00+00:00","article_modified_time":"2021-02-26T21:43:23+00:00","og_image":[{"width":500,"height":294,"url":"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/lic-jorge-emanuel-cabral.jpg?fit=500%2C294&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"Juntando latitas y vendiendo diarios, joven encarnaceno logr\u00f3 graduarse de la universidad","datePublished":"2019-03-03T00:19:00+00:00","dateModified":"2021-02-26T21:43:23+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\/"},"wordCount":321,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/lic-jorge-emanuel-cabral.jpg?fit=500%2C294&ssl=1","keywords":["fuerza de voluntad","progreso"],"articleSection":["Destacados"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/03\/02\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\/","url":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\/","name":"Juntando latitas y vendiendo diarios, joven encarnaceno logr\u00f3 graduarse de la universidad - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/lic-jorge-emanuel-cabral.jpg?fit=500%2C294&ssl=1","datePublished":"2019-03-03T00:19:00+00:00","dateModified":"2021-02-26T21:43:23+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/03\/02\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/lic-jorge-emanuel-cabral.jpg?fit=500%2C294&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/lic-jorge-emanuel-cabral.jpg?fit=500%2C294&ssl=1","width":500,"height":294,"caption":"Licenciado Jorge Emanuel Cabral"},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/juntando-latitas-y-vendiendo-diarios-joven-encarnaceno-logro-graduarse-de-la-universidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Juntando latitas y vendiendo diarios, joven encarnaceno logr\u00f3 graduarse de la universidad"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/lic-jorge-emanuel-cabral.jpg?fit=500%2C294&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1132,"url":"https:\/\/informatepy.com\/2021\/2019\/05\/10\/excontralor-ira-cuatro-anos-a-la-carcel\/","url_meta":{"origin":778,"position":0},"title":"Excontralor ir\u00e1 cuatro a\u00f1os a la c\u00e1rcel","date":"10 de mayo de 2019","format":false,"excerpt":"El Tribunal de Sentencia, integrado por Mesalina Fern\u00e1ndez (presidenta), Gloria Hermosa y Mercedes Aguirre, dieron a conocer este viernes su fallo contra el excontralor \u00d3scar Rub\u00e9n Vel\u00e1zquez y la exsubcontralora Nancy Torreblanca. Las magistradas condenaron a Vel\u00e1zquez a cuatro a\u00f1os de c\u00e1rcel y a Torreblanca a dos a\u00f1os (con suspensi\u00f3n\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/ex-contralor.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5522,"url":"https:\/\/informatepy.com\/2021\/2021\/06\/29\/miami-preparan-a-los-familiares-porque-los-pronosticos-no-son-buenos\/","url_meta":{"origin":778,"position":1},"title":"MIAMI: Preparan a los familiares porque los pron\u00f3sticos no son buenos","date":"29 de junio de 2021","format":false,"excerpt":"A m\u00e1s de una semana del derrumbe parcial en Miami, equipos terap\u00e9uticos trabajan a la par de los rescatistas para preparar a las familias. Los pron\u00f3sticos no son buenos.","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/Edificio-Miami-Colapso.jpg?fit=1120%2C747&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9301,"url":"https:\/\/informatepy.com\/2021\/2022\/01\/08\/rusia-busca-que-los-pedofilos-sean-enviados-a-prision-de-por-vida-en-siberia\/","url_meta":{"origin":778,"position":2},"title":"Rusia busca que los ped\u00f3filos sean enviados a prisi\u00f3n de por vida en Siberia","date":"8 de enero de 2022","format":false,"excerpt":"El oficialismo apura un proyecto de ley para agravar las penas y las condiciones de detenci\u00f3n de los violadores de ni\u00f1os. El secuestro, abuso sexual y asesinato de una ni\u00f1a de 5 a\u00f1os conmueve al pa\u00eds.","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/01\/abuso-sexual-infantil.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5909,"url":"https:\/\/informatepy.com\/2021\/2021\/07\/22\/conoce-a-tu-candidato-eugenia-aquino-candidata-a-concejal-de-asuncion-ppq\/","url_meta":{"origin":778,"position":3},"title":"Conoc\u00e9 a tu candidato: Eugenia Aquino (Candidata a Concejal de Asunci\u00f3n \u2013 PPQ)","date":"22 de julio de 2021","format":false,"excerpt":"\u00bfCu\u00e1ndo y por qu\u00e9 te sumaste a la pol\u00edtica? Empec\u00e9 a interesarme al percatarme el bajo nivel de gesti\u00f3n de la actual administraci\u00f3n. Conozco el sector p\u00fablico ya que tengo poco m\u00e1s de 5 a\u00f1os como Directora de la Escuela de Gastronom\u00eda en el SNPP. La improvisaci\u00f3n, ausencia de visi\u00f3n\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/eugenia-aquino-concejal.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4984,"url":"https:\/\/informatepy.com\/2021\/2021\/05\/22\/denuncias-de-acoso-una-relacion-oculta-con-una-empleada-y-vinculos-con-epstein-el-coctel-que-podria-destruir-la-imagen-de-bill-gates\/","url_meta":{"origin":778,"position":4},"title":"Denuncias de acoso, una relaci\u00f3n oculta con una empleada y v\u00ednculos con Epstein: el c\u00f3ctel que podr\u00eda destruir la imagen de Bill Gates","date":"22 de mayo de 2021","format":false,"excerpt":"Hace a\u00f1os sostiene una reputaci\u00f3n de fil\u00e1ntropo global y visionario, recientemente comprometido en la lucha contra el COVID-19, pero tras su divorcio de Melinda Gates, una serie de acusaciones en diversos medios y oscuros secretos guardados durante a\u00f1os jaquean el perfil del creador de Microsoft","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/EPSTEIN-Y-GATES.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":862,"url":"https:\/\/informatepy.com\/2021\/2019\/03\/15\/intendente-del-plra-gasta-casi-g-50-millones-por-alineacion-de-ruedas\/","url_meta":{"origin":778,"position":5},"title":"Intendente del PLRA gasta casi G. 50 millones por alineaci\u00f3n de ruedas","date":"15 de marzo de 2019","format":false,"excerpt":"En una factura legal expedida por una gomer\u00eda hacen figurar un gasto de casi G. 50 millones, por \u201calineaci\u00f3n de veh\u00edculos varios\u201d, seg\u00fan la denuncia. Un trabajo mec\u00e1nico de ese tipo no alcanzar\u00eda los G. 100.000\u00a0 por cada rodado y el parque automotor de la comuna no es numeroso como\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/factura-alineacion-itapua.jpeg?fit=552%2C414&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=778"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/778\/revisions"}],"predecessor-version":[{"id":3637,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/778\/revisions\/3637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/779"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=778"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}