{"id":776,"date":"2019-03-02T20:19:00","date_gmt":"2019-03-03T00:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=776"},"modified":"2021-02-26T17:43:30","modified_gmt":"2021-02-26T21:43:30","slug":"contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\/","title":{"rendered":"Contralor y su director jur\u00eddico son socios de SA con un capital de G. 1.000 millones"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La empresa \u201c6 de Abril SA\u201d se constituy\u00f3 el 9 de agosto de 2016 y tiene como actividad principal \u201cactividades inmobiliarias realizadas con bienes propios o arrendados\u201d. Su capital es de G. 1.000 millones y hasta la fecha declar\u00f3 ante la Subsecretar\u00eda de Estado de Tributaci\u00f3n \u201csin movimiento\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los principales socios de la referida son el contralor y el abogado N\u00fa\u00f1ez, quien llamativamente es el director jur\u00eddico de la Contralor\u00eda General a cargo de Garc\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todo esto se desprende del informe que Seprelad envi\u00f3 en mayo del a\u00f1o pasado a la Unidad de Delitos Econ\u00f3micos y Anticorrupci\u00f3n del Ministerio P\u00fablico. En dicho documento se resalta que Garc\u00eda no puede justificar el origen de G. 2.942 millones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los a\u00f1os 2012 y 2017, el contralor deposit\u00f3 en sus cuentas bancarias la suma de G. 4.462.355.395.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, durante ese mismo periodo declar\u00f3 ante la SET que tuvo un ingreso de G. 1.520 millones. Es por eso la diferencia de G. 2.942 millones, entre lo declarado ante Tributaci\u00f3n y lo depositado en los bancos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el informe de Seprelad, Garc\u00eda declar\u00f3 ante la SET en 2012 que tuvo un ingreso de G. 163 millones. Empero, ese mismo a\u00f1o deposit\u00f3 en sus cuentas bancarias G. 1.004 millones, lo que arroja una diferencia de G. 840.968.045 que no declar\u00f3 al fisco. Esta situaci\u00f3n se repite en los a\u00f1os 2014, 2015, 2016 y 2017.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los datos prove\u00eddos por la Seprelad son corroborados por la fiscala Victoria Acu\u00f1a que tiene a su cargo la investigaci\u00f3n por presunto enriquecimiento il\u00edcito y lavado de dinero del contralor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Conclusi\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con base al Informe de Inteligencia Financiera, la Seprelad concluy\u00f3 que: 1) la existencia de publicaciones period\u00edsticas negativas que vinculan a la persona analizada con presuntos hechos de producci\u00f3n de documentos de contenido falso y uso de documento de contenido falso; 2) No se ha podido observar documentaciones que avalen varias de las transacciones y operaciones realizadas por Garc\u00eda; 3) se observa una suma de G. 2.942 millones en concepto de dep\u00f3sito sin justificaci\u00f3n aparente y 4) se observa gran utilizaci\u00f3n de efectivo en las operaciones realizadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El primer punto se refiere a la imputaci\u00f3n que soporta Enrique Garc\u00eda por el uso de documentos falsos, para justificar la no apelaci\u00f3n de un fallo judicial que conden\u00f3 a la Municipalidad de Asunci\u00f3n, donde fue director jur\u00eddico, a pagar US$ 3,6 millones a la firma Ivesur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Garc\u00eda fue procurador general, desde setiembre de 2008 hasta junio de 2012, durante el gobierno de Lugo. Fue adem\u00e1s presidente del Consejo impulsor del Sistema Nacional de Integridad, CISNI. Posteriormente, se dedic\u00f3 a la actividad privada y lleg\u00f3 a ser director jur\u00eddico de la Municipalidad de Asunci\u00f3n, hasta que fue nombrado contralor general por el periodo 2016-2018.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La empresa \u201c6 de Abril SA\u201d se constituy\u00f3 el 9 de agosto de 2016 y tiene como actividad principal \u201cactividades inmobiliarias realizadas con bienes propios o arrendados\u201d. Su capital es de G. 1.000 millones y hasta la fecha declar\u00f3 ante la Subsecretar\u00eda de Estado de Tributaci\u00f3n \u201csin movimiento\u201d. Los principales socios de la referida son [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":777,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[177],"tags":[439,440,441,432],"ppma_author":[1039],"class_list":["post-776","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-contraloria","tag-enrique-garcia","tag-enriquecimiento-ilicito","tag-seprelad"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contralor y su director jur\u00eddico son socios de SA con un capital de G. 1.000 millones - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/03\/02\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contralor y su director jur\u00eddico son socios de SA con un capital de G. 1.000 millones - Informatepy\" \/>\n<meta property=\"og:description\" content=\"La empresa \u201c6 de Abril SA\u201d se constituy\u00f3 el 9 de agosto de 2016 y tiene como actividad principal \u201cactividades inmobiliarias realizadas con bienes propios o arrendados\u201d. Su capital es de G. 1.000 millones y hasta la fecha declar\u00f3 ante la Subsecretar\u00eda de Estado de Tributaci\u00f3n \u201csin movimiento\u201d. Los principales socios de la referida son [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/03\/02\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-03T00:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-26T21:43:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/enriqua-garcia-y-cesar-nuC3B1ez.jpg?fit=765%2C573&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"765\" \/>\n\t<meta property=\"og:image:height\" content=\"573\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/02\\\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/02\\\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"Contralor y su director jur\u00eddico son socios de SA con un capital de G. 1.000 millones\",\"datePublished\":\"2019-03-03T00:19:00+00:00\",\"dateModified\":\"2021-02-26T21:43:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/02\\\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\\\/\"},\"wordCount\":479,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/02\\\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/enriqua-garcia-y-cesar-nuC3B1ez.jpg?fit=765%2C573&ssl=1\",\"keywords\":[\"contraloria\",\"enrique garcia\",\"enriquecimiento ilicito\",\"seprelad\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/02\\\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/02\\\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/02\\\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\\\/\",\"name\":\"Contralor y su director jur\u00eddico son socios de SA con un capital de G. 1.000 millones - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/02\\\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/02\\\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/enriqua-garcia-y-cesar-nuC3B1ez.jpg?fit=765%2C573&ssl=1\",\"datePublished\":\"2019-03-03T00:19:00+00:00\",\"dateModified\":\"2021-02-26T21:43:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/02\\\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/02\\\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/02\\\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/enriqua-garcia-y-cesar-nuC3B1ez.jpg?fit=765%2C573&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/enriqua-garcia-y-cesar-nuC3B1ez.jpg?fit=765%2C573&ssl=1\",\"width\":765,\"height\":573,\"caption\":\"Enrique Garc\u00eda junto C\u00e9sar D\u00edaz, su socio comercial - Foto ABC\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/03\\\/02\\\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contralor y su director jur\u00eddico son socios de SA con un capital de G. 1.000 millones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contralor y su director jur\u00eddico son socios de SA con un capital de G. 1.000 millones - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\/","og_locale":"es_ES","og_type":"article","og_title":"Contralor y su director jur\u00eddico son socios de SA con un capital de G. 1.000 millones - Informatepy","og_description":"La empresa \u201c6 de Abril SA\u201d se constituy\u00f3 el 9 de agosto de 2016 y tiene como actividad principal \u201cactividades inmobiliarias realizadas con bienes propios o arrendados\u201d. Su capital es de G. 1.000 millones y hasta la fecha declar\u00f3 ante la Subsecretar\u00eda de Estado de Tributaci\u00f3n \u201csin movimiento\u201d. Los principales socios de la referida son [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\/","og_site_name":"Informatepy","article_published_time":"2019-03-03T00:19:00+00:00","article_modified_time":"2021-02-26T21:43:30+00:00","og_image":[{"width":765,"height":573,"url":"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/enriqua-garcia-y-cesar-nuC3B1ez.jpg?fit=765%2C573&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"Contralor y su director jur\u00eddico son socios de SA con un capital de G. 1.000 millones","datePublished":"2019-03-03T00:19:00+00:00","dateModified":"2021-02-26T21:43:30+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\/"},"wordCount":479,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/enriqua-garcia-y-cesar-nuC3B1ez.jpg?fit=765%2C573&ssl=1","keywords":["contraloria","enrique garcia","enriquecimiento ilicito","seprelad"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/03\/02\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\/","url":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\/","name":"Contralor y su director jur\u00eddico son socios de SA con un capital de G. 1.000 millones - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/enriqua-garcia-y-cesar-nuC3B1ez.jpg?fit=765%2C573&ssl=1","datePublished":"2019-03-03T00:19:00+00:00","dateModified":"2021-02-26T21:43:30+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/03\/02\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/enriqua-garcia-y-cesar-nuC3B1ez.jpg?fit=765%2C573&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/enriqua-garcia-y-cesar-nuC3B1ez.jpg?fit=765%2C573&ssl=1","width":765,"height":573,"caption":"Enrique Garc\u00eda junto C\u00e9sar D\u00edaz, su socio comercial - Foto ABC"},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/03\/02\/contralor-y-su-director-juridico-son-socios-de-sa-con-un-capital-de-g-1-000-millones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Contralor y su director jur\u00eddico son socios de SA con un capital de G. 1.000 millones"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/enriqua-garcia-y-cesar-nuC3B1ez.jpg?fit=765%2C573&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":788,"url":"https:\/\/informatepy.com\/2021\/2019\/03\/04\/contraloria-aprieta-a-quinonez-con-supuestas-malversaciones\/","url_meta":{"origin":776,"position":0},"title":"Contralor\u00eda \u00abaprieta\u00bb a Qui\u00f1\u00f3nez con supuestas malversaciones","date":"4 de marzo de 2019","format":false,"excerpt":"El enfrentamiento entre la Fiscal\u00eda y la Contralor\u00eda parece no tener fin. Primeramente la titular del Ministerio P\u00fablico, Sandra Qui\u00f1\u00f3nez, accion\u00f3 ante la Corte Suprema para poder rendir su ejecuci\u00f3n presupuestaria ante el Tribunal de Cuentas y no solo ante la Contralor\u00eda. Ello porque el titular del \u00f3rgano contralor, Jos\u00e9\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/sandra-quiC3B1onez.jpg?fit=670%2C573&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":797,"url":"https:\/\/informatepy.com\/2021\/2019\/03\/05\/senado-debe-definir-si-trata-el-juicio-politico-al-contralor\/","url_meta":{"origin":776,"position":1},"title":"Senado debe definir si trata el juicio pol\u00edtico al contralor","date":"5 de marzo de 2019","format":false,"excerpt":"En la C\u00e1mara de Diputados, ya el a\u00f1o pasado se aprob\u00f3 la acusaci\u00f3n por mal desempe\u00f1o del contralor general de la Rep\u00fablica Jos\u00e9 Enrique Garc\u00eda. En noviembre, se design\u00f3 como fiscales acusadores a los legisladores Ram\u00f3n Romero Roa (ANR, samanieguista), Celeste Amarilla (PLRA, efrainista) y Hern\u00e1n David Rivas (ANR, cartista).\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/enriqua-garcia-y-cesar-nuC3B1ez.jpg?fit=765%2C573&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1073,"url":"https:\/\/informatepy.com\/2021\/2019\/04\/25\/sesion-extraordinaria-de-diputados-tratara-hoy-renuncia-del-contralor\/","url_meta":{"origin":776,"position":2},"title":"Sesi\u00f3n extraordinaria de Diputados tratar\u00e1 hoy renuncia del Contralor","date":"25 de abril de 2019","format":false,"excerpt":"Esta tarde, la C\u00e1mara de Diputados prev\u00e9 una sesi\u00f3n extraordinaria donde tratar\u00e1n la renuncia al cargo del Contralor General, Enrique Garc\u00eda. La sesi\u00f3n extra est\u00e1 convocada para las 14 horas, seg\u00fan inform\u00f3 Ram\u00f3n Romero Roa, uno de los fiscales acusadores en el juicio pol\u00edtico al titular de la Contralor\u00eda. De\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/enriqua-garcia-y-cesar-nuC3B1ez.jpg?fit=765%2C573&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4942,"url":"https:\/\/informatepy.com\/2021\/2021\/05\/18\/el-grupo-zuccolillo-colgado-del-estado-con-contratos-que-superan-los-us-17-millones\/","url_meta":{"origin":776,"position":3},"title":"El Grupo Zuccolillo, colgado del Estado con contratos que superan los US$ 17 millones","date":"18 de mayo de 2021","format":false,"excerpt":"La imprenta Mercurio SA, perteneciente al Grupo Zuccolillo, por medio de diferentes adjudicaciones le factur\u00f3 solo al MEC unos 16,5 millones de d\u00f3lares; adem\u00e1s, es proveedora de los boletines de voto para la Justicia Electoral; mientras, el propio Abc Color, a trav\u00e9s de la Editorial Azeta, obtuvo m\u00e1s de 75\u2026","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/Natalia-Zuccolillo-directora-del-diario-Abc-Color-y-Miguel-Angel-Zaldivar-director-de-la-imprenta-Mercurio-SA..jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":735,"url":"https:\/\/informatepy.com\/2021\/2020\/02\/26\/la-generosidad-de-nicanor-con-operadores\/","url_meta":{"origin":776,"position":4},"title":"La generosidad de Nicanor con operadores","date":"26 de febrero de 2020","format":false,"excerpt":"En cinco meses, el director paraguayo incorpor\u00f3 a 179 funcionarios, entre nuevos, contratados y comisionados. El sueldo de primer mundo de estos privilegiados cuesta a la binacional G. 3.045 millones al mes, monto que se dispara a G. 39.596 millones en un a\u00f1o, incluido pago de aguinaldo. El masivo ingreso\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/nicanor-duarte-yacyreta.jpg?fit=1000%2C668&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9813,"url":"https:\/\/informatepy.com\/2021\/2022\/01\/29\/casanas-levi-sobre-denuncia-de-giuzzo-juridicamente-no-tiene-ningun-sustento-ni-de-parte-de-seprelad-ni-de-parte-del-denunciante\/","url_meta":{"origin":776,"position":5},"title":"Casa\u00f1as Levi sobre denuncia de Giuzzo: \u00abJur\u00eddicamente no tiene ning\u00fan sustento ni de parte de Seprelad ni de parte del denunciante\u00bb","date":"29 de enero de 2022","format":false,"excerpt":"Hay solamente dos instancias en donde denunciar hechos punibles, la Fiscal\u00eda y la Polic\u00eda, seg\u00fan el abogado Jos\u00e9 Casa\u00f1as Levi, quien dijo que no tiene ning\u00fan sustento jur\u00eddico que la presentaci\u00f3n de Arnaldo Giuzzio contra Horacio Cartes haya sido ante la Seprelad. \u201cNo me convence tanto que sea una cuesti\u00f3n\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/Jose-Casanas-Levi.jpg?fit=1200%2C817&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=776"}],"version-history":[{"count":2,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/776\/revisions"}],"predecessor-version":[{"id":3639,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/776\/revisions\/3639"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/777"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=776"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}