{"id":7714,"date":"2021-10-15T09:03:10","date_gmt":"2021-10-15T13:03:10","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=7714"},"modified":"2021-10-15T09:03:12","modified_gmt":"2021-10-15T13:03:12","slug":"el-pasaporte-de-la-fe","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2021\/10\/15\/el-pasaporte-de-la-fe\/","title":{"rendered":"El pasaporte de la fe"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Iglesia Cat\u00f3lica, desde su origen, ha sido defensora de la dignidad humana. En el tercer milenio de su historia, se ha destacado por sacrificarse ella misma para preservar la Verdadera Doctrina al mismo tiempo que para llevar su mensaje de civilizaci\u00f3n, justicia social y aut\u00e9ntica libertad a todos los confines de la tierra. Su misma supervivencia, a pesar de tantos avatares, vendavales y tempestades de la historia no es sino un testimonio de la Promesa que su Divino Fundador le ha hecho: que estar\u00eda con ella hasta el fin de los tiempos. No pocos desaf\u00edos fueron los que superaron los Ap\u00f3stoles y sus descendientes, los Obispos de cada Di\u00f3cesis. Incluso la corrupci\u00f3n y el pecado de los hombres que la conforman la han herido muchas veces, aunque ella resiste, persiste y prevalece a lo largo de la historia por los m\u00e9ritos del Esp\u00edritu Santo que habita en ella, vivific\u00e1ndola y renov\u00e1ndola en la tradici\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Primera y principal defensora de la dignidad humana desde la misma concepci\u00f3n, la Iglesia de Roma tambi\u00e9n es <em>\u201cParens Scientiarum\u201d<\/em>, es decir, Madre de las Ciencias. El conocimiento cient\u00edfico moderno naci\u00f3 bajo sus alas, creci\u00f3 alimentado por ella en los monasterios, escuelas de traductores, c\u00e1tedras y universidades, que fueron creaci\u00f3n suya. \u00bfAcaso hay algo en nuestro mundo que no haya sido nutrido desde el R\u00edo T\u00edber?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Historia Universal podr\u00eda ser relatada f\u00e1cilmente como la Historia de la Iglesia Cat\u00f3lica contra los dominios y principados de este mundo. Pues no han faltado poderosos monarcas, emperadores, jefes de estado u oligarqu\u00edas internacionales que quisieron utilizarla para sus propios fines. Sin embargo, todos estos intentos fracasaron siempre, muchas veces de manera estrepitosa. Los grandes Imperios han pasado, pasan y pasar\u00e1n, pero la Iglesia Cat\u00f3lica sigue all\u00ed, contra viento y marea, contra miles de tempestades, contra los pron\u00f3sticos de todos los que vaticinaron tantas veces su inminente destrucci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todos estos sacrificios se han superado con inteligencia y valent\u00eda. A diferencia de lo que ha ocurrido con los hermanos del Rito Oriental as\u00ed como con las Sectas Protestantes, Roma siempre se preserv\u00f3 \u00edntegra y supo inmunizarse de todo intento de quedar como instrumento del poder secular y mundano. Es cierto que en muchos casos existi\u00f3 \u201ccooperaci\u00f3n\u201d, pero nunca \u201cservilismo\u201d ni mucho menos \u201csometimiento\u201d. Todo lo contrario, la sangre de los m\u00e1rtires fue alimento y renovaci\u00f3n para la Iglesia Cat\u00f3lica cuando esta se vio en situaciones extremas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue all\u00ed, en esos momentos de m\u00e1xima tensi\u00f3n, cuando la \u201cFe Verdadera\u201d se ha mostrado al mundo y ha dado innumerables frutos de salvaci\u00f3n. Los m\u00e1s poderosos emperadores de la historia no prevalecieron sobre ella. Las hordas de b\u00e1rbaros y v\u00e1ndalos no prevalecieron sobre ella. Las m\u00e1s destructivas guerras de la historia no prevalecieron sobre ella. Pestes verdaderamente mort\u00edferas, con tasas de letalidad que no se comparan a nada que hayamos visto en nuestros d\u00edas, no prevalecieron sobre ella. La Iglesia Cat\u00f3lica ha sido, desde siempre, el \u201cpasaporte de la salvaci\u00f3n\u201d. Y jam\u00e1s ha pedido nada a cambio, si exceptuamos a los corruptos y pecadores de simon\u00eda que siempre han existido y existir\u00e1n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero hoy en d\u00eda, como muchos se\u00f1alan, se vive una crisis de la fe. Los seres humanos, tiranizados por las dulces cadenas de una tecnocracia olig\u00e1rquica que ofrece hedonismo y cultura de la muerte como distractores de la realidad, se alejaron de la Iglesia Cat\u00f3lica y se han entregado a una vida paganizada y pauperizada en todos los \u00e1mbitos de la existencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No obstante, ser\u00eda muy vano centrar la culpa exclusivamente a los placeres de este mundo. Acaso no ha dicho Nuestro Se\u00f1or: <em>\u201c\u00bfpor qu\u00e9 miras la espiga en el ojo de tu hermano si t\u00fa no has visto la viga que est\u00e1 en el tuyo?\u201d<\/em>. M\u00e1s concretamente, deber\u00edamos preguntarnos si los Obispos, Sacerdotes y Di\u00e1conos que pastorean a la Iglesia Cat\u00f3lica se han mostrado dignos de sus ancestros y trabajado para que el pueblo los vea como \u201cRocas de Fe\u201d y no como simples ostentadores de potestades de las que, muchos de ellos, son indignos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recientemente se ha dado un interesante ejemplo de esta disyuntiva con las declaraciones realizadas por el Obispo de la Di\u00f3cesis de Caacup\u00e9, Su Excelencia Mons. Ricardo Valenzuela R\u00edos, que generaron todo tipo de reacciones especialmente en las redes sociales. Hab\u00eda declarado el Ep\u00edscopo que a la festividad de Nuestra Se\u00f1ora de la Inmaculada Concepci\u00f3n de Caacup\u00e9, principal celebraci\u00f3n de la religiosidad popular en el pa\u00eds cuyo evento central es el 8 de diciembre, solo podr\u00edan asistir los que estaban \u201cvacunados contra el COVID\u201d, entre otras restricciones. Por supuesto que muchos en la feligres\u00eda cat\u00f3lica al igual que simples observadores neutrales han considerado a estas declaraciones como poco menos que \u201cpeligrosas\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algunos dir\u00e1n que las instrucciones del Obispo Ricardo Valenzuela obedecen a la necesidad de preservar a los participantes ante una situaci\u00f3n de gravedad que ha azotado al mundo entero desde finales del a\u00f1o 2019 y de la que a duras penas estamos saliendo, para bien y para mal, con verdades y mentiras. Otros ir\u00e1n al extremo opuesto y se\u00f1alar\u00e1n que todo se trata de una \u201coscura conspiraci\u00f3n\u201d para implantar a los seres humanos con el \u201cmicrochip\u201d que es una representaci\u00f3n simb\u00f3lica del \u201cn\u00famero de la bestia\u201d, seg\u00fan la alocada y poco seria libre-interpretaci\u00f3n de las Escrituras. Desde luego, en esta l\u00ednea de pensamiento entrar\u00e1n a tallar los sectarios que consideran a la \u201cExcelsa Mujer del Magnificat\u201d como s\u00edmbolo de idolatr\u00eda y al Vaticano como la Sede del Anticristo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ninguna de las dos posiciones se\u00f1aladas tiene validez dada la situaci\u00f3n actual. Descartemos como rid\u00edculo y her\u00e9tico considerar como idolatr\u00eda a la sana veneraci\u00f3n hacia la Madre de Jesucristo, a la que \u201ctodas las naciones alabar\u00e1n como la bienaventurada\u201d. Pero analicemos brevemente la postura que nos habla de \u201cpreservar\u201d a los participantes, observ\u00e1ndolo desde el sentido com\u00fan y desde la fe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Personalmente, considero que las vacunas son una gran tecnolog\u00eda que ha tra\u00eddo innumerables beneficios a la humanidad entera. En conjunto con los avances de la ciencia y el arte m\u00e9dico, lograron reducir e incluso erradicar la mortandad y morbilidad de enfermedades que eran terribles. Respecto al Covid, he recibido dos dosis de la vacuna \u201cPfizer\u201d pero no he subido rid\u00edculas fotograf\u00edas en las redes sociales de mi tarjeta verde, absurdo ritual mundano posmoderno. Habiendo dicho eso, considero que todo tratamiento m\u00e9dico, por m\u00e1s bueno y beneficioso que sea, debe ser aceptado por las personas que desean recibirlo y jam\u00e1s se tiene que imponer o coaccionar a su utilizaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pongamos aqu\u00ed un ejemplo sencillo. En la enc\u00edclica del Papa P\u00edo XII \u201cMystici Corporis\u201d (1943, p\u00e1rrafo 104) se lee claramente (extraemos el fragmento principal):<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>\u201cSi alguna vez, pues, aconteciere que contra la constante doctrina de esta Sede Apost\u00f3lica, alguien es llevado contra su voluntad a abrazar la fe cat\u00f3lica, Nos, conscientes de nuestro oficio, no podemos menos de reprobarlo\u201d<\/em>.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Imagine Ud. de lo que est\u00e1 hablando el Sumo Pont\u00edfice. Est\u00e1 diciendo, nada m\u00e1s y nada menos, que no se puede, de ninguna manera, \u201cforzar a alguien\u201d a ser cat\u00f3lico. Es decir, no se puede imponer, por la fuerza ni por otra manera imaginable, el \u201cm\u00e1ximo bien\u201d que un ser humano puede recibir, o sea, los Divinos Sacramentos de la Iglesia Cat\u00f3lica. Las personas deben convertirse libre y voluntariamente, todo lo dem\u00e1s est\u00e1 condenado (aunque no han faltado tristes episodios de conversiones forzadas, pero esto se ha hecho en contra de lo que ense\u00f1a la Doctrina Verdadera).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entonces, por a\u00f1adidura, si el \u201cm\u00e1ximo bien\u201d imaginable jam\u00e1s puede imponerse a las personas (la Conversi\u00f3n y los Divinos Sacramentos de la Iglesia Cat\u00f3lica), \u00bfqu\u00e9 ser\u00eda algo \u201cmenor\u201d como un simple tratamiento m\u00e9dico, que ata\u00f1e solamente a lo temporal y mundano?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No me detendr\u00e9 a buscar documentos del Magisterio para sustentar los argumentos de la pregunta anterior, cuya respuesta es m\u00e1s que evidente. Simplemente apelar\u00e9 a la <em>\u201cNota sobre la Moralidad del Uso de Algunas Vacunas contra la Covid 19\u201d <\/em>(21 diciembre 2020), de la Congregaci\u00f3n de la Doctrina de la Fe, publicada con aprobaci\u00f3n del mismo Papa Francisco:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cAl mismo tiempo, <strong>es evidente para la raz\u00f3n pr\u00e1ctica que la vacunaci\u00f3n no es, por regla general, una obligaci\u00f3n moral y que, por lo tanto, la vacunaci\u00f3n debe ser voluntaria<\/strong>. En cualquier caso, desde un punto de vista \u00e9tico, la moralidad de la vacunaci\u00f3n depende no s\u00f3lo del deber de proteger la propia salud, sino tambi\u00e9n del deber de perseguir el bien com\u00fan. Bien que, a falta de otros medios para detener o incluso prevenir la epidemia, puede hacer recomendable la vacunaci\u00f3n, especialmente para proteger a los m\u00e1s d\u00e9biles y m\u00e1s expuestos. <strong>Sin embargo, quienes, por razones de conciencia, rechazan las vacunas producidas a partir de l\u00edneas celulares procedentes de fetos abortados, deben tomar las medidas, con otros medios profil\u00e1cticos y con un comportamiento adecuado, para evitar que se conviertan en veh\u00edculos de transmisi\u00f3n del agente infeccioso\u2026\u201d<\/strong><\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMadre de las Ciencias\u201d, la Iglesia reconoce la importancia de la vacunaci\u00f3n pero tambi\u00e9n, como \u201cPrimera y Principal Defensora de la Dignidad Humana\u201d, acepta que hay dos motivos suficientemente v\u00e1lidos para que los cat\u00f3licos o cualquier persona pueda rechazar ser vacunada: su propia voluntad y los impedimentos de su propia conciencia. Por ejemplo, un cat\u00f3lico escrupuloso que no quiere ser vacunado con inmunizadores hechos con c\u00e9lulas de fetos abortados\u2026 \u00bfAcaso no deber\u00eda estar suficientemente justificado para un Obispo de la Iglesia?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por esta raz\u00f3n, nos llama poderosamente la atenci\u00f3n que el Monse\u00f1or Ricardo Valenzuela R\u00edos busque imponer a la poblaci\u00f3n devota a la V\u00edrgen Mar\u00eda los \u201cpasaportes de vacunaci\u00f3n\u201d. \u00bfCu\u00e1l es la necesidad de dicha impostura? La feligres\u00eda cat\u00f3lica tiene derecho a saber en qu\u00e9 se sustenta el Ep\u00edscopo de la Di\u00f3cesis de Caacup\u00e9. Porque, por lo que tenemos en el Magisterio, no hay fundamentos espirituales (y solo citamos dos ejemplos que vienen a colaci\u00f3n; por cierto que he son documentos oficiales y no publicaciones de prensa que manipulan asquerosamente mucho de lo referente al Papa Francisco).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quiz\u00e1s tenga Su Excelencia el Obispo de Caacup\u00e9 otros motivos, del orden temporal. Pero \u00bfa qu\u00e9 o qui\u00e9nes orienta su obediencia al haber establecido dichas disposiciones? Queremos creer que Monse\u00f1or Ricardo Valenzuela est\u00e1 actuando de buena fe. Al fin y al cabo, todos queremos librarnos de una vez por todas de las restricciones totalitarias que nos han impuesto respecto a la llamada \u201cpandemia\u201d. Y esto solo se lograr\u00e1, contrariamente a lo que muchos creen, con una Iglesia que reverdezca su frondosa historia y levante, contra la poca fe de este mundo posmoderno, la luz de la esperanza y el valor contra las doctrinas del miedo y la cultura de la muerte, que encontr\u00f3 un nuevo \u00eddolo al que adorar en el Covid 19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Divino Maestro ha dejado a su Iglesia para que ella sea el pasaporte gratuito y sin restricciones a la Salvaci\u00f3n Eterna. \u00bfEs entonces v\u00e1lido que, por motivos meramente temporales, pongamos pasaportes sanitarios a la fe del pueblo en la Inmaculada Madre de Dios, la que nos acerca a su Hijo? \u00bfA qui\u00e9nes estamos complaciendo con estas medidas? \u00bfA los poderosos de este mundo, quiz\u00e1s? Yo por mi parte, celebrar\u00e9 a la Virgen de Caacup\u00e9 en la parroquia de mi barrio. No me gusta que la burocracia de los tecn\u00f3cratas globalistas ponga barrera alguna para mi contacto directo con Ella. Dejar\u00e9 la \u201cperegrinaci\u00f3n\u201d para el a\u00f1o que viene, total, que el Sant\u00edsimo Sacramento tambi\u00e9n est\u00e1 en las capillitas del vecindario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Iglesia Cat\u00f3lica, desde su origen, ha sido defensora de la dignidad humana. En el tercer milenio de su historia, se ha destacado por sacrificarse ella misma para preservar la Verdadera Doctrina al mismo tiempo que para llevar su mensaje de civilizaci\u00f3n, justicia social y aut\u00e9ntica libertad a todos los confines de la tierra. Su [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":7729,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[248],"tags":[1036,1368,1475],"ppma_author":[1467],"class_list":["post-7714","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis","tag-destacada","tag-pasaporte-sanitario","tag-religion"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El pasaporte de la fe - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2021\/10\/15\/el-pasaporte-de-la-fe\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El pasaporte de la fe - Informatepy\" \/>\n<meta property=\"og:description\" content=\"La Iglesia Cat\u00f3lica, desde su origen, ha sido defensora de la dignidad humana. En el tercer milenio de su historia, se ha destacado por sacrificarse ella misma para preservar la Verdadera Doctrina al mismo tiempo que para llevar su mensaje de civilizaci\u00f3n, justicia social y aut\u00e9ntica libertad a todos los confines de la tierra. Su [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2021\/10\/15\/el-pasaporte-de-la-fe\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-15T13:03:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-15T13:03:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/pasaporte-de-la-fe.jpg?fit=1280%2C722&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"722\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Emilio Urdapilleta\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/ProfMoriarty_Py\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emilio Urdapilleta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/10\\\/15\\\/el-pasaporte-de-la-fe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/10\\\/15\\\/el-pasaporte-de-la-fe\\\/\"},\"author\":{\"name\":\"Emilio Urdapilleta\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/267b31d70b533b1add84d218beff391f\"},\"headline\":\"El pasaporte de la fe\",\"datePublished\":\"2021-10-15T13:03:10+00:00\",\"dateModified\":\"2021-10-15T13:03:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/10\\\/15\\\/el-pasaporte-de-la-fe\\\/\"},\"wordCount\":2057,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/10\\\/15\\\/el-pasaporte-de-la-fe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/pasaporte-de-la-fe.jpg?fit=1280%2C722&ssl=1\",\"keywords\":[\"destacada\",\"pasaporte sanitario\",\"religion\"],\"articleSection\":[\"Analisis\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/10\\\/15\\\/el-pasaporte-de-la-fe\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/10\\\/15\\\/el-pasaporte-de-la-fe\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/10\\\/15\\\/el-pasaporte-de-la-fe\\\/\",\"name\":\"El pasaporte de la fe - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/10\\\/15\\\/el-pasaporte-de-la-fe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/10\\\/15\\\/el-pasaporte-de-la-fe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/pasaporte-de-la-fe.jpg?fit=1280%2C722&ssl=1\",\"datePublished\":\"2021-10-15T13:03:10+00:00\",\"dateModified\":\"2021-10-15T13:03:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/10\\\/15\\\/el-pasaporte-de-la-fe\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/10\\\/15\\\/el-pasaporte-de-la-fe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/10\\\/15\\\/el-pasaporte-de-la-fe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/pasaporte-de-la-fe.jpg?fit=1280%2C722&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/pasaporte-de-la-fe.jpg?fit=1280%2C722&ssl=1\",\"width\":1280,\"height\":722},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/10\\\/15\\\/el-pasaporte-de-la-fe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El pasaporte de la fe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/267b31d70b533b1add84d218beff391f\",\"name\":\"Emilio Urdapilleta\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/emilio-urdapilleta.jpg?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/emilio-urdapilleta.jpg?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/emilio-urdapilleta.jpg?fit=96%2C96&ssl=1\",\"caption\":\"Emilio Urdapilleta\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/ProfMoriarty_Py\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/eurdapilleta\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El pasaporte de la fe - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2021\/10\/15\/el-pasaporte-de-la-fe\/","og_locale":"es_ES","og_type":"article","og_title":"El pasaporte de la fe - Informatepy","og_description":"La Iglesia Cat\u00f3lica, desde su origen, ha sido defensora de la dignidad humana. En el tercer milenio de su historia, se ha destacado por sacrificarse ella misma para preservar la Verdadera Doctrina al mismo tiempo que para llevar su mensaje de civilizaci\u00f3n, justicia social y aut\u00e9ntica libertad a todos los confines de la tierra. Su [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2021\/10\/15\/el-pasaporte-de-la-fe\/","og_site_name":"Informatepy","article_published_time":"2021-10-15T13:03:10+00:00","article_modified_time":"2021-10-15T13:03:12+00:00","og_image":[{"width":1280,"height":722,"url":"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/pasaporte-de-la-fe.jpg?fit=1280%2C722&ssl=1","type":"image\/jpeg"}],"author":"Emilio Urdapilleta","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/ProfMoriarty_Py","twitter_misc":{"Escrito por":"Emilio Urdapilleta","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2021\/10\/15\/el-pasaporte-de-la-fe\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2021\/10\/15\/el-pasaporte-de-la-fe\/"},"author":{"name":"Emilio Urdapilleta","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/267b31d70b533b1add84d218beff391f"},"headline":"El pasaporte de la fe","datePublished":"2021-10-15T13:03:10+00:00","dateModified":"2021-10-15T13:03:12+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2021\/10\/15\/el-pasaporte-de-la-fe\/"},"wordCount":2057,"commentCount":1,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2021\/10\/15\/el-pasaporte-de-la-fe\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/pasaporte-de-la-fe.jpg?fit=1280%2C722&ssl=1","keywords":["destacada","pasaporte sanitario","religion"],"articleSection":["Analisis"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2021\/10\/15\/el-pasaporte-de-la-fe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2021\/10\/15\/el-pasaporte-de-la-fe\/","url":"https:\/\/informatepy.com\/2021\/2021\/10\/15\/el-pasaporte-de-la-fe\/","name":"El pasaporte de la fe - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2021\/10\/15\/el-pasaporte-de-la-fe\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2021\/10\/15\/el-pasaporte-de-la-fe\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/pasaporte-de-la-fe.jpg?fit=1280%2C722&ssl=1","datePublished":"2021-10-15T13:03:10+00:00","dateModified":"2021-10-15T13:03:12+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2021\/10\/15\/el-pasaporte-de-la-fe\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2021\/10\/15\/el-pasaporte-de-la-fe\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2021\/10\/15\/el-pasaporte-de-la-fe\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/pasaporte-de-la-fe.jpg?fit=1280%2C722&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/pasaporte-de-la-fe.jpg?fit=1280%2C722&ssl=1","width":1280,"height":722},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2021\/10\/15\/el-pasaporte-de-la-fe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"El pasaporte de la fe"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/267b31d70b533b1add84d218beff391f","name":"Emilio Urdapilleta","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/emilio-urdapilleta.jpg?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/emilio-urdapilleta.jpg?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/emilio-urdapilleta.jpg?fit=96%2C96&ssl=1","caption":"Emilio Urdapilleta"},"sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/ProfMoriarty_Py"],"url":"https:\/\/informatepy.com\/2021\/author\/eurdapilleta\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/pasaporte-de-la-fe.jpg?fit=1280%2C722&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":8731,"url":"https:\/\/informatepy.com\/2021\/2021\/12\/08\/pasaporte-sanitario-el-cliente-nunca-pierde\/","url_meta":{"origin":7714,"position":0},"title":"Pasaporte sanitario: El cliente nunca pierde","date":"8 de diciembre de 2021","format":false,"excerpt":"Los comerciantes en todos aquellos pa\u00edses donde se ha instalado el tristemente c\u00e9lebre \u201cPasaporte Covid\u201d se van manifestando y denunciando la p\u00e9rdida de clientes a partir de la instauraci\u00f3n del mismo. Por ejemplo, el presidente de la agrupaci\u00f3n de restaurantes\u00a0COBRECA, Pablo Gonz\u00e1lez (Espa\u00f1a), ha lamentado que \u00abla hosteler\u00eda es manipulada\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/restaurantes-vacios.jpg?fit=980%2C681&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6752,"url":"https:\/\/informatepy.com\/2021\/2021\/08\/26\/original-protesta-en-francia-contra-el-pasaporte-sanitario\/","url_meta":{"origin":7714,"position":1},"title":"Original protesta en Francia contra el pasaporte sanitario","date":"26 de agosto de 2021","format":false,"excerpt":"Los ciudadanos franceses que se oponen a la exigencia de un pasaporte sanitario (de vacunaci\u00f3n) para el ingreso a los espacios p\u00fablicos, han inaugurado una nueva modalidad de protesta contra el gobierno. Con la intenci\u00f3n de \"obligar\" a los propietarios de los comercios a presionar al gobierno junto con ellos\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/restauramtes-vacios-paris.jpg?fit=720%2C471&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9445,"url":"https:\/\/informatepy.com\/2021\/2022\/01\/14\/el-reino-unido-eliminaria-el-pasaporte-covid-este-mes\/","url_meta":{"origin":7714,"position":2},"title":"El Reino Unido eliminar\u00eda el pasaporte Covid este mes","date":"14 de enero de 2022","format":false,"excerpt":"El secretario de salud del Reino Unido, Sajid Javid, concluy\u00f3 que los pasaportes Covid ya no ser\u00e1n necesarios a medida que la ola por \u00d3micron vaya cediendo. Agreg\u00f3 frente a los parlamentarios que compart\u00eda su \u201cincomodidad instintiva\u201d por esta pol\u00edtica. Al parecer, la \u00fanica medida contra el Covid que permanezca\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/covid-marshal.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12156,"url":"https:\/\/informatepy.com\/2021\/2022\/06\/15\/te-mostramos-porque-los-gobiernos-quieren-desesperadamente-pasaportes-de-salud-digitales\/","url_meta":{"origin":7714,"position":3},"title":"Te mostramos porque los gobiernos quieren \u00abdesesperadamente\u00bb pasaportes de salud digitales","date":"15 de junio de 2022","format":false,"excerpt":"Muchos a\u00fan no creen y consideran te\u00f3ricos de la conspiraci\u00f3n a aquellos que se niegan a someterse a los pasaportes digitales de salud por considerar que los mismos ser\u00e1n usados para coartar la libertades civiles de los ciudadanos. Seg\u00fan inform\u00f3 la agencia Reuters, una protesta planeada por cientos de depositantes\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/pasaporte-covid.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8001,"url":"https:\/\/informatepy.com\/2021\/2021\/10\/29\/el-apartheid-sanitario\/","url_meta":{"origin":7714,"position":4},"title":"El apartheid sanitario","date":"29 de octubre de 2021","format":false,"excerpt":"Como \u201canimales con capacidad de razonar\u201d que creemos ser (yo suelo poner ese aforismo en much\u00edsima duda), los humanos tomamos decisiones respecto a los diferentes \u00e1mbitos de nuestras existencias, muchas de ellas te\u00f3ricamente sustentadas por la l\u00f3gica y el conocimiento debidamente demostrado de las posibles consecuencias de cada acto. El\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/judios-alemania-nazi.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11100,"url":"https:\/\/informatepy.com\/2021\/2022\/04\/09\/llevando-la-estupidez-a-un-nuevo-nivel-piden-pasaporte-de-apoyo-a-ucrania-para-ingresar-a-un-restaurant\/","url_meta":{"origin":7714,"position":5},"title":"Llevando la estupidez a un nuevo nivel: Piden \u00abpasaporte de apoyo a Ucrania\u00bb para ingresar a un restaurant","date":"9 de abril de 2022","format":false,"excerpt":"El pasaporte Covid ya fue, est\u00e1 demod\u00e9 y por eso, para ingresar a algunos restaurantes de la Columbia Brit\u00e1nica en Canad\u00e1, se pide a los clientes que exhiban el \"pasaporte de apoyo a Ucrania\". En el cartel exhibido en la puerta de un restaurant se indicaba a los potenciales clientes\u2026","rel":"","context":"En \u00abCultura\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/pasaporte-apoyo-ucrania.jpg?fit=1200%2C897&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1467,"user_id":33,"is_guest":0,"slug":"eurdapilleta","display_name":"Emilio Urdapilleta","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/emilio-urdapilleta.jpg?fit=96%2C96&ssl=1","first_name":"Emilio","last_name":"Urdapilleta","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/7714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=7714"}],"version-history":[{"count":2,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/7714\/revisions"}],"predecessor-version":[{"id":7730,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/7714\/revisions\/7730"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/7729"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=7714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=7714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=7714"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=7714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}