{"id":686,"date":"2019-02-23T20:19:00","date_gmt":"2019-02-24T00:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=686"},"modified":"2021-02-22T14:26:41","modified_gmt":"2021-02-22T18:26:41","slug":"702","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/02\/23\/702\/","title":{"rendered":"Avanza el plan de becas 2019 de la Gobernaci\u00f3n de Central"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Esta ma\u00f1ana, la Gobernaci\u00f3n del Departamento Central convoc\u00f3 a los j\u00f3venes que aprobaron la primera etapa de evaluaci\u00f3n curricular y documental para el programa de Becas de Juventud GDC 2019. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La cita fue en la Facultad de Ciencias Econ\u00f3micas de la UNA, donde concurrieron 538 postulantes que buscan obtener una beca de estudios universitarios. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta ma\u00f1ana, la Gobernaci\u00f3n del Departamento Central convoc\u00f3 a los j\u00f3venes que aprobaron la primera etapa de evaluaci\u00f3n curricular y documental para el programa de Becas de Juventud GDC 2019. La cita fue en la Facultad de Ciencias Econ\u00f3micas de la UNA, donde concurrieron 538 postulantes que buscan obtener una beca de estudios universitarios.<\/p>\n","protected":false},"author":1,"featured_media":687,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[177],"tags":[397,333],"ppma_author":[1039],"class_list":["post-686","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-becas-2019","tag-gobernacion-central"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avanza el plan de becas 2019 de la Gobernaci\u00f3n de Central - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/02\/23\/702\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avanza el plan de becas 2019 de la Gobernaci\u00f3n de Central - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Esta ma\u00f1ana, la Gobernaci\u00f3n del Departamento Central convoc\u00f3 a los j\u00f3venes que aprobaron la primera etapa de evaluaci\u00f3n curricular y documental para el programa de Becas de Juventud GDC 2019. La cita fue en la Facultad de Ciencias Econ\u00f3micas de la UNA, donde concurrieron 538 postulantes que buscan obtener una beca de estudios universitarios.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/02\/23\/702\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-24T00:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-22T18:26:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/becas-central-2019-1.jpg?fit=960%2C585&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"585\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/23\\\/702\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/23\\\/702\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"Avanza el plan de becas 2019 de la Gobernaci\u00f3n de Central\",\"datePublished\":\"2019-02-24T00:19:00+00:00\",\"dateModified\":\"2021-02-22T18:26:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/23\\\/702\\\/\"},\"wordCount\":68,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/23\\\/702\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/becas-central-2019-1.jpg?fit=960%2C585&ssl=1\",\"keywords\":[\"becas 2019\",\"gobernacion central\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/23\\\/702\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/23\\\/702\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/23\\\/702\\\/\",\"name\":\"Avanza el plan de becas 2019 de la Gobernaci\u00f3n de Central - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/23\\\/702\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/23\\\/702\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/becas-central-2019-1.jpg?fit=960%2C585&ssl=1\",\"datePublished\":\"2019-02-24T00:19:00+00:00\",\"dateModified\":\"2021-02-22T18:26:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/23\\\/702\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/23\\\/702\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/23\\\/702\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/becas-central-2019-1.jpg?fit=960%2C585&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/becas-central-2019-1.jpg?fit=960%2C585&ssl=1\",\"width\":960,\"height\":585},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/23\\\/702\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avanza el plan de becas 2019 de la Gobernaci\u00f3n de Central\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avanza el plan de becas 2019 de la Gobernaci\u00f3n de Central - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/02\/23\/702\/","og_locale":"es_ES","og_type":"article","og_title":"Avanza el plan de becas 2019 de la Gobernaci\u00f3n de Central - Informatepy","og_description":"Esta ma\u00f1ana, la Gobernaci\u00f3n del Departamento Central convoc\u00f3 a los j\u00f3venes que aprobaron la primera etapa de evaluaci\u00f3n curricular y documental para el programa de Becas de Juventud GDC 2019. La cita fue en la Facultad de Ciencias Econ\u00f3micas de la UNA, donde concurrieron 538 postulantes que buscan obtener una beca de estudios universitarios.","og_url":"https:\/\/informatepy.com\/2021\/2019\/02\/23\/702\/","og_site_name":"Informatepy","article_published_time":"2019-02-24T00:19:00+00:00","article_modified_time":"2021-02-22T18:26:41+00:00","og_image":[{"width":960,"height":585,"url":"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/becas-central-2019-1.jpg?fit=960%2C585&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/02\/23\/702\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/23\/702\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"Avanza el plan de becas 2019 de la Gobernaci\u00f3n de Central","datePublished":"2019-02-24T00:19:00+00:00","dateModified":"2021-02-22T18:26:41+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/23\/702\/"},"wordCount":68,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/23\/702\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/becas-central-2019-1.jpg?fit=960%2C585&ssl=1","keywords":["becas 2019","gobernacion central"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/02\/23\/702\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/02\/23\/702\/","url":"https:\/\/informatepy.com\/2021\/2019\/02\/23\/702\/","name":"Avanza el plan de becas 2019 de la Gobernaci\u00f3n de Central - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/23\/702\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/23\/702\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/becas-central-2019-1.jpg?fit=960%2C585&ssl=1","datePublished":"2019-02-24T00:19:00+00:00","dateModified":"2021-02-22T18:26:41+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/23\/702\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/02\/23\/702\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/02\/23\/702\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/becas-central-2019-1.jpg?fit=960%2C585&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/becas-central-2019-1.jpg?fit=960%2C585&ssl=1","width":960,"height":585},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/02\/23\/702\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Avanza el plan de becas 2019 de la Gobernaci\u00f3n de Central"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/becas-central-2019-1.jpg?fit=960%2C585&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":674,"url":"https:\/\/informatepy.com\/2021\/2019\/02\/22\/la-gobernacion-del-departamento-central-convoca-a-los-jovenes-que-aprobaron-la-primera-etapa-de-evaluacion-para-becas-2019\/","url_meta":{"origin":686,"position":0},"title":"La Gobernaci\u00f3n del Departamento Central convoca a los j\u00f3venes que aprobaron la primera etapa de evaluaci\u00f3n para Becas 2019","date":"22 de febrero de 2019","format":false,"excerpt":"La Gobernaci\u00f3n del Departamento Central convoca, para ma\u00f1ana a las 8 Hs, a los j\u00f3venes que aprobaron la primera etapa de evaluaci\u00f3n curricular y documental para el programa de Becas de Juventud GDC 2019. La convocatoria se llevar\u00e1 adelante en las instalaciones de la Facultad de Ciencias Econ\u00f3micas de la\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/becas-central-2019.jpg?fit=1000%2C800&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":748,"url":"https:\/\/informatepy.com\/2021\/2019\/02\/27\/la-gobernacion-de-central-culmino-la-correccion-de-examenes-para-acceder-a-las-becas-2019\/","url_meta":{"origin":686,"position":1},"title":"La Gobernaci\u00f3n de Central culmin\u00f3 la correcci\u00f3n de ex\u00e1menes para acceder a las Becas 2019","date":"27 de febrero de 2019","format":false,"excerpt":"La Gobernaci\u00f3n del Departamento Central, inform\u00f3 que se culmin\u00f3 con la correcci\u00f3n de los ex\u00e1menes de aquellos estudiantes que se encontraban habilitados para el examen de conocimientos b\u00e1sicos para acceder al Programa de Becas de Juventud GDC 2019, y ya se encuentra la informaci\u00f3n disponible en la p\u00e1gina web de\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/becas-2019.jpg?fit=800%2C445&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":728,"url":"https:\/\/informatepy.com\/2021\/2019\/02\/25\/gobernacion-de-central-impulsa-taller-de-lectura-para-docentes-del-nivel-inicial\/","url_meta":{"origin":686,"position":2},"title":"Gobernaci\u00f3n de Central impulsa taller de lectura para docentes del nivel inicial","date":"25 de febrero de 2019","format":false,"excerpt":"Con la consigna de que la educaci\u00f3n se se debe cimentar en la constante capacitaci\u00f3n de los docentes, la Gobernaci\u00f3n del Departamento Central impulsa el taller de lectura para docentes del nivel inicial. Este taller, \"Del Dicho al Hecho\u201d, buscan brindarle a los docentes del nivel inicial m\u00e1s y mejores\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/lectura-1.jpg?fit=1194%2C780&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":886,"url":"https:\/\/informatepy.com\/2021\/2019\/03\/17\/gobernacion-de-central-asiste-a-los-damnificados-por-las-intensas-lluvias\/","url_meta":{"origin":686,"position":3},"title":"Gobernaci\u00f3n de Central asiste a los damnificados por las intensas lluvias","date":"17 de marzo de 2019","format":false,"excerpt":"La gobernaci\u00f3n del departamento central se encuentra brindando asistencia los damnificados por las intensas lluvias en la ciudad de Limpio, donde se registraron las consecuencias m\u00e1s graves de la lluvia, donde el agua invadi\u00f3 m\u00e1s de 100 hogares. Adem\u00e1s de las tareas de asistencia, la gobernaci\u00f3n realiza un relevamiento para\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/IMG-20190317-WA00569563.jpg?fit=1040%2C780&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":642,"url":"https:\/\/informatepy.com\/2021\/2019\/02\/21\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\/","url_meta":{"origin":686,"position":4},"title":"La gobernaci\u00f3n de Central inicia campa\u00f1a de concientizaci\u00f3n contra el dengue","date":"21 de febrero de 2019","format":false,"excerpt":"En el marco de una campa\u00f1a de concientizaci\u00f3n de lucha contra el dengue, la Gobernaci\u00f3n del Departamento Central lleg\u00f3 a la Esc. B\u00e1s. N\u00b0 6433 \"J\u00f3venes Unidos\" de la ciudad de Luque, en forma de arte y conciencia. La obra, \"\u00d1ati'\u00fb \u00d1emos\u00ea\", llev\u00f3 un mensaje de prevenci\u00f3n para los m\u00e1s\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/IMG-20190221-WA0047.jpg?fit=1200%2C674&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":833,"url":"https:\/\/informatepy.com\/2021\/2019\/03\/12\/la-gobernacion-de-central-y-el-mag-avanzan-con-un-convenio-con-productores-agricolas\/","url_meta":{"origin":686,"position":5},"title":"La Gobernaci\u00f3n de Central y el MAG avanzan con un convenio con productores agr\u00edcolas","date":"12 de marzo de 2019","format":false,"excerpt":"En el marco del convenio firmado por la Gobernaci\u00f3n del Departamento Central y el Ministerio de Agricultura y Ganader\u00eda, se est\u00e1n llevando adelante reuniones de coordinaci\u00f3n con los productores. El convenio incluye, adem\u00e1s de la coordinaci\u00f3n de acciones conjuntas entre los productores y los organismos, la asistencia t\u00e9cnica a los\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/convenio-central-y-mag.jpg?fit=1200%2C921&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=686"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/686\/revisions"}],"predecessor-version":[{"id":3548,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/686\/revisions\/3548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/687"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=686"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}