{"id":642,"date":"2019-02-21T20:19:00","date_gmt":"2019-02-22T00:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=642"},"modified":"2021-02-20T16:03:08","modified_gmt":"2021-02-20T20:03:08","slug":"la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/02\/21\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\/","title":{"rendered":"La gobernaci\u00f3n de Central inicia campa\u00f1a de concientizaci\u00f3n contra el dengue"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En el marco de una campa\u00f1a de concientizaci\u00f3n de lucha contra el dengue, la Gobernaci\u00f3n del Departamento Central lleg\u00f3 a la Esc. B\u00e1s. N\u00b0 6433 \u00abJ\u00f3venes Unidos\u00bb de la ciudad de Luque, en forma de arte y conciencia.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/IMG-20190221-WA0046.jpg?w=740&#038;ssl=1\" alt=\"\" class=\"wp-image-652\" data-recalc-dims=\"1\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La obra, \u00ab\u00d1ati&#8217;\u00fb \u00d1emos\u00ea\u00bb, llev\u00f3 un mensaje de prevenci\u00f3n para los m\u00e1s peque\u00f1os, buscando as\u00ed, que los ni\u00f1os se conviertan en factores multiplicadores en sus casas y comunidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n, los alumnos de la Escuela B\u00e1sica N\u00b0 861 Perpetuo Socorro, de Luque, pudieron disfrutar de la puesta en escena de esta campa\u00f1a.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco de una campa\u00f1a de concientizaci\u00f3n de lucha contra el dengue, la Gobernaci\u00f3n del Departamento Central lleg\u00f3 a la Esc. B\u00e1s. N\u00b0 6433 \u00abJ\u00f3venes Unidos\u00bb de la ciudad de Luque, en forma de arte y conciencia. La obra, \u00ab\u00d1ati&#8217;\u00fb \u00d1emos\u00ea\u00bb, llev\u00f3 un mensaje de prevenci\u00f3n para los m\u00e1s peque\u00f1os, buscando as\u00ed, que los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":643,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[177],"tags":[381,333,374],"ppma_author":[1039],"class_list":["post-642","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-dengue","tag-gobernacion-central","tag-hugo-javier-gonzalez"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La gobernaci\u00f3n de Central inicia campa\u00f1a de concientizaci\u00f3n contra el dengue - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/02\/21\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La gobernaci\u00f3n de Central inicia campa\u00f1a de concientizaci\u00f3n contra el dengue - Informatepy\" \/>\n<meta property=\"og:description\" content=\"En el marco de una campa\u00f1a de concientizaci\u00f3n de lucha contra el dengue, la Gobernaci\u00f3n del Departamento Central lleg\u00f3 a la Esc. B\u00e1s. N\u00b0 6433 \u00abJ\u00f3venes Unidos\u00bb de la ciudad de Luque, en forma de arte y conciencia. La obra, \u00ab\u00d1ati&#8217;\u00fb \u00d1emos\u00ea\u00bb, llev\u00f3 un mensaje de prevenci\u00f3n para los m\u00e1s peque\u00f1os, buscando as\u00ed, que los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/02\/21\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-22T00:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-20T20:03:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/IMG-20190221-WA0047.jpg?fit=1267%2C712&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1267\" \/>\n\t<meta property=\"og:image:height\" content=\"712\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/21\\\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/21\\\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"La gobernaci\u00f3n de Central inicia campa\u00f1a de concientizaci\u00f3n contra el dengue\",\"datePublished\":\"2019-02-22T00:19:00+00:00\",\"dateModified\":\"2021-02-20T20:03:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/21\\\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\\\/\"},\"wordCount\":113,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/21\\\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/IMG-20190221-WA0047.jpg?fit=1267%2C712&ssl=1\",\"keywords\":[\"dengue\",\"gobernacion central\",\"hugo javier gonzalez\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/21\\\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/21\\\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/21\\\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\\\/\",\"name\":\"La gobernaci\u00f3n de Central inicia campa\u00f1a de concientizaci\u00f3n contra el dengue - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/21\\\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/21\\\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/IMG-20190221-WA0047.jpg?fit=1267%2C712&ssl=1\",\"datePublished\":\"2019-02-22T00:19:00+00:00\",\"dateModified\":\"2021-02-20T20:03:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/21\\\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/21\\\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/21\\\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/IMG-20190221-WA0047.jpg?fit=1267%2C712&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/IMG-20190221-WA0047.jpg?fit=1267%2C712&ssl=1\",\"width\":1267,\"height\":712},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/21\\\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La gobernaci\u00f3n de Central inicia campa\u00f1a de concientizaci\u00f3n contra el dengue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La gobernaci\u00f3n de Central inicia campa\u00f1a de concientizaci\u00f3n contra el dengue - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/02\/21\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\/","og_locale":"es_ES","og_type":"article","og_title":"La gobernaci\u00f3n de Central inicia campa\u00f1a de concientizaci\u00f3n contra el dengue - Informatepy","og_description":"En el marco de una campa\u00f1a de concientizaci\u00f3n de lucha contra el dengue, la Gobernaci\u00f3n del Departamento Central lleg\u00f3 a la Esc. B\u00e1s. N\u00b0 6433 \u00abJ\u00f3venes Unidos\u00bb de la ciudad de Luque, en forma de arte y conciencia. La obra, \u00ab\u00d1ati&#8217;\u00fb \u00d1emos\u00ea\u00bb, llev\u00f3 un mensaje de prevenci\u00f3n para los m\u00e1s peque\u00f1os, buscando as\u00ed, que los [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2019\/02\/21\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\/","og_site_name":"Informatepy","article_published_time":"2019-02-22T00:19:00+00:00","article_modified_time":"2021-02-20T20:03:08+00:00","og_image":[{"width":1267,"height":712,"url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/IMG-20190221-WA0047.jpg?fit=1267%2C712&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/02\/21\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/21\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"La gobernaci\u00f3n de Central inicia campa\u00f1a de concientizaci\u00f3n contra el dengue","datePublished":"2019-02-22T00:19:00+00:00","dateModified":"2021-02-20T20:03:08+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/21\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\/"},"wordCount":113,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/21\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/IMG-20190221-WA0047.jpg?fit=1267%2C712&ssl=1","keywords":["dengue","gobernacion central","hugo javier gonzalez"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/02\/21\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/02\/21\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\/","url":"https:\/\/informatepy.com\/2021\/2019\/02\/21\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\/","name":"La gobernaci\u00f3n de Central inicia campa\u00f1a de concientizaci\u00f3n contra el dengue - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/21\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/21\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/IMG-20190221-WA0047.jpg?fit=1267%2C712&ssl=1","datePublished":"2019-02-22T00:19:00+00:00","dateModified":"2021-02-20T20:03:08+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/21\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/02\/21\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/02\/21\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/IMG-20190221-WA0047.jpg?fit=1267%2C712&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/IMG-20190221-WA0047.jpg?fit=1267%2C712&ssl=1","width":1267,"height":712},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/02\/21\/la-gobernacion-de-central-inicia-campana-de-concientizacion-contra-el-dengue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"La gobernaci\u00f3n de Central inicia campa\u00f1a de concientizaci\u00f3n contra el dengue"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/IMG-20190221-WA0047.jpg?fit=1267%2C712&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1470,"url":"https:\/\/informatepy.com\/2021\/2019\/09\/03\/aumentan-los-casos-de-dengue-en-central\/","url_meta":{"origin":642,"position":0},"title":"Aumentan los casos de Dengue en Central","date":"3 de septiembre de 2019","format":false,"excerpt":"La Direcci\u00f3n General de Vigilancia del\u00a0Ministerio de Salud P\u00fablica\u00a0y Bienestar Social (MSPyBS) emiti\u00f3 un informe donde se informa que aumentaron los n\u00fameros de casos confirmados de dengue en el pa\u00eds. De acuerdo al reporte, se registraron siete casos en la \u00faltima semana del mes de agosto, de los cuales seis\u2026","rel":"","context":"En \u00abSalud\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/09\/dengue.jpg?fit=840%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11791,"url":"https:\/\/informatepy.com\/2021\/2022\/05\/26\/edgar-acosta-arranca-su-campana-por-la-gobernacion-de-central-atacando-a-su-correligionario-estigarribia\/","url_meta":{"origin":642,"position":1},"title":"Edgar Acosta arranca su campa\u00f1a por la gobernaci\u00f3n de Central atacando a su correligionario Estigarribia","date":"26 de mayo de 2022","format":false,"excerpt":"Edgar Acosta, diputado por el Partido Liberal confirm\u00f3 que es precandidato a la Gobernaci\u00f3n de Central y arranc\u00f3 su campa\u00f1a haciendo la \"gran Efra\u00edn\" y acus\u00f3 a su rival en el PLRA, Ricardo Estigarribia, de cartista. Seg\u00fan el diputado, el intendente de Villa Elisa cuenta con el respaldo del sector\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/05\/edgar-acosta.jpg?fit=900%2C602&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1693,"url":"https:\/\/informatepy.com\/2021\/2019\/12\/14\/aumentan-los-casos-de-dengue-en-capital-y-central\/","url_meta":{"origin":642,"position":2},"title":"Aumentan los casos de dengue en Capital y Central","date":"14 de diciembre de 2019","format":false,"excerpt":"La Direcci\u00f3n General de Vigilancia de la Salud advirti\u00f3 que los casos de dengue aumentar\u00e1n, incluso, respecto de las estimaciones realizadas a inicios del corriente a\u00f1o. El doctor Guillermo Sequera, titular de Vigilancia de la Salud, inform\u00f3 que: \u201cEstamos igual que al inicio de las dos grandes epidemias (2013 y\u2026","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/09\/dengue.jpg?fit=840%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4722,"url":"https:\/\/informatepy.com\/2021\/2021\/05\/01\/mayo-y-la-gobernacion-de-central-aun-no-entrega-las-meriendas-escolares\/","url_meta":{"origin":642,"position":3},"title":"Mayo y la Gobernaci\u00f3n de Central aun no entrega las meriendas escolares","date":"1 de mayo de 2021","format":false,"excerpt":"Del mismo modo en que sucediera hace un a\u00f1o, desde la Escuela Rep\u00fablica de Ecuador, de la ciudad de Lambar\u00e9, no cuentan que hasta el d\u00eda de la fecha 01 de mayo, no han recibido ni una merienda escolar a pesar de varios reclamos realizados. Cuando Etel Fern\u00e1ndez, nos hiciera\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/hugo-javier-gonzalez.jpg?fit=550%2C413&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":748,"url":"https:\/\/informatepy.com\/2021\/2019\/02\/27\/la-gobernacion-de-central-culmino-la-correccion-de-examenes-para-acceder-a-las-becas-2019\/","url_meta":{"origin":642,"position":4},"title":"La Gobernaci\u00f3n de Central culmin\u00f3 la correcci\u00f3n de ex\u00e1menes para acceder a las Becas 2019","date":"27 de febrero de 2019","format":false,"excerpt":"La Gobernaci\u00f3n del Departamento Central, inform\u00f3 que se culmin\u00f3 con la correcci\u00f3n de los ex\u00e1menes de aquellos estudiantes que se encontraban habilitados para el examen de conocimientos b\u00e1sicos para acceder al Programa de Becas de Juventud GDC 2019, y ya se encuentra la informaci\u00f3n disponible en la p\u00e1gina web de\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/becas-2019.jpg?fit=800%2C445&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":886,"url":"https:\/\/informatepy.com\/2021\/2019\/03\/17\/gobernacion-de-central-asiste-a-los-damnificados-por-las-intensas-lluvias\/","url_meta":{"origin":642,"position":5},"title":"Gobernaci\u00f3n de Central asiste a los damnificados por las intensas lluvias","date":"17 de marzo de 2019","format":false,"excerpt":"La gobernaci\u00f3n del departamento central se encuentra brindando asistencia los damnificados por las intensas lluvias en la ciudad de Limpio, donde se registraron las consecuencias m\u00e1s graves de la lluvia, donde el agua invadi\u00f3 m\u00e1s de 100 hogares. Adem\u00e1s de las tareas de asistencia, la gobernaci\u00f3n realiza un relevamiento para\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/IMG-20190317-WA00569563.jpg?fit=1040%2C780&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=642"}],"version-history":[{"count":2,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/642\/revisions"}],"predecessor-version":[{"id":3506,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/642\/revisions\/3506"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/643"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=642"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}