{"id":590,"date":"2019-02-18T20:19:00","date_gmt":"2019-02-18T20:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=590"},"modified":"2021-02-14T22:42:44","modified_gmt":"2021-02-14T22:42:44","slug":"minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/02\/18\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\/","title":{"rendered":"Minga ambiental en arroyo Mburica\u00f3 deja al descubierto la inacci\u00f3n del estado"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Ministerio del Ambiente y Desarrollo Sostenible y la Municipalidad de Asunci\u00f3n organizaron el d\u00eda s\u00e1bado una minga ambiental en el arroyo Mburica\u00f3, donde dijeron presente m\u00e1s de 1.000 ciudadanos de la zona y, como resultado, los voluntarios recogieron m\u00e1s de 43 toneladas de residuos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/basura-1.jpg?w=740&#038;ssl=1\" alt=\"\" class=\"wp-image-584\" data-recalc-dims=\"1\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de su buena voluntad para colaborar, la mayor parte\nde los ciudadanos que se presentaron a colaborar, manifestaron que: \u201cSi las\nautoridades no toman medidas dr\u00e1sticas y concretas contra los infractores\nseguiremos as\u00ed\u201d. \u201cAparte de la ignorancia e inconciencia de la gente que arroja\nsus desechos al arroyo, deja mucho que desear la recolecci\u00f3n de basuras de la\nMunicipalidad de Asunci\u00f3n, as\u00ed como la falta de control y sanciones a las\nempresas contaminantes de parte del Ministerio del Ambiente y Desarrollo\nSostenible (a cargo del Ariel Oviedo)\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si bien la iniciativa es plausible, este trabajo no sirve si las autoridades (Municipalidad y Ministerio de Desarrollo Sostenible) no imponen reglas claras y sanciones contundentes a quienes infrinjan las normas. Es necesario sancionar a las empresas y f\u00e1bricas que incumplan, pero es a\u00fan m\u00e1s importante concientizar al ciudadano de no arrojar basura en la calle. Esto es parche; sirve, pero no soluciona nada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio del Ambiente y Desarrollo Sostenible y la Municipalidad de Asunci\u00f3n organizaron el d\u00eda s\u00e1bado una minga ambiental en el arroyo Mburica\u00f3, donde dijeron presente m\u00e1s de 1.000 ciudadanos de la zona y, como resultado, los voluntarios recogieron m\u00e1s de 43 toneladas de residuos. A pesar de su buena voluntad para colaborar, la mayor [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":591,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[483],"tags":[348,349,350,351],"ppma_author":[1039],"class_list":["post-590","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipales","tag-ariel-oviedo","tag-arroyo-mburicao","tag-mario-ferreiro","tag-minga-de-limpieza"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Minga ambiental en arroyo Mburica\u00f3 deja al descubierto la inacci\u00f3n del estado - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/02\/18\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Minga ambiental en arroyo Mburica\u00f3 deja al descubierto la inacci\u00f3n del estado - Informatepy\" \/>\n<meta property=\"og:description\" content=\"El Ministerio del Ambiente y Desarrollo Sostenible y la Municipalidad de Asunci\u00f3n organizaron el d\u00eda s\u00e1bado una minga ambiental en el arroyo Mburica\u00f3, donde dijeron presente m\u00e1s de 1.000 ciudadanos de la zona y, como resultado, los voluntarios recogieron m\u00e1s de 43 toneladas de residuos. A pesar de su buena voluntad para colaborar, la mayor [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/02\/18\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-18T20:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-14T22:42:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/basura.jpg?fit=960%2C718&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"718\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/18\\\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/18\\\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"Minga ambiental en arroyo Mburica\u00f3 deja al descubierto la inacci\u00f3n del estado\",\"datePublished\":\"2019-02-18T20:19:00+00:00\",\"dateModified\":\"2021-02-14T22:42:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/18\\\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\\\/\"},\"wordCount\":220,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/18\\\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/basura.jpg?fit=960%2C718&ssl=1\",\"keywords\":[\"ariel oviedo\",\"arroyo mburicao\",\"mario ferreiro\",\"minga de limpieza\"],\"articleSection\":[\"Municipales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/18\\\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/18\\\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/18\\\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\\\/\",\"name\":\"Minga ambiental en arroyo Mburica\u00f3 deja al descubierto la inacci\u00f3n del estado - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/18\\\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/18\\\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/basura.jpg?fit=960%2C718&ssl=1\",\"datePublished\":\"2019-02-18T20:19:00+00:00\",\"dateModified\":\"2021-02-14T22:42:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/18\\\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/18\\\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/18\\\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/basura.jpg?fit=960%2C718&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/basura.jpg?fit=960%2C718&ssl=1\",\"width\":960,\"height\":718,\"caption\":\"Se recolectaron 43 toneladas de basura del arroyo Mburica\u00f3\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/18\\\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Minga ambiental en arroyo Mburica\u00f3 deja al descubierto la inacci\u00f3n del estado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Minga ambiental en arroyo Mburica\u00f3 deja al descubierto la inacci\u00f3n del estado - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/02\/18\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\/","og_locale":"es_ES","og_type":"article","og_title":"Minga ambiental en arroyo Mburica\u00f3 deja al descubierto la inacci\u00f3n del estado - Informatepy","og_description":"El Ministerio del Ambiente y Desarrollo Sostenible y la Municipalidad de Asunci\u00f3n organizaron el d\u00eda s\u00e1bado una minga ambiental en el arroyo Mburica\u00f3, donde dijeron presente m\u00e1s de 1.000 ciudadanos de la zona y, como resultado, los voluntarios recogieron m\u00e1s de 43 toneladas de residuos. A pesar de su buena voluntad para colaborar, la mayor [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2019\/02\/18\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\/","og_site_name":"Informatepy","article_published_time":"2019-02-18T20:19:00+00:00","article_modified_time":"2021-02-14T22:42:44+00:00","og_image":[{"width":960,"height":718,"url":"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/basura.jpg?fit=960%2C718&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/02\/18\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/18\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"Minga ambiental en arroyo Mburica\u00f3 deja al descubierto la inacci\u00f3n del estado","datePublished":"2019-02-18T20:19:00+00:00","dateModified":"2021-02-14T22:42:44+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/18\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\/"},"wordCount":220,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/18\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/basura.jpg?fit=960%2C718&ssl=1","keywords":["ariel oviedo","arroyo mburicao","mario ferreiro","minga de limpieza"],"articleSection":["Municipales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/02\/18\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/02\/18\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\/","url":"https:\/\/informatepy.com\/2021\/2019\/02\/18\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\/","name":"Minga ambiental en arroyo Mburica\u00f3 deja al descubierto la inacci\u00f3n del estado - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/18\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/18\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/basura.jpg?fit=960%2C718&ssl=1","datePublished":"2019-02-18T20:19:00+00:00","dateModified":"2021-02-14T22:42:44+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/18\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/02\/18\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/02\/18\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/basura.jpg?fit=960%2C718&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/basura.jpg?fit=960%2C718&ssl=1","width":960,"height":718,"caption":"Se recolectaron 43 toneladas de basura del arroyo Mburica\u00f3"},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/02\/18\/minga-de-limpieza-en-arroyo-mburicao-deja-al-descubierto-la-inaccion-del-estado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Minga ambiental en arroyo Mburica\u00f3 deja al descubierto la inacci\u00f3n del estado"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/basura.jpg?fit=960%2C718&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":14090,"url":"https:\/\/informatepy.com\/2021\/2022\/09\/27\/nenecho-contra-abc-y-uh\/","url_meta":{"origin":590,"position":0},"title":"Nenecho contra ABC y UH","date":"27 de septiembre de 2022","format":false,"excerpt":"Desde la Municipalidad de Asunci\u00f3n dieron a conocer las irregularidades entorno a los dos grupos empresariales de comunicaci\u00f3n ABC Color (de los Zuccolillo) y \u00daltima Hora-Telefuturo (de Vierci). Las acusaciones son de graves transgresiones a las normativas municipales vigentes. El intendente de Asunci\u00f3n, \u00d3scar \u201cNenecho Rodr\u00edguez\u201d, dispar\u00f3 a\u00a0trav\u00e9s de sus\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/09\/ABC_UH.jpg?fit=1200%2C664&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6040,"url":"https:\/\/informatepy.com\/2021\/2021\/07\/30\/municipio-politica-y-gestion-ambiental\/","url_meta":{"origin":590,"position":1},"title":"Municipio, pol\u00edtica y gesti\u00f3n ambiental","date":"30 de julio de 2021","format":false,"excerpt":"Los municipios se constituyen a trav\u00e9s la Carta Org\u00e1nica Municipal, lo cual es la normativa que contiene los fundamentos y principios de las acciones municipales. Esta Carta Org\u00e1nica Ordena y establece las cl\u00e1usulas que rigen el funcionamiento del Poder Ejecutivo y Legislativo Municipal. Al mismo tiempo, establece las normas en\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/ciudad-sostenible.jpg?fit=1170%2C650&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6594,"url":"https:\/\/informatepy.com\/2021\/2021\/08\/20\/negligencia-e-inaccion-para-la-proteccion-ambiental-de-los-recursos-hidricos\/","url_meta":{"origin":590,"position":2},"title":"Negligencia e inacci\u00f3n para la protecci\u00f3n ambiental de los recursos h\u00eddricos","date":"20 de agosto de 2021","format":false,"excerpt":"Foto ilustrativa Iron\u00edas del destino y haciendo apolog\u00eda del destino para la protecci\u00f3n y conservaci\u00f3n ambiental de los recursos h\u00eddricos del Paraguay, es hiriente detectar la inacci\u00f3n de la ESSAP y del Ministerio del Ambiente y Desarrollo Sostenible. Tras denuncias presentadas por vecinos del barrio Campo Grande, ante la falta\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/arroyos-asuncion.jpg?fit=696%2C522&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5866,"url":"https:\/\/informatepy.com\/2021\/2021\/07\/19\/conoce-a-tu-candidato-gisselle-barrail-pre-candidata-a-concejal-de-asuncion-plra\/","url_meta":{"origin":590,"position":3},"title":"Conoc\u00e9 a tu candidato: Gisselle Barrail (Candidata a Concejal de Asunci\u00f3n \u2013 PLRA)","date":"19 de julio de 2021","format":false,"excerpt":"\u00bfCu\u00e1ndo y por qu\u00e9 te sumaste a la pol\u00edtica? Soy militante partidaria desde los 18 a\u00f1os, y me sumo en \u00e9ste momento confiando en el desbloqueo de la lista (que funciona, porque \u00a0del orden 9 pas\u00e9 al orden \u00a06) \u00a0Porque creo firmemente que debemos involucrarnos, los que militamos en partidos\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/Gisselle-Barrail-1.jpg?fit=1200%2C676&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4272,"url":"https:\/\/informatepy.com\/2021\/2021\/04\/03\/conoce-a-tu-candidato-mingo-gonzalez-pre-candidato-a-intendente-de-lambare\/","url_meta":{"origin":590,"position":4},"title":"Conoc\u00e9 a tu candidato: Mingo Gonz\u00e1lez (Pre candidato a Intendente de Lambar\u00e9)","date":"3 de abril de 2021","format":false,"excerpt":"\u00bfCu\u00e1ndo y por qu\u00e9 te sumaste a la pol\u00edtica? En a\u00f1o 2015 decid\u00ed ser un actor activo porque estoy convencido de que el trabajo organizado y transparente puede acabar con la corrupci\u00f3n y la mala administraci\u00f3n.\u00a0 \u00bfC\u00f3mo ser\u00eda la ciudad qu\u00e9 so\u00f1as? Sue\u00f1o con una Lambar\u00e9 que utilice los recursos\u2026","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/mingo-gonzalez.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4229,"url":"https:\/\/informatepy.com\/2021\/2021\/03\/31\/conoce-a-tu-candidato-oscar-campuzano-pre-candidato-a-intendente-de-asuncion\/","url_meta":{"origin":590,"position":5},"title":"Conoc\u00e9 a tu candidato: Oscar Campuzano (Pre Candidato a Intendente de Asunci\u00f3n)","date":"31 de marzo de 2021","format":false,"excerpt":"\u00bfCu\u00e1ndo y por qu\u00e9 te sumaste a la pol\u00edtica? Me inicie en la pol\u00edtica en el Movimiento Popular Colorado (MOPOCO), por el a\u00f1o 1984 con Enrique Riera Escudero, me sume en aquellos tiempos por que viv\u00edamos en una dictadura militar amparada por el Partido Colorado, pero que sin embargo, exist\u00eda\u2026","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/oscar-campuzano.jpg?fit=1200%2C1107&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=590"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/590\/revisions"}],"predecessor-version":[{"id":3333,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/590\/revisions\/3333"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/591"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=590"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}