{"id":535,"date":"2019-02-14T20:19:00","date_gmt":"2019-02-14T20:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=535"},"modified":"2021-02-14T00:55:48","modified_gmt":"2021-02-14T00:55:48","slug":"mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/02\/14\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\/","title":{"rendered":"M\u00e1s Mentiras: Ni un solo alba\u00f1il en obra del Ministerio de Salud, que asegura est\u00e1 avanzando"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Sin avances. Los trabajos de la construcci\u00f3n del edificio para el local propio del Instituto Nacional de Alimentaci\u00f3n y Nutrici\u00f3n (INAN), dependiente del Ministerio de Salud P\u00fablica (MSP), sigue estancada pese a regularizarse la deuda con la empresa constructora. La arquitecta Leticia Herreros, directora de Recursos F\u00edsicos del MSP, asegur\u00f3 ayer a \u00daH que la construcci\u00f3n se retom\u00f3 recientemente y que est\u00e1 avanzando.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero la realidad es otra. Un equipo period\u00edstico de \u00daH visit\u00f3 ayer el predio ubicado detr\u00e1s del Instituto de Medicina Tropical (IMS), que est\u00e1 en la calle Santa Rosa, y constat\u00f3 la ausencia de obreros en la construcci\u00f3n. Los vecinos confirmaron que no hay alba\u00f1iles trabajando desde hace meses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Incluso, el mes pasado la arquitecta Herreros reafirm\u00f3 a \u00daH que se reiniciaron los trabajos, pero los vecinos confirman el abandono total de la obra. \u201cSe retom\u00f3 ya. Est\u00e1 avanzando. No a ritmo moral porque se le est\u00e1 intimando a la empresa para que d\u00e9 celeridad. Pero ya retomaron y est\u00e1 avanzado el trabajo\u201d, insiste la arquitecta Herreros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La intimaci\u00f3n que se le realiza a la empresa es para que avance en los trabajos de la edificaci\u00f3n, as\u00ed como la incorporaci\u00f3n de m\u00e1s obreros, admiti\u00f3 en otro momento la titular de Recursos F\u00edsicos. \u201cPara que d\u00e9 celeridad, para que incorpore mayor personal a la obra\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras la insistente pregunta, que no hay gente trabajando en el predio, aleg\u00f3 que \u201cno se nota porque ponen poco personal y la obra es muy grande\u201d. El plazo para la constructora MyT es hasta fin de a\u00f1o para culminar la construcci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ANTECEDENTES. La palada inicial del futuro local y laboratorio del Inan se realiz\u00f3 en enero del 2014, pero qued\u00f3 empantanada por casi dos a\u00f1os ante la falta de desembolso del anticipo a la empresa adjudicada, seg\u00fan inform\u00f3 la arquitecta Herreros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde ese tiempo hasta la fecha sigue el tira y afloja entre la cartera sanitaria y la constructora, pese a regularizar los pagos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El edificio nuevo, que contar\u00e1 con un laboratorio, ten\u00eda que culminar en un plazo de 24 meses, en enero del 2016, pero suman casi cinco a\u00f1os desde el inicio de la construcci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proyecto corresponde a la anterior gesti\u00f3n del ex ministro de Salud Antonio Barrios, con una inversi\u00f3n de G. 17.000 millones, seg\u00fan datos de la Direcci\u00f3n Nacional de Contrataciones P\u00fablicas (DNCP).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otro de los aspectos, que incidieron en que se extienda el tiempo, es un detalle que no se previ\u00f3 en la obra, por lo que se procedi\u00f3 a una adenda, seg\u00fan los datos de Contrataciones P\u00fablicas. La obra requer\u00eda una climatizaci\u00f3n independiente, que se licit\u00f3 y que se debe iniciar, dependiendo del avance de los trabajos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el 2014, las anteriores autoridades destacaron el proyecto debido a que contar\u00e1 con un laboratorio y que posicionar\u00e1 a la instituci\u00f3n como uno de los mejores de la regi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El INAN es un \u201cente rector en nutrici\u00f3n humana e inocuidad de los alimentos, con capacidad resolutiva, eficiente y oportuna, reconocida a nivel nacional e internacional\u201d, seg\u00fan datos institucionales. Actualmente, tiene su local sobre la avenida Sant\u00edsima Trinidad e Itap\u00faa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Se retom\u00f3 ya. Est\u00e1 avanzando, pero no a un ritmo normal porque se le est\u00e1 intimando a la empresa para que d\u00e9 celeridad. Arq. Leticia Herreros, de Recursos F\u00edsicos.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: UH<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sin avances. Los trabajos de la construcci\u00f3n del edificio para el local propio del Instituto Nacional de Alimentaci\u00f3n y Nutrici\u00f3n (INAN), dependiente del Ministerio de Salud P\u00fablica (MSP), sigue estancada pese a regularizarse la deuda con la empresa constructora. La arquitecta Leticia Herreros, directora de Recursos F\u00edsicos del MSP, asegur\u00f3 ayer a \u00daH que la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":536,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[177,1],"tags":[311,312],"ppma_author":[1039],"class_list":["post-535","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","category-sin-categoria","tag-inan","tag-ministerio-de-salud"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e1s Mentiras: Ni un solo alba\u00f1il en obra del Ministerio de Salud, que asegura est\u00e1 avanzando - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/02\/14\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1s Mentiras: Ni un solo alba\u00f1il en obra del Ministerio de Salud, que asegura est\u00e1 avanzando - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Sin avances. Los trabajos de la construcci\u00f3n del edificio para el local propio del Instituto Nacional de Alimentaci\u00f3n y Nutrici\u00f3n (INAN), dependiente del Ministerio de Salud P\u00fablica (MSP), sigue estancada pese a regularizarse la deuda con la empresa constructora. La arquitecta Leticia Herreros, directora de Recursos F\u00edsicos del MSP, asegur\u00f3 ayer a \u00daH que la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/02\/14\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-14T20:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-14T00:55:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/Edificio-INAN.jpg?fit=730%2C366&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"730\" \/>\n\t<meta property=\"og:image:height\" content=\"366\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/14\\\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/14\\\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"M\u00e1s Mentiras: Ni un solo alba\u00f1il en obra del Ministerio de Salud, que asegura est\u00e1 avanzando\",\"datePublished\":\"2019-02-14T20:19:00+00:00\",\"dateModified\":\"2021-02-14T00:55:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/14\\\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\\\/\"},\"wordCount\":593,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/14\\\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Edificio-INAN.jpg?fit=730%2C366&ssl=1\",\"keywords\":[\"inan\",\"ministerio de salud\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/14\\\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/14\\\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/14\\\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\\\/\",\"name\":\"M\u00e1s Mentiras: Ni un solo alba\u00f1il en obra del Ministerio de Salud, que asegura est\u00e1 avanzando - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/14\\\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/14\\\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Edificio-INAN.jpg?fit=730%2C366&ssl=1\",\"datePublished\":\"2019-02-14T20:19:00+00:00\",\"dateModified\":\"2021-02-14T00:55:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/14\\\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/14\\\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/14\\\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Edificio-INAN.jpg?fit=730%2C366&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Edificio-INAN.jpg?fit=730%2C366&ssl=1\",\"width\":730,\"height\":366,\"caption\":\"Abandono. Vecinos comentaron que desde hace meses no hay ning\u00fan obrero trabajando.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/14\\\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e1s Mentiras: Ni un solo alba\u00f1il en obra del Ministerio de Salud, que asegura est\u00e1 avanzando\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1s Mentiras: Ni un solo alba\u00f1il en obra del Ministerio de Salud, que asegura est\u00e1 avanzando - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/02\/14\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e1s Mentiras: Ni un solo alba\u00f1il en obra del Ministerio de Salud, que asegura est\u00e1 avanzando - Informatepy","og_description":"Sin avances. Los trabajos de la construcci\u00f3n del edificio para el local propio del Instituto Nacional de Alimentaci\u00f3n y Nutrici\u00f3n (INAN), dependiente del Ministerio de Salud P\u00fablica (MSP), sigue estancada pese a regularizarse la deuda con la empresa constructora. La arquitecta Leticia Herreros, directora de Recursos F\u00edsicos del MSP, asegur\u00f3 ayer a \u00daH que la [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2019\/02\/14\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\/","og_site_name":"Informatepy","article_published_time":"2019-02-14T20:19:00+00:00","article_modified_time":"2021-02-14T00:55:48+00:00","og_image":[{"width":730,"height":366,"url":"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/Edificio-INAN.jpg?fit=730%2C366&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/02\/14\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/14\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"M\u00e1s Mentiras: Ni un solo alba\u00f1il en obra del Ministerio de Salud, que asegura est\u00e1 avanzando","datePublished":"2019-02-14T20:19:00+00:00","dateModified":"2021-02-14T00:55:48+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/14\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\/"},"wordCount":593,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/14\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/Edificio-INAN.jpg?fit=730%2C366&ssl=1","keywords":["inan","ministerio de salud"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/02\/14\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/02\/14\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\/","url":"https:\/\/informatepy.com\/2021\/2019\/02\/14\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\/","name":"M\u00e1s Mentiras: Ni un solo alba\u00f1il en obra del Ministerio de Salud, que asegura est\u00e1 avanzando - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/14\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/14\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/Edificio-INAN.jpg?fit=730%2C366&ssl=1","datePublished":"2019-02-14T20:19:00+00:00","dateModified":"2021-02-14T00:55:48+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/14\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/02\/14\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/02\/14\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/Edificio-INAN.jpg?fit=730%2C366&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/Edificio-INAN.jpg?fit=730%2C366&ssl=1","width":730,"height":366,"caption":"Abandono. Vecinos comentaron que desde hace meses no hay ning\u00fan obrero trabajando."},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/02\/14\/mas-mentiras-ni-un-solo-albanil-en-obra-del-ministerio-de-salud-que-asegura-esta-avanzando\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"M\u00e1s Mentiras: Ni un solo alba\u00f1il en obra del Ministerio de Salud, que asegura est\u00e1 avanzando"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/Edificio-INAN.jpg?fit=730%2C366&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":11911,"url":"https:\/\/informatepy.com\/2021\/2022\/06\/03\/la-corte-suprema-uruguaya-falla-contra-el-ministerio-de-salud-y-obliga-a-cruzar-informacion-entre-poblacion-vacunada-y-fallecidos\/","url_meta":{"origin":535,"position":0},"title":"La Corte Suprema uruguaya falla contra el Ministerio de Salud y obliga a cruzar informaci\u00f3n entre poblaci\u00f3n vacunada y fallecidos","date":"3 de junio de 2022","format":false,"excerpt":"La Corte acaba de anular, en fallo un\u00e1nime, una sentencia del Tribunal de Apelaciones en 2021 que exoneraba al MSP de la obligaci\u00f3n de cruzar informaci\u00f3n entre poblaci\u00f3n vacunada y fallecidos","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/corte-suprema-uruguay.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10101,"url":"https:\/\/informatepy.com\/2021\/2022\/02\/15\/ips-dilata-pago-por-suspensiones-a-trabajadores-asegurados\/","url_meta":{"origin":535,"position":1},"title":"IPS dilata pago por suspensiones a trabajadores asegurados","date":"15 de febrero de 2022","format":false,"excerpt":"El Instituto de Previsi\u00f3n Social (IPS) sigue sin pagar a los trabajadores asegurados suspendidos por la pandemia. La gerente de Prestaciones Econ\u00f3micas, Cecilia Rodr\u00edguez, argument\u00f3 que esperan la aprobaci\u00f3n del decreto reglamentario para ejecutar los desembolsos estipulados en la Ley de Emergencia Sanitaria, la Nro. 6.524. Mencion\u00f3 que dentro del\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/Cecilia-Rodriguez-IPS.jpg?fit=660%2C330&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12576,"url":"https:\/\/informatepy.com\/2021\/2022\/07\/07\/uruguay-juez-resolvio-suspender-la-vacunacion-anticovid-a-ninos\/","url_meta":{"origin":535,"position":2},"title":"URUGUAY: Juez resolvi\u00f3 suspender la vacunaci\u00f3n anticovid a ni\u00f1os","date":"7 de julio de 2022","format":false,"excerpt":"El juez\u00a0Alejandro Recarey\u00a0determin\u00f3 este jueves al mediod\u00eda\u00a0la suspensi\u00f3n \"inmediata\" de la\u00a0vacunaci\u00f3n anticovid de ni\u00f1os\u00a0\"menores de 13 a\u00f1os\" bajo el \"apercibimiento de desacato\" en caso contrario. La medida ocurre despu\u00e9s de dos audiencias entre ayer y hoy a partir de la\u00a0acci\u00f3n de amparo que present\u00f3 el viernes el abogado Maximiliano Dentone.\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/corte-suprema-uruguay.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12136,"url":"https:\/\/informatepy.com\/2021\/2022\/06\/14\/ministerio-de-salud-reconoce-la-falta-de-medicamentos-para-pacientes-oncologicos\/","url_meta":{"origin":535,"position":3},"title":"Ministerio de Salud reconoce la falta de medicamentos para pacientes oncol\u00f3gicos","date":"14 de junio de 2022","format":false,"excerpt":"Derlis Le\u00f3n, director Insumos Estrat\u00e9gicos del Ministerio de Salud, reconoci\u00f3 que varios medicamentos para pacientes con c\u00e1ncer est\u00e1n en falta y prometi\u00f3 que en los pr\u00f3ximos d\u00edas la situaci\u00f3n ser\u00e1 normalizada. Mencion\u00f3 tambi\u00e9n que mediante la modificaci\u00f3n de una normativa que permite al Instituto Nacional del C\u00e1ncer (Incan) tener autonom\u00eda\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/ministerio-salud.webp?fit=800%2C600&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13589,"url":"https:\/\/informatepy.com\/2021\/2022\/08\/25\/inauguran-mejoras-en-el-hospital-ninos-de-acosta-nu\/","url_meta":{"origin":535,"position":4},"title":"Inauguran mejoras en el hospital \u201cNi\u00f1os de Acosta \u00d1u\u201d","date":"25 de agosto de 2022","format":false,"excerpt":"Se habilitaron una serie de mejoras en el Hospital General Pedi\u00e1trico \u201cNi\u00f1os de Acosta \u00d1u\u201d en las \u00e1reas de Terapia Intensiva, Oncohematolog\u00eda y Medicina Interna con el objetivo de brindar una mayor respuesta a los pacientes y con ello optimizar la atenci\u00f3n. En la tarde de ayer se realiz\u00f3 el\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/hosp-acosta-nu.jpg?fit=761%2C452&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8914,"url":"https:\/\/informatepy.com\/2021\/2021\/12\/20\/ministerio-publico-pide-ocho-anos-de-prision-para-ex-intendente-de-lambare\/","url_meta":{"origin":535,"position":5},"title":"Ministerio P\u00fablico pide ocho a\u00f1os de prisi\u00f3n para ex intendente de Lambar\u00e9","date":"20 de diciembre de 2021","format":false,"excerpt":"La Fiscal\u00eda pidi\u00f3 ocho a\u00f1os de c\u00e1rcel para el ex intendente de Lambar\u00e9, Roberto C\u00e1rdenas, por presuntas irregularidades en la construcci\u00f3n de quince instituciones educativas. Tambi\u00e9n pidi\u00f3 ordenar su prisi\u00f3n preventiva. Solicitaron la misma cantidad de a\u00f1os para Guido Salcedo, ex director de Administraci\u00f3n y Finanzas. El Ministerio P\u00fablico est\u00e1\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/roberto-cardenas.jpg?fit=1016%2C677&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=535"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/535\/revisions"}],"predecessor-version":[{"id":3281,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/535\/revisions\/3281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/536"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=535"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}