{"id":518,"date":"2019-02-12T20:19:00","date_gmt":"2019-02-12T20:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=518"},"modified":"2021-02-10T15:02:43","modified_gmt":"2021-02-10T15:02:43","slug":"essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/02\/12\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\/","title":{"rendered":"Essap pag\u00f3 US$ 10 mil por un curso que funcionaria no termin\u00f3"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Empresa de Servicios Sanitarios del Paraguay (Essap) pag\u00f3 G. 60 millones, unos US$ 10 mil, para una especializaci\u00f3n en derecho de la gerente jur\u00eddica del ente, Abg. Myriam Gonz\u00e1lez, en la prestigiosa Universidad de Salamanca, Espa\u00f1a, tres meses despu\u00e9s de ingresar a la instituci\u00f3n. Sin embargo, la funcionaria dilapid\u00f3 el dinero de la gente, ya que no asisti\u00f3 a todas las clases y por eso no trajo el diploma correspondiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Myriam es miembro suplente de la ANR por Colorado A\u00f1etete. Se confirma que se fue de paseo, tuvo tiempo hasta para disfrutar de una luna de miel con su amado por Irlanda, tal como ya hab\u00edamos difundido, pero no para completar la carga horaria del curso denominado \u201ccrimen organizado, terrorismo y corrupci\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 30 de enero pasado, en la Sala Francisco Salinas de la Universidad de Salamanca, los compa\u00f1eros de Myriam recibieron sus diplomas, pero por sus ausencias ella no pudo recibir el suyo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quince paraguayos, entre ellos varios de la funci\u00f3n p\u00fablica, participaron de esta especializaci\u00f3n y comentaron que la compatriota se acerc\u00f3 para pedir su diploma, pero su nombre estaba tachado en la planilla por no completar la carga horaria establecida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al tener que justificar y documentar su viaje, la funcionaria present\u00f3 en la Essap y en la Contralor\u00eda General de la Rep\u00fablica (CGR) una constancia de que estuvo en el curso, sin embargo este documento es diferente al que recibieron sus compa\u00f1eros que de verdad terminaron en tiempo y forma la capacitaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La constancia que present\u00f3 la abogada no tiene la firma del rector magn\u00edfico Ricardo Rivero Ortega ni del director de la especialidad, Eduardo Fabi\u00e1n Caparr\u00f3s. La abogada se escud\u00f3 en un certificado que le firm\u00f3 el director \u00d3scar Gonz\u00e1lez Benito, director gerente de la universidad, a modo de aclarar que s\u00ed particip\u00f3 del curso. El problema es que no complet\u00f3 la carga horaria requerida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>CARGA HORARIA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El curso tiene una carga horaria de 120 horas, de las cuales 60 horas son de car\u00e1cter presencial y se admite ausentarse solamente 5 horas; es decir, requer\u00eda cumplir con un 85% de asistencia, dicho porcentaje habilita para la realizaci\u00f3n de un trabajo de investigaci\u00f3n posterior a las restantes 60 horas y as\u00ed obtener el t\u00edtulo de especialista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero la flamante abogada, quien apenas aterriz\u00f3 en setiembre pasado a la Essap, vol\u00f3 a \u201cestudiar\u201d a Espa\u00f1a, se ausent\u00f3 m\u00e1s de lo debido en las clases y se fue al tacho el dinero que pag\u00f3 el Estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, el esc\u00e1ndalo incluye a su pareja Jos\u00e9 Arnaldo Bordignon Pintos, quien tambi\u00e9n se ubic\u00f3 como asesor en la Essap en noviembre pasado con un salario de G. 9,2 millones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dos meses despu\u00e9s de conseguir el cargo en la empresa estatal, el funcionario tom\u00f3 vuelo hacia Europa para as\u00ed compartir un tour rom\u00e1ntico con su amada Myriam gracias al padrinazgo de las autoridades de turno en la aguatera estatal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>FINALMENTE, PRESIDENTE LIBER\u00d3 ENTREGA DE DOCUMENTO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En reiteradas ocasiones pedimos acceder a la copia del diploma de Myriam. Nos acercamos a la instituci\u00f3n, donde tanto los de comunicaci\u00f3n como recursos humanos se desentendieron del caso ante la evidencia de que la funcionaria no trajo este documento. El s\u00e1bado pasado insistimos una vez m\u00e1s al presidente de la Essap, Natalicio Chase, quien finalmente nos facilit\u00f3 la constancia que present\u00f3 Myriam.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta ahora el presidente mantiene en el cargo a la funcionaria pese a la irregularidad que cometi\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>DICE QUE DEVOLVER\u00c1 LA PLATA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la Contralor\u00eda dijeron que actuaron de oficio a ra\u00edz de las publicaciones period\u00edsticas de La Naci\u00f3n y solicitaron las documentaciones correspondientes sobre el viaje. Sin embargo, admitieron que la constancia no es el diploma que deb\u00eda presentar la funcionaria si realmente completaba el curso que le pag\u00f3 la Essap.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En CGR informaron que entre los papeles que remiti\u00f3 Essap figura un documento escrito en el que la funcionaria se compromete a devolver la totalidad del vi\u00e1tico, cerca de G. 60 millones, antes del 15 de febrero, con esto apuntan al blanqueo del caso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>FUNCI\u00d3N P\u00daBLICA SE LAVA LAS MANOS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, la ministra de la Funci\u00f3n P\u00fablica, la doctora Cristina Bogado, indic\u00f3 que desde su instituci\u00f3n no pueden hacer nada y que ya depender\u00e1 exclusivamente del m\u00e1ximo representante de la entidad p\u00fablica para aplicar las sanciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDesde la funci\u00f3n p\u00fablica no podemos aplicar sanciones, ya depender\u00e1 exclusivamente en este caso del presidente de la Essap, Natalicio Chase, para aclarar este caso. L\u00f3gicamente existe un hecho irregular, la funcionaria no cumpli\u00f3 con su misi\u00f3n. Por m\u00e1s que devuelva su vi\u00e1tico, existe una irregularidad\u201d, manifest\u00f3 Bogado.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/AYDJEY7XXZCARNFP5CHBGTXBMM.jpg?w=740&#038;ssl=1\" alt=\"Este es el diploma que trajeron los funcionarios que s\u00ed completaron el curso en Salamanca. Como se puede ver cuenta con la firma del rector magn\u00edfico, del director gerente y del director de la especialidad.\" data-recalc-dims=\"1\"\/><figcaption><em>Este es el diploma que trajeron los funcionarios que s\u00ed completaron el curso en Salamanca. Como se puede ver cuenta con la firma del rector magn\u00edfico, del director gerente y del director de la especialidad.<\/em><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/XUFMSM72GBG6JLP4QO4XWNZL2U.jpg?w=740&#038;ssl=1\" alt=\"Esta es la constancia que present\u00f3 la funcionaria de Essap al no recibir el diploma por no asistir a las 60 horas de clases.\" data-recalc-dims=\"1\"\/><figcaption><em>Esta es la constancia que present\u00f3 la funcionaria de Essap al no recibir el diploma por no asistir a las 60 horas de clases.<\/em><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/FLE33XTMIFAT3KNLP34RPJ4YFE.jpg?w=740&#038;ssl=1\" alt=\"Jos\u00e9 Bordignon y Myriam Gonz\u00e1lez, cuando aprovecharon el curso pagado por la Essap para una luna de miel express en Irlanda.\" data-recalc-dims=\"1\"\/><figcaption><em>Jos\u00e9 Bordignon y Myriam Gonz\u00e1lez, cuando aprovecharon el curso pagado por la Essap para una luna de miel express en Irlanda.<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: La Nacion<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Empresa de Servicios Sanitarios del Paraguay (Essap) pag\u00f3 G. 60 millones, unos US$ 10 mil, para una especializaci\u00f3n en derecho de la gerente jur\u00eddica del ente, Abg. Myriam Gonz\u00e1lez, en la prestigiosa Universidad de Salamanca, Espa\u00f1a, tres meses despu\u00e9s de ingresar a la instituci\u00f3n. Sin embargo, la funcionaria dilapid\u00f3 el dinero de la gente, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":519,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[177],"tags":[233,300,301,235],"ppma_author":[1039],"class_list":["post-518","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-essap","tag-jose-bordignon","tag-myriam-gonzalez","tag-natalicio-chase"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Essap pag\u00f3 US$ 10 mil por un curso que funcionaria no termin\u00f3 - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/02\/12\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Essap pag\u00f3 US$ 10 mil por un curso que funcionaria no termin\u00f3 - Informatepy\" \/>\n<meta property=\"og:description\" content=\"La Empresa de Servicios Sanitarios del Paraguay (Essap) pag\u00f3 G. 60 millones, unos US$ 10 mil, para una especializaci\u00f3n en derecho de la gerente jur\u00eddica del ente, Abg. Myriam Gonz\u00e1lez, en la prestigiosa Universidad de Salamanca, Espa\u00f1a, tres meses despu\u00e9s de ingresar a la instituci\u00f3n. Sin embargo, la funcionaria dilapid\u00f3 el dinero de la gente, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/02\/12\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-12T20:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-10T15:02:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/egresados-cursos-essap-salamanca.jpg?fit=1200%2C765&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"765\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/12\\\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/12\\\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"Essap pag\u00f3 US$ 10 mil por un curso que funcionaria no termin\u00f3\",\"datePublished\":\"2019-02-12T20:19:00+00:00\",\"dateModified\":\"2021-02-10T15:02:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/12\\\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\\\/\"},\"wordCount\":894,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/12\\\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/egresados-cursos-essap-salamanca.jpg?fit=1200%2C765&ssl=1\",\"keywords\":[\"essap\",\"jose bordignon\",\"myriam gonzalez\",\"Natalicio Chase\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/12\\\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/12\\\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/12\\\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\\\/\",\"name\":\"Essap pag\u00f3 US$ 10 mil por un curso que funcionaria no termin\u00f3 - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/12\\\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/12\\\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/egresados-cursos-essap-salamanca.jpg?fit=1200%2C765&ssl=1\",\"datePublished\":\"2019-02-12T20:19:00+00:00\",\"dateModified\":\"2021-02-10T15:02:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/12\\\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/12\\\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/12\\\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/egresados-cursos-essap-salamanca.jpg?fit=1200%2C765&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/egresados-cursos-essap-salamanca.jpg?fit=1200%2C765&ssl=1\",\"width\":1200,\"height\":765,\"caption\":\"Compa\u00f1eros de Myriam Gonz\u00e1lez en curso de Salamanca que s\u00ed trajeron sus diplomas, durante el acto de clausura.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/12\\\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Essap pag\u00f3 US$ 10 mil por un curso que funcionaria no termin\u00f3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Essap pag\u00f3 US$ 10 mil por un curso que funcionaria no termin\u00f3 - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/02\/12\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\/","og_locale":"es_ES","og_type":"article","og_title":"Essap pag\u00f3 US$ 10 mil por un curso que funcionaria no termin\u00f3 - Informatepy","og_description":"La Empresa de Servicios Sanitarios del Paraguay (Essap) pag\u00f3 G. 60 millones, unos US$ 10 mil, para una especializaci\u00f3n en derecho de la gerente jur\u00eddica del ente, Abg. Myriam Gonz\u00e1lez, en la prestigiosa Universidad de Salamanca, Espa\u00f1a, tres meses despu\u00e9s de ingresar a la instituci\u00f3n. Sin embargo, la funcionaria dilapid\u00f3 el dinero de la gente, [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2019\/02\/12\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\/","og_site_name":"Informatepy","article_published_time":"2019-02-12T20:19:00+00:00","article_modified_time":"2021-02-10T15:02:43+00:00","og_image":[{"width":1200,"height":765,"url":"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/egresados-cursos-essap-salamanca.jpg?fit=1200%2C765&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/02\/12\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/12\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"Essap pag\u00f3 US$ 10 mil por un curso que funcionaria no termin\u00f3","datePublished":"2019-02-12T20:19:00+00:00","dateModified":"2021-02-10T15:02:43+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/12\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\/"},"wordCount":894,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/12\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/egresados-cursos-essap-salamanca.jpg?fit=1200%2C765&ssl=1","keywords":["essap","jose bordignon","myriam gonzalez","Natalicio Chase"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/02\/12\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/02\/12\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\/","url":"https:\/\/informatepy.com\/2021\/2019\/02\/12\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\/","name":"Essap pag\u00f3 US$ 10 mil por un curso que funcionaria no termin\u00f3 - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/12\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/12\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/egresados-cursos-essap-salamanca.jpg?fit=1200%2C765&ssl=1","datePublished":"2019-02-12T20:19:00+00:00","dateModified":"2021-02-10T15:02:43+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/12\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/02\/12\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/02\/12\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/egresados-cursos-essap-salamanca.jpg?fit=1200%2C765&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/egresados-cursos-essap-salamanca.jpg?fit=1200%2C765&ssl=1","width":1200,"height":765,"caption":"Compa\u00f1eros de Myriam Gonz\u00e1lez en curso de Salamanca que s\u00ed trajeron sus diplomas, durante el acto de clausura."},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/02\/12\/essap-pago-us-10-mil-por-un-curso-que-funcionaria-no-termino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Essap pag\u00f3 US$ 10 mil por un curso que funcionaria no termin\u00f3"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/egresados-cursos-essap-salamanca.jpg?fit=1200%2C765&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":450,"url":"https:\/\/informatepy.com\/2021\/2019\/02\/10\/blindaje-generalizado-en-la-essap-para-la-pareja-viajera\/","url_meta":{"origin":518,"position":0},"title":"Blindaje generalizado en la Essap para la pareja viajera","date":"10 de febrero de 2019","format":false,"excerpt":"En el caso de la gerente jur\u00ed\u00addica de la Empresa de Servi\u00adcios Sanitarios del Paraguay (Essap), Myriam Beatriz Gonz\u00e1lez, viaj\u00f3 a Espa\u00f1a para estudiar en la presti\u00adgiosa Universidad de Sala\u00admanca, desde el 14 enero y culmin\u00f3 el 30 del mismo mes. Para dicho curso, la privilegiada se alz\u00f3 con US$\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/Natalicio-Chase-presidente-de-Essap.jpg?fit=1200%2C933&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2239,"url":"https:\/\/informatepy.com\/2021\/2020\/11\/04\/denuncian-al-titular-de-la-essap-por-ser-funcionario-y-proveedor-del-estado-a-la-vez\/","url_meta":{"origin":518,"position":1},"title":"Denuncian al titular de la Essap por ser funcionario y proveedor del Estado a la vez","date":"4 de noviembre de 2020","format":false,"excerpt":"\u201cConstatamos con nuestro equipo t\u00e9cnico, que el actual titular de la Essap se dedicaba a ganar licitaciones p\u00fablicas, pero eso no est\u00e1 mal, lo que s\u00ed est\u00e1 mal es ser funcionario p\u00fablico o autoridad del Gobierno y a la par ser proveedor del estado\u201d, explic\u00f3 el diputado colorado Carlos Rejala\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/Natalicio-Chase-foto-IP.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12673,"url":"https:\/\/informatepy.com\/2021\/2022\/07\/15\/nenecho-analiza-acciones-legales-contra-la-essap-por-boicot\/","url_meta":{"origin":518,"position":2},"title":"Nenecho analiza acciones legales contra la Essap por boicot","date":"15 de julio de 2022","format":false,"excerpt":"La Empresa de Servicios Sanitarios del Paraguay (Essap) volvi\u00f3 a destruir un asfaltado que la Municipalidad de Asunci\u00f3n acababa de concluir sobre la calle Eusebio Lilo, lo que fue calificado como un boicot por el intendente de Asunci\u00f3n, Oscar \u201cNenecho\u201d Rodr\u00edguez, quien analiza probables acciones legales en contra del ente\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/07\/asfalto.jpg?fit=1024%2C512&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2113,"url":"https:\/\/informatepy.com\/2021\/2020\/08\/12\/volvieron-a-hacerlo-diputados-archiva-la-condonacion-de-deudas-de-ande-y-essap\/","url_meta":{"origin":518,"position":3},"title":"Volvieron a hacerlo: Diputados archiva la condonaci\u00f3n de deudas de Ande y Essap","date":"12 de agosto de 2020","format":false,"excerpt":"La C\u00e1mara de Diputados no consigui\u00f3 los votos necesarios para rechazar la objeci\u00f3n parcial del presidente, Mario Abdo Ben\u00edtez, al proyecto de ley del Senador Salym Buzarquis, por lo que no se pudo ratificar la sanci\u00f3n del Congreso y el Veto presidencial est\u00e1 vigente. El Veto qued\u00f3 aceptado con 43\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/bachi-nuC3B1ez-de-payaso.jpg?fit=1146%2C762&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6594,"url":"https:\/\/informatepy.com\/2021\/2021\/08\/20\/negligencia-e-inaccion-para-la-proteccion-ambiental-de-los-recursos-hidricos\/","url_meta":{"origin":518,"position":4},"title":"Negligencia e inacci\u00f3n para la protecci\u00f3n ambiental de los recursos h\u00eddricos","date":"20 de agosto de 2021","format":false,"excerpt":"Foto ilustrativa Iron\u00edas del destino y haciendo apolog\u00eda del destino para la protecci\u00f3n y conservaci\u00f3n ambiental de los recursos h\u00eddricos del Paraguay, es hiriente detectar la inacci\u00f3n de la ESSAP y del Ministerio del Ambiente y Desarrollo Sostenible. Tras denuncias presentadas por vecinos del barrio Campo Grande, ante la falta\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/arroyos-asuncion.jpg?fit=696%2C522&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5341,"url":"https:\/\/informatepy.com\/2021\/2021\/06\/14\/yo-los-conozco-son-25-mil-los-monos\/","url_meta":{"origin":518,"position":5},"title":"Yo los conozco son&#8230; 25 mil los monos","date":"14 de junio de 2021","format":false,"excerpt":"Un dicho del \u00e1mbito jur\u00eddico reza que \u201ca confesi\u00f3n de parte, relevo de pruebas\u201d. Es exac\u00adtamente esto lo que se puede aplicar a las palabras atri\u00adbuidas de Arnulfo Ram\u00f3n \u201cMonchi\u201d Fretes Sosa, pre\u00adsidente de la seccional colo\u00adrada N\u00b0 35 y funcionario de la Entidad Binacional Yacyret\u00e1 (EBY), quien durante el\u2026","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/Arnulfo-Ramon-Fretes-Sosa.jpg?fit=1200%2C783&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=518"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/518\/revisions"}],"predecessor-version":[{"id":3192,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/518\/revisions\/3192"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/519"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=518"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}