{"id":4565,"date":"2021-04-20T11:57:36","date_gmt":"2021-04-20T15:57:36","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=4565"},"modified":"2021-04-20T11:58:45","modified_gmt":"2021-04-20T15:58:45","slug":"por-primera-vez-japon-critica-acciones-chinas-en-taiwan","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2021\/04\/20\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\/","title":{"rendered":"Por primera vez, Jap\u00f3n critica acciones chinas en Taiw\u00e1n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El presidente de\u00a0<strong>Estados Unidos<\/strong>,\u00a0<strong>Joe Biden<\/strong>, consigui\u00f3 este viernes que el primer ministro de\u00a0<strong>Jap\u00f3n<\/strong>,\u00a0<strong>Yoshihide Suga<\/strong>, abandonara su reticencia a criticar a\u00a0<strong>China\u00a0<\/strong>por sus acciones en\u00a0<strong>Taiw\u00e1n\u00a0<\/strong>y en\u00a0<strong>Xianjiang<\/strong>, un paso m\u00e1s en su pulso estrat\u00e9gico con\u00a0<strong>Pek\u00edn<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Suga se convirti\u00f3 en el primer l\u00edder al que Biden recibe en persona desde que lleg\u00f3 al poder en enero, en una muestra del inter\u00e9s de\u00a0<strong>Washington\u00a0<\/strong>de reforzar sus alianzas tradicionales en\u00a0<strong>Asia\u00a0<\/strong>para contrarrestar la pujanza de\u00a0<strong>China<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00abVamos a trabajar juntos para demostrar que las democracias todav\u00eda pueden competir y conquistar el siglo XXI\u00bb<\/strong>, afirm\u00f3 Biden durante una rueda de prensa conjunta despu\u00e9s del encuentro.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Democracias contra autocracias<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El mandatario estadounidense trataba as\u00ed de marcar un contraste con la \u00abautocracia\u00bb de&nbsp;<strong>China<\/strong>, que se ha convertido en el desaf\u00edo estrat\u00e9gico central de su pol\u00edtica exterior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEstamos comprometidos a trabajar juntos para asumir los retos que presenta China, en temas como (las disputas territoriales en) el&nbsp;<strong>Mar de China Oriental<\/strong>, en el&nbsp;<strong>Mar de China Meridional<\/strong>; y tambi\u00e9n con respecto a&nbsp;<strong>Corea del Norte<\/strong>, para asegurar un&nbsp;<strong>Indopac\u00edfico&nbsp;<\/strong>libre y abierto\u00bb, agreg\u00f3 Biden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Suga a\u00f1adi\u00f3 que hab\u00edan tenido \u00abconversaciones serias sobre la influencia de China sobre la paz y prosperidad del Indopac\u00edfico\u00bb, un t\u00e9rmino impulsado por Estados Unidos para conceder un mayor papel a la India en sus planes de contener el auge militar y econ\u00f3mico de&nbsp;<strong>Pek\u00edn<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Una menci\u00f3n clave a Taiw\u00e1n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El primer ministro japon\u00e9s asegur\u00f3 adem\u00e1s que coincid\u00eda con Biden en<em><strong> \u00abla importancia de la paz y la estabilidad en el estrecho de Taiw\u00e1n\u00bb<\/strong><\/em>, tras las recientes incursiones de aviones chinos en la zona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A lo largo del \u00faltimo medio siglo, Jap\u00f3n ha evitado criticar la pol\u00edtica china hacia Taiw\u00e1n -al que Pek\u00edn considera como una provincia rebelde y no como un pa\u00eds independiente- para evitar una confrontaci\u00f3n con el gigante asi\u00e1tico, con el que mantiene importantes lazos econ\u00f3micos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La menci\u00f3n de Suga a Taiw\u00e1n fue escueta pero significativa, y el l\u00edder japon\u00e9s a\u00f1adi\u00f3 que hab\u00eda hablado tambi\u00e9n con Biden sobre los presuntos abusos de derechos humanos de los uigures en la regi\u00f3n noroccidental china de\u00a0<strong>Xinjiang<\/strong>.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\">La Rep\u00fablica &#8211; Ecuador<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de\u00a0Estados Unidos,\u00a0Joe Biden, consigui\u00f3 este viernes que el primer ministro de\u00a0Jap\u00f3n,\u00a0Yoshihide Suga, abandonara su reticencia a criticar a\u00a0China\u00a0por sus acciones en\u00a0Taiw\u00e1n\u00a0y en\u00a0Xianjiang, un paso m\u00e1s en su pulso estrat\u00e9gico con\u00a0Pek\u00edn. Suga se convirti\u00f3 en el primer l\u00edder al que Biden recibe en persona desde que lleg\u00f3 al poder en enero, en una muestra [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4566,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[302,173],"tags":[342,1036,1190,836],"ppma_author":[1051],"class_list":["post-4565","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacados","category-mundo","tag-china","tag-destacada","tag-japon","tag-taiwan"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Por primera vez, Jap\u00f3n critica acciones chinas en Taiw\u00e1n - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2021\/04\/20\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por primera vez, Jap\u00f3n critica acciones chinas en Taiw\u00e1n - Informatepy\" \/>\n<meta property=\"og:description\" content=\"El presidente de\u00a0Estados Unidos,\u00a0Joe Biden, consigui\u00f3 este viernes que el primer ministro de\u00a0Jap\u00f3n,\u00a0Yoshihide Suga, abandonara su reticencia a criticar a\u00a0China\u00a0por sus acciones en\u00a0Taiw\u00e1n\u00a0y en\u00a0Xianjiang, un paso m\u00e1s en su pulso estrat\u00e9gico con\u00a0Pek\u00edn. Suga se convirti\u00f3 en el primer l\u00edder al que Biden recibe en persona desde que lleg\u00f3 al poder en enero, en una muestra [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2021\/04\/20\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-20T15:57:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-20T15:58:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/Yoshihide-Suga.jpg?fit=678%2C381&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"678\" \/>\n\t<meta property=\"og:image:height\" content=\"381\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/04\\\/20\\\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/04\\\/20\\\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\"},\"headline\":\"Por primera vez, Jap\u00f3n critica acciones chinas en Taiw\u00e1n\",\"datePublished\":\"2021-04-20T15:57:36+00:00\",\"dateModified\":\"2021-04-20T15:58:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/04\\\/20\\\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\\\/\"},\"wordCount\":419,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/04\\\/20\\\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Yoshihide-Suga.jpg?fit=678%2C381&ssl=1\",\"keywords\":[\"china\",\"destacada\",\"japon\",\"taiwan\"],\"articleSection\":[\"Destacados\",\"Mundo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/04\\\/20\\\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/04\\\/20\\\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/04\\\/20\\\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\\\/\",\"name\":\"Por primera vez, Jap\u00f3n critica acciones chinas en Taiw\u00e1n - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/04\\\/20\\\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/04\\\/20\\\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Yoshihide-Suga.jpg?fit=678%2C381&ssl=1\",\"datePublished\":\"2021-04-20T15:57:36+00:00\",\"dateModified\":\"2021-04-20T15:58:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/04\\\/20\\\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/04\\\/20\\\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/04\\\/20\\\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Yoshihide-Suga.jpg?fit=678%2C381&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Yoshihide-Suga.jpg?fit=678%2C381&ssl=1\",\"width\":678,\"height\":381},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/04\\\/20\\\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Por primera vez, Jap\u00f3n critica acciones chinas en Taiw\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por primera vez, Jap\u00f3n critica acciones chinas en Taiw\u00e1n - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2021\/04\/20\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\/","og_locale":"es_ES","og_type":"article","og_title":"Por primera vez, Jap\u00f3n critica acciones chinas en Taiw\u00e1n - Informatepy","og_description":"El presidente de\u00a0Estados Unidos,\u00a0Joe Biden, consigui\u00f3 este viernes que el primer ministro de\u00a0Jap\u00f3n,\u00a0Yoshihide Suga, abandonara su reticencia a criticar a\u00a0China\u00a0por sus acciones en\u00a0Taiw\u00e1n\u00a0y en\u00a0Xianjiang, un paso m\u00e1s en su pulso estrat\u00e9gico con\u00a0Pek\u00edn. Suga se convirti\u00f3 en el primer l\u00edder al que Biden recibe en persona desde que lleg\u00f3 al poder en enero, en una muestra [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2021\/04\/20\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\/","og_site_name":"Informatepy","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2021-04-20T15:57:36+00:00","article_modified_time":"2021-04-20T15:58:45+00:00","og_image":[{"width":678,"height":381,"url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/Yoshihide-Suga.jpg?fit=678%2C381&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2021\/04\/20\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2021\/04\/20\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b"},"headline":"Por primera vez, Jap\u00f3n critica acciones chinas en Taiw\u00e1n","datePublished":"2021-04-20T15:57:36+00:00","dateModified":"2021-04-20T15:58:45+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2021\/04\/20\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\/"},"wordCount":419,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2021\/04\/20\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/Yoshihide-Suga.jpg?fit=678%2C381&ssl=1","keywords":["china","destacada","japon","taiwan"],"articleSection":["Destacados","Mundo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2021\/04\/20\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2021\/04\/20\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\/","url":"https:\/\/informatepy.com\/2021\/2021\/04\/20\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\/","name":"Por primera vez, Jap\u00f3n critica acciones chinas en Taiw\u00e1n - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2021\/04\/20\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2021\/04\/20\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/Yoshihide-Suga.jpg?fit=678%2C381&ssl=1","datePublished":"2021-04-20T15:57:36+00:00","dateModified":"2021-04-20T15:58:45+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2021\/04\/20\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2021\/04\/20\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2021\/04\/20\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/Yoshihide-Suga.jpg?fit=678%2C381&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/Yoshihide-Suga.jpg?fit=678%2C381&ssl=1","width":678,"height":381},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2021\/04\/20\/por-primera-vez-japon-critica-acciones-chinas-en-taiwan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Por primera vez, Jap\u00f3n critica acciones chinas en Taiw\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2021\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/Yoshihide-Suga.jpg?fit=678%2C381&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":9002,"url":"https:\/\/informatepy.com\/2021\/2021\/12\/25\/eeuu-y-japon-trazan-plan-militar-ante-un-eventual-ataque-de-china-a-taiwan\/","url_meta":{"origin":4565,"position":0},"title":"EEUU y Jap\u00f3n trazan plan militar ante un eventual ataque de China a Taiw\u00e1n","date":"25 de diciembre de 2021","format":false,"excerpt":"Aunque se trata de un plan preliminar, est\u00e1 previsto que ministros de ambos pa\u00edses lo formalicen a principios del pr\u00f3ximo a\u00f1o. Prev\u00e9 la instalaci\u00f3n de bases provisorias y la colaboraci\u00f3n log\u00edstica","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/ejercitos-usa-japon.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12079,"url":"https:\/\/informatepy.com\/2021\/2022\/06\/11\/para-el-financial-times-china-se-prepara-para-invadir-taiwan\/","url_meta":{"origin":4565,"position":1},"title":"Para el Financial Times China se prepara para invadir Taiw\u00e1n","date":"11 de junio de 2022","format":false,"excerpt":"Para el diario brit\u00e1nico Financial Times, es inminente una invasi\u00f3n de China hacia la isla de Taiw\u00e1n. \u00bfXI Jinping inspirado por la invasi\u00f3n a Ucrania?","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/ejercito-china.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10579,"url":"https:\/\/informatepy.com\/2021\/2022\/03\/13\/biden-prohibe-utilizar-mapas-que-muestren-a-taiwan-como-parte-de-china-comunista\/","url_meta":{"origin":4565,"position":2},"title":"Biden proh\u00edbe utilizar mapas que muestren a Taiw\u00e1n como parte de China comunista","date":"13 de marzo de 2022","format":false,"excerpt":"El presidente de los Estados Unidos, Joe Biden, firm\u00f3 un nuevo proyecto de ley en el que proh\u00edbe la utilizaci\u00f3n de mapas \"inexactos\" que muestren a la Rep\u00fablica de China Taiw\u00e1n como parte de China comunista por parte del Departamento de Estado y sus operaciones en el extranjero. El proyecto\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/Taiwan-China.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11769,"url":"https:\/\/informatepy.com\/2021\/2022\/05\/24\/china-amenaza-a-estados-unidos-por-su-compromiso-de-defender-a-taiwan\/","url_meta":{"origin":4565,"position":3},"title":"China amenaza a Estados Unidos por su compromiso de defender a Taiw\u00e1n","date":"24 de mayo de 2022","format":false,"excerpt":"La Oficina de Asuntos\u00a0de Taiw\u00e1n del Consejo de Estado\u00a0chino afirm\u00f3 que Estados Unidos est\u00e1 \u201cjugando con fuego\u201d, luego de que el presidente Joe Biden prometiera defender la isla aut\u00f3noma en caso de que Beijing intente tomar el control. Estados Unidos est\u00e1 \u201cusando la 'tarjeta de Taiw\u00e1n' para contener a China\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/china-estados-unidos.jpg?fit=1024%2C680&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4657,"url":"https:\/\/informatepy.com\/2021\/2021\/04\/27\/australia-evalua-opciones-militares-en-caso-de-que-china-invada-taiwan\/","url_meta":{"origin":4565,"position":4},"title":"Australia eval\u00faa opciones militares en caso de que China invada Taiw\u00e1n","date":"27 de abril de 2021","format":false,"excerpt":"A instancias de la administraci\u00f3n Biden, el gobierno australiano y el ej\u00e9rcito del pa\u00eds est\u00e1n trabajando intensamente con Estados Unidos para aumentar sus preparativos para lo que podr\u00eda ser una guerra contra China por el control de Taiw\u00e1n. Los planes situar\u00edan a las fuerzas australianas en la primera l\u00ednea de\u2026","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/fuerza-aerea-australiana.jpg?fit=1200%2C676&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5525,"url":"https:\/\/informatepy.com\/2021\/2021\/06\/30\/viceministro-de-defensa-japones-habla-de-la-necesidad-de-despertar-para-proteger-a-taiwan\/","url_meta":{"origin":4565,"position":5},"title":"Viceministro de Defensa japon\u00e9s habla de la necesidad de \u00abdespertar\u00bb para proteger a Taiw\u00e1n","date":"30 de junio de 2021","format":false,"excerpt":"El viceministro de Defensa de Jap\u00f3n advirti\u00f3 el lunes sobre una creciente amenaza que representa la colaboraci\u00f3n entre China y Rusia y dijo que era necesario \"despertar\" a la presi\u00f3n de Pek\u00edn sobre Taiw\u00e1n y proteger la isla \"como un pa\u00eds democr\u00e1tico\". En declaraciones al grupo de expertos del Instituto\u2026","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/Yasuhide-Nakayama.jpg?fit=1024%2C682&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1051,"user_id":4,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/4565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=4565"}],"version-history":[{"count":2,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/4565\/revisions"}],"predecessor-version":[{"id":4569,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/4565\/revisions\/4569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/4566"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=4565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=4565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=4565"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=4565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}