{"id":455,"date":"2019-02-10T20:19:00","date_gmt":"2019-02-10T20:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=455"},"modified":"2021-02-10T14:55:41","modified_gmt":"2021-02-10T14:55:41","slug":"juez-argentino-proceso-a-92-intendentes","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/02\/10\/juez-argentino-proceso-a-92-intendentes\/","title":{"rendered":"Juez Argentino proces\u00f3 a 92 intendentes"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\n\nEl juez&nbsp;<strong>Claudio Bonadio<\/strong>&nbsp;dispuso este jueves (07\/02) el procesamiento de casi un centenar de intendentes de todo el pa\u00eds, en el marco de una causa que investiga la malversaci\u00f3n de las arcas del Tesoro entre 2013 y 2015 para que distintas municipalidades llevaran adelante tratamientos de residuos s\u00f3lidos urbanos, es decir, la basura que se genera en cada casa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la causa ya estaban procesados los ex jefes de Gabinete&nbsp;<strong>An\u00edbal Fern\u00e1ndez, Jorge Capitanich&nbsp;<\/strong>y<strong>&nbsp;Juan Abal Medina<\/strong>, as\u00ed como otros tres ex secretarios de Ambiente durante el kirchnerismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora, el juez Bonadio resolvi\u00f3 procesar a 92 intendentes de distintas comunas, entre los que se encuentran&nbsp;<strong>Francisco \u00abBarba\u00bb Guti\u00e9rrez<\/strong>&nbsp;y<strong>Francisco \u00abPaco\u00bb Dura\u00f1ona<\/strong>. <a href=\"https:\/\/twitter.com\/pjprovinciaba\/status\/1093962395771383810\/photo\/1\">Ver imagen en Twitter<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/twitter.com\/pjprovinciaba\/status\/1093962395771383810\/photo\/1\"><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/Dy6I_XjWsAIhP13?format=jpg&amp;name=small\" alt=\"Ver imagen en Twitter\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/twitter.com\/pjprovinciaba\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/naUbmxPO_normal.jpg?w=740&#038;ssl=1\" alt=\"\" data-recalc-dims=\"1\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/twitter.com\/pjprovinciaba\"><strong>Partido Justicialista de la Provincia de Bs As<\/strong>@pjprovinciaba<\/a><a href=\"https:\/\/twitter.com\/pjprovinciaba\/status\/1093962395771383810\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el <a href=\"https:\/\/twitter.com\/pjprovinciaba\">@pjprovinciaba<\/a> ratificamos nuestra preocupaci\u00f3n ante una nueva ofensiva judicial por parte del Gobierno, en este caso hacia intendentes peronistas, que no constituye una acci\u00f3n aislada, sino que deja en evidencia c\u00f3mo opera la maquinaria electoral de Cambiemos.<a href=\"https:\/\/twitter.com\/hashtag\/PJ2019?src=hash\">#PJ2019<\/a><a href=\"https:\/\/twitter.com\/intent\/like?tweet_id=1093962395771383810\">142<\/a><a href=\"https:\/\/twitter.com\/pjprovinciaba\/status\/1093962395771383810\">16:58 &#8211; 8 feb. 2019<\/a><a href=\"https:\/\/twitter.com\/pjprovinciaba\/status\/1093962395771383810\">102 personas est\u00e1n hablando de esto<\/a><a href=\"https:\/\/support.twitter.com\/articles\/20175256\">Informaci\u00f3n y privacidad de Twitter Ads<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8212;&#8212;&#8212;&#8212;&#8212;-<br><br>Los procesados fueron embargados por 3 millones de pesos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los procesamientos se dan en el marco de una megacausa de medio ambiente que investiga qu\u00e9 pas\u00f3 con los 600 millones de pesos que se les dieron a las municipalidades para llevar adelante la Gesti\u00f3n Integral de Residuos S\u00f3lidos (GIRSU). El juez busca averiguar si los intendentes beneficiados con esos fondos lo destinaron a obras o en qu\u00e9 lo invirtieron. &nbsp;<br><br><em>\u00abCada intendente con su accionar contribuy\u00f3 activamente en la concreci\u00f3n de un perjuicio a las arcas del Estado, aproximadamente de una suma aproximada de $604.529.670,00. Maniobra que habr\u00edan llevado a cabo junto a las autoridades nacionales anteriormente procesadas por este Tribunal, y cuyas conductas fueron valoradas \u00adrespecto de la mayor\u00eda\u00ad de igual manera por la Alzada\u00bb<\/em>, sostuvo la resoluci\u00f3n a la que accedi\u00f3 Infobae.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Justamente, antes de que se conociera la decisi\u00f3n de Bonadio, el Partido Justicialista de la provincia de Buenos Aires emiti\u00f3 un duro comunicado para repudiar \u201c<em>las versiones de extorsi\u00f3n a intendentes peronistas como parte de una presunta estrategia electoral de Cambiemos. Los \u2018carpetazos\u2019 y falsas denuncias p\u00fablicas que carecen de sustento jur\u00eddico son un mecanismo que atenta contra la democracia y que est\u00e1 muy lejos de la premisa que prometi\u00f3 el propio Gobierno: consolidar una Justicia libre e independiente\u201d.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cSi Dur\u00e1n Barba ve que a Cambiemos no le dan los n\u00fameros, tendr\u00eda que hacer una autocr\u00edtica y no apelar al enga\u00f1o, como ya hizo en 2015 y 2017, para sostener un modelo que es, justamente, insostenible. El rechazo hacia el Gobierno no es por otra cosa que por su propia incapacidad. Con m\u00e1s de 210 mil despidos en 11 meses, la p\u00e9rdida del salario real m\u00e1s alta desde 2002 y una inflaci\u00f3n acumulada del 145%, lo esperable ser\u00eda que concentren toda su energ\u00eda en buscar herramientas para paliar y resolver el desastre social y econ\u00f3mico al que est\u00e1n condenando a las argentinas y los argentinos\u201d<\/em>, a\u00f1ade.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cLos y las bonaerenses est\u00e1n hartos de pagar tarifazos imposibles; de sufrir constantemente cortes de suministro de agua y luz porque las empresas prestadoras, a quienes el Gobierno les autoriza subas rid\u00edculas, no invierten ni dan respuesta; de vivir con angustia porque no llegan a fin de mes y temen perder su empleo. Les pedimos a los funcionarios de Cambiemos que construyan gobernabilidad ocup\u00e1ndose de lo que realmente le duele y preocupa a la gente de la Provincia y de toda la Argentina, y que dejen de intentar hacer da\u00f1o con mentiras a intendentes que junto a las organizaciones sociales hoy son quienes ponen la cara todos los d\u00edas y contienen los efectos de la crisis para que no sea a\u00fan peor<\/em>\u201d, completa el comunicado.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los intendentes que quedaron procesados son:&nbsp;<strong>Claudia Panzardi, Mateo Daniel Capitanich, Gustavo Karasiuk, \u00c1ngel Ernesto Gonz\u00e1lez, Francisco Winnik, Alfredo Pastor, Gustavo Steven, Carlos Andion, Hugo Sager, Walter Corra, Alicia Leiva, Eladio Aguirre, Elba Lescano, Jorge Batalla, Aldo Leiva, Mar\u00eda Susana Simonofsky, Gerado Cipolini, Jorge Rodr\u00edguez, Oscar Nievas, Jos\u00e9 Carbajal, Carlos Palacios, Pedro Bodnarczuk, Lorenzo Heffner, H\u00e9ctor Vega, Carlos Ib\u00e1\u00f1ez, Pedro Maidana, Antonio Jos\u00e9 Rodas, Estela Mitore, Di\u00f3genes Requena, Rosario Belkys Avalos, Alfredo Zamora, Ra\u00fal Cant\u00edn, Jos\u00e9 C\u00f3rdoba, Teodoro Camino, Jos\u00e9 Bodlovic, Horacio Mazu, Rafel Williams, Pablo Salazar, Gustavo Racca, Roberto Dehesa, Monica Stumpo, Jos\u00e9 Freyre, H\u00e9ctor Godoy, Jos\u00e9 L\u00f3pez, Juan Carlos Bacalini, Gullermo Cornaglia, Fernando Almada, Cesar Dip, Juan Orellana, Julio Castro, Rodolfo Cappellini, Luis Erro, Juan Carlos Kloss, Rub\u00e9n V\u00e1zquez, Jos\u00e9 Luis Dume, Luis Stanicia, Alberto Escudero, Juan Manuel Pereyra, Eduardo Galantini, Ernesto Dom\u00ednguez, Hermes Bordon&nbsp;<\/strong>y<strong>&nbsp;Federico Neis<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El juez incluy\u00f3 tambi\u00e9n a&nbsp;<strong>Juan Ram\u00f3n Barrionuevo, Jos\u00e9 Inza, Pablo Zurro, Alberto Conocchiari, Mar\u00eda Gianini de Lafleur, Ricardo Casi, Walter Torchio, Gast\u00f3n Arias, N\u00e9stor \u00c1lvarez, Diana Arguello, H\u00e9ctor Olivera, Oscar Ostoich, Jorge Eijo, Mart\u00edn Caso, Gustavo Walker, Gustavo Trankels, Marcos Luis Fern\u00e1ndez, Francisco Iribarren, Enrique Tkacik, Marta M\u00e9dici, Curetti Ricardo&nbsp;<\/strong>y<strong>&nbsp;Alfredo Fisher.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, la n\u00f3mina de procesados agreg\u00f3 a<strong>&nbsp;Jos\u00e9 Medina, Marcelo Skansi, Carlos Racciatti, Juan Carlos Bartoletti, Gusatavo Cocconi, Francisco Echarren, Francisco Dura\u00f1ona<\/strong><strong>y Vedia&nbsp;<\/strong>y<strong>&nbsp;Francisco Guti\u00e9rrez.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto, dict\u00f3 el sobreseimiento de&nbsp;<strong>Omar Goye, Nancy Sand Giorasi&nbsp;<\/strong>y<strong>Carlos Espinola<\/strong>, mientras que recibi\u00f3 la falta de m\u00e9rito&nbsp;<strong>Ricardo Moccero<\/strong>.\n\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El juez&nbsp;Claudio Bonadio&nbsp;dispuso este jueves (07\/02) el procesamiento de casi un centenar de intendentes de todo el pa\u00eds, en el marco de una causa que investiga la malversaci\u00f3n de las arcas del Tesoro entre 2013 y 2015 para que distintas municipalidades llevaran adelante tratamientos de residuos s\u00f3lidos urbanos, es decir, la basura que se genera [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":456,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[173],"tags":[240,241,242,243,244,245,246,247],"ppma_author":[1039],"class_list":["post-455","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","tag-cfk","tag-claudio-bonadio","tag-corrupcion","tag-juez-bonadio","tag-kircherismo","tag-kirchner","tag-peronismo","tag-pj"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Juez Argentino proces\u00f3 a 92 intendentes - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/02\/10\/juez-argentino-proceso-a-92-intendentes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Juez Argentino proces\u00f3 a 92 intendentes - Informatepy\" \/>\n<meta property=\"og:description\" content=\"El juez&nbsp;Claudio Bonadio&nbsp;dispuso este jueves (07\/02) el procesamiento de casi un centenar de intendentes de todo el pa\u00eds, en el marco de una causa que investiga la malversaci\u00f3n de las arcas del Tesoro entre 2013 y 2015 para que distintas municipalidades llevaran adelante tratamientos de residuos s\u00f3lidos urbanos, es decir, la basura que se genera [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/02\/10\/juez-argentino-proceso-a-92-intendentes\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-10T20:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-10T14:55:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/claudio-bonadio.jpg?fit=728%2C500&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"728\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/10\\\/juez-argentino-proceso-a-92-intendentes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/10\\\/juez-argentino-proceso-a-92-intendentes\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"Juez Argentino proces\u00f3 a 92 intendentes\",\"datePublished\":\"2019-02-10T20:19:00+00:00\",\"dateModified\":\"2021-02-10T14:55:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/10\\\/juez-argentino-proceso-a-92-intendentes\\\/\"},\"wordCount\":951,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/10\\\/juez-argentino-proceso-a-92-intendentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/claudio-bonadio.jpg?fit=728%2C500&ssl=1\",\"keywords\":[\"cfk\",\"claudio bonadio\",\"corrupcion\",\"juez bonadio\",\"kircherismo\",\"kirchner\",\"peronismo\",\"pj\"],\"articleSection\":[\"Mundo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/10\\\/juez-argentino-proceso-a-92-intendentes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/10\\\/juez-argentino-proceso-a-92-intendentes\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/10\\\/juez-argentino-proceso-a-92-intendentes\\\/\",\"name\":\"Juez Argentino proces\u00f3 a 92 intendentes - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/10\\\/juez-argentino-proceso-a-92-intendentes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/10\\\/juez-argentino-proceso-a-92-intendentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/claudio-bonadio.jpg?fit=728%2C500&ssl=1\",\"datePublished\":\"2019-02-10T20:19:00+00:00\",\"dateModified\":\"2021-02-10T14:55:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/10\\\/juez-argentino-proceso-a-92-intendentes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/10\\\/juez-argentino-proceso-a-92-intendentes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/10\\\/juez-argentino-proceso-a-92-intendentes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/claudio-bonadio.jpg?fit=728%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/claudio-bonadio.jpg?fit=728%2C500&ssl=1\",\"width\":728,\"height\":500,\"caption\":\"Juez Federal Claudio Bonad\u00edo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/02\\\/10\\\/juez-argentino-proceso-a-92-intendentes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Juez Argentino proces\u00f3 a 92 intendentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Juez Argentino proces\u00f3 a 92 intendentes - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/02\/10\/juez-argentino-proceso-a-92-intendentes\/","og_locale":"es_ES","og_type":"article","og_title":"Juez Argentino proces\u00f3 a 92 intendentes - Informatepy","og_description":"El juez&nbsp;Claudio Bonadio&nbsp;dispuso este jueves (07\/02) el procesamiento de casi un centenar de intendentes de todo el pa\u00eds, en el marco de una causa que investiga la malversaci\u00f3n de las arcas del Tesoro entre 2013 y 2015 para que distintas municipalidades llevaran adelante tratamientos de residuos s\u00f3lidos urbanos, es decir, la basura que se genera [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2019\/02\/10\/juez-argentino-proceso-a-92-intendentes\/","og_site_name":"Informatepy","article_published_time":"2019-02-10T20:19:00+00:00","article_modified_time":"2021-02-10T14:55:41+00:00","og_image":[{"width":728,"height":500,"url":"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/claudio-bonadio.jpg?fit=728%2C500&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/02\/10\/juez-argentino-proceso-a-92-intendentes\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/10\/juez-argentino-proceso-a-92-intendentes\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"Juez Argentino proces\u00f3 a 92 intendentes","datePublished":"2019-02-10T20:19:00+00:00","dateModified":"2021-02-10T14:55:41+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/10\/juez-argentino-proceso-a-92-intendentes\/"},"wordCount":951,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/10\/juez-argentino-proceso-a-92-intendentes\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/claudio-bonadio.jpg?fit=728%2C500&ssl=1","keywords":["cfk","claudio bonadio","corrupcion","juez bonadio","kircherismo","kirchner","peronismo","pj"],"articleSection":["Mundo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/02\/10\/juez-argentino-proceso-a-92-intendentes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/02\/10\/juez-argentino-proceso-a-92-intendentes\/","url":"https:\/\/informatepy.com\/2021\/2019\/02\/10\/juez-argentino-proceso-a-92-intendentes\/","name":"Juez Argentino proces\u00f3 a 92 intendentes - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/10\/juez-argentino-proceso-a-92-intendentes\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/10\/juez-argentino-proceso-a-92-intendentes\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/claudio-bonadio.jpg?fit=728%2C500&ssl=1","datePublished":"2019-02-10T20:19:00+00:00","dateModified":"2021-02-10T14:55:41+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/02\/10\/juez-argentino-proceso-a-92-intendentes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/02\/10\/juez-argentino-proceso-a-92-intendentes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/02\/10\/juez-argentino-proceso-a-92-intendentes\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/claudio-bonadio.jpg?fit=728%2C500&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/claudio-bonadio.jpg?fit=728%2C500&ssl=1","width":728,"height":500,"caption":"Juez Federal Claudio Bonad\u00edo"},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/02\/10\/juez-argentino-proceso-a-92-intendentes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Juez Argentino proces\u00f3 a 92 intendentes"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/claudio-bonadio.jpg?fit=728%2C500&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":7791,"url":"https:\/\/informatepy.com\/2021\/2021\/10\/18\/juez-suspende-preliminar-para-ex-titular-de-la-dinac-en-el-caso-de-los-tapabocas-de-oro\/","url_meta":{"origin":455,"position":0},"title":"Juez suspende preliminar para ex titular de la Dinac en el caso de los tapabocas de oro","date":"18 de octubre de 2021","format":false,"excerpt":"El juez penal de Garant\u00edas Gustavo Amarilla decidi\u00f3 suspendi\u00f3 la audiencia preliminar para el ex presidente de la Dinac, \u00c9dgar Melgarejo","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/edgard-melgarejo.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8612,"url":"https:\/\/informatepy.com\/2021\/2021\/12\/02\/nueva-chicana-de-mario-ferreiro-en-la-causa-por-recaudacion-paralela\/","url_meta":{"origin":455,"position":1},"title":"Nueva chicana de Mario Ferreiro en la causa por recaudaci\u00f3n paralela","date":"2 de diciembre de 2021","format":false,"excerpt":"El destituido intendente de Asunci\u00f3n, Mario Ferreiro, volvi\u00f3 a suspender ayer la audiencia preliminar prevista en el caso de la caja paralela en la Municipalidad de Asunci\u00f3n. La audiencia que estaba a cargo a la jueza Alicia Pedrozo, quien no tuvo otra opci\u00f3n que suspenderla tras haber recibido un certificado\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/mario-ferreiro-meme.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1022,"url":"https:\/\/informatepy.com\/2021\/2019\/04\/14\/intendente-de-ypane-denunciado-por-violencia-familiar\/","url_meta":{"origin":455,"position":2},"title":"Intendente de Ypan\u00e9 denunciado por violencia familiar","date":"14 de abril de 2019","format":false,"excerpt":"La v\u00edctima es Natalia Sosa, con quien, Ortiz Albrecht manten\u00eda hasta hace poco una relaci\u00f3n sentimental de m\u00e1s de cuatro a\u00f1os. Refiere Sosa que el intendente de Ypan\u00e9 comenz\u00f3 a maltratarla poco despu\u00e9s de haber formalizado la relaci\u00f3n, aunque sin llegar a los golpes. Pero a partir de noviembre del\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/Horacio-Ortiz-Albrecht.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":7152,"url":"https:\/\/informatepy.com\/2021\/2021\/09\/15\/jueces-con-temor-a-una-tapa-de-abc-deberian-ser-removidos-de-su-cargo\/","url_meta":{"origin":455,"position":3},"title":"Jueces con temor a una tapa de ABC deber\u00edan ser removidos de su cargo","date":"15 de septiembre de 2021","format":false,"excerpt":"Se suspendi\u00f3 el juicio oral y p\u00fablico del periodista de Abc Color, Juan Carlos Lezcano, querellado por difamaci\u00f3n, calumnia e injuria por el exsenador liberal Dionisio Amarilla Guirland.","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/09\/juanki-lezcano.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4939,"url":"https:\/\/informatepy.com\/2021\/2021\/05\/17\/parlasuriano-del-plra-e-intendente-de-la-anr-seran-juzgados-por-negocios-irregulares-con-el-indert\/","url_meta":{"origin":455,"position":4},"title":"Parlasuriano del PLRA e intendente de la ANR ser\u00e1n juzgados por negocios irregulares con el INDERT","date":"17 de mayo de 2021","format":false,"excerpt":"El Tribunal de Apelaciones anul\u00f3 la absoluci\u00f3n del parlasuriano Milciades Dur\u00e9 del Partido Liberal Radical Aut\u00e9ntico, y del intendente de Iru\u00f1a, Justo Gamarra de la Asociaci\u00f3n Nacional Republicana. De esta manera, el tribunal orden\u00f3 la realizaci\u00f3n de un nuevo juicio oral por la compra irregular de tierras de San Agust\u00edn\u2026","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/pedro-milciades-dure.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9440,"url":"https:\/\/informatepy.com\/2021\/2022\/01\/14\/fiscalia-recusara-al-juez-de-la-causa-de-rgd-por-llamarlo-a-declarar-antes-de-la-indagatoria\/","url_meta":{"origin":455,"position":5},"title":"Fiscal\u00eda recusar\u00e1 al juez de la causa de RGD por llamarlo a declarar antes de la indagatoria","date":"14 de enero de 2022","format":false,"excerpt":"La fiscal Sandra Ledesma denunci\u00f3 que el juez Civil Enrique Sanabria convoc\u00f3 a Ram\u00f3n Gonz\u00e1lez Daher a declarar, lo que es totalmente irregular ya que ella todav\u00eda no tom\u00f3 la declaraci\u00f3n indagatoria al imputado. Por esa raz\u00f3n la agente adelant\u00f3 que recusar\u00e1 al magistrado ante la gravedad del hecho. No\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/01\/ramon-gonzalez-daher.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=455"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/455\/revisions"}],"predecessor-version":[{"id":3185,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/455\/revisions\/3185"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/456"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=455"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}