{"id":426,"date":"2017-07-09T20:17:00","date_gmt":"2017-07-09T20:17:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=426"},"modified":"2021-02-08T23:19:50","modified_gmt":"2021-02-08T23:19:50","slug":"arrestan-a-estrella-de-hollywood","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/arrestan-a-estrella-de-hollywood\/","title":{"rendered":"Arrestan a estrella de Hollywood"},"content":{"rendered":"<p>El actor Shia LaBeouf fue arrestado el s\u00e1bado por ebriedad en la v\u00eda p\u00fablica en Georgia, pero fue puesto en libertad luego de pagar una fianza de 7.000 d\u00f3lares, informaron las autoridades.<\/p>\n<p>La polic\u00eda del condado de Chatham dijo que el actor de 31 a\u00f1os fue arrestado a las cuatro de la ma\u00f1ana la polic\u00eda de Savannah.<\/p>\n<p>Adem\u00e1s del cargo por ebriedad, tambi\u00e9n fue arrestado por alteraci\u00f3n del orden p\u00fablico y obstrucci\u00f3n de la justicia.<\/p>\n<p>La polic\u00eda dijo que LaBeouf pidi\u00f3 un cigarrillo a una persona que estaba pasando y que cuando \u00e9sta se neg\u00f3, el actor se alter\u00f3 y utiliz\u00f3 \u201clenguaje inapropiado y groser\u00edas delante de mujeres y ni\u00f1os que estaban presentes\u201d.<\/p>\n<p>Cuando se le pidi\u00f3 que se retirara, el actor se rehus\u00f3 y se volvi\u00f3 agresivo hacia un agente, inform\u00f3 la polic\u00eda. Despu\u00e9s corri\u00f3 hacia un hotel cercano para evitar ser arrestado.<\/p>\n<p>No es el primer encontronazo que tiene con la ley: En 2008, recibi\u00f3 un llamado de atenci\u00f3n por conducir ebrio en West Hollywood. En 2014 compareci\u00f3 ante un tribunal, acusado de penetrar en propiedad ajena y conducta desordenada luego de perturbar una representaci\u00f3n del musical de Broadway \u201cCabaret\u201d. En enero de 2017, el actor fue detenido por agresi\u00f3n tras protagonizar un momento de tensi\u00f3n cuando un partidario de la \u201csupremac\u00eda blanca\u201d intent\u00f3 boicotear su protesta contra Donald Trump.<\/p>\n<p>El actor se encuentra en el estado de Georgia filmando la cinta \u201cThe Peanut Butter Falcon\u201d en la ciudad de Savannah junto a Dakota Johnson y Bruce Dern.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El actor Shia LaBeouf fue arrestado el s\u00e1bado por ebriedad en la v\u00eda p\u00fablica en Georgia, pero fue puesto en libertad luego de pagar una fianza de 7.000 d\u00f3lares, informaron las autoridades. La polic\u00eda del condado de Chatham dijo que el actor de 31 a\u00f1os fue arrestado a las cuatro de la ma\u00f1ana la polic\u00eda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":427,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[202],"tags":[203,204],"ppma_author":[1039],"class_list":["post-426","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-show","tag-hollywood","tag-shia-labeouf"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arrestan a estrella de Hollywood - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2017\/07\/09\/arrestan-a-estrella-de-hollywood\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arrestan a estrella de Hollywood - Informatepy\" \/>\n<meta property=\"og:description\" content=\"El actor Shia LaBeouf fue arrestado el s\u00e1bado por ebriedad en la v\u00eda p\u00fablica en Georgia, pero fue puesto en libertad luego de pagar una fianza de 7.000 d\u00f3lares, informaron las autoridades. La polic\u00eda del condado de Chatham dijo que el actor de 31 a\u00f1os fue arrestado a las cuatro de la ma\u00f1ana la polic\u00eda [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2017\/07\/09\/arrestan-a-estrella-de-hollywood\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-09T20:17:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-08T23:19:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/LaBeouf.jpg?fit=630%2C433&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"433\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2017\\\/07\\\/09\\\/arrestan-a-estrella-de-hollywood\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2017\\\/07\\\/09\\\/arrestan-a-estrella-de-hollywood\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"Arrestan a estrella de Hollywood\",\"datePublished\":\"2017-07-09T20:17:00+00:00\",\"dateModified\":\"2021-02-08T23:19:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2017\\\/07\\\/09\\\/arrestan-a-estrella-de-hollywood\\\/\"},\"wordCount\":273,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2017\\\/07\\\/09\\\/arrestan-a-estrella-de-hollywood\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/LaBeouf.jpg?fit=630%2C433&ssl=1\",\"keywords\":[\"hollywood\",\"Shia LaBeouf\"],\"articleSection\":[\"Show\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2017\\\/07\\\/09\\\/arrestan-a-estrella-de-hollywood\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2017\\\/07\\\/09\\\/arrestan-a-estrella-de-hollywood\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2017\\\/07\\\/09\\\/arrestan-a-estrella-de-hollywood\\\/\",\"name\":\"Arrestan a estrella de Hollywood - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2017\\\/07\\\/09\\\/arrestan-a-estrella-de-hollywood\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2017\\\/07\\\/09\\\/arrestan-a-estrella-de-hollywood\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/LaBeouf.jpg?fit=630%2C433&ssl=1\",\"datePublished\":\"2017-07-09T20:17:00+00:00\",\"dateModified\":\"2021-02-08T23:19:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2017\\\/07\\\/09\\\/arrestan-a-estrella-de-hollywood\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2017\\\/07\\\/09\\\/arrestan-a-estrella-de-hollywood\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2017\\\/07\\\/09\\\/arrestan-a-estrella-de-hollywood\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/LaBeouf.jpg?fit=630%2C433&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/LaBeouf.jpg?fit=630%2C433&ssl=1\",\"width\":630,\"height\":433},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2017\\\/07\\\/09\\\/arrestan-a-estrella-de-hollywood\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arrestan a estrella de Hollywood\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arrestan a estrella de Hollywood - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/arrestan-a-estrella-de-hollywood\/","og_locale":"es_ES","og_type":"article","og_title":"Arrestan a estrella de Hollywood - Informatepy","og_description":"El actor Shia LaBeouf fue arrestado el s\u00e1bado por ebriedad en la v\u00eda p\u00fablica en Georgia, pero fue puesto en libertad luego de pagar una fianza de 7.000 d\u00f3lares, informaron las autoridades. La polic\u00eda del condado de Chatham dijo que el actor de 31 a\u00f1os fue arrestado a las cuatro de la ma\u00f1ana la polic\u00eda [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/arrestan-a-estrella-de-hollywood\/","og_site_name":"Informatepy","article_published_time":"2017-07-09T20:17:00+00:00","article_modified_time":"2021-02-08T23:19:50+00:00","og_image":[{"width":630,"height":433,"url":"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/LaBeouf.jpg?fit=630%2C433&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/arrestan-a-estrella-de-hollywood\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/arrestan-a-estrella-de-hollywood\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"Arrestan a estrella de Hollywood","datePublished":"2017-07-09T20:17:00+00:00","dateModified":"2021-02-08T23:19:50+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/arrestan-a-estrella-de-hollywood\/"},"wordCount":273,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/arrestan-a-estrella-de-hollywood\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/LaBeouf.jpg?fit=630%2C433&ssl=1","keywords":["hollywood","Shia LaBeouf"],"articleSection":["Show"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2017\/07\/09\/arrestan-a-estrella-de-hollywood\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/arrestan-a-estrella-de-hollywood\/","url":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/arrestan-a-estrella-de-hollywood\/","name":"Arrestan a estrella de Hollywood - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/arrestan-a-estrella-de-hollywood\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/arrestan-a-estrella-de-hollywood\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/LaBeouf.jpg?fit=630%2C433&ssl=1","datePublished":"2017-07-09T20:17:00+00:00","dateModified":"2021-02-08T23:19:50+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/arrestan-a-estrella-de-hollywood\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2017\/07\/09\/arrestan-a-estrella-de-hollywood\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/arrestan-a-estrella-de-hollywood\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/LaBeouf.jpg?fit=630%2C433&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/LaBeouf.jpg?fit=630%2C433&ssl=1","width":630,"height":433},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/arrestan-a-estrella-de-hollywood\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Arrestan a estrella de Hollywood"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/LaBeouf.jpg?fit=630%2C433&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":13948,"url":"https:\/\/informatepy.com\/2021\/2022\/09\/16\/son-sus-costumbres-mujer-muere-despues-de-ser-golpeada-por-la-temida-policia-moral-de-iran-por-usar-el-hiyab-incorrectamente\/","url_meta":{"origin":426,"position":0},"title":"Son sus costumbres: Mujer muere despu\u00e9s de ser golpeada por la temida polic\u00eda moral de Ir\u00e1n por \u00abusar el hiyab incorrectamente\u00bb","date":"16 de septiembre de 2022","format":false,"excerpt":"Mahsa Amini, de 22 a\u00f1os, fue declarada con muerte cerebral despu\u00e9s de que, seg\u00fan los informes, la polic\u00eda la golpeara hasta dejarla en coma el martes. La joven hab\u00eda viajado desde la provincia occidental de Kurdist\u00e1n para ver a familiares en la capital,\u00a0Teher\u00e1n\u00a0y, seg\u00fan la polic\u00eda, Mahsa no sigui\u00f3 las\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/09\/mahsa-amini.jpg?fit=1200%2C736&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11766,"url":"https:\/\/informatepy.com\/2021\/2022\/05\/24\/espana-arresta-a-periodista-y-politico-ucraniano-por-escribir-en-contra-de-zelensky\/","url_meta":{"origin":426,"position":1},"title":"Espa\u00f1a arresta a periodista y pol\u00edtico ucraniano por escribir en contra de Zelensky","date":"24 de mayo de 2022","format":false,"excerpt":"La\u00a0Polic\u00eda Nacional espa\u00f1ola\u00a0detuvo en Tarragona al bloguero y pol\u00edtico ucraniano\u00a0Anatoli Shar\u00ed, acusado por Ucrania de \u201calta traici\u00f3n\u201d y \u201cviolaci\u00f3n de la seguridad nacional\u201d por sus\u00a0posiciones \"pro-rusas\". Despu\u00e9s de declarar en la Audiencia Nacional,\u00a0Shar\u00ed qued\u00f3 en libertad condicional con medidas cautelares\u00a0y queda a la espera de que se decida si ser\u00e1\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/05\/anatoli-shari.jpeg?fit=1200%2C634&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":7816,"url":"https:\/\/informatepy.com\/2021\/2021\/10\/19\/arresten-a-bill-gates-manifestantes-invaden-downing-street-durante-la-visita-del-filantropo\/","url_meta":{"origin":426,"position":2},"title":"\u00a1Arresten a Bill Gates!: Manifestantes invaden Downing Street durante la visita del \u00abfil\u00e1ntropo\u00bb","date":"19 de octubre de 2021","format":false,"excerpt":"Decenas de manifestantes bloquearon la carretera que conduce a Downing Street cuando el primer ministro Boris Johnson organiz\u00f3 una cena para las principales figuras empresariales internacionales para promover el Reino Unido global.","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/insultan-a-bill-gates-en-londres.webp?fit=590%2C350&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5003,"url":"https:\/\/informatepy.com\/2021\/2021\/05\/24\/gobierno-chino-arresta-a-un-obispo-7-sacerdotes-y-10-seminaristas\/","url_meta":{"origin":426,"position":3},"title":"Gobierno chino arresta a un obispo, 7 sacerdotes y 10 seminaristas","date":"24 de mayo de 2021","format":false,"excerpt":"El gobierno chino arrest\u00f3 a Mons. Joseph Zhang Weizhu, Obispo de Xianxian (China), as\u00ed como a siete sacerdotes y 10 seminaristas entre el 20 y el 21 de mayo.","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/papa-francisco-china.jpg?fit=1200%2C790&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12112,"url":"https:\/\/informatepy.com\/2021\/2022\/06\/12\/biden-y-su-democracia-al-estilo-nicaraguense-arresta-a-candidato-a-gobernador-del-partido-republicano\/","url_meta":{"origin":426,"position":4},"title":"Biden y su democracia al estilo nicaraguense: Arrestan a candidato a gobernador del Partido Republicano","date":"12 de junio de 2022","format":false,"excerpt":"Ryan Kelley, candidato a gobernador de Michigan por el Partido Republicano, fue arrestado este jueves por el FBI (Federal Bureau of Investigation) bajo la falsa premisa de que ingres\u00f3 al Capitolio y golpe\u00f3 polic\u00edas a pesar de que innumerables evidencias f\u00edlmicas hab\u00edan demostrado su inocencia. Ryan Kelley, quien era uno\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/ryan-kelley.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3977,"url":"https:\/\/informatepy.com\/2021\/2021\/03\/13\/formosa-argentina-gobernador-insfran-decreta-penas-de-arresto-a-quienes-se-manifiesten-o-abran-sus-comercios\/","url_meta":{"origin":426,"position":5},"title":"FORMOSA, ARGENTINA: Gobernador Insfr\u00e1n planea penas de arresto a quienes se manifiesten o abran sus comercios","date":"13 de marzo de 2021","format":false,"excerpt":"A pesar de los cuestionamientos a su accionar represivo en los \u00faltimos d\u00edas, y con la clara intenci\u00f3n de detener las protestas en su contra, el gobernador de Formosa (Argentina) firm\u00f3 un proyecto de ley que sancionar\u00e1 con arresto a quienes no cumplan las disposiciones sanitarias impuestas en esa provincia.\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/gildo-insfran.jpeg?fit=678%2C381&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=426"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/426\/revisions"}],"predecessor-version":[{"id":2864,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/426\/revisions\/2864"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/427"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=426"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}