{"id":414,"date":"2017-07-09T20:17:00","date_gmt":"2017-07-09T20:17:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=414"},"modified":"2021-02-08T23:21:08","modified_gmt":"2021-02-08T23:21:08","slug":"leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\/","title":{"rendered":"Leonel \u00c1lvarez: \u00abQueremos llevar a Cerro a lo m\u00e1s alto\u00bb"},"content":{"rendered":"<p>El DT, que firm\u00f3 contrato hasta diciembre de 2018 y que ya viene trabajando con el plantel azulgrana hace una semana, se mostr\u00f3 expectante y confiado ante este nuevo reto en su carrera.<\/p>\n<p>\u00abMuy ilusionado con el proyecto, esperamos estar a la altura de esta responsabilidad, de esta presi\u00f3n, porque siempre nos ha gustado tener presi\u00f3n\u00bb, dijo el estratega en conferencia de prensa.<\/p>\n<p>PROCESOS GANADORES. Leonel dej\u00f3 en claro que viene a buscar el \u00e9xito en el Cicl\u00f3n: \u00abLa idea es situar a Cerro en el lugar que se merece, y ganar t\u00edtulos, ha eso venimos, me gustan los procesos ganadores, queremos llevar a Cerro a lo m\u00e1s alto\u00bb, desliz\u00f3.<\/p>\n<p>Ante la consulta de c\u00f3mo encontr\u00f3 al plantel de jugadores, \u00c1lvarez indic\u00f3: \u00abEncontramos a los muchachos con una gran respuesta para trabajar, estamos bien, pero la idea es tener un equipo m\u00e1s competitivo\u00bb.<\/p>\n<p>El Cicl\u00f3n de Barrio Obrero se prepara para lo que ser\u00e1 su partido del martes por la Copa Sudamericana 2017, desde las 20.45 horas, ante el Boston River de Uruguay, en el estadio Defensores del Chaco. D10<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El DT, que firm\u00f3 contrato hasta diciembre de 2018 y que ya viene trabajando con el plantel azulgrana hace una semana, se mostr\u00f3 expectante y confiado ante este nuevo reto en su carrera. \u00abMuy ilusionado con el proyecto, esperamos estar a la altura de esta responsabilidad, de esta presi\u00f3n, porque siempre nos ha gustado tener [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":415,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[183],"tags":[186,187,188],"ppma_author":[1039],"class_list":["post-414","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-apf","tag-cerro-porteno","tag-leonel-alvarez"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Leonel \u00c1lvarez: &quot;Queremos llevar a Cerro a lo m\u00e1s alto&quot; - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2017\/07\/09\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leonel \u00c1lvarez: &quot;Queremos llevar a Cerro a lo m\u00e1s alto&quot; - Informatepy\" \/>\n<meta property=\"og:description\" content=\"El DT, que firm\u00f3 contrato hasta diciembre de 2018 y que ya viene trabajando con el plantel azulgrana hace una semana, se mostr\u00f3 expectante y confiado ante este nuevo reto en su carrera. \u00abMuy ilusionado con el proyecto, esperamos estar a la altura de esta responsabilidad, de esta presi\u00f3n, porque siempre nos ha gustado tener [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2017\/07\/09\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-09T20:17:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-08T23:21:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/LeonelAlvarez.jpg?fit=657%2C388&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"657\" \/>\n\t<meta property=\"og:image:height\" content=\"388\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2017\\\/07\\\/09\\\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2017\\\/07\\\/09\\\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"Leonel \u00c1lvarez: \u00abQueremos llevar a Cerro a lo m\u00e1s alto\u00bb\",\"datePublished\":\"2017-07-09T20:17:00+00:00\",\"dateModified\":\"2021-02-08T23:21:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2017\\\/07\\\/09\\\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\\\/\"},\"wordCount\":196,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2017\\\/07\\\/09\\\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/LeonelAlvarez.jpg?fit=657%2C388&ssl=1\",\"keywords\":[\"apf\",\"cerro porte\u00f1o\",\"leonel alvarez\"],\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2017\\\/07\\\/09\\\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2017\\\/07\\\/09\\\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2017\\\/07\\\/09\\\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\\\/\",\"name\":\"Leonel \u00c1lvarez: \\\"Queremos llevar a Cerro a lo m\u00e1s alto\\\" - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2017\\\/07\\\/09\\\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2017\\\/07\\\/09\\\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/LeonelAlvarez.jpg?fit=657%2C388&ssl=1\",\"datePublished\":\"2017-07-09T20:17:00+00:00\",\"dateModified\":\"2021-02-08T23:21:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2017\\\/07\\\/09\\\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2017\\\/07\\\/09\\\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2017\\\/07\\\/09\\\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/LeonelAlvarez.jpg?fit=657%2C388&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/LeonelAlvarez.jpg?fit=657%2C388&ssl=1\",\"width\":657,\"height\":388},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2017\\\/07\\\/09\\\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Leonel \u00c1lvarez: \u00abQueremos llevar a Cerro a lo m\u00e1s alto\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Leonel \u00c1lvarez: \"Queremos llevar a Cerro a lo m\u00e1s alto\" - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\/","og_locale":"es_ES","og_type":"article","og_title":"Leonel \u00c1lvarez: \"Queremos llevar a Cerro a lo m\u00e1s alto\" - Informatepy","og_description":"El DT, que firm\u00f3 contrato hasta diciembre de 2018 y que ya viene trabajando con el plantel azulgrana hace una semana, se mostr\u00f3 expectante y confiado ante este nuevo reto en su carrera. \u00abMuy ilusionado con el proyecto, esperamos estar a la altura de esta responsabilidad, de esta presi\u00f3n, porque siempre nos ha gustado tener [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\/","og_site_name":"Informatepy","article_published_time":"2017-07-09T20:17:00+00:00","article_modified_time":"2021-02-08T23:21:08+00:00","og_image":[{"width":657,"height":388,"url":"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/LeonelAlvarez.jpg?fit=657%2C388&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"Leonel \u00c1lvarez: \u00abQueremos llevar a Cerro a lo m\u00e1s alto\u00bb","datePublished":"2017-07-09T20:17:00+00:00","dateModified":"2021-02-08T23:21:08+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\/"},"wordCount":196,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/LeonelAlvarez.jpg?fit=657%2C388&ssl=1","keywords":["apf","cerro porte\u00f1o","leonel alvarez"],"articleSection":["Deportes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2017\/07\/09\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\/","url":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\/","name":"Leonel \u00c1lvarez: \"Queremos llevar a Cerro a lo m\u00e1s alto\" - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/LeonelAlvarez.jpg?fit=657%2C388&ssl=1","datePublished":"2017-07-09T20:17:00+00:00","dateModified":"2021-02-08T23:21:08+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2017\/07\/09\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/LeonelAlvarez.jpg?fit=657%2C388&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/LeonelAlvarez.jpg?fit=657%2C388&ssl=1","width":657,"height":388},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2017\/07\/09\/leonel-alvarez-queremos-llevar-a-cerro-a-lo-mas-alto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Leonel \u00c1lvarez: \u00abQueremos llevar a Cerro a lo m\u00e1s alto\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/LeonelAlvarez.jpg?fit=657%2C388&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":801,"url":"https:\/\/informatepy.com\/2021\/2019\/03\/08\/quien-es-jose-chamot\/","url_meta":{"origin":414,"position":0},"title":"\u00bfQui\u00e9n es Jos\u00e9 Chamot?","date":"8 de marzo de 2019","format":false,"excerpt":"Cuando se mencionaban a varios conocidos entrenadores para hacerse cargo de Libertad, apareci\u00f3 uno que no estaba en los planes. Jos\u00e9 Antonio Chamot es el nombre del flamante director t\u00e9cnico de los Repolleros. El ex futbolista de la selecci\u00f3n argentina es el elegido para reemplazar al colombiano Leonel de Jes\u00fas\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/Jose-Chamot.jpg?fit=590%2C440&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1277,"url":"https:\/\/informatepy.com\/2021\/2019\/06\/21\/sergio-diaz-vuelve-a-cerro-porteno\/","url_meta":{"origin":414,"position":1},"title":"Sergio D\u00edaz vuelve a Cerro Porte\u00f1o","date":"21 de junio de 2019","format":false,"excerpt":"Cerro Porte\u00f1o concret\u00f3 el regreso de Sergio D\u00edaz a Barrio Obrero para reforzar el plantel que tendr\u00e1 como desaf\u00edo, en el segundo semestre del a\u00f1o, el torneo Clausura, la Copa Paraguay y la llave de octavos de final de la Libertadores ante San Lorenzo de Almagro. El Chico D\u00edaz se\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/sergio-diaz-cerro-porteC3B1o.jpg?fit=631%2C547&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11342,"url":"https:\/\/informatepy.com\/2021\/2022\/04\/26\/feliz-cumpleanos-desbloqueo-de-listas-sabanas\/","url_meta":{"origin":414,"position":2},"title":"\u00a1Feliz Cumplea\u00f1os desbloqueo de listas s\u00e1banas!","date":"26 de abril de 2022","format":false,"excerpt":"Hace 20 a\u00f1os, un 25 de Abril del a\u00f1o 2002, el entonces candidato a la Presidencia de la Rep\u00fablica por el Partido Patria Querida, Pedro Fadul, iniciaba una \u201cCruzada contra los candidatos puestos a dedo\u201d, entregando al Congreso Nacional una carpeta con 70.000 firmas para desbloquear las listas cerradas de\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/sebastian-alvarez-analisis.png?fit=1200%2C656&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":14109,"url":"https:\/\/informatepy.com\/2021\/2022\/09\/28\/futsal-cerro-puso-huevo-y-clasifico-a-semis\/","url_meta":{"origin":414,"position":3},"title":"Futsal: Cerro \u201cpuso huevo\u201d y clasific\u00f3 a semis","date":"28 de septiembre de 2022","format":false,"excerpt":"El cicl\u00f3n de barrio obrero sac\u00f3 a relucir su jerarqu\u00eda en el futsal, y le pas\u00f3 por encima al Panta Walon de Per\u00fa en la copa libertadores de futsal con un contundente 4-1. Por los cuartos de final de la principal competencia continental de futsal, los azulgranas llegaban como favoritos\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/09\/cerro-futsal1.jpg?fit=1200%2C633&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1631,"url":"https:\/\/informatepy.com\/2021\/2019\/11\/24\/realmente-quieren-un-clasico-en-paz\/","url_meta":{"origin":414,"position":4},"title":"\u00bfRealmente quieren un cl\u00e1sico en paz?","date":"24 de noviembre de 2019","format":false,"excerpt":"\u00daltimo supercl\u00e1sico del a\u00f1o, Olimpia recibir\u00e1 la visita a su cl\u00e1sico rival, Cerro Porte\u00f1o y, nuestros dirigentes, a pesar de intentar que todo sea una fiesta, se \"provocan\" a trav\u00e9s de las redes sociales. D\u00edas atr\u00e1s, Ariel Mart\u00ednez, habr\u00eda declarado que: \u201cEstamos a cuatro d\u00edas del cl\u00e1sico y a\u00fan Olimpia\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/trovato-zapag.jpg?fit=590%2C440&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":7994,"url":"https:\/\/informatepy.com\/2021\/2021\/10\/28\/la-solucion-es-el-problema\/","url_meta":{"origin":414,"position":5},"title":"La soluci\u00f3n es el problema","date":"28 de octubre de 2021","format":false,"excerpt":"El 4 de octubre la Suprema Corte de Justicia anunciaba la entrada en vigencia el Sistema Integral de Gesti\u00f3n Registral Electr\u00f3nica (e-SIGR), en la Direcci\u00f3n General de los Registros P\u00fablicos. Unos d\u00edas despu\u00e9s, a la luz de los acontecimientos de larga data y que todos ya sabemos entorno a la\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/direccion-de-registros-publicos.jpg?fit=1200%2C831&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=414"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/414\/revisions"}],"predecessor-version":[{"id":2866,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/414\/revisions\/2866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/415"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=414"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}