{"id":2502,"date":"2021-02-03T20:21:00","date_gmt":"2021-02-03T20:21:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/2021\/02\/03\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\/"},"modified":"2021-02-13T13:25:15","modified_gmt":"2021-02-13T13:25:15","slug":"de-fuegos-artificiales-pantomima-y-persecuciones-politicas","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2021\/02\/03\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\/","title":{"rendered":"De Fuegos Artificiales, Pantomima y Persecuciones Pol\u00edticas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En la ma\u00f1ana de hoy el nunca bien ponderado Jefe de Gabinete Civil de la Presidencia de la Rep\u00fablica Juan Ernesto Villamayor fue salvado \u201cpor la campana\u201d, en votaci\u00f3n nominal que arroj\u00f3 los siguientes n\u00fameros: 52 votos a favor del voto de censura, 19 en contra y 9 ausentes, como adelantamos en d\u00edas anteriores el bloque oficialista, ejerci\u00f3 la defensa furibunda del hombre fuerte del gobierno, catalogado por analistas como el \u201ccerebro\u201d del Gobierno Central&nbsp; y caracterizado por su tremendo dominio de la oratoria, me animo a describirlo como un seductor de masas nato y consumado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La oposici\u00f3n, encabezada por Kattya Gonz\u00e1lez, por su parte adelant\u00f3 el voto de censura en consonancia con el discurso de \u201clucha contra la corrupci\u00f3n\u201d al que nos tienen acostumbrados en todos los espacios de los medios de comunicaci\u00f3n que le dan resonancia tal y como alguna vez hicieron con Mario Abdo Ben\u00edtez que decant\u00f3 en su victoria en las internas de diciembre de 2017, sin embargo al concluir las votaciones nominales y ante la moci\u00f3n de orden presentada por el diputado cartista Basilio Nu\u00f1ez para la rectificaci\u00f3n o confirmaci\u00f3n de los votos, Gonz\u00e1lez sali\u00f3 al paso en un arrebato de fastidio a exigir el cierre del debate en clara oposici\u00f3n de agotar las instancias para el logro del voto de censura para Villamayor, tan anhelado por la ciudadan\u00eda com\u00fan, leg\u00edtimos mandantes del parlamento, esgrimiendo que hab\u00edan temas m\u00e1s importantes a ser tratados en el ORDEN DEL D\u00cdA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Senador Salyn Buzarquis no se qued\u00f3 atr\u00e1s ante los comentarios de repudio que inundaron las redes sociales, utiliz\u00f3 su cuenta de Facebook para defender a su hermano el Diputado Liberal Antonio Buzarquis, quien estuvo ausente en el tratamiento de un tema CENTRAL en la Sesi\u00f3n Extraordinaria, argumentando que el voto de censura \u201cno es vinculante, y se estaba trabajando por conseguir los votos para el Juicio Pol\u00edtico a la Fiscal General del Estado\u201d, trat\u00e1ndola de EMPLEADA DE CARTES, en alusi\u00f3n directa al ex Presidente de la Rep\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debo recordarle al Senador del PLRA, Salyn Buzarquis que el caso de Texos, las deudas de PDVSA, la participaci\u00f3n del abogado del t\u00edo del Presidente de la Rep\u00fablica como negociador y beneficiario de una comisi\u00f3n de nada m\u00e1s y nada menos que 26 millones de d\u00f3lares&nbsp; estuvieron en el CENTRO del debate ciudadano &nbsp;por las serias denuncias que pesan sobre Villamayor y que acapar\u00f3 a la Opini\u00f3n P\u00fablica Nacional e internacional debido al escandaloso acuerdo secreto denunciado desde las p\u00e1ginas del afamado Washington Post\u201d entre el Comisionado de Recuperaci\u00f3n de Activos del Gobierno Interino de Juan Guaid\u00f3 y Juan Ernesto Villamayor, quien debi\u00f3 enfrentar una &nbsp;interpelaci\u00f3n ante la C\u00e1mara Baja.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Buzarquis calific\u00f3 las cr\u00edticas de sus colegas y al voto de censura como \u201cfuegos artificiales\u201d para distraer la atenci\u00f3n\u201d de la \u201cverdadera JUGADA\u201d (usando sus palabras). En lo que estamos de acuerdo es en que efectivamente, los sectores de la oposici\u00f3n, utilizaron estos fuegos artificiales para encubrir: La sistem\u00e1tica persecuci\u00f3n pol\u00edtica a la que someten a la FISCAL GENERAL DEL ESTADO, Sandra Qui\u00f1onez cada 6 meses en sus intentos de Juicio Pol\u00edtico para removerla del cargo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De un tiempo a esta parte las C\u00e1maras del Congreso son el epicentro de grandes presentaciones teatrales, con p\u00e9simos actores que esconden tras investiduras los personajes m\u00e1s nefastos de la casta pol\u00edtica paraguaya, un insulto a la inteligencia y un atentado a la moral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Pantomima es el recurso favorito de la oposici\u00f3n, una representaci\u00f3n teatral para que todo el populacho les crea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La clase pol\u00edtica debe entender que los comunes ya no son los mismos que en el pasado, se encuentran hastiados de estas representaciones inconducentes para tapar la impunidad y las jugadas pol\u00edticas por conveniencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El d\u00eda de hoy, los diputados salvaron al Cerebro, a la mano negra que corrompe desde sus cimientos al gobierno y que hace mucho tiempo perdi\u00f3 la confianza de un pueblo enfermo, pobre y agotado por la IMPUNIDAD. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>\u201cCuando el gobierno viola los derechos del pueblo, la insurrecci\u00f3n es para el pueblo el m\u00e1s sagrado e indispensable de los deberes.\u201c<\/strong><\/em> Maximilien Robespierre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la ma\u00f1ana de hoy el nunca bien ponderado Jefe de Gabinete Civil de la Presidencia de la Rep\u00fablica Juan Ernesto Villamayor fue salvado \u201cpor la campana\u201d, en votaci\u00f3n nominal que arroj\u00f3 los siguientes n\u00fameros: 52 votos a favor del voto de censura, 19 en contra y 9 ausentes, como adelantamos en d\u00edas anteriores el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2503,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[177],"tags":[437,242,347],"ppma_author":[1039],"class_list":["post-2502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-camara-de-diputados","tag-corrupcion","tag-juan-ernesto-villamayor"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>De Fuegos Artificiales, Pantomima y Persecuciones Pol\u00edticas - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2021\/02\/03\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De Fuegos Artificiales, Pantomima y Persecuciones Pol\u00edticas - Informatepy\" \/>\n<meta property=\"og:description\" content=\"En la ma\u00f1ana de hoy el nunca bien ponderado Jefe de Gabinete Civil de la Presidencia de la Rep\u00fablica Juan Ernesto Villamayor fue salvado \u201cpor la campana\u201d, en votaci\u00f3n nominal que arroj\u00f3 los siguientes n\u00fameros: 52 votos a favor del voto de censura, 19 en contra y 9 ausentes, como adelantamos en d\u00edas anteriores el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2021\/02\/03\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-03T20:21:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-13T13:25:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/villamayor-presidente1-scaled-1.jpg?fit=2560%2C1415&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1415\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/02\\\/03\\\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/02\\\/03\\\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"De Fuegos Artificiales, Pantomima y Persecuciones Pol\u00edticas\",\"datePublished\":\"2021-02-03T20:21:00+00:00\",\"dateModified\":\"2021-02-13T13:25:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/02\\\/03\\\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\\\/\"},\"wordCount\":741,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/02\\\/03\\\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/villamayor-presidente1-scaled-1.jpg?fit=2560%2C1415&ssl=1\",\"keywords\":[\"c\u00e1mara de diputados\",\"corrupcion\",\"juan ernesto villamayor\"],\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/02\\\/03\\\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/02\\\/03\\\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/02\\\/03\\\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\\\/\",\"name\":\"De Fuegos Artificiales, Pantomima y Persecuciones Pol\u00edticas - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/02\\\/03\\\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/02\\\/03\\\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/villamayor-presidente1-scaled-1.jpg?fit=2560%2C1415&ssl=1\",\"datePublished\":\"2021-02-03T20:21:00+00:00\",\"dateModified\":\"2021-02-13T13:25:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/02\\\/03\\\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/02\\\/03\\\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/02\\\/03\\\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/villamayor-presidente1-scaled-1.jpg?fit=2560%2C1415&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/villamayor-presidente1-scaled-1.jpg?fit=2560%2C1415&ssl=1\",\"width\":2560,\"height\":1415,\"caption\":\"Juan Ernesto Villamayor, \u00bfEl poder detr\u00e1s del poder?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2021\\\/02\\\/03\\\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"De Fuegos Artificiales, Pantomima y Persecuciones Pol\u00edticas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De Fuegos Artificiales, Pantomima y Persecuciones Pol\u00edticas - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2021\/02\/03\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\/","og_locale":"es_ES","og_type":"article","og_title":"De Fuegos Artificiales, Pantomima y Persecuciones Pol\u00edticas - Informatepy","og_description":"En la ma\u00f1ana de hoy el nunca bien ponderado Jefe de Gabinete Civil de la Presidencia de la Rep\u00fablica Juan Ernesto Villamayor fue salvado \u201cpor la campana\u201d, en votaci\u00f3n nominal que arroj\u00f3 los siguientes n\u00fameros: 52 votos a favor del voto de censura, 19 en contra y 9 ausentes, como adelantamos en d\u00edas anteriores el [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2021\/02\/03\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\/","og_site_name":"Informatepy","article_published_time":"2021-02-03T20:21:00+00:00","article_modified_time":"2021-02-13T13:25:15+00:00","og_image":[{"width":2560,"height":1415,"url":"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/villamayor-presidente1-scaled-1.jpg?fit=2560%2C1415&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2021\/02\/03\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2021\/02\/03\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"De Fuegos Artificiales, Pantomima y Persecuciones Pol\u00edticas","datePublished":"2021-02-03T20:21:00+00:00","dateModified":"2021-02-13T13:25:15+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2021\/02\/03\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\/"},"wordCount":741,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2021\/02\/03\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/villamayor-presidente1-scaled-1.jpg?fit=2560%2C1415&ssl=1","keywords":["c\u00e1mara de diputados","corrupcion","juan ernesto villamayor"],"articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2021\/02\/03\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2021\/02\/03\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\/","url":"https:\/\/informatepy.com\/2021\/2021\/02\/03\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\/","name":"De Fuegos Artificiales, Pantomima y Persecuciones Pol\u00edticas - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2021\/02\/03\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2021\/02\/03\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/villamayor-presidente1-scaled-1.jpg?fit=2560%2C1415&ssl=1","datePublished":"2021-02-03T20:21:00+00:00","dateModified":"2021-02-13T13:25:15+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2021\/02\/03\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2021\/02\/03\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2021\/02\/03\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/villamayor-presidente1-scaled-1.jpg?fit=2560%2C1415&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/villamayor-presidente1-scaled-1.jpg?fit=2560%2C1415&ssl=1","width":2560,"height":1415,"caption":"Juan Ernesto Villamayor, \u00bfEl poder detr\u00e1s del poder?"},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2021\/02\/03\/de-fuegos-artificiales-pantomima-y-persecuciones-politicas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"De Fuegos Artificiales, Pantomima y Persecuciones Pol\u00edticas"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/villamayor-presidente1-scaled-1.jpg?fit=2560%2C1415&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":2492,"url":"https:\/\/informatepy.com\/2021\/2021\/02\/02\/caso-villamayor-el-comunicador-eduardo-pipo-dios-denuncia-la-compra-de-votos-en-diputados\/","url_meta":{"origin":2502,"position":0},"title":"Caso Villamayor: El comunicador Eduardo Pipo Dios, denuncia la compra de votos en diputados","date":"2 de febrero de 2021","format":false,"excerpt":"A trav\u00e9s de su cuenta de Twitter, el comunicador Eduardo Pipo Dios denunci\u00f3 la compra de votos en la c\u00e1mara de diputados en el caso del voto de censura en contra de Juan Ernesto Villamayor. Sin brindar datos concretos pero muchas pistas, fue \"marcando\" a aquellos diputados que votar\u00edan en\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/villamayor-censurado-scaled-1.jpg?fit=1200%2C725&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2498,"url":"https:\/\/informatepy.com\/2021\/2021\/02\/03\/salvado\/","url_meta":{"origin":2502,"position":1},"title":"Salvado","date":"3 de febrero de 2021","format":false,"excerpt":"Los diputados trataron este mi\u00e9rcoles en sesi\u00f3n extraordinaria el pedido de censura para el jefe de Gabinete Civil de la Presidencia, Juan Ernesto Villamayor. Tras un largo debate, 52 legisladores votaron a favor del voto de censura y 19 votaron en contra. En tanto que hubo 9 ausentes en ese\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/villamayor-salvado-scaled-1.jpg?fit=1200%2C663&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2387,"url":"https:\/\/informatepy.com\/2021\/2021\/01\/10\/legisladores-instan-a-abdo-a-destituir-a-villamayor-antes-del-voto-de-censura\/","url_meta":{"origin":2502,"position":2},"title":"Legisladores instan a Abdo a destituir a Villamayor antes del voto de censura","date":"10 de enero de 2021","format":false,"excerpt":"El viernes se present\u00f3 de forma oficial el pedido de interpelaci\u00f3n ante la Comisi\u00f3n Permanente del Congreso para el jefe de Gabinete de la Presidencia, Juan Ernesto Villamayor, salpicado en el pol\u00e9mico acuerdo secreto de Petropar con PDVSA. Mediante esta herramienta constitucional, de ser aprobada la solicitud, el pol\u00edtico deber\u00e1\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/juan-ernesto-villamayor-1.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2100,"url":"https:\/\/informatepy.com\/2021\/2020\/08\/03\/villamayor-con-su-soberbia-habitual-se-refiere-al-caso-friedmann\/","url_meta":{"origin":2502,"position":3},"title":"Villamayor con su soberbia habitual se refiere al caso Friedmann","date":"3 de agosto de 2020","format":false,"excerpt":"Finalizada la reuni\u00f3n de Gabinete Civil, Juan Ernesto Villamayor, al ser consultado acerca de cuan atentos est\u00e1n a las denuncias en contra del Ministro Friedmann por un faltante de 2.295 millones de guaran\u00edes de la merienda escolar, respondi\u00f3 que: \u201cNo, porque este es el momento en que estamos descuento el\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/juan-ernesto-villamayor-1.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1490,"url":"https:\/\/informatepy.com\/2021\/2019\/09\/11\/un-dia-irreal\/","url_meta":{"origin":2502,"position":4},"title":"Un d\u00eda irreal","date":"11 de septiembre de 2019","format":false,"excerpt":"El presidente Mario Abdo Ben\u00edtez, el vice Hugo Vel\u00e1zquez, el ministro del Interior, Juan Ernesto Villamayor pasaban un buen momento en la fiesta por el aniversario del Partido Colorado. En el mismo momento, el Ministerio P\u00fablico, oficiaba a la Polic\u00eda Nacional para encomendar \"LA BUSQUEDA y LOCALIZACI\u00d3N de UN CHANCHO\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/09\/reo3.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3305,"url":"https:\/\/informatepy.com\/2021\/2021\/02\/14\/periodista-denuncia-aprietes-de-parte-del-arquitecto-alfaro\/","url_meta":{"origin":2502,"position":5},"title":"Periodista denuncia \u00abaprietes\u00bb de parte del Arquitecto Alfaro","date":"14 de febrero de 2021","format":false,"excerpt":"Nadie, o casi nadie, conoc\u00eda al Arquitecto Eduardo Alfaro hasta que alcanz\u00f3 sus 15 minutos de fama. Mientras que su hijo quiso que esos 15 minutos llegaran a trav\u00e9s de un sentido posteo acerca de las virtudes de su padre para ser pr\u00f3ximo concejal de la ciudad de Asunci\u00f3n, la\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/arquitecto-eduardo-alfaro.jpg?fit=960%2C960&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/2502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=2502"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/2502\/revisions"}],"predecessor-version":[{"id":2519,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/2502\/revisions\/2519"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/2503"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=2502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=2502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=2502"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=2502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}