{"id":2359,"date":"2020-12-20T20:20:00","date_gmt":"2020-12-20T20:20:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=2359"},"modified":"2021-02-08T17:45:33","modified_gmt":"2021-02-08T17:45:33","slug":"el-suicidio-del-periodismo-norteamericano","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2020\/12\/20\/el-suicidio-del-periodismo-norteamericano\/","title":{"rendered":"El suicidio del periodismo norteamericano"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hubo una \u00e9poca de titanes. Titanes del periodismo. Sobran nombres, ejemplos\u2026 quedan firmas, casos\u2026 leyendas. Hombres, mujeres que entregaron y se jugaron todo\u2026 literalmente todo, para dar con esa beta de oro informativo que, en muchos casos, logr\u00f3 cambiar la historia. Estos titanes no pensaban en otra cosa que descubrir la verdad. La verdad. \u00a1Dios!, esa palabra\u2026 Verdad, es tan extra\u00f1a e inusual en estos tiempos, que hace rato se ha ido alejando del norte period\u00edstico mundial, al ser absorbida por estos enormes monstruos \u2014dinosaurios con trajes digitales\u2014 en que se han convertido los medios de comunicaci\u00f3n tradicionales: enti\u00e9ndase, los que tienen \u2014o tuvieron\u2014 peso real; los que alguna vez fueron estandartes de libertad y \u2014muy pesar de ser empresas privadas\u2014 respetaban la gran misi\u00f3n sagrada de contar, narrar, descubrir hechos\u2026 o sea eso,&nbsp;la verdad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Titanes fueron Woodward y Bernstein, reporteros del&nbsp;<em>Washington Post<\/em>,&nbsp;al meterse de cabeza dentro del sistema sucio y visceral del presidente Richard Nixon. Casi a ciegas, y llevados por el olfato e instinto que posee aquel que decide dedicar su vida a la gran aventura extra\u00f1a, paranoica y monumental, que es el periodismo, penetraron, excavaron y explotaron algo que hoy se resume simplemente como&nbsp;<em>Watergate.<\/em>&nbsp;Una historia, una investigaci\u00f3n\u2026 miles de palabras impresas en papel, que llevaron a la renuncia de un presidente. Vaya logro\u2026 y todo por contar, ni m\u00e1s ni menos, la verdad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero esa \u00e9poca se perdi\u00f3, difuminada entre tonos grises y oscuros; entre mareas de mentiras y la conveniencia de los grandes medios cuya historia\u2026 bueno, ya es una simple historia pisoteada por el grupo de magnates que hoy, en estos tiempos extra\u00f1os y violentos, manejan todo aquello que se publica y, m\u00e1s importante, lo que no.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hablar de las elecciones actuales\u2026 del \u00bftriunfo de Biden? Y la \u00bfderrota de Trump?, es un caso que demuestra un hecho triste pero real: el periodismo norteamericano, de mano de los medios tradicionales (los que alguna vez tuvieron el coraje de exponer a corruptos y sabandijas) est\u00e1 aniquilado. Nadie lo asesin\u00f3. Fue un suicidio premeditado. Y uno que ser\u00e1 recordado para siempre, ya que abre un nuevo portal hacia la negligencia y arroja un escupitajo al oficio del periodista.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bffraude?<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Alguna vez, en medio de una entrevista para la&nbsp;<em>BBC<\/em>, compar\u00e9 a Venezuela con un apartamento repleto de maleantes y terroristas\u2026 y, que de no ser controlado, terminar\u00eda acabando con todo el edificio. Piso por piso. Esto hace rato comenz\u00f3. Aunque lo que muchos ignoraban es que llegar\u00eda a inyectarse dentro de las venas de la pol\u00edtica norteamericana, como un nefasto pinchazo de hero\u00edna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando se hizo p\u00fablico que la empresa Smartmatic (responsable de, seguramente, el desfile de elecciones m\u00e1s fraudulentas de la historia de esta galaxia, las venezolanas) estaba vinculada directamente con el sistema electoral que organiz\u00f3 las elecciones Trump-Biden, simplemente esper\u00e9\u2026 esper\u00e9 ese gran reportaje que hilara una historia muy sencilla de atrapar \u2014hasta para el periodista m\u00e1s novato\u2014\u2026 y segu\u00ed esperando\u2026 y ya sabemos que esa gran historia no se public\u00f3 ni se publicar\u00e1.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Black Lives Marxistas<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">No pretendo dar una clase magistral sobre lo que, al menos en hechos, convierte a estas elecciones en una de las operaciones m\u00e1s fraudulentas y, peor todav\u00eda, absurdamente f\u00e1cil de comprobar. Basta con hacer una simple b\u00fasqueda de Black Lives Matter (la organizaci\u00f3n que apoya no solo al r\u00e9gimen narcoterrorista venezolano y al cubano); su visita a Venezuela durante unas elecciones. Y posteriormente ver una fotocopia de hechos que, durante un tiempo, dieron la impresi\u00f3n de que una estrategia \u2014la misma que los venezolanos hemos sufrido durante m\u00e1s de dos d\u00e9cadas de agon\u00eda\u2014 los saqueos, la divisi\u00f3n, la violencia\u2026 todo en el pre\u00e1mbulo electoral. Luego, tarjetas de votaci\u00f3n dispersas por todo el pa\u00eds\u2026 conteo secreto de votos, murtos votando\u2026 es una terrible pel\u00edcula que los venezolanos conocen pero que, por alg\u00fan motivo, los medios de comunicaci\u00f3n norteamericanos, sencillamente prefirieron dejar a un lado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo que ha pasado en Los Estados Unidos contra un hombre como Trump, es la muestra inequ\u00edvoca, del grado de peligro que este hombre representa para un sistema pol\u00edtico y econ\u00f3mico que no admite cambios y que se siente amenazado por todo aquello que pueda ir contra sus intereses. Trump es un renegado. Un&nbsp;<em>outsider<\/em>. Ergo, un enemigo de la vieja pol\u00edtica bipartidista americana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No se requer\u00eda a otros Woodward y Bernstein para amarrar una historia en la que se desarroll\u00f3 una conspiraci\u00f3n para sacar del juego al hombre que quiere acabar con \u201cel juego\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora, el papeleo. Las denuncias. Cortes. Pero\u2026 \u00bfd\u00f3nde est\u00e1 la gran historia de c\u00f3mo se realiz\u00f3 algo tan grotesco como evidente? Pues, ciertamente no la leer\u00e1n, ver\u00e1n o escuchar\u00e1n en los medios de comunicaci\u00f3n que ahora solo difunden propaganda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recuerdo la frase lapidaria de Richard Nixon al ser entrevistado por el gran David Frost: \u201cSi un presidente lo hace\u2026 no es ilegal\u201d. En el caso de las elecciones Trump-Biden\u2026 si a un presidente le cometen fraude\u2026 resulta que no solo es ilegal\u2026 sino que ni siquiera se publicar\u00e1.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hubo una \u00e9poca de titanes. Titanes del periodismo. Sobran nombres, ejemplos\u2026 quedan firmas, casos\u2026 leyendas. Hombres, mujeres que entregaron y se jugaron todo\u2026 literalmente todo, para dar con esa beta de oro informativo que, en muchos casos, logr\u00f3 cambiar la historia. Estos titanes no pensaban en otra cosa que descubrir la verdad. La verdad. \u00a1Dios!, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2360,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[248,302],"tags":[832,989],"ppma_author":[1039],"class_list":["post-2359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis","category-destacados","tag-estados-unidos","tag-periodismo"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El suicidio del periodismo norteamericano - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2020\/12\/20\/el-suicidio-del-periodismo-norteamericano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El suicidio del periodismo norteamericano - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Hubo una \u00e9poca de titanes. Titanes del periodismo. Sobran nombres, ejemplos\u2026 quedan firmas, casos\u2026 leyendas. Hombres, mujeres que entregaron y se jugaron todo\u2026 literalmente todo, para dar con esa beta de oro informativo que, en muchos casos, logr\u00f3 cambiar la historia. Estos titanes no pensaban en otra cosa que descubrir la verdad. La verdad. \u00a1Dios!, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2020\/12\/20\/el-suicidio-del-periodismo-norteamericano\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-20T20:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-08T17:45:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/periodismo.jpg?fit=800%2C500&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/12\\\/20\\\/el-suicidio-del-periodismo-norteamericano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/12\\\/20\\\/el-suicidio-del-periodismo-norteamericano\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"El suicidio del periodismo norteamericano\",\"datePublished\":\"2020-12-20T20:20:00+00:00\",\"dateModified\":\"2021-02-08T17:45:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/12\\\/20\\\/el-suicidio-del-periodismo-norteamericano\\\/\"},\"wordCount\":891,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/12\\\/20\\\/el-suicidio-del-periodismo-norteamericano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/periodismo.jpg?fit=800%2C500&ssl=1\",\"keywords\":[\"estados unidos\",\"periodismo\"],\"articleSection\":[\"Analisis\",\"Destacados\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/12\\\/20\\\/el-suicidio-del-periodismo-norteamericano\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/12\\\/20\\\/el-suicidio-del-periodismo-norteamericano\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/12\\\/20\\\/el-suicidio-del-periodismo-norteamericano\\\/\",\"name\":\"El suicidio del periodismo norteamericano - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/12\\\/20\\\/el-suicidio-del-periodismo-norteamericano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/12\\\/20\\\/el-suicidio-del-periodismo-norteamericano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/periodismo.jpg?fit=800%2C500&ssl=1\",\"datePublished\":\"2020-12-20T20:20:00+00:00\",\"dateModified\":\"2021-02-08T17:45:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/12\\\/20\\\/el-suicidio-del-periodismo-norteamericano\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/12\\\/20\\\/el-suicidio-del-periodismo-norteamericano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/12\\\/20\\\/el-suicidio-del-periodismo-norteamericano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/periodismo.jpg?fit=800%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/periodismo.jpg?fit=800%2C500&ssl=1\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/12\\\/20\\\/el-suicidio-del-periodismo-norteamericano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El suicidio del periodismo norteamericano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El suicidio del periodismo norteamericano - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2020\/12\/20\/el-suicidio-del-periodismo-norteamericano\/","og_locale":"es_ES","og_type":"article","og_title":"El suicidio del periodismo norteamericano - Informatepy","og_description":"Hubo una \u00e9poca de titanes. Titanes del periodismo. Sobran nombres, ejemplos\u2026 quedan firmas, casos\u2026 leyendas. Hombres, mujeres que entregaron y se jugaron todo\u2026 literalmente todo, para dar con esa beta de oro informativo que, en muchos casos, logr\u00f3 cambiar la historia. Estos titanes no pensaban en otra cosa que descubrir la verdad. La verdad. \u00a1Dios!, [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2020\/12\/20\/el-suicidio-del-periodismo-norteamericano\/","og_site_name":"Informatepy","article_published_time":"2020-12-20T20:20:00+00:00","article_modified_time":"2021-02-08T17:45:33+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/periodismo.jpg?fit=800%2C500&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2020\/12\/20\/el-suicidio-del-periodismo-norteamericano\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2020\/12\/20\/el-suicidio-del-periodismo-norteamericano\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"El suicidio del periodismo norteamericano","datePublished":"2020-12-20T20:20:00+00:00","dateModified":"2021-02-08T17:45:33+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2020\/12\/20\/el-suicidio-del-periodismo-norteamericano\/"},"wordCount":891,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2020\/12\/20\/el-suicidio-del-periodismo-norteamericano\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/periodismo.jpg?fit=800%2C500&ssl=1","keywords":["estados unidos","periodismo"],"articleSection":["Analisis","Destacados"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2020\/12\/20\/el-suicidio-del-periodismo-norteamericano\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2020\/12\/20\/el-suicidio-del-periodismo-norteamericano\/","url":"https:\/\/informatepy.com\/2021\/2020\/12\/20\/el-suicidio-del-periodismo-norteamericano\/","name":"El suicidio del periodismo norteamericano - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2020\/12\/20\/el-suicidio-del-periodismo-norteamericano\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2020\/12\/20\/el-suicidio-del-periodismo-norteamericano\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/periodismo.jpg?fit=800%2C500&ssl=1","datePublished":"2020-12-20T20:20:00+00:00","dateModified":"2021-02-08T17:45:33+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2020\/12\/20\/el-suicidio-del-periodismo-norteamericano\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2020\/12\/20\/el-suicidio-del-periodismo-norteamericano\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2020\/12\/20\/el-suicidio-del-periodismo-norteamericano\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/periodismo.jpg?fit=800%2C500&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/periodismo.jpg?fit=800%2C500&ssl=1","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2020\/12\/20\/el-suicidio-del-periodismo-norteamericano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"El suicidio del periodismo norteamericano"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/periodismo.jpg?fit=800%2C500&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1956,"url":"https:\/\/informatepy.com\/2021\/2020\/04\/27\/caso-salum-periodistas-insisten-con-su-version-a-pesar-de-las-pruebas-en-contrario\/","url_meta":{"origin":2359,"position":0},"title":"CASO SALUM: Periodistas insisten con su versi\u00f3n a pesar de las pruebas en contrario","date":"27 de abril de 2020","format":false,"excerpt":"El empresario Karim Salum arrib\u00f3 al Paraguay el 22 de abril, a las 17.00, a partir de ese momento, diversas versiones manifestaron que el hombre se habr\u00eda presentado a trabajar al d\u00eda siguiente a su oficina. Por esta raz\u00f3n, la representante del Ministerio P\u00fablico retir\u00f3 copias completas del circuito cerrado\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/aeropuerto-interior.jpg?fit=600%2C400&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8044,"url":"https:\/\/informatepy.com\/2021\/2021\/10\/30\/el-odio-te-ciega\/","url_meta":{"origin":2359,"position":1},"title":"El odio te ciega","date":"30 de octubre de 2021","format":false,"excerpt":"Que Horacio Cartes es el blanco preferido de muchos \"periodistas\" no es novedad. \u00bfTiene aspectos criticables Horacio Cartes? por supuesto, como todos nosotros; incluso, los pseudo periodistas \"due\u00f1os de la verdad\". En una reuni\u00f3n pol\u00edtica en el departamento de Paraguar\u00ed, Horacio Cartes dio un discurso donde estim\u00f3 que: \"Santi, si\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/rocio-pereira-da-costa-telefuturo.jpg?fit=622%2C548&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4596,"url":"https:\/\/informatepy.com\/2021\/2021\/04\/23\/ultima-hora-en-sus-ultimas-horas\/","url_meta":{"origin":2359,"position":2},"title":"\u00daltima Hora en sus \u00faltimas horas","date":"23 de abril de 2021","format":false,"excerpt":"Diario de mierda, no sirve ni para limpiarse el orto, al contrario, te ensucia m\u00e1s. Les digo yo que lo usaba cuando estaba en Aspen por falta de papel higi\u00e9nico. No hab\u00eda a causa de esos desfases tan comunes en el Paraguay por falta de pienso. Se acaba pero no\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/tapa-UH.jpg?fit=1200%2C950&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2050,"url":"https:\/\/informatepy.com\/2021\/2020\/07\/11\/de-periodistas-de-mierda-y-excusas-estupidas\/","url_meta":{"origin":2359,"position":3},"title":"De periodistas de mierda y excusas est\u00fapidas","date":"11 de julio de 2020","format":false,"excerpt":"Toda la semana, a partir de la difusi\u00f3n de unos v\u00eddeos del circuito cerrado del PLRA en la fat\u00eddica noche del 31 de marzo de 2017, se estuvo debatiendo la capacidad moral de determinados periodistas para brindar determinadas noticias pero, en todo este debate nunca apareci\u00f3 la verdad. Que el\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/periodismo-de-mierda_primera-vocal.jpg?fit=675%2C521&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4191,"url":"https:\/\/informatepy.com\/2021\/2021\/03\/28\/puta-prensa-pyrague\/","url_meta":{"origin":2359,"position":4},"title":"Puta prensa pyrague","date":"28 de marzo de 2021","format":false,"excerpt":"Si te tienen que contar algo para que sepas, entonces no sabes nada. Si dependes del soplo al o\u00eddo para enterarte de lo que sucede, es porque no ten\u00e9s idea. De eso m\u00e1s que nada se trata hoy d\u00eda la informaci\u00f3n, que en verdad es desinformaci\u00f3n, mera fabricaci\u00f3n que se\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/telefuturo-tv-basura.jpg?fit=1200%2C755&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6230,"url":"https:\/\/informatepy.com\/2021\/2021\/08\/06\/con-el-presupuesto-que-plantea-giuzzio-para-vencer-al-epp-ande-moderniza-las-redes-electricas\/","url_meta":{"origin":2359,"position":5},"title":"Con el presupuesto que plantea Giuzzio para vencer al EPP, ANDE moderniza las redes el\u00e9ctricas","date":"6 de agosto de 2021","format":false,"excerpt":"Arnaldo Giuzzio, ministro del Interior, estima en unos 130 millones de d\u00f3lares la nueva inversi\u00f3n necesaria en equipamientos tecnol\u00f3gicos para vencer a los criminales del norte.","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/Arnaldo-Giuzzio.jpg?fit=1200%2C758&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/2359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=2359"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/2359\/revisions"}],"predecessor-version":[{"id":2576,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/2359\/revisions\/2576"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/2360"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=2359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=2359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=2359"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=2359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}