{"id":2334,"date":"2020-12-08T20:20:00","date_gmt":"2020-12-08T20:20:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=2334"},"modified":"2021-02-08T19:03:53","modified_gmt":"2021-02-08T19:03:53","slug":"murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2020\/12\/08\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\/","title":{"rendered":"Muri\u00f3 Alejandro Sabella, un s\u00edmbolo de la sobriedad y la jerarqu\u00eda en la elite del f\u00fatbol"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El reconocido ex futbolista y entrenador&nbsp;Alejandro Sabella&nbsp;muri\u00f3&nbsp;<strong>este martes a los a los 66 a\u00f1os<\/strong>&nbsp;por un virus intrahospitalario que complic\u00f3 una cardiopat\u00eda aguda.&nbsp;<\/p>\n\n\n\n\n\n<p class=\"wp-block-paragraph\">Se apaga otra vida del f\u00fatbol y se encienden los recuerdos. Aquellos que marcaron a la persona en el d\u00eda a d\u00eda, independientemente de esa pelota que fue su v\u00ednculo con la notoriedad. Alejandro Sabella fue un buen padre, esposo y amigo, pero fundamentalmente, un gran profesional. Fue ese \u201c10\u201d elegante que se destac\u00f3 en River, muy a pesar de jugar bajo la sombra del&nbsp;<em>Beto&nbsp;<\/em>Alonso;&nbsp;que triunf\u00f3 en Inglaterra antes de la Guerra y dej\u00f3 una huella imborrable en Estudiantes. Tambi\u00e9n,&nbsp;<strong>un notable entrenador que se dio el gusto de ganar la Copa Libertadores<\/strong>&nbsp;y estuvo muy cerca de igualar a uno de sus maestros, Carlos Salvador Bilardo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Su salud no estaba bien.&nbsp;<\/strong>A tal punto, que despu\u00e9s del Mundial de Brasil 2014, el que la Selecci\u00f3n Argentina estuvo a minutos de ganar pero sucumbi\u00f3 contra Alemania en el Maracan\u00e1, no volvi\u00f3 a dirigir. Por m\u00e1s que no le hayan faltado ofertas, claro. Y lo llora el pa\u00eds futbolero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pudo ser abogado y dar\u00e1n fe aquellos j\u00f3venes que transitaban la Facultad de Derecho en la d\u00e9cada del setenta sin imaginar que, muy pronto, llegar\u00edan los a\u00f1os de plomo. Eran los tiempos del pantal\u00f3n Oxford y el cabello largo, el look dominante. Sin embargo, a Sabella le tiraba m\u00e1s la pelota que los libros y se sent\u00eda m\u00e1s c\u00f3modo con shorcitos y botines, sobre el verde c\u00e9sped que lo consagrar\u00eda como futbolista. Fue en 1975, nada menos, cuando cambi\u00f3 el mapa del f\u00fatbol para River y para el&nbsp;<em>Cabez\u00f3n<\/em>, apodo que arrastraba desde que era un ni\u00f1o inquieto de Barrio Norte. Ya hab\u00eda debutado con la banda roja, pero la esperada consagraci\u00f3n despu\u00e9s de 18 a\u00f1os aciagos lo motoriz\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hab\u00eda llegado a N\u00fa\u00f1ez a trav\u00e9s de un delegado amigo del pap\u00e1 de un compa\u00f1ero de Gimnasia y Esgrima de Buenos Aires. Del club insignia de los bosques de Palermo se hizo socio a los 4 a\u00f1os. Su padre, Luis, alias&nbsp;<em>Toto<\/em>, jugaba el torneo senior, pero al menor de sus hijos lo acompa\u00f1aba en los campeonatos internos. Era com\u00fan verlo a Don Sabella anotar en su planilla, detr\u00e1s del arco, las estad\u00edsticas de cada partido. Junto al l\u00edder de la familia estaba Nelly, la mam\u00e1. Su hermano mayor, Marcelo, jugaba al f\u00fatbol, aunque m\u00e1s tarde ser\u00eda ingeniero agr\u00f3nomo como su pap\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sabella era diestro, pero<em>&nbsp;\u201ccomo todos los 10 eran zurdos\u201d<\/em>&nbsp;aprendi\u00f3 y nunca dej\u00f3 de patear con la izquierda. Lo prob\u00f3 Bruno Rodolfi, hist\u00f3rico volante central mendocino,<strong>&nbsp;diez veces campe\u00f3n con River.<\/strong>&nbsp;Qued\u00f3, claro. Porque era de f\u00edsico chiquito, pero talentoso. Y pensar que era fan\u00e1tico de Boca y admirador de Rojitas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ya era&nbsp;<em>Pachorra<\/em>, apodo con el que el relator Marcelo Araujo lo bautiz\u00f3 en el Sudamericano Juvenil de 1974 porque le gustaba dormir la siesta. Roberto Perfumo le dec\u00eda el&nbsp;<em>\u201cMago\u201d<\/em>. Fueron 4 a\u00f1os en River y decidi\u00f3 emigrar. No hab\u00eda lugar para Alonso y para \u00e9l. Ubaldo Ratt\u00edn, representante del Sheffield United en la Argentina, le ofreci\u00f3 jugar en Inglaterra. Ya le hab\u00eda dicho \u201cno\u201d Mario Zanabria, figura de Boca,&nbsp;y Sabella no dud\u00f3. Los ingleses quedaron encantados con su juego despu\u00e9s de un Supercl\u00e1sico y lo ficharon.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con Sheffield se fue al descenso, pero en el a\u00f1o 2000 fue elegido como uno de los mejores futbolistas del siglo por el club del condado de Yorkshire del Sur. A bordo de su talento fue transferido al Leeds United. Jug\u00f3 23 partidos y marc\u00f3 2 goles hasta que lleg\u00f3 Carlos Salvador Bilardo para convencer a los ingleses de que le dieran el pase por\u2026&nbsp;<strong>\u00a12 mil d\u00f3lares!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Estudiantes no s\u00f3lo jug\u00f3 tres temporadas; hizo de La Plata su nueva casa. All\u00ed conoci\u00f3 a Silvana, su se\u00f1ora y madre de dos de sus cuatro hijos en segundas nupcias. Se consagr\u00f3 en el Metropolitano de 1982 y del Nacional de 1983. En 1985 recal\u00f3 en Gremio y fue bicampe\u00f3n ga\u00facho. Regres\u00f3 a La Plata. Ferro e Irapuato de M\u00e9xico marcaron el final de su carrera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De River se hab\u00eda llevado una amistad grande con Daniel Passarella. Y a N\u00fa\u00f1ez volvi\u00f3 junto al&nbsp;<em>Kaiser&nbsp;<\/em>como ayudante de campo. Con perfil bajo, tambi\u00e9n acompa\u00f1\u00f3 al entrenador en la Selecci\u00f3n Argentina. Fue una revancha personal para Sabella, que no hab\u00eda podido jugar el Mundial \u201986. Compet\u00eda con Diego Maradona y Ricardo Enrique Bochini, ni m\u00e1s ni menos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con su amigo tambi\u00e9n estuvo en el Parma de Italia, la Selecci\u00f3n de Uruguay, Monterrey de M\u00e9xico, Corinthians de Brasil y de nuevo en River. Passarella opt\u00f3 por la pol\u00edtica y se candidate\u00f3 a presidente en Udaondo y Figueroa Alcorta y Sabella recibi\u00f3 un llamado inesperado, el de Juan Ram\u00f3n Ver\u00f3n. El pap\u00e1 de la&nbsp;<em>Brujita&nbsp;<\/em>le hizo un contacto con Estudiantes. Y despu\u00e9s de 15 a\u00f1os como segunda guitarra, asumi\u00f3 el rol estelar. Lo que sigui\u00f3 fue una de las p\u00e1ginas m\u00e1s gloriosas de la historia pincha:<strong>&nbsp;la cuarta Copa Libertadores en 2009.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aquel equipo qued\u00f3 en la historia: Mariano And\u00fajar; Cristian Cellay, Rolando Schiavi, Leandro Des\u00e1bato, Germ\u00e1n R\u00e9; Enzo P\u00e9rez, Rodrigo Bra\u00f1a, Juan Sebasti\u00e1n Ver\u00f3n, Leandro Ben\u00edtez; Gast\u00f3n Fern\u00e1ndez y Mauro Boselli tocaron el cielo del Mineirao con las manos y ba\u00f1aron de gloria a Estudiantes ante Cruzeiro. Apost\u00f3 a la m\u00edstica y tuvo su resultado. De hecho, la primera charla t\u00e9cnica la dio con una camiseta rojiblanca en la mano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lo esencial era invisible a los ojos<\/strong>, dec\u00eda el escritor y aviador franc\u00e9s. Sabella escond\u00eda detr\u00e1s de su mirada a un tipo noble, leal. \u00abPersonas como vos nos dejan mucho m\u00e1s que glorias deportivas&#8230; Sos el orgullo de un equipo con coraz\u00f3n\u00bb, fue la leyenda del pasacalle que sus amigos le colgaron en la puerta de su casa de Tolosa cuando volvi\u00f3 del Mundial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los alemanes le quitaron la posibilidad de subirse al pedestal de C\u00e9sar Luis Menotti y el propio Bilardo, uno de sus mentores. Los otros fueron Angel Labruna, su primer entrenador; Valdir Espinoza, el estratega que en Gremio le ense\u00f1\u00f3 que<em>&nbsp;\u201cel f\u00fatbol es una lucha por los espacios, el que mejor y m\u00e1s r\u00e1pido los ocupa, gana\u201d<\/em>; Rubens Minelli, otro brasile\u00f1o; Harry Haslan, entrenador en Sheffield; y Eduardo Luj\u00e1n Manera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nunca volvi\u00f3 a ver aquella final en el Maracan\u00e1 que lo marc\u00f3.&nbsp;<em>\u201cQuiero creer que es como un acto de defensa del ser humano, de la mente: no lo quer\u00e9s ver de nuevo para no armargarte. Me parece que hay un poco de eso\u00bb<\/em>, confes\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No pudo cruzar el Rubic\u00f3n, como hab\u00eda dicho despu\u00e9s de vencer a Holanda por penales. Julio C\u00e9sar hab\u00eda dicho, cuando se meti\u00f3 en el r\u00edo junto a sus tropas para recuperar Roma,&nbsp;<em>\u201cla suerte est\u00e1 echada\u201d<\/em>. Sabella lo sab\u00eda, por eso no quiso volver a dirigir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cEl d\u00eda a d\u00eda es demasiado exigente\u201d<\/em>, dijo hace dos a\u00f1os, cuando se pudo recuperar de un c\u00e1ncer. Entonces, asegur\u00f3: \u00abCuando yo estaba peleando para ver si segu\u00eda ac\u00e1 con ustedes o me iba para el otro lado, me acord\u00e9 lo que les dec\u00eda a mis alumnos, a mis jugadores:<em>&nbsp;&#8216;No pueden dar menos del 100%&#8217;.<\/em>&nbsp;Y si se los ped\u00eda a ellos, yo ten\u00eda que luchar para mantenerme con vida\u00bb. Y luch\u00f3 hasta el final, claro. Hasta que el coraz\u00f3n le fall\u00f3 y dijo adi\u00f3s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El reconocido ex futbolista y entrenador&nbsp;Alejandro Sabella&nbsp;muri\u00f3&nbsp;este martes a los a los 66 a\u00f1os&nbsp;por un virus intrahospitalario que complic\u00f3 una cardiopat\u00eda aguda.&nbsp; Se apaga otra vida del f\u00fatbol y se encienden los recuerdos. Aquellos que marcaron a la persona en el d\u00eda a d\u00eda, independientemente de esa pelota que fue su v\u00ednculo con la notoriedad. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2335,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[183],"tags":[982,486],"ppma_author":[1039],"class_list":["post-2334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-alejandro-sabella","tag-futbol-argentino"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Muri\u00f3 Alejandro Sabella, un s\u00edmbolo de la sobriedad y la jerarqu\u00eda en la elite del f\u00fatbol - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2020\/12\/08\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Muri\u00f3 Alejandro Sabella, un s\u00edmbolo de la sobriedad y la jerarqu\u00eda en la elite del f\u00fatbol - Informatepy\" \/>\n<meta property=\"og:description\" content=\"El reconocido ex futbolista y entrenador&nbsp;Alejandro Sabella&nbsp;muri\u00f3&nbsp;este martes a los a los 66 a\u00f1os&nbsp;por un virus intrahospitalario que complic\u00f3 una cardiopat\u00eda aguda.&nbsp; Se apaga otra vida del f\u00fatbol y se encienden los recuerdos. Aquellos que marcaron a la persona en el d\u00eda a d\u00eda, independientemente de esa pelota que fue su v\u00ednculo con la notoriedad. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2020\/12\/08\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-08T20:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-08T19:03:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/sabella.jpeg?fit=722%2C442&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"722\" \/>\n\t<meta property=\"og:image:height\" content=\"442\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/12\\\/08\\\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/12\\\/08\\\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"Muri\u00f3 Alejandro Sabella, un s\u00edmbolo de la sobriedad y la jerarqu\u00eda en la elite del f\u00fatbol\",\"datePublished\":\"2020-12-08T20:20:00+00:00\",\"dateModified\":\"2021-02-08T19:03:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/12\\\/08\\\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\\\/\"},\"wordCount\":1369,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/12\\\/08\\\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/sabella.jpeg?fit=722%2C442&ssl=1\",\"keywords\":[\"alejandro sabella\",\"futbol argentino\"],\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/12\\\/08\\\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/12\\\/08\\\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/12\\\/08\\\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\\\/\",\"name\":\"Muri\u00f3 Alejandro Sabella, un s\u00edmbolo de la sobriedad y la jerarqu\u00eda en la elite del f\u00fatbol - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/12\\\/08\\\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/12\\\/08\\\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/sabella.jpeg?fit=722%2C442&ssl=1\",\"datePublished\":\"2020-12-08T20:20:00+00:00\",\"dateModified\":\"2021-02-08T19:03:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/12\\\/08\\\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/12\\\/08\\\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/12\\\/08\\\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/sabella.jpeg?fit=722%2C442&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/sabella.jpeg?fit=722%2C442&ssl=1\",\"width\":722,\"height\":442},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/12\\\/08\\\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Muri\u00f3 Alejandro Sabella, un s\u00edmbolo de la sobriedad y la jerarqu\u00eda en la elite del f\u00fatbol\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Muri\u00f3 Alejandro Sabella, un s\u00edmbolo de la sobriedad y la jerarqu\u00eda en la elite del f\u00fatbol - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2020\/12\/08\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\/","og_locale":"es_ES","og_type":"article","og_title":"Muri\u00f3 Alejandro Sabella, un s\u00edmbolo de la sobriedad y la jerarqu\u00eda en la elite del f\u00fatbol - Informatepy","og_description":"El reconocido ex futbolista y entrenador&nbsp;Alejandro Sabella&nbsp;muri\u00f3&nbsp;este martes a los a los 66 a\u00f1os&nbsp;por un virus intrahospitalario que complic\u00f3 una cardiopat\u00eda aguda.&nbsp; Se apaga otra vida del f\u00fatbol y se encienden los recuerdos. Aquellos que marcaron a la persona en el d\u00eda a d\u00eda, independientemente de esa pelota que fue su v\u00ednculo con la notoriedad. [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2020\/12\/08\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\/","og_site_name":"Informatepy","article_published_time":"2020-12-08T20:20:00+00:00","article_modified_time":"2021-02-08T19:03:53+00:00","og_image":[{"width":722,"height":442,"url":"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/sabella.jpeg?fit=722%2C442&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2020\/12\/08\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2020\/12\/08\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"Muri\u00f3 Alejandro Sabella, un s\u00edmbolo de la sobriedad y la jerarqu\u00eda en la elite del f\u00fatbol","datePublished":"2020-12-08T20:20:00+00:00","dateModified":"2021-02-08T19:03:53+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2020\/12\/08\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\/"},"wordCount":1369,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2020\/12\/08\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/sabella.jpeg?fit=722%2C442&ssl=1","keywords":["alejandro sabella","futbol argentino"],"articleSection":["Deportes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2020\/12\/08\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2020\/12\/08\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\/","url":"https:\/\/informatepy.com\/2021\/2020\/12\/08\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\/","name":"Muri\u00f3 Alejandro Sabella, un s\u00edmbolo de la sobriedad y la jerarqu\u00eda en la elite del f\u00fatbol - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2020\/12\/08\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2020\/12\/08\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/sabella.jpeg?fit=722%2C442&ssl=1","datePublished":"2020-12-08T20:20:00+00:00","dateModified":"2021-02-08T19:03:53+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2020\/12\/08\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2020\/12\/08\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2020\/12\/08\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/sabella.jpeg?fit=722%2C442&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/sabella.jpeg?fit=722%2C442&ssl=1","width":722,"height":442},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2020\/12\/08\/murio-alejandro-sabella-un-simbolo-de-la-sobriedad-y-la-jerarquia-en-la-elite-del-futbol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Muri\u00f3 Alejandro Sabella, un s\u00edmbolo de la sobriedad y la jerarqu\u00eda en la elite del f\u00fatbol"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/sabella.jpeg?fit=722%2C442&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":13272,"url":"https:\/\/informatepy.com\/2021\/2022\/08\/12\/otra-verguenza-de-la-conmebol-y-van\/","url_meta":{"origin":2334,"position":0},"title":"Otra verg\u00fcenza de la CONMEBOL (y van&#8230;)","date":"12 de agosto de 2022","format":false,"excerpt":"\"El \u00e1rbitro es el gran responsable y se lo dije en la cara\", coment\u00f3 con\u00a0bronca el\u00a0Ruso Zielinski, DT de Estudiantes de la Plata, y\u00a0tiene raz\u00f3n (La ten\u00eda antes) luego de que la Conmebol diera a conocer los audios del VAR sobre el gol anulado a\u00a0Luciano Lollo, jugada que pudo cambiar\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/alejandro-dominguez.webp?fit=1200%2C706&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9027,"url":"https:\/\/informatepy.com\/2021\/2021\/12\/25\/muere-mukhaled-al-raqadi-futbolista-de-oman-por-un-infarto-en-un-calentamiento\/","url_meta":{"origin":2334,"position":1},"title":"Muere Mukhaled Al-Raqadi, futbolista de Om\u00e1n, por un infarto en un calentamiento","date":"25 de diciembre de 2021","format":false,"excerpt":"El fallecimiento del oman\u00ed se suma al de Mario Cacic, el pasado 21 de diciembre, bajo las mismas condiciones","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/Mukhaled-Al-Raqad.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9019,"url":"https:\/\/informatepy.com\/2021\/2021\/12\/25\/un-futbolista-de-23-anos-muere-tras-sufrir-un-ataque-cardiaco-en-el-entrenamiento\/","url_meta":{"origin":2334,"position":2},"title":"Un futbolista croata de 23 a\u00f1os muere tras sufrir un ataque card\u00edaco en el entrenamiento","date":"25 de diciembre de 2021","format":false,"excerpt":"El jugador del NK Nehaj croata estaba en coma y los m\u00e9dicos no pudieron hacer nada por \u00e9l","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/marin-cacic.jpg?fit=958%2C596&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10924,"url":"https:\/\/informatepy.com\/2021\/2022\/04\/02\/dominguez-en-la-conmebol-hasta-el-2027\/","url_meta":{"origin":2334,"position":3},"title":"Dom\u00ednguez en la Conmebol hasta el 2027","date":"2 de abril de 2022","format":false,"excerpt":"Alejandro Dom\u00ednguez fue reelecto como presidente de la Conmebol y continuar\u00e1 un mandato m\u00e1s al frente del m\u00e1ximo organismo del continente. El directivo paraguayo sum\u00f3 la totalidad de los diez votos posibles en su lista \u00fanica e iniciar\u00e1 su mandato formal en 2023. Dom\u00ednguez estar\u00e1 acompa\u00f1ado por Francisco Javier Egas\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/alejandor-dominguez.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1079,"url":"https:\/\/informatepy.com\/2021\/2019\/04\/26\/murio-el-padre-del-futbolista-emiliano-sala\/","url_meta":{"origin":2334,"position":4},"title":"Muri\u00f3 el padre del futbolista Emiliano Sala","date":"26 de abril de 2019","format":false,"excerpt":"La muerte vuelve a golpear a la familia de\u00a0Emiliano Sala: esta madrugada falleci\u00f3 Horacio, el pap\u00e1 del futbolista, como consecuencia de un ataque card\u00edaco. Sucede a s\u00f3lo tres meses del tr\u00e1gico accidente a\u00e9reo en el canal de la Mancha, que se llev\u00f3 la vida del delantero. El pap\u00e1 de Emiliano\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/emiliano-salas.jpg?fit=611%2C308&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13066,"url":"https:\/\/informatepy.com\/2021\/2022\/08\/02\/conmebol-lanza-su-candidatura-al-mundial-2030\/","url_meta":{"origin":2334,"position":5},"title":"Conmebol lanza su candidatura al mundial 2030","date":"2 de agosto de 2022","format":false,"excerpt":"El m\u00edtico Estadio Centenario de Montevideo fue el lugar elegido por las autoridades de la Conmebol y del gobierno uruguayo para el lanzamiento de la candidatura de Sudam\u00e9rica para la organizaci\u00f3n del mundial de futbol FIFA a realizarse en el a\u00f1o 2030. La idea est\u00e1 basada en que cuando se\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/mundial2030.jpg?fit=1200%2C749&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/2334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=2334"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/2334\/revisions"}],"predecessor-version":[{"id":2609,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/2334\/revisions\/2609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/2335"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=2334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=2334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=2334"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=2334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}