{"id":2299,"date":"2020-11-29T20:20:00","date_gmt":"2020-11-29T20:20:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=2299"},"modified":"2021-02-08T19:25:21","modified_gmt":"2021-02-08T19:25:21","slug":"covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2020\/11\/29\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\/","title":{"rendered":"COVID 19: Oscar Romero da positivo y los mellizos quedan en cuarentena"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Oscar y \u00c1ngel Romero fueron puestos en cuarentena luego que el mediocampista de San Lorenzo de Almagro (Argentina) y la selecci\u00f3n paraguaya diera positivo al COVID 19 en la prueba realizada por su club.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a lo informado por el club a trav\u00e9s de su cuenta de twitter, si bien \u00c1ngel no dio positivo, fue puesto en cuarentena por prevenci\u00f3n y hasta que Oscar se recupere.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\u26a0\ufe0f Comunicamos que Oscar Romero esta tarde dio positivo al test de Covid. Tanto \u00e9l como su hermano Angel (por ser contacto estrecho) se encuentran aislados siguiendo el protocolo sanitario, aunque en perfectas condiciones.<br><br>Pronta recuperaci\u00f3n Oscar, te esperamos con todo ?<\/p>&mdash; San Lorenzo (@SanLorenzo) <a href=\"https:\/\/twitter.com\/SanLorenzo\/status\/1332858021005963271?ref_src=twsrc%5Etfw\">November 29, 2020<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n, San Lorenzo de Almagro inform\u00f3 que el jugador se encuentra en perfecto estado de salud<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oscar y \u00c1ngel Romero fueron puestos en cuarentena luego que el mediocampista de San Lorenzo de Almagro (Argentina) y la selecci\u00f3n paraguaya diera positivo al COVID 19 en la prueba realizada por su club. De acuerdo a lo informado por el club a trav\u00e9s de su cuenta de twitter, si bien \u00c1ngel no dio positivo, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1754,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[183],"tags":[935,486,973,289],"ppma_author":[1039],"class_list":["post-2299","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-angel-romero","tag-futbol-argentino","tag-oscar-romero","tag-seleccion-paraguaya"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COVID 19: Oscar Romero da positivo y los mellizos quedan en cuarentena - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2020\/11\/29\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COVID 19: Oscar Romero da positivo y los mellizos quedan en cuarentena - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Oscar y \u00c1ngel Romero fueron puestos en cuarentena luego que el mediocampista de San Lorenzo de Almagro (Argentina) y la selecci\u00f3n paraguaya diera positivo al COVID 19 en la prueba realizada por su club. De acuerdo a lo informado por el club a trav\u00e9s de su cuenta de twitter, si bien \u00c1ngel no dio positivo, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2020\/11\/29\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-29T20:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-08T19:25:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/mellis-romero.jpg?fit=630%2C354&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"354\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/29\\\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/29\\\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"COVID 19: Oscar Romero da positivo y los mellizos quedan en cuarentena\",\"datePublished\":\"2020-11-29T20:20:00+00:00\",\"dateModified\":\"2021-02-08T19:25:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/29\\\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\\\/\"},\"wordCount\":102,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/29\\\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/mellis-romero.jpg?fit=630%2C354&ssl=1\",\"keywords\":[\"angel romero\",\"futbol argentino\",\"oscar romero\",\"seleccion paraguaya\"],\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/29\\\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/29\\\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/29\\\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\\\/\",\"name\":\"COVID 19: Oscar Romero da positivo y los mellizos quedan en cuarentena - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/29\\\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/29\\\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/mellis-romero.jpg?fit=630%2C354&ssl=1\",\"datePublished\":\"2020-11-29T20:20:00+00:00\",\"dateModified\":\"2021-02-08T19:25:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/29\\\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/29\\\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/29\\\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/mellis-romero.jpg?fit=630%2C354&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/mellis-romero.jpg?fit=630%2C354&ssl=1\",\"width\":630,\"height\":354},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/29\\\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COVID 19: Oscar Romero da positivo y los mellizos quedan en cuarentena\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COVID 19: Oscar Romero da positivo y los mellizos quedan en cuarentena - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2020\/11\/29\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\/","og_locale":"es_ES","og_type":"article","og_title":"COVID 19: Oscar Romero da positivo y los mellizos quedan en cuarentena - Informatepy","og_description":"Oscar y \u00c1ngel Romero fueron puestos en cuarentena luego que el mediocampista de San Lorenzo de Almagro (Argentina) y la selecci\u00f3n paraguaya diera positivo al COVID 19 en la prueba realizada por su club. De acuerdo a lo informado por el club a trav\u00e9s de su cuenta de twitter, si bien \u00c1ngel no dio positivo, [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2020\/11\/29\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\/","og_site_name":"Informatepy","article_published_time":"2020-11-29T20:20:00+00:00","article_modified_time":"2021-02-08T19:25:21+00:00","og_image":[{"width":630,"height":354,"url":"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/mellis-romero.jpg?fit=630%2C354&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2020\/11\/29\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2020\/11\/29\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"COVID 19: Oscar Romero da positivo y los mellizos quedan en cuarentena","datePublished":"2020-11-29T20:20:00+00:00","dateModified":"2021-02-08T19:25:21+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2020\/11\/29\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\/"},"wordCount":102,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2020\/11\/29\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/mellis-romero.jpg?fit=630%2C354&ssl=1","keywords":["angel romero","futbol argentino","oscar romero","seleccion paraguaya"],"articleSection":["Deportes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2020\/11\/29\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2020\/11\/29\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\/","url":"https:\/\/informatepy.com\/2021\/2020\/11\/29\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\/","name":"COVID 19: Oscar Romero da positivo y los mellizos quedan en cuarentena - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2020\/11\/29\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2020\/11\/29\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/mellis-romero.jpg?fit=630%2C354&ssl=1","datePublished":"2020-11-29T20:20:00+00:00","dateModified":"2021-02-08T19:25:21+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2020\/11\/29\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2020\/11\/29\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2020\/11\/29\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/mellis-romero.jpg?fit=630%2C354&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/mellis-romero.jpg?fit=630%2C354&ssl=1","width":630,"height":354},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2020\/11\/29\/covid-19-oscar-romero-da-positivo-y-los-mellizos-quedan-en-cuarentena\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"COVID 19: Oscar Romero da positivo y los mellizos quedan en cuarentena"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/mellis-romero.jpg?fit=630%2C354&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1753,"url":"https:\/\/informatepy.com\/2021\/2020\/02\/16\/los-mellis-romero-acusados-de-divismo-con-un-pie-afuera-de-san-lorenzo\/","url_meta":{"origin":2299,"position":0},"title":"Los \u00abMellis\u00bb Romero, acusados de \u00abDivismo\u00bb, con un pie afuera de San Lorenzo","date":"16 de febrero de 2020","format":false,"excerpt":"Al igual que ocurri\u00f3 en medio de la pretemporada, los hermanos\u00a0\u00d3scar y \u00c1ngel Romero\u00a0protagonizaron un nuevo\u00a0encontronazo con el entrenador Diego Monarriz, por el cual no salieron a disputar el segundo tiempo en la derrota frente a\u00a0Talleres en C\u00f3rdoba, por la\u00a0vig\u00e9sima fecha de la Superliga. Seg\u00fan trascendi\u00f3 en los pasillo del\u00a0Mario\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/mellis-romero.jpg?fit=630%2C354&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2166,"url":"https:\/\/informatepy.com\/2021\/2020\/09\/20\/angel-romero-separado-del-plantel-por-lesionar-a-un-companero\/","url_meta":{"origin":2299,"position":1},"title":"\u00c1ngel Romero separado del plantel por lesionar a un compa\u00f1ero","date":"20 de septiembre de 2020","format":false,"excerpt":"Las aguas se calmaron, pero apenas un poco. La pr\u00e1ctica del viernes, en la cual \u00c1ngel Romero le entr\u00f3 con vehemencia a Andr\u00e9s Herrera provoc\u00e1ndole la fractura del peron\u00e9 de su pierna izquierda durante un ejercicio t\u00e1ctico de ataque \u2013 defensa, dej\u00f3 secuelas El malestar que hay dentro del plantel\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/09\/angel-romero.jpg?fit=990%2C557&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1904,"url":"https:\/\/informatepy.com\/2021\/2020\/04\/20\/desiree-masi-rechaza-una-flexibilizacion-de-la-cuarentena\/","url_meta":{"origin":2299,"position":2},"title":"Desir\u00e9e Masi rechaza una flexibilizaci\u00f3n de la cuarentena","date":"20 de abril de 2020","format":false,"excerpt":"El director de Vigilancia de la Salud,\u00a0Guillermo Sequera, dio a entender que se debe comenzar a analizar la flexibilizaci\u00f3n de la cuarentena y que es conveniente \"comenzar a enfermarnos de manera controlada\". \"Si dijo eso y se acab\u00f3 ah\u00ed el an\u00e1lisis, est\u00e1 equivocado (sobre la posibilidad de flexibilizar la cuarentena)\u201d,\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/Senadora-desiree-masi.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1122,"url":"https:\/\/informatepy.com\/2021\/2019\/05\/06\/el-guma-golea-a-san-lorenzo-pero-podria-perder-los-puntos-por-incluir-5-extranjeros-en-cancha\/","url_meta":{"origin":2299,"position":3},"title":"El Guma golea a San Lorenzo, pero podr\u00eda perder los puntos por incluir 5 extranjeros en cancha","date":"6 de mayo de 2019","format":false,"excerpt":"Libertad se impuso 4 a 3 al Sportivo San Lorenzo, en el juego correspondiente a la vig\u00e9sima fecha del campeonato Apertura 2019. El mejor de la noche fue el experimentado delantero gumarelo \u00d3scar \u201cTacuara\u201d Cardozo. Pero, m\u00e1s all\u00e1 del triunfo, el equipo liberte\u00f1o podr\u00eda pedir los puntos (si Sportivo San\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/tacuara-cardozo.jpeg?fit=1000%2C617&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1384,"url":"https:\/\/informatepy.com\/2021\/2019\/08\/01\/cerro-dio-la-talla\/","url_meta":{"origin":2299,"position":4},"title":"Cerro dio la talla","date":"1 de agosto de 2019","format":false,"excerpt":"Cerro Porte\u00f1o\u00a0venci\u00f3 por 2-1 a San Lorenzo de Almagro este mi\u00e9rcoles en el estadio Gral. Pablo Rojas e inscribi\u00f3 su nombre entre los ocho mejores de Am\u00e9rica. El Cicl\u00f3n empez\u00f3 perdiendo con gol de Adam Bareiro y jugaba mal, pero en la complementaria lo dio vuelta con tantos de Joaqu\u00edn\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/Larrivey.jpg?fit=730%2C486&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1933,"url":"https:\/\/informatepy.com\/2021\/2020\/04\/23\/nuevo-brote-de-covid-19-en-china-pone-a-10-millones-de-personas-en-aislamiento\/","url_meta":{"origin":2299,"position":5},"title":"Nuevo brote de Covid-19 en China pone a 10 millones de personas en aislamiento","date":"23 de abril de 2020","format":false,"excerpt":"El gobierno de\u00a0China\u00a0puso en\u00a0aislamiento\u00a0y\u00a0cuarentena\u00a0a m\u00e1s de\u00a010 millones de personas\u00a0ante un\u00a0nuevo brote de Covid-19\u00a0registrado en la ciudad de\u00a0Harbin, en la provincia de\u00a0Heilongjiang.\u00a0 De acuerdo a informaci\u00f3n de\u00a0Reuters\u00a0medio del lugar han dado a conocer que hasta la fecha\u00a0se han detectado\u00a0540\u00a0casos positivos locales y\u00a0385\u00a0importados, por lo que las autoridades del pa\u00eds asi\u00e1tico ejecutaron\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/corona-virus-harbin.jpg?fit=1200%2C749&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/2299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=2299"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/2299\/revisions"}],"predecessor-version":[{"id":2632,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/2299\/revisions\/2632"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/1754"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=2299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=2299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=2299"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=2299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}