{"id":2269,"date":"2020-11-15T20:20:00","date_gmt":"2020-11-15T20:20:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=2269"},"modified":"2021-02-08T19:45:42","modified_gmt":"2021-02-08T19:45:42","slug":"joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2020\/11\/15\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\/","title":{"rendered":"Joe Biden estafa a los aportantes de su fundaci\u00f3n de lucha contra el c\u00e1ncer"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La organizaci\u00f3n ben\u00e9fica contra el c\u00e1ncer del&nbsp;candidato dem\u00f3crata, Joe Biden,&nbsp;gast\u00f3 la mayor parte de su dinero en la n\u00f3mina del personal y no dio nada a la investigaci\u00f3n, seg\u00fan se deduce de su declaraciones de impuestos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reportado por&nbsp;primera vez por&nbsp;The New York Post&nbsp;, las declaraciones de impuestos mostraron que <strong>\u00abThe Biden Cancer Initiative\u00bb<\/strong> acumul\u00f3 $ 4,809,619 en contribuciones, pero gast\u00f3 $ 3,070,301 en salarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Joe y&nbsp;Jill Biden&nbsp;fundaron The Biden Cancer Initiative en 2017 para ayudar a encontrar una cura y &#8216;soluciones para acelerar el progreso en la prevenci\u00f3n del c\u00e1ncer&#8217;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gregory Simon, presidente de la fundaci\u00f3n de Biden y ex ejecutivo de Pfizer, seg\u00fan los informes, recibi\u00f3 $ 429,850 durante el a\u00f1o fiscal 2018, seg\u00fan las presentaciones consultadas por DailyMail.com<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Simon, quien encabez\u00f3 el grupo de trabajo contra el c\u00e1ncer de la administraci\u00f3n Obama, recibi\u00f3 casi el doble de sus ganancias de 2017, que fueron de $ 224,539.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Danielle Carnival, ex jefa de personal del grupo de trabajo Cancer Moonshot de Obama, recibi\u00f3 258.207 d\u00f3lares en 2018.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Director de Comunicaciones, el Director de Pol\u00edtica Cient\u00edfica y el Director de Participaci\u00f3n tambi\u00e9n recibieron salarios de seis cifras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las declaraciones de impuestos mostraron que The Biden Cancer Initiative gast\u00f3 $ 56,738 en conferencias y $ 59,356 en gastos de viaje siempre seg\u00fan sus propias declaraciones de impuestos de 2017.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esas cifras aumentaron al a\u00f1o siguiente y los costos de las conferencias se dispararon a la asombrosa cantidad de $ 742,953 para conferencias y $ 97,149 en viajes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las casillas que indicaban las distribuciones de subvenciones permanecieron en blanco, lo que sugiere que la organizaci\u00f3n ben\u00e9fica no aport\u00f3 dinero a becas de estudio para la lucha contra el c\u00e1ncer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Iniciativa contra el C\u00e1ncer de Biden se cre\u00f3 despu\u00e9s de que el hijo mayor de Joe, Beau Biden, muriera en 2015 tras sufrir un diagn\u00f3stico de c\u00e1ncer cerebral.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La organizaci\u00f3n ben\u00e9fica contra el c\u00e1ncer del&nbsp;candidato dem\u00f3crata, Joe Biden,&nbsp;gast\u00f3 la mayor parte de su dinero en la n\u00f3mina del personal y no dio nada a la investigaci\u00f3n, seg\u00fan se deduce de su declaraciones de impuestos. Reportado por&nbsp;primera vez por&nbsp;The New York Post&nbsp;, las declaraciones de impuestos mostraron que \u00abThe Biden Cancer Initiative\u00bb acumul\u00f3 $ [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2270,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[173],"tags":[832,941],"ppma_author":[1039],"class_list":["post-2269","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","tag-estados-unidos","tag-joe-biden"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Joe Biden estafa a los aportantes de su fundaci\u00f3n de lucha contra el c\u00e1ncer - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2020\/11\/15\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Joe Biden estafa a los aportantes de su fundaci\u00f3n de lucha contra el c\u00e1ncer - Informatepy\" \/>\n<meta property=\"og:description\" content=\"La organizaci\u00f3n ben\u00e9fica contra el c\u00e1ncer del&nbsp;candidato dem\u00f3crata, Joe Biden,&nbsp;gast\u00f3 la mayor parte de su dinero en la n\u00f3mina del personal y no dio nada a la investigaci\u00f3n, seg\u00fan se deduce de su declaraciones de impuestos. Reportado por&nbsp;primera vez por&nbsp;The New York Post&nbsp;, las declaraciones de impuestos mostraron que \u00abThe Biden Cancer Initiative\u00bb acumul\u00f3 $ [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2020\/11\/15\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-15T20:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-08T19:45:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/biden.jpg?fit=634%2C423&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"634\" \/>\n\t<meta property=\"og:image:height\" content=\"423\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/15\\\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/15\\\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"Joe Biden estafa a los aportantes de su fundaci\u00f3n de lucha contra el c\u00e1ncer\",\"datePublished\":\"2020-11-15T20:20:00+00:00\",\"dateModified\":\"2021-02-08T19:45:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/15\\\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\\\/\"},\"wordCount\":342,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/15\\\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/biden.jpg?fit=634%2C423&ssl=1\",\"keywords\":[\"estados unidos\",\"joe biden\"],\"articleSection\":[\"Mundo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/15\\\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/15\\\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/15\\\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\\\/\",\"name\":\"Joe Biden estafa a los aportantes de su fundaci\u00f3n de lucha contra el c\u00e1ncer - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/15\\\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/15\\\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/biden.jpg?fit=634%2C423&ssl=1\",\"datePublished\":\"2020-11-15T20:20:00+00:00\",\"dateModified\":\"2021-02-08T19:45:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/15\\\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/15\\\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/15\\\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/biden.jpg?fit=634%2C423&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/biden.jpg?fit=634%2C423&ssl=1\",\"width\":634,\"height\":423,\"caption\":\"Joe Biden revoc\u00f3 el permiso presidencial para el proyecto de extensi\u00f3n del oleoducto Keystone XL en su primer d\u00eda. (EFE)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/15\\\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Joe Biden estafa a los aportantes de su fundaci\u00f3n de lucha contra el c\u00e1ncer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Joe Biden estafa a los aportantes de su fundaci\u00f3n de lucha contra el c\u00e1ncer - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2020\/11\/15\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\/","og_locale":"es_ES","og_type":"article","og_title":"Joe Biden estafa a los aportantes de su fundaci\u00f3n de lucha contra el c\u00e1ncer - Informatepy","og_description":"La organizaci\u00f3n ben\u00e9fica contra el c\u00e1ncer del&nbsp;candidato dem\u00f3crata, Joe Biden,&nbsp;gast\u00f3 la mayor parte de su dinero en la n\u00f3mina del personal y no dio nada a la investigaci\u00f3n, seg\u00fan se deduce de su declaraciones de impuestos. Reportado por&nbsp;primera vez por&nbsp;The New York Post&nbsp;, las declaraciones de impuestos mostraron que \u00abThe Biden Cancer Initiative\u00bb acumul\u00f3 $ [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2020\/11\/15\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\/","og_site_name":"Informatepy","article_published_time":"2020-11-15T20:20:00+00:00","article_modified_time":"2021-02-08T19:45:42+00:00","og_image":[{"width":634,"height":423,"url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/biden.jpg?fit=634%2C423&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2020\/11\/15\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2020\/11\/15\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"Joe Biden estafa a los aportantes de su fundaci\u00f3n de lucha contra el c\u00e1ncer","datePublished":"2020-11-15T20:20:00+00:00","dateModified":"2021-02-08T19:45:42+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2020\/11\/15\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\/"},"wordCount":342,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2020\/11\/15\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/biden.jpg?fit=634%2C423&ssl=1","keywords":["estados unidos","joe biden"],"articleSection":["Mundo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2020\/11\/15\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2020\/11\/15\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\/","url":"https:\/\/informatepy.com\/2021\/2020\/11\/15\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\/","name":"Joe Biden estafa a los aportantes de su fundaci\u00f3n de lucha contra el c\u00e1ncer - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2020\/11\/15\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2020\/11\/15\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/biden.jpg?fit=634%2C423&ssl=1","datePublished":"2020-11-15T20:20:00+00:00","dateModified":"2021-02-08T19:45:42+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2020\/11\/15\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2020\/11\/15\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2020\/11\/15\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/biden.jpg?fit=634%2C423&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/biden.jpg?fit=634%2C423&ssl=1","width":634,"height":423,"caption":"Joe Biden revoc\u00f3 el permiso presidencial para el proyecto de extensi\u00f3n del oleoducto Keystone XL en su primer d\u00eda. (EFE)"},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2020\/11\/15\/joe-biden-estafa-a-los-aportantes-de-su-fundacion-de-lucha-contra-el-cancer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Joe Biden estafa a los aportantes de su fundaci\u00f3n de lucha contra el c\u00e1ncer"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/biden.jpg?fit=634%2C423&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":7306,"url":"https:\/\/informatepy.com\/2021\/2021\/09\/24\/joe-biden-podria-deber-hasta-us-500000-en-impuestos-atrasados\/","url_meta":{"origin":2269,"position":0},"title":"Joe Biden podr\u00eda deber hasta u$s 500,000 en impuestos atrasados","date":"24 de septiembre de 2021","format":false,"excerpt":"Un legislador republicano alega que Joe Biden puede deber hasta $ 500,000 en impuestos atrasados. \u201cJoe Biden quiere aumentar los impuestos en 2,1 billones de d\u00f3lares mientras afirma que los ricos deben pagar su 'parte justa'.\u00a0Pero en 2017, el multimillonario Joe Biden eludi\u00f3 sus impuestos sobre la n\u00f3mina, los mismos\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/09\/biden-sonriente.jpg?fit=1015%2C571&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12616,"url":"https:\/\/informatepy.com\/2021\/2022\/07\/11\/the-new-york-times-le-dice-no-a-la-reeleccion-de-joe-biden\/","url_meta":{"origin":2269,"position":1},"title":"The New York Times le dice no a la reelecci\u00f3n de Joe Biden","date":"11 de julio de 2022","format":false,"excerpt":"El reconocido medio estadounidense, The New York Times, apura al presidente Joe Biden para que no se postule a la reelecci\u00f3n. Temen por el partido dem\u00f3crata.","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/joe-biden-helado.jpeg?fit=948%2C465&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5831,"url":"https:\/\/informatepy.com\/2021\/2021\/07\/16\/joe-biden-el-empleado-del-mes-de-las-big-tech\/","url_meta":{"origin":2269,"position":2},"title":"Joe Biden, el empleado del mes de las Big Tech","date":"16 de julio de 2021","format":false,"excerpt":"Joe Biden pretende limitar la libertad de expresi\u00f3n de los usuarios de redes sociales","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/joe-biden-empleado-del-mes.jpg?fit=1080%2C915&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11063,"url":"https:\/\/informatepy.com\/2021\/2022\/04\/08\/bancos-estadounidenses-senalaron-mas-de-150-transacciones-financieras-sospechosas-de-la-familia-biden\/","url_meta":{"origin":2269,"position":3},"title":"Bancos estadounidenses se\u00f1alaron m\u00e1s de 150 transacciones financieras sospechosas de la familia Biden","date":"8 de abril de 2022","format":false,"excerpt":"Los bancos estadounidenses se\u00f1alaron m\u00e1s de 150 transacciones financieras sospechosas de Hunter y James Biden, seg\u00fan CBS News el mi\u00e9rcoles.","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/hunter-biden.jpg?fit=636%2C382&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4582,"url":"https:\/\/informatepy.com\/2021\/2021\/04\/22\/black-lives-matter-ahora-se-queja-de-joe-biden\/","url_meta":{"origin":2269,"position":4},"title":"Black Lives Matter ahora se queja de Joe Biden","date":"22 de abril de 2021","format":false,"excerpt":"Pocos meses despu\u00e9s de la asunci\u00f3n de Joe Biden como presidente de los Estados Unidos, Black LIves Matter (BLM) uno de los grupos que m\u00e1s \"trabaj\u00f3\" para la salida de Donald Trump de la Casa Blanca, descubri\u00f3 quien es verdaderamente Joe Biden y el grupo pol\u00edtico que el representa. En\u2026","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/BLM.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5447,"url":"https:\/\/informatepy.com\/2021\/2021\/06\/22\/el-presupuesto-2021-de-joe-biden-es-el-primero-en-40-anos-en-tener-subsidios-para-clinicas-de-abortos\/","url_meta":{"origin":2269,"position":5},"title":"El Presupuesto 2021 de Joe Biden es el primero en 40 a\u00f1os en tener subsidios para cl\u00ednicas de abortos","date":"22 de junio de 2021","format":false,"excerpt":"En el documento del presupuesto para el A\u00f1o Fiscal 2021, el gobierno de Joe Biden no incluy\u00f3 la hist\u00f3rica Enmienda Hyde, que evita subsidios a las cl\u00ednicas de abortos desde 1980.","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/biden-en-misa.jpg?fit=770%2C471&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/2269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=2269"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/2269\/revisions"}],"predecessor-version":[{"id":2659,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/2269\/revisions\/2659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/2270"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=2269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=2269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=2269"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=2269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}