{"id":2237,"date":"2020-11-03T20:20:00","date_gmt":"2020-11-03T20:20:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=2237"},"modified":"2021-02-08T19:58:02","modified_gmt":"2021-02-08T19:58:02","slug":"si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2020\/11\/03\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\/","title":{"rendered":"Si escuchas rock y eres de izquierda, hay algo que deber\u00edas saber"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El proceso que continu\u00f3 al carnicero&nbsp;Joseph Stalin&nbsp;en la Uni\u00f3n Sovi\u00e9tica, quien falleci\u00f3 en 1953, puede que no haya tenido los genocidios de los primeros a\u00f1os del r\u00e9gimen.&nbsp;Sin embargo, la idea del proceso de apertura en materia de libertades individuales que muchos historiadores destacan tiene mucho de falacia. Hasta en la \u00faltima d\u00e9cada de su existencia, la URSS se dedic\u00f3 a prohibir y regular cada aspecto de la vida de los rusos, incluso la m\u00fasica que escuchaban.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante la reciente muerte del guitarrista&nbsp;<em>Eddie Van Halen<\/em>, los medios de comunicaci\u00f3n lo homenajearon como se merece y recordaron varios cap\u00edtulos interesantes de su vida. Haber grabado con Michael Jackson de forma encubierta el solo de&nbsp;<em>Beat It<\/em>&nbsp;es, sin dudas, uno de los m\u00e1s divertidos. Su desaparici\u00f3n f\u00edsica, como suele ocurrir, hizo que la prensa ponga el foco en su carrera. Lamentablemente, los comunicadores progresistas, que lo reconocieron como uno de los mejores guitarristas de la historia, dejaron de lado un recuerdo digno de menci\u00f3n: su banda,&nbsp;<em>Van Halen<\/em>, estuvo prohibida por la dictadura sovi\u00e9tica. De hecho, adquirir un disco del grupo era imposible y poseerlo, un delito. Para el r\u00e9gimen,&nbsp;<em>Van Halen<\/em>&nbsp;era portavoz de \u201cpropaganda anticomunista\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Probablemente, los bur\u00f3cratas de la dictadura habr\u00e1n reinterpretado a&nbsp;Marx&nbsp;que, antes de la existencia del&nbsp;<em>rock<\/em>, asegur\u00f3 que la religi\u00f3n era nociva ya que era \u201cel opio de los pueblos\u201d, adormec\u00eda a los proletarios y no les permit\u00eda ver su ignominia. \u00bfAcaso la m\u00fasica ejerc\u00eda ese efecto durante los ochenta? O quiz\u00e1s la cuesti\u00f3n pasaba por otro lado y hab\u00eda un temor expl\u00edcito que la juventud pueda encontrar en la m\u00fasica moderna un veh\u00edculo para expresar un descontento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sea como sea, el&nbsp;<em>punk<\/em>&nbsp;era el g\u00e9nero preferido de los censuradores comunistas:&nbsp;<em>Sex Pistols<\/em>,&nbsp;<em>Ramones<\/em>&nbsp;y&nbsp;<em>Madness<\/em>&nbsp;eran considerados material subversivo. Lo curioso es que, en la lista de razones, la KGB reconoc\u00eda que el&nbsp;<em>punk<\/em>, por el s\u00f3lo hecho de ser&nbsp;<em>punk<\/em>, ya era motivo de prohibici\u00f3n. Entre las bandas prohibidas aparece&nbsp;<em>B-52<\/em>. S\u00ed, por&nbsp;<em>punk<\/em>&nbsp;y por violentos. Es probable que el agente de inteligencia encargado de hacer el reporte, directamente ni haya escuchado el disco. No tiene sentido. En fin, an\u00e9cdotas del comunismo.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Ramones - Poison Heart (Official Video)\" width=\"740\" height=\"555\" src=\"https:\/\/www.youtube.com\/embed\/OfIfzVf8t6E?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Pero la \u201cviolencia\u201d no era lo \u00fanico que le preocupaba al r\u00e9gimen. Las bellas Tina Turner y Donna Summer tambi\u00e9n engalanaban la lista de artistas prohibidas por el comunismo. La int\u00e9rprete de&nbsp;<em>What\u00b4s love got to do with it<\/em>&nbsp;no tuvo distribuci\u00f3n en la&nbsp;Uni\u00f3n Sovi\u00e9tica&nbsp;en el mejor momento de su carrera. La justificaci\u00f3n en la lista de la censura ten\u00eda una sola palabra: \u201csexo\u201d. Una explicaci\u00f3n similar aparec\u00eda en el casillero de la morocha que inmortaliz\u00f3&nbsp;<em>Hot Stuff:<\/em>&nbsp;\u201cerotismo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>AC\/DC<\/em>: \u201cneofascismo\u201d;&nbsp;<em>Scorpions<\/em>&nbsp;y&nbsp;<em>Iron Maiden<\/em>: \u201cviolencia\u201d;&nbsp;<em>Pink Floyd<\/em>: \u201cinterferencia en los asuntos de la Uni\u00f3n Sovi\u00e9tica\u201d;&nbsp;<em>Judas Priest<\/em>: \u201canticomunismo\u00bb;&nbsp;<em>Kiss<\/em>: \u00abnacionalismo\u00bb. No se salv\u00f3 casi nadie. Pero la nota de color se la lleva sin dudas el cantante&nbsp;espa\u00f1ol&nbsp;Julio Iglesias, censurado por \u201cneofascista\u201d.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informe-kgb.jpeg?w=740&#038;ssl=1\" alt=\"\" class=\"wp-image-3173\" data-recalc-dims=\"1\"\/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La m\u00fasica, y las distintas manifestaciones art\u00edsticas en general, suelen ser controladas y reguladas por todos los procesos autoritarios. Las dictaduras en Am\u00e9rica Latina, que justificaban su existencia en la lucha contra el comunismo, en menor medida, tambi\u00e9n hac\u00edan cosas similares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Curiosamente, los modelos pol\u00edticos que aceptan la diversidad y las cr\u00edticas, logran instituciones m\u00e1s s\u00f3lidas que los experimentos basados en el pu\u00f1o de hierro. Las democracias liberales y republicanas, de donde nacieron todos estos artistas censurados bajo el socialismo real, siguen vigentes. La URSS es historia, aunque todav\u00eda unos pocos trasnochados reivindiquen su modelo fracasado y autoritario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfDar\u00e1 alguna explicaci\u00f3n el progresismo, que se jacta de cultural y que, al mismo tiempo, sigue mirando con cari\u00f1o la experiencia sovi\u00e9tica?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El proceso que continu\u00f3 al carnicero&nbsp;Joseph Stalin&nbsp;en la Uni\u00f3n Sovi\u00e9tica, quien falleci\u00f3 en 1953, puede que no haya tenido los genocidios de los primeros a\u00f1os del r\u00e9gimen.&nbsp;Sin embargo, la idea del proceso de apertura en materia de libertades individuales que muchos historiadores destacan tiene mucho de falacia. Hasta en la \u00faltima d\u00e9cada de su existencia, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2238,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[202],"tags":[963,964],"ppma_author":[1039],"class_list":["post-2237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-show","tag-comunismo","tag-rnr"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Si escuchas rock y eres de izquierda, hay algo que deber\u00edas saber - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2020\/11\/03\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Si escuchas rock y eres de izquierda, hay algo que deber\u00edas saber - Informatepy\" \/>\n<meta property=\"og:description\" content=\"El proceso que continu\u00f3 al carnicero&nbsp;Joseph Stalin&nbsp;en la Uni\u00f3n Sovi\u00e9tica, quien falleci\u00f3 en 1953, puede que no haya tenido los genocidios de los primeros a\u00f1os del r\u00e9gimen.&nbsp;Sin embargo, la idea del proceso de apertura en materia de libertades individuales que muchos historiadores destacan tiene mucho de falacia. Hasta en la \u00faltima d\u00e9cada de su existencia, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2020\/11\/03\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-03T20:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-08T19:58:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/comunismo.png?fit=624%2C385&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"624\" \/>\n\t<meta property=\"og:image:height\" content=\"385\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/03\\\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/03\\\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"Si escuchas rock y eres de izquierda, hay algo que deber\u00edas saber\",\"datePublished\":\"2020-11-03T20:20:00+00:00\",\"dateModified\":\"2021-02-08T19:58:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/03\\\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\\\/\"},\"wordCount\":731,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/03\\\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/comunismo.png?fit=624%2C385&ssl=1\",\"keywords\":[\"comunismo\",\"rnr\"],\"articleSection\":[\"Show\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/03\\\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/03\\\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/03\\\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\\\/\",\"name\":\"Si escuchas rock y eres de izquierda, hay algo que deber\u00edas saber - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/03\\\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/03\\\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/comunismo.png?fit=624%2C385&ssl=1\",\"datePublished\":\"2020-11-03T20:20:00+00:00\",\"dateModified\":\"2021-02-08T19:58:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/03\\\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/03\\\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/03\\\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/comunismo.png?fit=624%2C385&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/comunismo.png?fit=624%2C385&ssl=1\",\"width\":624,\"height\":385},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/11\\\/03\\\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Si escuchas rock y eres de izquierda, hay algo que deber\u00edas saber\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Si escuchas rock y eres de izquierda, hay algo que deber\u00edas saber - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2020\/11\/03\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\/","og_locale":"es_ES","og_type":"article","og_title":"Si escuchas rock y eres de izquierda, hay algo que deber\u00edas saber - Informatepy","og_description":"El proceso que continu\u00f3 al carnicero&nbsp;Joseph Stalin&nbsp;en la Uni\u00f3n Sovi\u00e9tica, quien falleci\u00f3 en 1953, puede que no haya tenido los genocidios de los primeros a\u00f1os del r\u00e9gimen.&nbsp;Sin embargo, la idea del proceso de apertura en materia de libertades individuales que muchos historiadores destacan tiene mucho de falacia. Hasta en la \u00faltima d\u00e9cada de su existencia, [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2020\/11\/03\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\/","og_site_name":"Informatepy","article_published_time":"2020-11-03T20:20:00+00:00","article_modified_time":"2021-02-08T19:58:02+00:00","og_image":[{"width":624,"height":385,"url":"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/comunismo.png?fit=624%2C385&ssl=1","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2020\/11\/03\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2020\/11\/03\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"Si escuchas rock y eres de izquierda, hay algo que deber\u00edas saber","datePublished":"2020-11-03T20:20:00+00:00","dateModified":"2021-02-08T19:58:02+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2020\/11\/03\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\/"},"wordCount":731,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2020\/11\/03\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/comunismo.png?fit=624%2C385&ssl=1","keywords":["comunismo","rnr"],"articleSection":["Show"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2020\/11\/03\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2020\/11\/03\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\/","url":"https:\/\/informatepy.com\/2021\/2020\/11\/03\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\/","name":"Si escuchas rock y eres de izquierda, hay algo que deber\u00edas saber - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2020\/11\/03\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2020\/11\/03\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/comunismo.png?fit=624%2C385&ssl=1","datePublished":"2020-11-03T20:20:00+00:00","dateModified":"2021-02-08T19:58:02+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2020\/11\/03\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2020\/11\/03\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2020\/11\/03\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/comunismo.png?fit=624%2C385&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/comunismo.png?fit=624%2C385&ssl=1","width":624,"height":385},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2020\/11\/03\/si-escuchas-rock-y-eres-de-izquierda-hay-algo-que-deberias-saber\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Si escuchas rock y eres de izquierda, hay algo que deber\u00edas saber"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/comunismo.png?fit=624%2C385&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":4729,"url":"https:\/\/informatepy.com\/2021\/2021\/05\/01\/kim-jong-un-controlara-el-corte-de-pelo-y-la-musica-que-escuchan-los-adolescentes\/","url_meta":{"origin":2237,"position":0},"title":"Kim Jong-un controlar\u00e1 el corte de pelo y la m\u00fasica que escuchan los adolescentes","date":"1 de mayo de 2021","format":false,"excerpt":"Llam\u00f3 a la Liga Juvenil de Corea del Norte a evitar el \"veneno peligroso\" de estas modas en medio de una cruzada por las influencias extranjeras.","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/congre-liga-juvenil-corea-del-norte.jpeg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":539,"url":"https:\/\/informatepy.com\/2021\/2019\/02\/14\/las-personas-que-cantan-en-el-auto-son-mas-felices-y-estables\/","url_meta":{"origin":2237,"position":1},"title":"Las personas que cantan en el auto son m\u00e1s felices y estables","date":"14 de febrero de 2019","format":false,"excerpt":"Si se trata de mejorar la calidad de vida de todos los conductores de cualquier ciudad del mundo, entonces comencemos a tomar en cuenta estos estudios que aseguran que las personas que cantan en el auto son m\u00e1s felices y estables. Estamos seguros que la mayor\u00eda de las personas que\u2026","rel":"","context":"En \u00abSalud\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/cantando-en-el-auto.jpg?fit=564%2C317&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13116,"url":"https:\/\/informatepy.com\/2021\/2022\/08\/04\/habra-escuchado-bien\/","url_meta":{"origin":2237,"position":2},"title":"\u00bfHabr\u00e1 escuchado bien?","date":"4 de agosto de 2022","format":false,"excerpt":"El actual vicepresidente de la Rep\u00fablica y precandidato a la presidencia, Hugo Vel\u00e1zquez, anunci\u00f3 que presentar\u00e1 su renuncia a la vicepresidencia en el transcurso de \u201ceste mes\u201d. A pesar que lleva meses haciendo campa\u00f1a proselitista, Hugo Vel\u00e1zquez no renunci\u00f3 al cargo que ostenta, lo que llev\u00f3 a varios se\u00f1alamientos por\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/07\/lourdes-samaniego-y-hugo-velazquez.jpg?fit=660%2C330&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1249,"url":"https:\/\/informatepy.com\/2021\/2019\/06\/06\/hoy-podria-definirse-la-suerte-de-dionisio-amarilla\/","url_meta":{"origin":2237,"position":3},"title":"Hoy podr\u00eda definirse la suerte de Dionisio Amarilla","date":"6 de junio de 2019","format":false,"excerpt":"La Comisi\u00f3n de Asuntos Constitucionales deb\u00eda dicta\u00adminar sobre el tema ayer, pero luego de escuchar al legislador del PLRA, quien es acusado de uso indebido de influencias, decidi\u00f3 que se postergue una semana m\u00e1s el tratamiento para volver a escuchar su des\u00adcargo. De igual forma, las bancadas de Frente Guasu,\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/dionisio-amarilla.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8514,"url":"https:\/\/informatepy.com\/2021\/2021\/11\/27\/monges-inaugura-bancada-y-escucha-ofertas\/","url_meta":{"origin":2237,"position":4},"title":"Monges inaugura bancada y&#8230; \u00bfEscucha ofertas?","date":"27 de noviembre de 2021","format":false,"excerpt":"Los senadores Juan Dar\u00edo Monges, Mart\u00edn Ar\u00e9valo, Derlis Osorio y Javier Zacar\u00edas Ir\u00fan, inauguraron una nueva bancada en la c\u00e1mara alta con la intenci\u00f3n de mantenerse \"alejados de lo que tenga que ver con la campa\u00f1a de Hugo Vel\u00e1zquez para el 2023\". Monges, en su car\u00e1cter de presidente del nuevo\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/senador-juan-dario-monges.jpg?fit=952%2C619&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5458,"url":"https:\/\/informatepy.com\/2021\/2021\/06\/24\/enrique-bacchetta-es-lamentable-escuchar-de-un-companero-propiciar-la-ilegalidad\/","url_meta":{"origin":2237,"position":5},"title":"Enrique Bacchetta: \u201cEs lamentable escuchar de un compa\u00f1ero propiciar la ilegalidad\u00bb","date":"24 de junio de 2021","format":false,"excerpt":"El senador Enrique Bacchetta manifest\u00f3 que es lamentable la postura del nuevo vicepresidente del Congreso, Sixto Pereira, de estar propiciando las invasiones de propiedades y creando zozobra e incomodidad a sectores productivos del pa\u00eds. \u201cEs lamentable escuchar de un compa\u00f1ero propiciar la ilegalidad porque propiciar invasiones de propiedades porque eso\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/enrique-bacchetta-1.jpg?fit=1000%2C563&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/2237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=2237"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/2237\/revisions"}],"predecessor-version":[{"id":2680,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/2237\/revisions\/2680"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/2238"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=2237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=2237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=2237"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=2237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}