{"id":2205,"date":"2020-10-08T20:20:00","date_gmt":"2020-10-08T20:20:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=2205"},"modified":"2021-02-08T20:10:46","modified_gmt":"2021-02-08T20:10:46","slug":"los-fueros-no-dan-patente-de-corso","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2020\/10\/08\/los-fueros-no-dan-patente-de-corso\/","title":{"rendered":"Los fueros no dan patente de corso"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Que la C\u00e1mara de Diputados es la C\u00e1mara de la verg\u00fcenza no hay duda, ellos han hecho m\u00e9ritos suficientes para ese nombre y nadie deber\u00eda discutirlo pero, lo sucedido con la Diputada Amarilla en los \u00faltimos d\u00edas no responde a ese bien ganado nombre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan est\u00e1 establecido en la Ley de fueros: \u201c<strong><em>Ning\u00fan miembro del Congreso puede ser acusado judicialmente por las opiniones que emita en el desempe\u00f1o de sus funciones\u201d. <\/em><\/strong>Esto no es discutible, lo que s\u00ed es discutible es que es una opini\u00f3n y que es una acusaci\u00f3n. Por definici\u00f3n, una opini\u00f3n es \u201cla idea o concepto en que se tiene a una persona o cosa\u201d, por ejemplo, la gente tiene una buena opini\u00f3n de Juan. Por el contrario, una acusaci\u00f3n es una acci\u00f3n muy diferente a la opini\u00f3n y, le guste o no a la Diputada, lo de ella no es una opini\u00f3n, ella directamente acus\u00f3 a sus pares de haber llegado a la c\u00e1mara con dinero sucio. Los acus\u00f3 de mafiosos o de narcotraficantes o de contrabandistas o de cualquier otra clase de delitos y, como ya es su costumbre, no present\u00f3 ninguna prueba.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-layout-flow wp-block-quote-is-layout-flow\"><p>Si un diputado tuviese la ocurrencia de afirmar que tal o cual diputada es una prostituta, \u00bfCorresponder\u00eda aplicarle una sanci\u00f3n a ese diputado?<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, la diputada deber\u00eda recordar que, en su car\u00e1cter de legisladora, por el art\u00edculo 286 del C\u00f3digo Procesal Penal, est\u00e1 obligada a denunciar ante el Ministerio P\u00fabico todo delito del que tome conocimiento en ejercicio de sus funciones, como en este caso. De no hacerlo, son dos las opciones, o la diputada incumple el art\u00edculo 81 del Reglamento Interno de la C\u00e1mara de Diputados que reza: <strong><em>\u201cSon absolutamente prohibidas a los Diputados las alusiones irrespetuosas y las imputaciones de mala intenci\u00f3n o de m\u00f3viles ileg\u00edtimos hacia la C\u00e1mara y sus miembros, en las sesiones y fuera de ellas\u201d<\/em><\/strong> o, simplemente, es una charlatana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tal vez no sea lo suficientemente claro para explicar mi punto y, cuando eso sucede, nada mejor que apelar al sentido com\u00fan del lector. Les pregunto: Si un diputado tuviese la ocurrencia de afirmar que tal o cual diputada es una prostituta, \u00bfCorresponder\u00eda aplicarle una sanci\u00f3n a ese diputado? claro que s\u00ed, entonces \u00bfPor qu\u00e9 no hacerlo en este caso?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como afirm\u00e9 en el t\u00edtulo, los fueros son para opiniones, no les da patente de corso a los diputados o senadores para ir por la vida injuriando a otros enancados en una falsa moralidad. Dejen de abusar del desconocimiento de muchos ciudadanos para andar por los medios llorando dictadura y amenazando a la Corte de Justicia, trabajen en beneficio de sus mandantes y, si toman conocimiento de un delito, den\u00fancienlo en la justicia presenten pruebas y h\u00e1ganse cargo; nosotros, \u00ablos comunes\u00bb, se lo vamos a agradecer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Que la C\u00e1mara de Diputados es la C\u00e1mara de la verg\u00fcenza no hay duda, ellos han hecho m\u00e9ritos suficientes para ese nombre y nadie deber\u00eda discutirlo pero, lo sucedido con la Diputada Amarilla en los \u00faltimos d\u00edas no responde a ese bien ganado nombre. Seg\u00fan est\u00e1 establecido en la Ley de fueros: \u201cNing\u00fan miembro del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2206,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[248],"tags":[437,596,948],"ppma_author":[1039],"class_list":["post-2205","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis","tag-camara-de-diputados","tag-celeste-amarilla","tag-fueros-parlamentarios"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los fueros no dan patente de corso - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2020\/10\/08\/los-fueros-no-dan-patente-de-corso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los fueros no dan patente de corso - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Que la C\u00e1mara de Diputados es la C\u00e1mara de la verg\u00fcenza no hay duda, ellos han hecho m\u00e9ritos suficientes para ese nombre y nadie deber\u00eda discutirlo pero, lo sucedido con la Diputada Amarilla en los \u00faltimos d\u00edas no responde a ese bien ganado nombre. Seg\u00fan est\u00e1 establecido en la Ley de fueros: \u201cNing\u00fan miembro del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2020\/10\/08\/los-fueros-no-dan-patente-de-corso\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-08T20:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-08T20:10:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/bandera-pirata.jpg?fit=670%2C400&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/10\\\/08\\\/los-fueros-no-dan-patente-de-corso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/10\\\/08\\\/los-fueros-no-dan-patente-de-corso\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"Los fueros no dan patente de corso\",\"datePublished\":\"2020-10-08T20:20:00+00:00\",\"dateModified\":\"2021-02-08T20:10:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/10\\\/08\\\/los-fueros-no-dan-patente-de-corso\\\/\"},\"wordCount\":505,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/10\\\/08\\\/los-fueros-no-dan-patente-de-corso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/bandera-pirata.jpg?fit=670%2C400&ssl=1\",\"keywords\":[\"c\u00e1mara de diputados\",\"celeste amarilla\",\"fueros parlamentarios\"],\"articleSection\":[\"Analisis\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/10\\\/08\\\/los-fueros-no-dan-patente-de-corso\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/10\\\/08\\\/los-fueros-no-dan-patente-de-corso\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/10\\\/08\\\/los-fueros-no-dan-patente-de-corso\\\/\",\"name\":\"Los fueros no dan patente de corso - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/10\\\/08\\\/los-fueros-no-dan-patente-de-corso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/10\\\/08\\\/los-fueros-no-dan-patente-de-corso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/bandera-pirata.jpg?fit=670%2C400&ssl=1\",\"datePublished\":\"2020-10-08T20:20:00+00:00\",\"dateModified\":\"2021-02-08T20:10:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/10\\\/08\\\/los-fueros-no-dan-patente-de-corso\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/10\\\/08\\\/los-fueros-no-dan-patente-de-corso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/10\\\/08\\\/los-fueros-no-dan-patente-de-corso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/bandera-pirata.jpg?fit=670%2C400&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/bandera-pirata.jpg?fit=670%2C400&ssl=1\",\"width\":670,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/10\\\/08\\\/los-fueros-no-dan-patente-de-corso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los fueros no dan patente de corso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los fueros no dan patente de corso - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2020\/10\/08\/los-fueros-no-dan-patente-de-corso\/","og_locale":"es_ES","og_type":"article","og_title":"Los fueros no dan patente de corso - Informatepy","og_description":"Que la C\u00e1mara de Diputados es la C\u00e1mara de la verg\u00fcenza no hay duda, ellos han hecho m\u00e9ritos suficientes para ese nombre y nadie deber\u00eda discutirlo pero, lo sucedido con la Diputada Amarilla en los \u00faltimos d\u00edas no responde a ese bien ganado nombre. Seg\u00fan est\u00e1 establecido en la Ley de fueros: \u201cNing\u00fan miembro del [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2020\/10\/08\/los-fueros-no-dan-patente-de-corso\/","og_site_name":"Informatepy","article_published_time":"2020-10-08T20:20:00+00:00","article_modified_time":"2021-02-08T20:10:46+00:00","og_image":[{"width":670,"height":400,"url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/bandera-pirata.jpg?fit=670%2C400&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2020\/10\/08\/los-fueros-no-dan-patente-de-corso\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2020\/10\/08\/los-fueros-no-dan-patente-de-corso\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"Los fueros no dan patente de corso","datePublished":"2020-10-08T20:20:00+00:00","dateModified":"2021-02-08T20:10:46+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2020\/10\/08\/los-fueros-no-dan-patente-de-corso\/"},"wordCount":505,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2020\/10\/08\/los-fueros-no-dan-patente-de-corso\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/bandera-pirata.jpg?fit=670%2C400&ssl=1","keywords":["c\u00e1mara de diputados","celeste amarilla","fueros parlamentarios"],"articleSection":["Analisis"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2020\/10\/08\/los-fueros-no-dan-patente-de-corso\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2020\/10\/08\/los-fueros-no-dan-patente-de-corso\/","url":"https:\/\/informatepy.com\/2021\/2020\/10\/08\/los-fueros-no-dan-patente-de-corso\/","name":"Los fueros no dan patente de corso - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2020\/10\/08\/los-fueros-no-dan-patente-de-corso\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2020\/10\/08\/los-fueros-no-dan-patente-de-corso\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/bandera-pirata.jpg?fit=670%2C400&ssl=1","datePublished":"2020-10-08T20:20:00+00:00","dateModified":"2021-02-08T20:10:46+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2020\/10\/08\/los-fueros-no-dan-patente-de-corso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2020\/10\/08\/los-fueros-no-dan-patente-de-corso\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2020\/10\/08\/los-fueros-no-dan-patente-de-corso\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/bandera-pirata.jpg?fit=670%2C400&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/bandera-pirata.jpg?fit=670%2C400&ssl=1","width":670,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2020\/10\/08\/los-fueros-no-dan-patente-de-corso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Los fueros no dan patente de corso"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/bandera-pirata.jpg?fit=670%2C400&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":10536,"url":"https:\/\/informatepy.com\/2021\/2022\/03\/10\/propios-y-ajenos-contra-celeste-amarilla\/","url_meta":{"origin":2205,"position":0},"title":"Propios y ajenos contra Celeste Amarilla","date":"10 de marzo de 2022","format":false,"excerpt":"Luego de \"arrugar\" con el pedido de suspensi\u00f3n del diputado Basilio N\u00fa\u00f1ez y al mismo tiempo en que ensaya disculpas y busca desviar la atenci\u00f3n de sus palabras contra sus colegas, diputados de diversas bancadas y partidos hicieron causa com\u00fan contra Celeste Amarilla. En la sesi\u00f3n de ayer, Cristina Villalba\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/celeste-amarilla-desierto.png?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":14038,"url":"https:\/\/informatepy.com\/2021\/2022\/09\/23\/esta-vigente-y-se-aplica-una-ley-que-menciona-la-pena-de-muerte-la-ley-de-garantia-de-fueros\/","url_meta":{"origin":2205,"position":1},"title":"Est\u00e1 vigente y se aplica, una ley que menciona la pena de muerte: La ley de \u00abGarant\u00eda de fueros\u00bb","date":"23 de septiembre de 2022","format":false,"excerpt":"Suena a disparate, pero de disparate no tiene un pelo. Hay una controvertida ley, la N\u00b0 323\/55 \u2018\u2018De Garant\u00eda de Fueros\u201d cuya vigencia persiste a pesar de que algunos sostienen que se encontrar\u00eda expresamente derogada. Lo cierto, lo concreto y lo real, es que existen diversos expedientes judiciales, que demuestran\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/sebastian-alvarez-analisis.png?fit=1200%2C656&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5822,"url":"https:\/\/informatepy.com\/2021\/2021\/07\/16\/caso-merienda-escolar-sin-desafuero-de-diputado-no-puede-avanzar-proceso-de-investigacion\/","url_meta":{"origin":2205,"position":2},"title":"Caso merienda escolar: sin desafuero de diputado no puede avanzar proceso de investigaci\u00f3n","date":"16 de julio de 2021","format":false,"excerpt":"Sobre la acusaci\u00f3n al senador Rodolfo Friedmann y su esposa Marly Figueredo, por lavado de dinero, administraci\u00f3n en provecho propio, cohecho pasivo agravado y asociaci\u00f3n criminal, el fiscal Osmar Legal, cont\u00f3 que el obst\u00e1culo sigue siendo con relaci\u00f3n al diputado Ever Noguera, quien no fue desaforado en la causa y\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/FRIEDMANN-NOGUERA-1.jpg?fit=800%2C500&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10883,"url":"https:\/\/informatepy.com\/2021\/2022\/03\/30\/celeste-amarilla-la-ostra-del-parlamento-paraguayo\/","url_meta":{"origin":2205,"position":3},"title":"Celeste Amarilla, la ostra del Parlamento Paraguayo","date":"30 de marzo de 2022","format":false,"excerpt":"Estamos acostumbrados (algunos estamos hartos en realidad) a los exabruptos de la diputada liberal Celeste Amarilla, quien sin ton ni son lanza improperios a quien se cruce en su camino. En esta ocasi\u00f3n, la v\u00edctima involuntaria de la ordinariez de la parlamentaria fue el Embajador de la Rep\u00fablica de China\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/celeste-amarilla-2.jpg?fit=1200%2C664&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10425,"url":"https:\/\/informatepy.com\/2021\/2022\/03\/04\/quien-es-carlos-maria-lopez-el-que-se-saco-la-loteria-y-termino-como-presidente-de-la-camara-de-diputados\/","url_meta":{"origin":2205,"position":4},"title":"\u00bfQui\u00e9n es Carlos Mar\u00eda L\u00f3pez, el que \u00abse sac\u00f3 la loter\u00eda\u00bb y termin\u00f3 como presidente de la C\u00e1mara de Diputados?","date":"4 de marzo de 2022","format":false,"excerpt":"Carlos Mar\u00eda L\u00f3pez, el diputado del Partido Liberal Radical Aut\u00e9ntico, que result\u00f3 electo como presidente de la C\u00e1mara de Diputados a partir del 01 de Julio luego de una convulsionada sesi\u00f3n, afirm\u00f3 que \"Yo saqu\u00e9 la loter\u00eda\" al reconocer que su candidatura fue producto del azar. Carlos Mar\u00eda L\u00f3pez fue\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/carlos-maria-lopez.jpg?fit=600%2C315&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4767,"url":"https:\/\/informatepy.com\/2021\/2021\/05\/05\/alliana-es-reelecto-como-presidente-de-la-camara-de-diputados\/","url_meta":{"origin":2205,"position":5},"title":"Alliana es reelecto como presidente de la C\u00e1mara de Diputados","date":"5 de mayo de 2021","format":false,"excerpt":"El diputado Pedro Alliana, fue reelecto como presidente de la C\u00e1mara de Diputados con 64 votos favorables. Adem\u00e1s de los 43 diputados pertenecientes a la Asociaci\u00f3n Nacional Republicana, el actual presidente de la c\u00e1mara obtuvo 21 votos de otras fuerzas pol\u00edticas. 19 liberales m\u00e1s los diputados Carlos Rejala y Tito\u2026","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/pedro-alliana-diputado.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/2205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=2205"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/2205\/revisions"}],"predecessor-version":[{"id":2702,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/2205\/revisions\/2702"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/2206"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=2205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=2205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=2205"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=2205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}