{"id":1886,"date":"2020-04-18T20:20:00","date_gmt":"2020-04-18T20:20:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=1886"},"modified":"2021-02-20T16:43:17","modified_gmt":"2021-02-20T20:43:17","slug":"cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2020\/04\/18\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\/","title":{"rendered":"Cal\u00e9 Galaverna, y el fin de una era en la pol\u00edtica paraguaya"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Quienes seguimos paso a paso el debate y la posterior\naprobaci\u00f3n del proyecto de ley del Senador Sergio Godoy donde se plantean topes\nsalariales y el recorte de gastos superfluos en los entes del estado, tal vez,\nsin darnos cuenta, presenciamos los \u00faltimos estertores de la vieja pol\u00edtica. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un momento del debate, cuando el experimentado senador\nCal\u00e9 Galaverna expon\u00eda sus razones para votar en contra del proyecto y\nasegurando que muy probablemente se trataba de una conspiraci\u00f3n para <strong><em>\u201cdesestabilizar\nla administraci\u00f3n del gobierno\u201d;<\/em><\/strong> entra en escena el proyectista, quien\naparentemente hab\u00eda dejado abierto su micr\u00f3fono mientras conversaba con alguien\nde su entorno que se hallaba junto a \u00e9l, y afirm\u00f3: <em>\u201c<strong>Claro que es una conspiraci\u00f3n, una conspiraci\u00f3n contra la\nclase privilegiada<\/strong>\u201d.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas palabras del senador Sergio Godoy calaron hondo en el concepto de pol\u00edtica de Juan Carlos Galaverna, quien le replic\u00f3: <strong><em>\u201cMe encanta que vos sos hombre de pueblo, me encanta que Godoy, hombre de pueblo, venido de las ra\u00edces populares del coloradismo, de una militancia casi incomparable en las bases partidarias, con presencia impresionante en las seccionales, vibrando con las necesidades populares,\u00a0ahora hable de que est\u00e1 conspirando contra las clases privilegiadas\u201d<\/em><\/strong>, para terminar espet\u00e1ndole: <strong><em>\u201cQu\u00e9 ganas de decir que te vayas a la puta por c\u00ednico y por mentiroso, pero no lo puedo hacer por guardar las formas\u201d.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas palabras, las del senador Galaverna, resonaron en la\nsociedad como un edificio derrumb\u00e1ndose, escuchamos caer piedra sobre piedra una\nconstrucci\u00f3n pol\u00edtica que a Cal\u00e9 le llev\u00f3 m\u00e1s de 30 a\u00f1os levantar y que en\npocos segundos termin\u00f3 en el suelo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Probablemente, este exabrupto de Juan Carlos Galaverna finalmente no sea producto de este proyecto de ley en particular, seguramente le molesta, m\u00e1s que nada, no haber sabido (tal vez por primera vez) leer el humor social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ND<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quienes seguimos paso a paso el debate y la posterior aprobaci\u00f3n del proyecto de ley del Senador Sergio Godoy donde se plantean topes salariales y el recorte de gastos superfluos en los entes del estado, tal vez, sin darnos cuenta, presenciamos los \u00faltimos estertores de la vieja pol\u00edtica. En un momento del debate, cuando el [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1887,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[248],"tags":[841,314,842,479,539,843],"ppma_author":[1065],"class_list":["post-1886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis","tag-cale-galaverna","tag-honor-colorado","tag-juan-carlos-galaverna","tag-nd","tag-senado-paraguayo","tag-sergio-godoy"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cal\u00e9 Galaverna, y el fin de una era en la pol\u00edtica paraguaya - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2020\/04\/18\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cal\u00e9 Galaverna, y el fin de una era en la pol\u00edtica paraguaya - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Quienes seguimos paso a paso el debate y la posterior aprobaci\u00f3n del proyecto de ley del Senador Sergio Godoy donde se plantean topes salariales y el recorte de gastos superfluos en los entes del estado, tal vez, sin darnos cuenta, presenciamos los \u00faltimos estertores de la vieja pol\u00edtica. En un momento del debate, cuando el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2020\/04\/18\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-18T20:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-20T20:43:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/calC3A9-galaverna.jpg?fit=760%2C420&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nicol\u00e1s D\u00b4Ursi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/NicoDursi\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicol\u00e1s D\u00b4Ursi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/04\\\/18\\\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/04\\\/18\\\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\\\/\"},\"author\":{\"name\":\"Nicol\u00e1s D\u00b4Ursi\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/5f11462f4da127b423f029d0dbae9131\"},\"headline\":\"Cal\u00e9 Galaverna, y el fin de una era en la pol\u00edtica paraguaya\",\"datePublished\":\"2020-04-18T20:20:00+00:00\",\"dateModified\":\"2021-02-20T20:43:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/04\\\/18\\\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\\\/\"},\"wordCount\":330,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/04\\\/18\\\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/calC3A9-galaverna.jpg?fit=760%2C420&ssl=1\",\"keywords\":[\"cale galaverna\",\"honor colorado\",\"juan carlos galaverna\",\"ND\",\"senado paraguayo\",\"sergio godoy\"],\"articleSection\":[\"Analisis\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/04\\\/18\\\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/04\\\/18\\\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/04\\\/18\\\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\\\/\",\"name\":\"Cal\u00e9 Galaverna, y el fin de una era en la pol\u00edtica paraguaya - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/04\\\/18\\\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/04\\\/18\\\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/calC3A9-galaverna.jpg?fit=760%2C420&ssl=1\",\"datePublished\":\"2020-04-18T20:20:00+00:00\",\"dateModified\":\"2021-02-20T20:43:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/04\\\/18\\\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/04\\\/18\\\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/04\\\/18\\\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/calC3A9-galaverna.jpg?fit=760%2C420&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/calC3A9-galaverna.jpg?fit=760%2C420&ssl=1\",\"width\":760,\"height\":420,\"caption\":\"Senador Juan Carlos \\\"Cal\u00e9\\\" Galaverna\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/04\\\/18\\\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cal\u00e9 Galaverna, y el fin de una era en la pol\u00edtica paraguaya\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/5f11462f4da127b423f029d0dbae9131\",\"name\":\"Nicol\u00e1s D\u00b4Ursi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/nicolas-dursi.jpg?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/nicolas-dursi.jpg?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/nicolas-dursi.jpg?fit=96%2C96&ssl=1\",\"caption\":\"Nicol\u00e1s D\u00b4Ursi\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/NicoDursi\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/ndursi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cal\u00e9 Galaverna, y el fin de una era en la pol\u00edtica paraguaya - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2020\/04\/18\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\/","og_locale":"es_ES","og_type":"article","og_title":"Cal\u00e9 Galaverna, y el fin de una era en la pol\u00edtica paraguaya - Informatepy","og_description":"Quienes seguimos paso a paso el debate y la posterior aprobaci\u00f3n del proyecto de ley del Senador Sergio Godoy donde se plantean topes salariales y el recorte de gastos superfluos en los entes del estado, tal vez, sin darnos cuenta, presenciamos los \u00faltimos estertores de la vieja pol\u00edtica. En un momento del debate, cuando el [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2020\/04\/18\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\/","og_site_name":"Informatepy","article_published_time":"2020-04-18T20:20:00+00:00","article_modified_time":"2021-02-20T20:43:17+00:00","og_image":[{"width":760,"height":420,"url":"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/calC3A9-galaverna.jpg?fit=760%2C420&ssl=1","type":"image\/jpeg"}],"author":"Nicol\u00e1s D\u00b4Ursi","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/NicoDursi","twitter_misc":{"Escrito por":"Nicol\u00e1s D\u00b4Ursi","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2020\/04\/18\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2020\/04\/18\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\/"},"author":{"name":"Nicol\u00e1s D\u00b4Ursi","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/5f11462f4da127b423f029d0dbae9131"},"headline":"Cal\u00e9 Galaverna, y el fin de una era en la pol\u00edtica paraguaya","datePublished":"2020-04-18T20:20:00+00:00","dateModified":"2021-02-20T20:43:17+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2020\/04\/18\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\/"},"wordCount":330,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2020\/04\/18\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/calC3A9-galaverna.jpg?fit=760%2C420&ssl=1","keywords":["cale galaverna","honor colorado","juan carlos galaverna","ND","senado paraguayo","sergio godoy"],"articleSection":["Analisis"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2020\/04\/18\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2020\/04\/18\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\/","url":"https:\/\/informatepy.com\/2021\/2020\/04\/18\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\/","name":"Cal\u00e9 Galaverna, y el fin de una era en la pol\u00edtica paraguaya - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2020\/04\/18\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2020\/04\/18\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/calC3A9-galaverna.jpg?fit=760%2C420&ssl=1","datePublished":"2020-04-18T20:20:00+00:00","dateModified":"2021-02-20T20:43:17+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2020\/04\/18\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2020\/04\/18\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2020\/04\/18\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/calC3A9-galaverna.jpg?fit=760%2C420&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/calC3A9-galaverna.jpg?fit=760%2C420&ssl=1","width":760,"height":420,"caption":"Senador Juan Carlos \"Cal\u00e9\" Galaverna"},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2020\/04\/18\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Cal\u00e9 Galaverna, y el fin de una era en la pol\u00edtica paraguaya"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/5f11462f4da127b423f029d0dbae9131","name":"Nicol\u00e1s D\u00b4Ursi","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/nicolas-dursi.jpg?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/nicolas-dursi.jpg?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/nicolas-dursi.jpg?fit=96%2C96&ssl=1","caption":"Nicol\u00e1s D\u00b4Ursi"},"sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/NicoDursi"],"url":"https:\/\/informatepy.com\/2021\/author\/ndursi\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/calC3A9-galaverna.jpg?fit=760%2C420&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":10306,"url":"https:\/\/informatepy.com\/2021\/2022\/02\/24\/narcotrafico-cale-galaverna-sin-nombrarlo-apunto-a-hugo-velazquez\/","url_meta":{"origin":1886,"position":0},"title":"Narcotr\u00e1fico: \u00abCal\u00e9\u00bb Galaverna, sin nombrarlo, apunt\u00f3 a Hugo Vel\u00e1zquez","date":"24 de febrero de 2022","format":false,"excerpt":"Con la tradicional \"picard\u00eda\" que lo caracteriza al momento de lanzar sus bombas, el senador Juan Carlos \"Cal\u00e9\" Galaverna, apunt\u00f3 al vicepresidente Hugo Vel\u00e1zquez como cabeza del narcotr\u00e1fico en el pa\u00eds. En sus declaraciones, el senador afirm\u00f3 que la cabeza del narcotr\u00e1fico est\u00e1 \"por encima de los ministros y por\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/calC3A9-galaverna.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13814,"url":"https:\/\/informatepy.com\/2021\/2022\/09\/08\/el-senado-analizara-una-declaracion-en-contra-de-injerencia-de-estados-unidos\/","url_meta":{"origin":1886,"position":1},"title":"El Senado analizar\u00e1 una declaraci\u00f3n en contra de injerencia de Estados Unidos","date":"8 de septiembre de 2022","format":false,"excerpt":"A propuesta del senador Juan Carlos Galaverna, el pleno del Senado tratar\u00e1 sobre tablas un proyecto de Declaraci\u00f3n presentado por varios legisladores de Honor Colorado, en contra de la intromisi\u00f3n del embajador de los Estados Unidos. La declaraci\u00f3n \u201cpor la que se exalta la soberan\u00eda de nuestra Rep\u00fablica del Paraguay\u201d,\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/calC3A9-galaverna.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":14029,"url":"https:\/\/informatepy.com\/2021\/2022\/09\/22\/cale-ruega-que-presenten-pruebas-sobre-amenazas-de-muerte-lanzadas-por-miguel-godoy\/","url_meta":{"origin":1886,"position":2},"title":"Cal\u00e9 ruega que presenten pruebas sobre amenazas de muerte lanzadas por Miguel Godoy","date":"22 de septiembre de 2022","format":false,"excerpt":"El senador por Honor Colorado Juan Carlos Galaverna, pidi\u00f3 esta ma\u00f1ana a su colega Carlos Filizzola, de Frente Guasu, que presente pruebas de que el defensor del Pueblo, Miguel Godoy, emiti\u00f3 amenazas de muerte o planea plantar drogas en contra de quienes intentan llevar adelante su juicio pol\u00edtico. Coment\u00f3 que,\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/calC3A9-galaverna.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":7952,"url":"https:\/\/informatepy.com\/2021\/2021\/10\/25\/cale-galaverna-firma-el-certificado-de-defuncion-de-anetete\/","url_meta":{"origin":1886,"position":3},"title":"Cal\u00e9 Galaverna firma el certificado de defunci\u00f3n de A\u00f1etet\u00e9","date":"25 de octubre de 2021","format":false,"excerpt":"'Cal\u00e9' Galaverna, sostuvo que el movimiento A\u00f1etete fue desintegrado y responsabiliz\u00f3 al presidente Mario Abdo Ben\u00edtez.","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/calC3A9-galaverna.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8840,"url":"https:\/\/informatepy.com\/2021\/2021\/12\/13\/honor-colorado-se-fortalece-y-cartes-va-por-la-presidencia-de-la-anr\/","url_meta":{"origin":1886,"position":4},"title":"Honor Colorado se fortalece y Cartes va por la presidencia de la ANR","date":"13 de diciembre de 2021","format":false,"excerpt":"El movimiento Honor Colorado con los nuevos refuerzos y de frente al 2023, se convirti\u00f3 en el movimiento m\u00e1s fuerte, casi hegem\u00f3nico dentro del partido colorado. En la reuni\u00f3n que se llev\u00f3 adelante el d\u00eda de hoy, Honor Colorado sum\u00f3 a los gobernadores de Guair\u00e1, San Pedro y Canindey\u00fa. Tambi\u00e9n,\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/reunion-casa-cartes-dic-2021.jpg?fit=680%2C510&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5022,"url":"https:\/\/informatepy.com\/2021\/2021\/05\/24\/presidencia-del-senado-galaverna-el-que-mas-se-acerca\/","url_meta":{"origin":1886,"position":5},"title":"Presidencia del Senado: \u00bfGalaverna el candidato de consenso?","date":"24 de mayo de 2021","format":false,"excerpt":"Las bancadas opositoras del Senado est\u00e1n sintiendo la consecuencia de la cantidad de candidatos a presidir la c\u00e1mara, por lo que el acuerdo al que pensaban llegar, que les hubiera dado 28 votos (se requieren 23) para imponer a alguien del sector, se aleja cada d\u00eda m\u00e1s, seg\u00fan reconoce Fernando\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/calC3A9-galaverna.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1065,"user_id":5,"is_guest":0,"slug":"ndursi","display_name":"Nicol\u00e1s D\u00b4Ursi","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/nicolas-dursi.jpg?fit=96%2C96&ssl=1","first_name":"Nicol\u00e1s","last_name":"D\u00b4Ursi","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=1886"}],"version-history":[{"count":2,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1886\/revisions"}],"predecessor-version":[{"id":3527,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1886\/revisions\/3527"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/1887"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=1886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=1886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=1886"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=1886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}