{"id":1874,"date":"2020-04-16T20:20:00","date_gmt":"2020-04-16T20:20:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=1874"},"modified":"2021-02-09T18:27:56","modified_gmt":"2021-02-09T18:27:56","slug":"futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2020\/04\/16\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\/","title":{"rendered":"FUTURO: Intelectuales debaten sobre el mundo post pandemia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Mientras las autoridades en casi todos los rincones del planeta insisten en la necesidad de aplanar la curva del coronavirus para reducir la mortalidad y evitar el colapso de los sistemas de salud, los intelectuales ya est\u00e1n preocupados del mundo al que nos enfrentaremos tras el fin de esta pandemia. <strong>T\u00e9rminos como globalizaci\u00f3n, comunismo, vigilancia digital, soberan\u00eda, capitalismo y solidaridad se han vuelto comunes<\/strong> en las reflexiones de reconocidos fil\u00f3sofos, historiadores y escritores sobre el impacto del Covid-19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El fil\u00f3sofo italiano Giorgio Agamben fue uno de los primeros en abrir los fuegos. En su columna titulada <em><strong>\u201cLa invenci\u00f3n de una epidemia\u201d<\/strong><\/em>, publicada originalmente el 26 de febrero en la revista italiana Quodlibet, el autor de la serie&nbsp;<em>Homo Sacer<\/em>&nbsp;minimiza al coronavirus, diciendo que era apenas diferente de una simple gripe y reflexiona acerca de la relaci\u00f3n entre el miedo a una epidemia que extiende el p\u00e1nico a trav\u00e9s del planeta y la aceptaci\u00f3n -en nombre de la seguridad- de medidas que limitan gravemente la libertad de las personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A juicio de Agamben, dos factores pueden ayudar a explicar este comportamiento que califica de <em><strong>\u201cdesproporcionado\u201d. \u201cPrimero, una vez m\u00e1s, hay una tendencia creciente a utilizar el estado de excepci\u00f3n como paradigma normal de gobierno\u201d<\/strong><\/em>, plantea.<em><strong> \u201cEl otro factor, no menos inquietante, es el estado de temor que se ha extendido expl\u00edcitamente en los \u00faltimos a\u00f1os al interior de las conciencias de los individuos y que se traduce en una necesidad real de estados de p\u00e1nico colectivo, frente a los cuales la epidemia vuelve a ofrecer, una vez m\u00e1s, el pretexto ideal\u201d<\/strong><\/em>, agrega.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-layout-flow wp-block-quote-is-layout-flow\"><p> \u00abHay una necesidad real de estados de p\u00e1nico colectivo, frente a los cuales la epidemia ofrece el pretexto ideal\u00bb <\/p><cite> Giorgio Agamben, fil\u00f3sofo italiano <\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>\u201cDe esta manera, en un c\u00edrculo vicioso y perverso, la limitaci\u00f3n de la libertad impuesta por los gobiernos se acepta en nombre de un deseo de seguridad que ha sido inducido por los mismos gobernantes que ahora intervienen para satisfacerlo\u201d<\/strong><\/em>, postula Agamben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al d\u00eda siguiente, el fil\u00f3sofo esloveno Slavoj \u017di\u017eek plante\u00f3 en una columna publicada en el portal ruso RT que esta epidemia era <em><strong>\u201cun golpe a lo Kill Bill\u201d<\/strong><\/em> al sistema capitalista e, incluso, podr\u00eda conducir a la reinvenci\u00f3n del comunismo. <em><strong>\u00abA menudo se escucha la especulaci\u00f3n de que el coronavirus puede conducir a la ca\u00edda del gobierno comunista en China\u00bb<\/strong><\/em>, escribe. No obstante, asegura que existe una paradoja:<em><strong> \u00abEl coronavirus tambi\u00e9n nos obligar\u00e1 a reinventar el comunismo basado en la confianza en las personas y en la ciencia\u00bb<\/strong><\/em>.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-layout-flow wp-block-quote-is-layout-flow\"><p> \u00abEl coronavirus es un golpe al capitalismo a lo \u2018Kill Bill\u2019 que podr\u00eda reinventar el comunismo\u00bb<\/p><cite> Slavoj \u017di\u017eek, fil\u00f3sofo y soci\u00f3logo esloveno <\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">En otro art\u00edculo publicado en RT el 10 de marzo, titulado \u201cEl coronavirus nos obliga a decidir entre el comunismo global o la ley de la jungla\u201d, \u017di\u017eek explica sus dichos. <em><strong>\u201cCuando suger\u00ed que la epidemia de coronavirus puede dar una nueva dosis de vitalidad al comunismo, mi reivindicaci\u00f3n fue, como era de esperar, ridiculizada. Parece que el duro enfoque del Estado chino ha funcionado, al menos ha funcionado mucho mejor que las medidas que se est\u00e1n tomando ahora mismo en Italia. Sin embargo, la vieja l\u00f3gica autoritaria de los comunistas en el poder ha demostrado tambi\u00e9n sus claras limitaciones. Una de ellas es que el miedo a llevar malas noticias a aquellos en el poder (y tambi\u00e9n al p\u00fablico) importa m\u00e1s que los resultados efectivos\u201d<\/strong><\/em>, detalla.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00abSin embargo, la vieja l\u00f3gica autoritaria de los comunistas en el poder ha demostrado tambi\u00e9n sus claras limitaciones\u00bb<\/p><cite>  Slavoj \u017di\u017eek, fil\u00f3sofo y soci\u00f3logo esloveno <\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cIgual que en una campa\u00f1a militar, la informaci\u00f3n tiene que ser compartida y los planes coordinados. A esto es a lo que me refiero con el \u2018comunismo\u2019 que hoy se necesita. O, como dice Will Hutton: \u2018En este momento est\u00e1 muriendo una forma de globalizaci\u00f3n no regulada, basada en el libre mercado, con su propensi\u00f3n a las crisis y las pandemias. Pero est\u00e1 naciendo una nueva forma que reconoce la interdependencia y la primac\u00eda de la acci\u00f3n colectiva basada en la evidencia\u2019\u201d, sostiene \u017di\u017eek.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y el fil\u00f3sofo esloveno agrega un nuevo elemento en su an\u00e1lisis. A su juicio, la pandemia <em><strong>\u201cno es solo una se\u00f1al de los l\u00edmites de la globalizaci\u00f3n mercantil, tambi\u00e9n se\u00f1ala el l\u00edmite, a\u00fan m\u00e1s fatal, del populismo nacionalista que insiste en la soberan\u00eda absoluta del Estado\u201d<\/strong><\/em>. En ese sentido, sugiere:<em><strong> \u201cQuiz\u00e1s otro virus, ideol\u00f3gico y mucho m\u00e1s beneficioso, se propague y con suerte nos infectar\u00e1: el virus de pensar en una sociedad alternativa, una sociedad m\u00e1s all\u00e1 del Estado-naci\u00f3n, una sociedad que se actualiza a s\u00ed misma en las formas de solidaridad y cooperaci\u00f3n global\u201d<\/strong><\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Pero el vaticinio de \u017di\u017eek sobre el futuro del capitalismo y el r\u00e9gimen chino gener\u00f3 debate. Uno de los primeros en pronunciarse fue el fil\u00f3sofo surcoreano Byung-Chul Han. En la columna titulada \u201cLa emergencia viral y el mundo de ma\u00f1ana\u201d, publicada en el diario El Pa\u00eds, el autor de&nbsp;<em>La sociedad del cansancio<\/em>&nbsp;es categ\u00f3rico: \u201c\u017di\u017eek afirma que el virus ha asestado al capitalismo un golpe mortal, y evoca un oscuro comunismo. Cree incluso que el virus podr\u00eda hacer caer el r\u00e9gimen chino. \u017di\u017eek se equivoca. Nada de eso suceder\u00e1. <em><strong>China podr\u00e1 vender ahora su Estado policial digital como un modelo de \u00e9xito contra la pandemia. China exhibir\u00e1 la superioridad de su sistema a\u00fan con m\u00e1s orgullo. Y tras la pandemia, el capitalismo continuar\u00e1 a\u00fan con m\u00e1s pujanza<\/strong><\/em>\u201d. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su columna, el fil\u00f3sofo surcoreano tambi\u00e9n contrasta las medidas adoptadas y los resultados dispares obtenidos en Asia y Europa frente a la pandemia del coronavirus. Y es precisamente en este \u201cEstado policial digital\u201d donde Han radica el motivo de estas diferencias. <strong><em>\u201cLos pa\u00edses asi\u00e1ticos est\u00e1n gestionando mejor esta crisis que Occidente. Mientras all\u00ed se trabaja con datos y mascarillas, aqu\u00ed se llega tarde y se levantan fronteras\u201d<\/em><\/strong>, grafica. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-layout-flow wp-block-quote-is-layout-flow\"><p> \u00ab\u017di\u017eek cree incluso que el virus podr\u00eda hacer caer el r\u00e9gimen chino. Se equivoca. Nada de eso suceder\u00e1\u00bb <\/p><cite> Byung Chul Han, fil\u00f3sofo y ensayista surcoreano <\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNi en China ni en otros Estados asi\u00e1ticos, como Corea del Sur, Hong Kong, Singapur, Taiw\u00e1n o Jap\u00f3n, existe una conciencia cr\u00edtica ante la vigilancia digital o el big data\u201d, afirma Han. \u201cNadie se enoja por el frenes\u00ed de las autoridades para recopilar datos\u201d, agrega. Y da sus razones para ello: <em><strong>\u201cTienen una mentalidad autoritaria, que les viene de su tradici\u00f3n cultural (confucianismo). Las personas son menos renuentes y m\u00e1s obedientes que en Europa. Tambi\u00e9n conf\u00edan m\u00e1s en el Estado\u201d<\/strong><\/em>. \u201cEso obedece tambi\u00e9n a un motivo cultural. En Asia impera el colectivismo. No hay un individualismo acentuado\u201d, comenta. Con todo, Han es cr\u00edtico de cierta vigilancia digital. <strong><em>\u201cOjal\u00e1 que tras la conmoci\u00f3n que ha causado este virus no llegue a Europa un r\u00e9gimen policial digital como el chino. Si llegara a suceder eso, como teme Agamben, el estado de excepci\u00f3n pasar\u00eda a ser la situaci\u00f3n normal. Entonces el virus habr\u00eda logrado lo que ni siquiera el terrorismo isl\u00e1mico consigui\u00f3 del todo\u201d<\/em><\/strong>, advierte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El&nbsp;historiador israel\u00ed Yuval Noah Harari&nbsp;plantea, por su parte, que las medidas que se est\u00e1n adoptando frente a la pandemia se articulan en torno a dos frentes diferentes. El primero tiene que ver con las restricciones de movimiento, y aqu\u00ed se trata de <strong><em>\u201cdecidir entre la vigilancia totalitaria y el empoderamiento de la ciudadan\u00eda\u201d<\/em><\/strong>. El segundo, con las soluciones, y aqu\u00ed hay que optar por <em><strong>\u201cel aislamiento nacionalista o la solidaridad global\u201d<\/strong><\/em>, explica el autor de&nbsp;<em>Sapiens<\/em>&nbsp;y&nbsp;<em>21 lecciones para el siglo XXI<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> En su columna publicada en el Financial Times, titulada \u201cEl mundo despu\u00e9s del coronavirus\u201d, Harari dice que hay dos formas de frenar la pandemia. \u201cUna de ellas es que el gobierno monitorice a la gente y castigue a quienes incumplen las normas\u201d, afirma el escritor, que se\u00f1ala a China como principal ejemplo de la monitorizaci\u00f3n biom\u00e9trica. Sin embargo, existe otra posibilidad: \u201cPodemos elegir proteger nuestra salud y frenar la pandemia sin instaurar reg\u00edmenes de vigilancia totalitaria, dando la fuerza a la ciudadan\u00eda. En las \u00faltimas semanas algunos de <em><strong>los esfuerzos m\u00e1s exitosos se produjeron en Corea del Sur, Singapur y Taiw\u00e1n. Mientras estos pa\u00edses han hecho uso de aplicaciones de rastreo no han renunciado a un uso honesto y de cooperaci\u00f3n para mantener a la sociedad bien informada<\/strong><\/em>\u201d. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-layout-flow wp-block-quote-is-layout-flow\"><p> \u00abPodemos frenar la pandemia sin instaurar reg\u00edmenes de vigilancia totalitaria, dando la fuerza a la ciudadan\u00eda\u00bb <\/p><cite> Yuval Noah Harari, historiador y fil\u00f3sofo israel\u00ed <\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"> El segundo frente se presenta a la hora de plantear las soluciones, si desde la \u00f3ptica del aislamiento nacionalista o la solidaridad global. En este punto, Harari es claro: es tiempo de actuar m\u00e1s globalmente que nunca, porque <strong><em>\u201clas decisiones que tomen los gobiernos y pueblos en las pr\u00f3ximas semanas probablemente dar\u00e1n forma al mundo que tendremos en los pr\u00f3ximos a\u00f1os\u201d<\/em><\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> En conversaci\u00f3n con Vice, la periodista y escritora canadiense Naomi Klein se refiere a la forma en la que el \u201cshock\u201d del coronavirus est\u00e1 llevando a la cadena de acontecimientos que describi\u00f3 en su libro&nbsp;<em>La doctrina del shock<\/em>&nbsp;(2007). \u201cEl shock en realidad es el mismo virus. Se le ha tratado de manera que maximice la confusi\u00f3n y minimice la protecci\u00f3n\u201d, afirma Klein, quien denuncia: \u201cLas \u00e9lites pol\u00edticas y econ\u00f3micas entienden que los momentos de crisis son la ocasi\u00f3n para hacer avanzar su lista de deseos de pol\u00edticas impopulares que polarizan a\u00fan m\u00e1s la riqueza\u201d. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-layout-flow wp-block-quote-is-layout-flow\"><p> \u00abEl shock es en realidad el mismo virus. Se le ha tratado de manera que maximice la confusi\u00f3n y minimice la protecci\u00f3n\u00bb <\/p><cite> Naomi Klein, periodista y escritora canadiense <\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"> Al respecto, Michel Maffesoli, soci\u00f3logo y fil\u00f3sofo franc\u00e9s, sostiene que \u201cla crisis sanitaria, portadora de muerte individual, es el indicio de una crisis civilizatoria: la muerte del paradigma progresista\u201d. \u201cDe manera todav\u00eda m\u00e1s flagrante, esta crisis sanitaria decreta la muerte de la mundializaci\u00f3n, valor dominante de una \u00e9lite que, sea cual sea su tendencia, sigue obnubilada con la idea de un mercado sin l\u00edmites ni fronteras\u201d, postula el acad\u00e9mico. En este escenario, asegura, se producir\u00e1 lo que el soci\u00f3logo Vilfredo Pareto llam\u00f3 \u201cuna circulaci\u00f3n de las \u00e9lites\u201d. \u201cTal circulaci\u00f3n, con la ayuda de internet, testifica la muerte de la verticalidad del poder en beneficio de la horizontalidad de la potencia societal\u201d. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00abLa crisis sanitaria, portadora de muerte individual, es el indicio de una crisis civilizatoria: la muerte del paradigma progresista\u00bb <\/p><cite> Michel Maffesoli, soci\u00f3logo y fil\u00f3sofo franc\u00e9s <\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"> Timothy Garton Ash, historiador brit\u00e1nico y profesor de Estudios Europeos en la Universidad de Oxford, en cambio, cree que esta pandemia <em><strong>\u201ces un examen para el liberalismo y las democracias\u201d<\/strong><\/em>. \u201cEstamos ante el coronatest de nuestros sistemas pol\u00edticos\u201d, coment\u00f3 en una entrevista con el diario El Mundo. Pero es optimista. \u201cA medio plazo, las democracias encontrar\u00e1n la v\u00eda para salir adelante. Y es probable que la reacci\u00f3n contra el virus nos deje algunas cosas que ser\u00e1n buenas para el futuro del liberalismo. Tener m\u00e1s solidaridad, algo que hemos echado en falta los \u00faltimos 30 a\u00f1os, con un liberalismo puramente individualista y centrado en el libre mercado\u201d, afirma. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-layout-flow wp-block-quote-is-layout-flow\"><p> \u00abEsta pandemia va a estar en los libros de Historia. Aparecer\u00e1 como ep\u00edgrafe en el cap\u00edtulo del auge de China\u00bb <\/p><cite> Timothy Garton Ash, historiador brit\u00e1nico <\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"> \u201cAnte una pandemia, miramos a los sistemas alternativos como se miraba al fascismo y al comunismo, para ver qui\u00e9n lo hace mejor, cu\u00e1l cumple. Ah\u00ed tenemos un desaf\u00edo, pero el resultado hist\u00f3rico de las democracias frente a las dictaduras en los \u00faltimos 100 a\u00f1os es brutal. Reaccionamos m\u00e1s despacio, pero lo hacemos mejor al final\u201d, asegura Garton Ash. Con todo, reconoce: \u201cEsta pandemia va a estar en los libros de Historia, pero no tendr\u00e1 un cap\u00edtulo propio. Aparecer\u00e1 probablemente como ep\u00edgrafe en el cap\u00edtulo del auge de China\u201d. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mientras las autoridades en casi todos los rincones del planeta insisten en la necesidad de aplanar la curva del coronavirus para reducir la mortalidad y evitar el colapso de los sistemas de salud, los intelectuales ya est\u00e1n preocupados del mundo al que nos enfrentaremos tras el fin de esta pandemia. T\u00e9rminos como globalizaci\u00f3n, comunismo, vigilancia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1875,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[248],"tags":[802,819,803,811,838,839,451,825,840],"ppma_author":[1039],"class_list":["post-1874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis","tag-coronavirus","tag-covid","tag-covid19","tag-derechos-civiles","tag-derechos-humanos","tag-estado-policial","tag-libertad","tag-libertad-de-expresion","tag-libertades-civiles"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FUTURO: Intelectuales debaten sobre el mundo post pandemia - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2020\/04\/16\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FUTURO: Intelectuales debaten sobre el mundo post pandemia - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Mientras las autoridades en casi todos los rincones del planeta insisten en la necesidad de aplanar la curva del coronavirus para reducir la mortalidad y evitar el colapso de los sistemas de salud, los intelectuales ya est\u00e1n preocupados del mundo al que nos enfrentaremos tras el fin de esta pandemia. T\u00e9rminos como globalizaci\u00f3n, comunismo, vigilancia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2020\/04\/16\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-16T20:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-09T18:27:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/estado-policial.png?fit=1280%2C671&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"671\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/04\\\/16\\\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/04\\\/16\\\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"FUTURO: Intelectuales debaten sobre el mundo post pandemia\",\"datePublished\":\"2020-04-16T20:20:00+00:00\",\"dateModified\":\"2021-02-09T18:27:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/04\\\/16\\\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\\\/\"},\"wordCount\":2118,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/04\\\/16\\\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/estado-policial.png?fit=1280%2C671&ssl=1\",\"keywords\":[\"coronavirus\",\"covid\",\"covid19\",\"derechos civiles\",\"derechos humanos\",\"estado policial\",\"libertad\",\"libertad de expresi\u00f3n\",\"libertades civiles\"],\"articleSection\":[\"Analisis\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/04\\\/16\\\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/04\\\/16\\\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/04\\\/16\\\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\\\/\",\"name\":\"FUTURO: Intelectuales debaten sobre el mundo post pandemia - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/04\\\/16\\\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/04\\\/16\\\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/estado-policial.png?fit=1280%2C671&ssl=1\",\"datePublished\":\"2020-04-16T20:20:00+00:00\",\"dateModified\":\"2021-02-09T18:27:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/04\\\/16\\\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/04\\\/16\\\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/04\\\/16\\\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/estado-policial.png?fit=1280%2C671&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/estado-policial.png?fit=1280%2C671&ssl=1\",\"width\":1280,\"height\":671,\"caption\":\"En un tiempo de enga\u00f1o universal, decir la verdad es un acto revolucionario\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/04\\\/16\\\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FUTURO: Intelectuales debaten sobre el mundo post pandemia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FUTURO: Intelectuales debaten sobre el mundo post pandemia - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2020\/04\/16\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\/","og_locale":"es_ES","og_type":"article","og_title":"FUTURO: Intelectuales debaten sobre el mundo post pandemia - Informatepy","og_description":"Mientras las autoridades en casi todos los rincones del planeta insisten en la necesidad de aplanar la curva del coronavirus para reducir la mortalidad y evitar el colapso de los sistemas de salud, los intelectuales ya est\u00e1n preocupados del mundo al que nos enfrentaremos tras el fin de esta pandemia. T\u00e9rminos como globalizaci\u00f3n, comunismo, vigilancia [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2020\/04\/16\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\/","og_site_name":"Informatepy","article_published_time":"2020-04-16T20:20:00+00:00","article_modified_time":"2021-02-09T18:27:56+00:00","og_image":[{"width":1280,"height":671,"url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/estado-policial.png?fit=1280%2C671&ssl=1","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2020\/04\/16\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2020\/04\/16\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"FUTURO: Intelectuales debaten sobre el mundo post pandemia","datePublished":"2020-04-16T20:20:00+00:00","dateModified":"2021-02-09T18:27:56+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2020\/04\/16\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\/"},"wordCount":2118,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2020\/04\/16\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/estado-policial.png?fit=1280%2C671&ssl=1","keywords":["coronavirus","covid","covid19","derechos civiles","derechos humanos","estado policial","libertad","libertad de expresi\u00f3n","libertades civiles"],"articleSection":["Analisis"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2020\/04\/16\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2020\/04\/16\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\/","url":"https:\/\/informatepy.com\/2021\/2020\/04\/16\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\/","name":"FUTURO: Intelectuales debaten sobre el mundo post pandemia - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2020\/04\/16\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2020\/04\/16\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/estado-policial.png?fit=1280%2C671&ssl=1","datePublished":"2020-04-16T20:20:00+00:00","dateModified":"2021-02-09T18:27:56+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2020\/04\/16\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2020\/04\/16\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2020\/04\/16\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/estado-policial.png?fit=1280%2C671&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/estado-policial.png?fit=1280%2C671&ssl=1","width":1280,"height":671,"caption":"En un tiempo de enga\u00f1o universal, decir la verdad es un acto revolucionario"},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2020\/04\/16\/futuro-intelectuales-debaten-sobre-el-mundo-post-pandemia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"FUTURO: Intelectuales debaten sobre el mundo post pandemia"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/estado-policial.png?fit=1280%2C671&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":2366,"url":"https:\/\/informatepy.com\/2021\/2020\/12\/27\/estan-avisados-el-coronavirus-no-sera-la-ultima-pandemia\/","url_meta":{"origin":1874,"position":0},"title":"ESTAN AVISADOS: el coronavirus no ser\u00e1 la \u00faltima pandemia","date":"27 de diciembre de 2020","format":false,"excerpt":"La Organizaci\u00f3n Mundial de la Salud (OMS) advirti\u00f3 este s\u00e1bado que la del coronavirus no ser\u00e1 la \u00faltima pandemia y subray\u00f3 que los avances sanitarios resultar\u00e1n insuficientes si no hay\u00a0cambios con respecto al calentamiento global y el bienestar animal. El director general de la OMS, Tedros Adhanom Ghebreyesus, alert\u00f3 ante\u00a0\"el\u2026","rel":"","context":"En \u00abSalud\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/ovejas-al-matadero.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":7705,"url":"https:\/\/informatepy.com\/2021\/2021\/10\/14\/la-pandemia-de-coronavirus-ha-generado-53-millones-de-casos-mas-de-depresion-en-todo-el-mundo\/","url_meta":{"origin":1874,"position":1},"title":"La pandemia de coronavirus ha generado 53 millones de casos m\u00e1s de depresi\u00f3n en todo el mundo","date":"14 de octubre de 2021","format":false,"excerpt":"2020 cerr\u00f3 como uno de los a\u00f1os donde m\u00e1s problemas de salud mental se diagnosticaron en todo el mundo. Los casos de ansiedad tambi\u00e9n aumentaron a 76 millones adicionales con respecto a a\u00f1os anteriores.","rel":"","context":"En \u00abSalud\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/depresion3.jpg?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":7611,"url":"https:\/\/informatepy.com\/2021\/2021\/10\/10\/el-foro-economico-mundial-y-la-pandemia\/","url_meta":{"origin":1874,"position":2},"title":"El Foro Econ\u00f3mico Mundial y la pandemia","date":"10 de octubre de 2021","format":false,"excerpt":"\u00bfC\u00f3mo est\u00e1 involucrado el Foro Econ\u00f3mico Mundial de Davos en la pandemia de coronavirus? El Foro Econ\u00f3mico Mundial de Davos (WEF) es un foro de primer nivel para gobiernos, corporaciones globales y empresarios internacionales.\u00a0Fundado en 1971 por el ingeniero y economista Klaus Schwab, el WEF describe\u00a0su misi\u00f3n\u00a0como \"dar forma a\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/10\/klaus-schwab.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9351,"url":"https:\/\/informatepy.com\/2021\/2022\/01\/11\/deterioro-de-los-estados-de-derecho-en-pandemia\/","url_meta":{"origin":1874,"position":3},"title":"Deterioro de los estados de derecho en pandemia","date":"11 de enero de 2022","format":false,"excerpt":"Todo estado de derecho resulta indispensable para preservar nuestros derechos y libertades y procurar nuestro bienestar. Es de p\u00fablico conocimiento que la pandemia ha derivado en la declaraci\u00f3n de \u201cestado de alarma\u201d, o \u201cestado de emergencia sanitaria\u201d en la mayor\u00eda de los pa\u00edses y ello ha contribuido a agudizar el\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/sebastian-alvarez-analisis.png?fit=1200%2C656&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5255,"url":"https:\/\/informatepy.com\/2021\/2021\/06\/07\/el-genoma-del-covid-19-demostraria-que-salio-de-un-laboratorio\/","url_meta":{"origin":1874,"position":4},"title":"El genoma del COVID-19 demostrar\u00eda que sali\u00f3 de un laboratorio","date":"7 de junio de 2021","format":false,"excerpt":"Dos expertos estadounidenses aseguran que ning\u00fan coronavirus natural tiene la combinaci\u00f3n que presenta el ADN del SARS-CoV-2.","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/laboratorio-wuham.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5946,"url":"https:\/\/informatepy.com\/2021\/2021\/07\/27\/eeuu-anula-la-autorizacion-y-el-pcr-no-sera-valido-como-prueba-para-detectar-el-covid-19\/","url_meta":{"origin":1874,"position":5},"title":"EEUU anula la autorizaci\u00f3n y el PCR no ser\u00e1 v\u00e1lido como prueba para detectar el Covid-19","date":"27 de julio de 2021","format":false,"excerpt":"Los CDC (Centros del Control de Enfermedades), que se encargan de la gesti\u00f3n de la pandemia de coronavirus en Estados Unidos, han emitido un comunicado anunciando que, a partir del 31 de diciembre de 2021, retirar\u00e1n la autorizaci\u00f3n a la Administraci\u00f3n de Alimentos y Medicamentos de los EE.UU. (FDA) para\u2026","rel":"","context":"En \u00abCiencia y Tecnolog\u00eda\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/test-pcr.jpg?fit=1000%2C667&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=1874"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1874\/revisions"}],"predecessor-version":[{"id":3084,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1874\/revisions\/3084"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/1875"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=1874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=1874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=1874"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=1874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}