{"id":1767,"date":"2020-03-20T20:20:00","date_gmt":"2020-03-20T20:20:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=1767"},"modified":"2021-02-14T22:27:22","modified_gmt":"2021-02-14T22:27:22","slug":"asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2020\/03\/20\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\/","title":{"rendered":"Asunci\u00f3n y la unidad colorada que no va se va a dar"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Independientemente de la tan mentada unidad colorada para\nlas pr\u00f3ximas elecciones municipales, si es que acaso fueran celebradas, no se\nva a dar, al menos en la ciudad de Asunci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre quienes no se plegar\u00edan a la unidad partidaria, se\nencuentra el actual Intendente de Asunci\u00f3n, Oscar \u201cNenecho\u201d Rodr\u00edguez quien, al\nverse fuera del armado colorado, cerr\u00f3 filas con el \u201cMovimiento Tenonder\u00e3\u201d liderado\npor el Diputado Juan Carlos Osorio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta movida del Intendente Nenecho Rodr\u00edguez para seguir ocupando el principal sill\u00f3n municipal, adem\u00e1s del \u201cMovimiento Tenonder\u00e3\u201d, est\u00e1 apoyada por un grupo de Concejales capitalinos. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/nenecho-y-concejales.jpg?w=740&#038;ssl=1\" alt=\"\" class=\"wp-image-2381\" data-recalc-dims=\"1\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En la foto, podemos ver al Intendente Oscar Rodr\u00edguez con\nlos Concejales Gabriel Calonga, Fabiana de S\u00e1nchez, Mariano C\u00e1ceres, Carmen\nForcado, Antonio Gaona, C\u00e9sar Ojeda y Jos\u00e9 Alvarenga. Quienes se reunieron el\njueves pasado con la idea de ir delineando las pr\u00f3ximas acciones de campa\u00f1a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Independientemente de la tan mentada unidad colorada para las pr\u00f3ximas elecciones municipales, si es que acaso fueran celebradas, no se va a dar, al menos en la ciudad de Asunci\u00f3n. Entre quienes no se plegar\u00edan a la unidad partidaria, se encuentra el actual Intendente de Asunci\u00f3n, Oscar \u201cNenecho\u201d Rodr\u00edguez quien, al verse fuera del armado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1768,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[483],"tags":[],"ppma_author":[1039],"class_list":["post-1767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipales"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Asunci\u00f3n y la unidad colorada que no va se va a dar - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2020\/03\/20\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Asunci\u00f3n y la unidad colorada que no va se va a dar - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Independientemente de la tan mentada unidad colorada para las pr\u00f3ximas elecciones municipales, si es que acaso fueran celebradas, no se va a dar, al menos en la ciudad de Asunci\u00f3n. Entre quienes no se plegar\u00edan a la unidad partidaria, se encuentra el actual Intendente de Asunci\u00f3n, Oscar \u201cNenecho\u201d Rodr\u00edguez quien, al verse fuera del armado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2020\/03\/20\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-20T20:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-14T22:27:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/nenecho-y-juanki.png?fit=718%2C412&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"718\" \/>\n\t<meta property=\"og:image:height\" content=\"412\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/03\\\/20\\\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/03\\\/20\\\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"Asunci\u00f3n y la unidad colorada que no va se va a dar\",\"datePublished\":\"2020-03-20T20:20:00+00:00\",\"dateModified\":\"2021-02-14T22:27:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/03\\\/20\\\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\\\/\"},\"wordCount\":166,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/03\\\/20\\\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/nenecho-y-juanki.png?fit=718%2C412&ssl=1\",\"articleSection\":[\"Municipales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/03\\\/20\\\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/03\\\/20\\\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/03\\\/20\\\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\\\/\",\"name\":\"Asunci\u00f3n y la unidad colorada que no va se va a dar - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/03\\\/20\\\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/03\\\/20\\\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/nenecho-y-juanki.png?fit=718%2C412&ssl=1\",\"datePublished\":\"2020-03-20T20:20:00+00:00\",\"dateModified\":\"2021-02-14T22:27:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/03\\\/20\\\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/03\\\/20\\\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/03\\\/20\\\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/nenecho-y-juanki.png?fit=718%2C412&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/nenecho-y-juanki.png?fit=718%2C412&ssl=1\",\"width\":718,\"height\":412,\"caption\":\"\\\"Nenecho\\\" Rodr\u00edguez y Juan Carlos Osorio en momentos de coincidencia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2020\\\/03\\\/20\\\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asunci\u00f3n y la unidad colorada que no va se va a dar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Asunci\u00f3n y la unidad colorada que no va se va a dar - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2020\/03\/20\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\/","og_locale":"es_ES","og_type":"article","og_title":"Asunci\u00f3n y la unidad colorada que no va se va a dar - Informatepy","og_description":"Independientemente de la tan mentada unidad colorada para las pr\u00f3ximas elecciones municipales, si es que acaso fueran celebradas, no se va a dar, al menos en la ciudad de Asunci\u00f3n. Entre quienes no se plegar\u00edan a la unidad partidaria, se encuentra el actual Intendente de Asunci\u00f3n, Oscar \u201cNenecho\u201d Rodr\u00edguez quien, al verse fuera del armado [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2020\/03\/20\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\/","og_site_name":"Informatepy","article_published_time":"2020-03-20T20:20:00+00:00","article_modified_time":"2021-02-14T22:27:22+00:00","og_image":[{"width":718,"height":412,"url":"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/nenecho-y-juanki.png?fit=718%2C412&ssl=1","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2020\/03\/20\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2020\/03\/20\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"Asunci\u00f3n y la unidad colorada que no va se va a dar","datePublished":"2020-03-20T20:20:00+00:00","dateModified":"2021-02-14T22:27:22+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2020\/03\/20\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\/"},"wordCount":166,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2020\/03\/20\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/nenecho-y-juanki.png?fit=718%2C412&ssl=1","articleSection":["Municipales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2020\/03\/20\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2020\/03\/20\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\/","url":"https:\/\/informatepy.com\/2021\/2020\/03\/20\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\/","name":"Asunci\u00f3n y la unidad colorada que no va se va a dar - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2020\/03\/20\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2020\/03\/20\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/nenecho-y-juanki.png?fit=718%2C412&ssl=1","datePublished":"2020-03-20T20:20:00+00:00","dateModified":"2021-02-14T22:27:22+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2020\/03\/20\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2020\/03\/20\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2020\/03\/20\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/nenecho-y-juanki.png?fit=718%2C412&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/nenecho-y-juanki.png?fit=718%2C412&ssl=1","width":718,"height":412,"caption":"\"Nenecho\" Rodr\u00edguez y Juan Carlos Osorio en momentos de coincidencia"},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2020\/03\/20\/asuncion-y-la-unidad-colorada-que-no-va-se-va-a-dar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Asunci\u00f3n y la unidad colorada que no va se va a dar"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/nenecho-y-juanki.png?fit=718%2C412&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":2422,"url":"https:\/\/informatepy.com\/2021\/2021\/01\/19\/nenecho-buscara-la-intendencia-con-el-apoyo-de-honor-colorado\/","url_meta":{"origin":1767,"position":0},"title":"Nenecho buscar\u00e1 la intendencia con el apoyo de Honor Colorado","date":"19 de enero de 2021","format":false,"excerpt":"El movimiento Honor Colorado decidi\u00f3 apoyar en las pr\u00f3ximas elecciones municipales a \u00d3scar \u201cNenecho\u201d Rodr\u00edguez, luego de que este anunciara su intenci\u00f3n de seguir en el cargo. Fue el diputado Ra\u00fal Latorre el encargado de confirmar el apoyo que el movimiento liderado por el ex presidente Horacio Cartes brindar\u00e1 a\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/nenecho.jpg?fit=730%2C485&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2504,"url":"https:\/\/informatepy.com\/2021\/2021\/02\/04\/nenecho-no-compra-apoyos-nenecho-no-tiene-apoyos\/","url_meta":{"origin":1767,"position":1},"title":"Nenecho no \u201ccompra\u201d apoyos, Nenecho no tiene apoyos","date":"4 de febrero de 2021","format":false,"excerpt":"En las \u00faltimas horas se conoci\u00f3 la existencia de una reuni\u00f3n en el palacio de L\u00f3pez, esta vez, quienes se reunieron fueron el Diputado Juan Carlos Osorio y el presidente Mario Abdo. Lo que se supo de esta reuni\u00f3n, es que en este mitin se decidi\u00f3 que el Movimiento Tenonder\u00e3\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/nenecho-y-juanki.png?fit=718%2C412&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6537,"url":"https:\/\/informatepy.com\/2021\/2021\/08\/18\/nenecho-encabeza-encuesta-de-multitarget-de-cara-a-las-municipales-de-octubre\/","url_meta":{"origin":1767,"position":2},"title":"\u00abNenecho\u00bb encabeza encuesta de Multitarget de cara a las municipales de octubre","date":"18 de agosto de 2021","format":false,"excerpt":"La lucha por la intendencia de Asunci\u00f3n, est\u00e1 centrada solo en dos de los candidatos a la Intendencia de Asunci\u00f3n, Oscar \u201cNenecho\u201d Rodr\u00edguez (ANR) y Eduardo Nakayama (Alianza PLRA-PPQ-PDP). De acuerdo a la encuesta realizada por Multitarget S.A. (empresa especializada en Estudios de Opini\u00f3n P\u00fablica e Investigaci\u00f3n de Mercados; Comunicaci\u00f3n\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/Nenecho-vs-Nakayama.png?fit=822%2C472&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2111,"url":"https:\/\/informatepy.com\/2021\/2020\/08\/13\/nenecho-miente-sobre-sus-aspiraciones\/","url_meta":{"origin":1767,"position":3},"title":"Nenecho miente sobre sus aspiraciones","date":"13 de agosto de 2020","format":false,"excerpt":"En las \u00faltimas horas, al ser consultado acerca de su reelecci\u00f3n, el actual intendente de la ciudad de Asunci\u00f3n, Oscar \"Nenecho\" Rodr\u00edguez, puso en duda su continuidad al frente del municipio capitalino pero, lo cierto, es que tiene todo muy claro desde el momento mismo en que asumi\u00f3 \"traicionando\" al\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/nenecho.jpg?fit=730%2C485&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2250,"url":"https:\/\/informatepy.com\/2021\/2020\/11\/08\/nenecho-y-el-misterio-del-terere-mas-caro-del-2020\/","url_meta":{"origin":1767,"position":4},"title":"Nenecho y el misterio del terer\u00e9 m\u00e1s caro del 2020","date":"8 de noviembre de 2020","format":false,"excerpt":"Varios meses de buen marketing (digamos la verdad, no es m\u00e1s que buen marketing, asfalto pintado y nada de reforma estructural de la mafia municipal) fueron tiradas a la basura en una sola foto. Nenecho, fuera de los esquemas de poder real dentro del Partido Colorado podr\u00eda estar buscando potenciales\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/nenecho-y-lilian-samaniego.jpg?fit=730%2C548&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5278,"url":"https:\/\/informatepy.com\/2021\/2021\/06\/09\/nenecho-dice-que-la-tapa-de-abc-costo-us-15-000-y-que-la-plata-salio-de-mburuvicha-roga\/","url_meta":{"origin":1767,"position":5},"title":"\u00abNenecho\u00bb dice que la tapa de ABC cost\u00f3 US$ 15.000 y que la plata sali\u00f3 de Mburuvicha R\u00f3ga","date":"9 de junio de 2021","format":false,"excerpt":"El intendente de Asunci\u00f3n, sostuvo que la \"campa\u00f1a sucia\" en su contra por parte del diario ABC Color est\u00e1 siendo financiada desde Mburuvicha R\u00f3ga. Emplaz\u00f3 adem\u00e1s a dicho medio de comunicaci\u00f3n a que presente pruebas reales.","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/01\/nenecho-rodriguez-intendente-de-asuncion.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=1767"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1767\/revisions"}],"predecessor-version":[{"id":3314,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1767\/revisions\/3314"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/1768"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=1767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=1767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=1767"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=1767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}