{"id":1664,"date":"2019-12-04T20:19:00","date_gmt":"2019-12-04T20:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=1664"},"modified":"2021-02-08T19:16:19","modified_gmt":"2021-02-08T19:16:19","slug":"se-calienta-la-interna-cerrista","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/12\/04\/se-calienta-la-interna-cerrista\/","title":{"rendered":"Se calienta la interna cerrista"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Las cosas no est\u00e1n nada bien en Cerro Porte\u00f1o luego de haber perdido el cl\u00e1sico con Olimpia y la posibilidad de acceder en forma directa a la Copa Libertadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apenas terminado el encuentro con Libertad, se viraliz\u00f3 el Hashtag en las redes sociales #RechazoGestionZapag, donde los hinchas del conjunto azulgrana manifestaron su disconformidad con la gesti\u00f3n de la familia Zapag, ya que las cr\u00edticas no solo se agotaron en lo hecho por Ra\u00fal Zapag, sino que trajeron del recuerdo lo hecho por su hermano Juan Jos\u00e9 e incluso por su padre, Abraham Zapag.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los m\u00e1s ac\u00e9rrimos cr\u00edticos de la gesti\u00f3n, es el ex apoderado de la lista que llev\u00f3 a Ra\u00fal a la presidencia del club de Barrio Obrero,  Rodney Vel\u00e1zquez, quien solt\u00f3 declaraciones de grueso calibre hacia la figura de Ra\u00fal Zapag. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-layout-flow wp-block-quote-is-layout-flow\"><p> <strong><em>\u201cmientras el rival est\u00e1 por conseguir el tetracampeonato rompiendo todas las estad\u00edsticas, Ra\u00fal solo hizo m\u00e9ritos para convertir a Cerro en el hazmerre\u00edr de Sudam\u00e9rica\u201d. <\/em><\/strong> <\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Primero, Vel\u00e1zquez, pidi\u00f3 disculpas en su cuenta de Twitter por haber acompa\u00f1ado la lista de Zapag:  <strong><em>\u201cPido disculpas por haber apostado mi confianza en el flaco Ra\u00fal. Hoy rechazo su gesti\u00f3n y estar\u00e9 el 23 diciembre para rechazar el balance\u201d<\/em><\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Posteriormente, en declaraciones radiales a la emisora Cardinal,  afirm\u00f3 que: <strong><em>\u201cmientras el rival est\u00e1 por conseguir el tetracampeonato rompiendo todas las estad\u00edsticas, Ra\u00fal solo hizo m\u00e9ritos para convertir a Cerro en el hazmerre\u00edr de Sudam\u00e9rica\u201d. <\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las cosas no est\u00e1n nada bien en Cerro Porte\u00f1o luego de haber perdido el cl\u00e1sico con Olimpia y la posibilidad de acceder en forma directa a la Copa Libertadores. Apenas terminado el encuentro con Libertad, se viraliz\u00f3 el Hashtag en las redes sociales #RechazoGestionZapag, donde los hinchas del conjunto azulgrana manifestaron su disconformidad con la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1665,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[183],"tags":[186,187,252,590,430,445],"ppma_author":[1039],"class_list":["post-1664","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-apf","tag-cerro-porteno","tag-futbol-paraguayo","tag-juan-jose-zapag","tag-raul-zapag","tag-zapag"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se calienta la interna cerrista - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/12\/04\/se-calienta-la-interna-cerrista\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se calienta la interna cerrista - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Las cosas no est\u00e1n nada bien en Cerro Porte\u00f1o luego de haber perdido el cl\u00e1sico con Olimpia y la posibilidad de acceder en forma directa a la Copa Libertadores. Apenas terminado el encuentro con Libertad, se viraliz\u00f3 el Hashtag en las redes sociales #RechazoGestionZapag, donde los hinchas del conjunto azulgrana manifestaron su disconformidad con la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/12\/04\/se-calienta-la-interna-cerrista\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-04T20:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-08T19:16:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/rechazo-gestion-zapag.jpg?fit=1634%2C1023&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1634\" \/>\n\t<meta property=\"og:image:height\" content=\"1023\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/12\\\/04\\\/se-calienta-la-interna-cerrista\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/12\\\/04\\\/se-calienta-la-interna-cerrista\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"Se calienta la interna cerrista\",\"datePublished\":\"2019-12-04T20:19:00+00:00\",\"dateModified\":\"2021-02-08T19:16:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/12\\\/04\\\/se-calienta-la-interna-cerrista\\\/\"},\"wordCount\":266,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/12\\\/04\\\/se-calienta-la-interna-cerrista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/rechazo-gestion-zapag.jpg?fit=1634%2C1023&ssl=1\",\"keywords\":[\"apf\",\"cerro porte\u00f1o\",\"futbol paraguayo\",\"juan jose zapag\",\"raul zapag\",\"zapag\"],\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/12\\\/04\\\/se-calienta-la-interna-cerrista\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/12\\\/04\\\/se-calienta-la-interna-cerrista\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/12\\\/04\\\/se-calienta-la-interna-cerrista\\\/\",\"name\":\"Se calienta la interna cerrista - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/12\\\/04\\\/se-calienta-la-interna-cerrista\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/12\\\/04\\\/se-calienta-la-interna-cerrista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/rechazo-gestion-zapag.jpg?fit=1634%2C1023&ssl=1\",\"datePublished\":\"2019-12-04T20:19:00+00:00\",\"dateModified\":\"2021-02-08T19:16:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/12\\\/04\\\/se-calienta-la-interna-cerrista\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/12\\\/04\\\/se-calienta-la-interna-cerrista\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/12\\\/04\\\/se-calienta-la-interna-cerrista\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/rechazo-gestion-zapag.jpg?fit=1634%2C1023&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/rechazo-gestion-zapag.jpg?fit=1634%2C1023&ssl=1\",\"width\":1634,\"height\":1023},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/12\\\/04\\\/se-calienta-la-interna-cerrista\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se calienta la interna cerrista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se calienta la interna cerrista - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/12\/04\/se-calienta-la-interna-cerrista\/","og_locale":"es_ES","og_type":"article","og_title":"Se calienta la interna cerrista - Informatepy","og_description":"Las cosas no est\u00e1n nada bien en Cerro Porte\u00f1o luego de haber perdido el cl\u00e1sico con Olimpia y la posibilidad de acceder en forma directa a la Copa Libertadores. Apenas terminado el encuentro con Libertad, se viraliz\u00f3 el Hashtag en las redes sociales #RechazoGestionZapag, donde los hinchas del conjunto azulgrana manifestaron su disconformidad con la [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2019\/12\/04\/se-calienta-la-interna-cerrista\/","og_site_name":"Informatepy","article_published_time":"2019-12-04T20:19:00+00:00","article_modified_time":"2021-02-08T19:16:19+00:00","og_image":[{"width":1634,"height":1023,"url":"https:\/\/i1.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/rechazo-gestion-zapag.jpg?fit=1634%2C1023&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/12\/04\/se-calienta-la-interna-cerrista\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/12\/04\/se-calienta-la-interna-cerrista\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"Se calienta la interna cerrista","datePublished":"2019-12-04T20:19:00+00:00","dateModified":"2021-02-08T19:16:19+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/12\/04\/se-calienta-la-interna-cerrista\/"},"wordCount":266,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/12\/04\/se-calienta-la-interna-cerrista\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/rechazo-gestion-zapag.jpg?fit=1634%2C1023&ssl=1","keywords":["apf","cerro porte\u00f1o","futbol paraguayo","juan jose zapag","raul zapag","zapag"],"articleSection":["Deportes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/12\/04\/se-calienta-la-interna-cerrista\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/12\/04\/se-calienta-la-interna-cerrista\/","url":"https:\/\/informatepy.com\/2021\/2019\/12\/04\/se-calienta-la-interna-cerrista\/","name":"Se calienta la interna cerrista - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/12\/04\/se-calienta-la-interna-cerrista\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/12\/04\/se-calienta-la-interna-cerrista\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/rechazo-gestion-zapag.jpg?fit=1634%2C1023&ssl=1","datePublished":"2019-12-04T20:19:00+00:00","dateModified":"2021-02-08T19:16:19+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/12\/04\/se-calienta-la-interna-cerrista\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/12\/04\/se-calienta-la-interna-cerrista\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/12\/04\/se-calienta-la-interna-cerrista\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/rechazo-gestion-zapag.jpg?fit=1634%2C1023&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/rechazo-gestion-zapag.jpg?fit=1634%2C1023&ssl=1","width":1634,"height":1023},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/12\/04\/se-calienta-la-interna-cerrista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Se calienta la interna cerrista"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/rechazo-gestion-zapag.jpg?fit=1634%2C1023&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1920,"url":"https:\/\/informatepy.com\/2021\/2020\/04\/22\/se-agrava-la-crisis-en-cerro-porteno\/","url_meta":{"origin":1664,"position":0},"title":"Se agrava la crisis en Cerro Porte\u00f1o","date":"22 de abril de 2020","format":false,"excerpt":"Las declaraciones de Mario Grana a un medio radial, donde manifest\u00f3 que con kits de alimentos ellos no pod\u00edan pagar los servicios b\u00e1sicos como luz, agua y dem\u00e1s, calaron hondo en la directiva azulgrana, al punto que se decidi\u00f3 desvincular al formador de inferiores de la instituci\u00f3n. Esta destituci\u00f3n de\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/mario-grana-CCP.jpg?fit=600%2C379&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":746,"url":"https:\/\/informatepy.com\/2021\/2019\/02\/27\/zapag-sale-a-respaldar-a-jubero-ante-los-rumores\/","url_meta":{"origin":1664,"position":1},"title":"Zapag sale a respaldar a Jubero ante los rumores","date":"27 de febrero de 2019","format":false,"excerpt":"Cerro Porte\u00f1o\u00a0no levanta cabeza. El Cicl\u00f3n de Barrio Obrero no pudo en el estadio Erico Galeano y cay\u00f3 derrotado este martes por 2-1 ante la revelaci\u00f3n San Lorenzo por la octava fecha del torneo Apertura 2019. Tras el partido,\u00a0Ra\u00fal Zapag, mandam\u00e1s de la instituci\u00f3n azulgrana, dio total respaldo al entrenador\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/nani-zapag-jubero.jpeg?fit=730%2C486&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1177,"url":"https:\/\/informatepy.com\/2021\/2019\/05\/21\/cerro-porteno-y-una-autocritica-que-se-demora\/","url_meta":{"origin":1664,"position":2},"title":"Cerro Porte\u00f1o y una autocr\u00edtica que se demora","date":"21 de mayo de 2019","format":false,"excerpt":"Barras, falta de logros deportivos, errores dirigenciales graves y una larga lista de etc\u00e9teras hacen que se f\u00e1cil realizar diagn\u00f3sticos sobre la realidad de un gran del futbol paraguayo como lo es Cerro Porte\u00f1o. De un tiempo a esta parte, uno de los grandes del futbol paraguayo no para de\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/cerristas.jpg?fit=712%2C678&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1226,"url":"https:\/\/informatepy.com\/2021\/2019\/05\/27\/escandalo-institucional-en-cerro\/","url_meta":{"origin":1664,"position":3},"title":"Esc\u00e1ndalo Institucional en Cerro (Asi ven a Cerro en Argentina)","date":"27 de mayo de 2019","format":false,"excerpt":"El presente de San Lorenzo no es f\u00e1cil. Necesitado de remontar en lo futbol\u00edstico, busca entrenador y tendr\u00e1 por delante un mercado con varias salidas de jugadores. Sin embargo, su actualidad es mejor que la de Cerro Porte\u00f1o, su rival (la ida es el 24\/7) en los octavos de la\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/raul-zapag.jpeg?fit=730%2C486&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9520,"url":"https:\/\/informatepy.com\/2021\/2022\/01\/18\/impugnaciones-cruzadas-en-cerro-porteno-calientan-la-asamblea\/","url_meta":{"origin":1664,"position":4},"title":"Impugnaciones cruzadas en Cerro Porte\u00f1o calientan la asamblea","date":"18 de enero de 2022","format":false,"excerpt":"Cuando faltan pocos d\u00edas para la asamblea, se calentaron las elecciones en Cerro Porte\u00f1o con impugnaciones cruzadas entre las diferentes listas. Las primeras impugnaciones habr\u00edan partido de la lista encabezada por Juan Jos\u00e9 Zapag, que present\u00f3 la solicitud de impugnaci\u00f3n de 4 miembros de las listas rivales. Quienes no estar\u00edan\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/nueva-olla-cerro-porteC3B1o.jpg?fit=690%2C520&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1873,"url":"https:\/\/informatepy.com\/2021\/2020\/04\/13\/haedo-apunto-a-juan-jose-zapag-por-el-atraso-en-los-salarios\/","url_meta":{"origin":1664,"position":5},"title":"Haedo apunt\u00f3 a Juan Jos\u00e9 Zapag por el atraso en los salarios","date":"13 de abril de 2020","format":false,"excerpt":"El capit\u00e1n de Cerro Porte\u00f1o, Nelson Haedo Vald\u00e9z, convers\u00f3 hoy con la 780 AM sobre la complicada situaci\u00f3n financiera que atraviesa la instituci\u00f3n azulgrana en medio de la pausa en el campeonato, pues los futbolistas no perciben sus salarios desde hace varios meses. El delantero, manifest\u00f3 que es \u201cdif\u00edcil\u201d hablar\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/Nelson-Haedo-valdez.jpeg?fit=730%2C486&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=1664"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1664\/revisions"}],"predecessor-version":[{"id":2621,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1664\/revisions\/2621"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/1665"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=1664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=1664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=1664"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=1664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}