{"id":1536,"date":"2019-09-29T20:19:00","date_gmt":"2019-09-29T20:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=1536"},"modified":"2021-02-08T20:40:14","modified_gmt":"2021-02-08T20:40:14","slug":"cretinos-o-hijos-de-puta","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/09\/29\/cretinos-o-hijos-de-puta\/","title":{"rendered":"\u00bfCretinos o hijos de puta?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">No suelo emplear lenguaje soez al momento de expresarme,\npero esta vez, siento el deseo de hacerlo o, tal vez, es porque no encuentro palabras\nm\u00e1s adecuadas para expresar lo que siento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los \u00faltimos d\u00edas hemos fuimos advertidos por la actividad de un diputado, Luis Urbieta de la ANR Concepci\u00f3n, quien pretende a trav\u00e9s de un proyecto de ley ampliar el art\u00edculo 234 de la ley 1.160\/97, del C\u00f3digo Penal Paraguayo; e incluir entre \u201clos actos vand\u00e1licos\u201d el arrojar huevos a personas o bienes, en pocas palabras, pretenden condenar con hasta 10 a\u00f1os de c\u00e1rcel los escraches que la ciudadan\u00eda ha puesto de moda en los \u00faltimos tiempos.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/Diputado-Luis-Urbieta.jpg?w=740&#038;ssl=1\" alt=\"\" data-id=\"1972\" data-link=\"http:\/\/informatepy.com\/?attachment_id=1972\" class=\"wp-image-1972\" data-recalc-dims=\"1\"\/><figcaption class=\"blocks-gallery-item__caption\">Diputado Luis Urbieta (ANR )<\/figcaption><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Seguramente, este proyecto comenz\u00f3 a dar vueltas en su \u201ccabecita loca\u201d, luego de haber sido \u00e9l mismo escrachado en el barrio San Agust\u00edn de&nbsp;Concepci\u00f3n, por supuestas irregularidades cuando fue gobernador de ese departamento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin soluci\u00f3n de continuidad, La magistrada de ejecuci\u00f3n penal Mercedes Carolina Aguirre Ugarte otorg\u00f3 la libertad transitoria a la docente Sonia Felisa C\u00e1ceres de Paredes, sentenciada por abuso sexual infantil de dos de sus alumnas de 5 a\u00f1os; mientras que un Tribunal de Sentencias de Paraguar\u00ed (integrado por Hugo R\u00edos, Gerardo Ruiz D\u00edaz y Jorge Gim\u00e9nez Samaniego), libera a  Blas Venancio G\u00f3mez Barrios, condenado por abusar de su hijastra desde los 7 hasta los 9 a\u00f1os, \u201ccelebrando\u201d que durante los abusos, el degenerado no penetr\u00f3 a la ni\u00f1a. El juez Jorge Gim\u00e9nez Samaniego consider\u00f3 que el condenado no cumpla el castigo en la c\u00e1rcel, ya que lo considera un \u201ctipo lindo, preparado, que sabe hablar\u201d por lo que apost\u00f3 por \u00e9l y lo benefici\u00f3 con medidas como no acercarse a la menor durante dos a\u00f1os y no salir del pa\u00eds.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/blas-venancio-gomez-barrios.jpg?w=740&#038;ssl=1\" alt=\"\" data-id=\"1970\" data-link=\"http:\/\/informatepy.com\/?attachment_id=1970\" class=\"wp-image-1970\" data-recalc-dims=\"1\"\/><figcaption class=\"blocks-gallery-item__caption\"> Blas Venancio G\u00f3mez Barrios &#8211; Gentileza<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/sonia-caceres-de-paredes.jpg?w=740&#038;ssl=1\" alt=\"\" data-id=\"1971\" data-link=\"http:\/\/informatepy.com\/?attachment_id=1971\" class=\"wp-image-1971\" data-recalc-dims=\"1\"\/><figcaption class=\"blocks-gallery-item__caption\">Sonia C\u00e1ceres de Paredes &#8211; Archivo<\/figcaption><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A veces se me hace imposible imaginar el nivel de cretinismo de quienes nos gobiernan. A veces pienso que ya no me van a sorprender quienes ostentan alg\u00fan poder del estado; luego vienen y se superan. Lo \u00fanico que espero que es lo hagan de cretinos nada m\u00e1s, porque si lo hicieran de hijos de puta ser\u00eda mucho m\u00e1s peligroso\u2026 para nosotros. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>No suelo emplear lenguaje soez al momento de expresarme, pero esta vez, siento el deseo de hacerlo o, tal vez, es porque no encuentro palabras m\u00e1s adecuadas para expresar lo que siento. En los \u00faltimos d\u00edas hemos fuimos advertidos por la actividad de un diputado, Luis Urbieta de la ANR Concepci\u00f3n, quien pretende a trav\u00e9s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1537,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[248],"tags":[284,710,639],"ppma_author":[1039],"class_list":["post-1536","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis","tag-abuso-sexual","tag-justicia-paraguaya","tag-luis-urbieta"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfCretinos o hijos de puta? - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/09\/29\/cretinos-o-hijos-de-puta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfCretinos o hijos de puta? - Informatepy\" \/>\n<meta property=\"og:description\" content=\"No suelo emplear lenguaje soez al momento de expresarme, pero esta vez, siento el deseo de hacerlo o, tal vez, es porque no encuentro palabras m\u00e1s adecuadas para expresar lo que siento. En los \u00faltimos d\u00edas hemos fuimos advertidos por la actividad de un diputado, Luis Urbieta de la ANR Concepci\u00f3n, quien pretende a trav\u00e9s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/09\/29\/cretinos-o-hijos-de-puta\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-29T20:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-08T20:40:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/09\/justicia-puta.png?fit=500%2C475&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"475\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/09\\\/29\\\/cretinos-o-hijos-de-puta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/09\\\/29\\\/cretinos-o-hijos-de-puta\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"\u00bfCretinos o hijos de puta?\",\"datePublished\":\"2019-09-29T20:19:00+00:00\",\"dateModified\":\"2021-02-08T20:40:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/09\\\/29\\\/cretinos-o-hijos-de-puta\\\/\"},\"wordCount\":393,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/09\\\/29\\\/cretinos-o-hijos-de-puta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/justicia-puta.png?fit=500%2C475&ssl=1\",\"keywords\":[\"abuso sexual\",\"Justicia paraguaya\",\"luis urbieta\"],\"articleSection\":[\"Analisis\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/09\\\/29\\\/cretinos-o-hijos-de-puta\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/09\\\/29\\\/cretinos-o-hijos-de-puta\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/09\\\/29\\\/cretinos-o-hijos-de-puta\\\/\",\"name\":\"\u00bfCretinos o hijos de puta? - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/09\\\/29\\\/cretinos-o-hijos-de-puta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/09\\\/29\\\/cretinos-o-hijos-de-puta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/justicia-puta.png?fit=500%2C475&ssl=1\",\"datePublished\":\"2019-09-29T20:19:00+00:00\",\"dateModified\":\"2021-02-08T20:40:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/09\\\/29\\\/cretinos-o-hijos-de-puta\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/09\\\/29\\\/cretinos-o-hijos-de-puta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/09\\\/29\\\/cretinos-o-hijos-de-puta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/justicia-puta.png?fit=500%2C475&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/justicia-puta.png?fit=500%2C475&ssl=1\",\"width\":500,\"height\":475},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/09\\\/29\\\/cretinos-o-hijos-de-puta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfCretinos o hijos de puta?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfCretinos o hijos de puta? - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/09\/29\/cretinos-o-hijos-de-puta\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfCretinos o hijos de puta? - Informatepy","og_description":"No suelo emplear lenguaje soez al momento de expresarme, pero esta vez, siento el deseo de hacerlo o, tal vez, es porque no encuentro palabras m\u00e1s adecuadas para expresar lo que siento. En los \u00faltimos d\u00edas hemos fuimos advertidos por la actividad de un diputado, Luis Urbieta de la ANR Concepci\u00f3n, quien pretende a trav\u00e9s [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2019\/09\/29\/cretinos-o-hijos-de-puta\/","og_site_name":"Informatepy","article_published_time":"2019-09-29T20:19:00+00:00","article_modified_time":"2021-02-08T20:40:14+00:00","og_image":[{"width":500,"height":475,"url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/09\/justicia-puta.png?fit=500%2C475&ssl=1","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/09\/29\/cretinos-o-hijos-de-puta\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/09\/29\/cretinos-o-hijos-de-puta\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"\u00bfCretinos o hijos de puta?","datePublished":"2019-09-29T20:19:00+00:00","dateModified":"2021-02-08T20:40:14+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/09\/29\/cretinos-o-hijos-de-puta\/"},"wordCount":393,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/09\/29\/cretinos-o-hijos-de-puta\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/09\/justicia-puta.png?fit=500%2C475&ssl=1","keywords":["abuso sexual","Justicia paraguaya","luis urbieta"],"articleSection":["Analisis"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/09\/29\/cretinos-o-hijos-de-puta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/09\/29\/cretinos-o-hijos-de-puta\/","url":"https:\/\/informatepy.com\/2021\/2019\/09\/29\/cretinos-o-hijos-de-puta\/","name":"\u00bfCretinos o hijos de puta? - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/09\/29\/cretinos-o-hijos-de-puta\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/09\/29\/cretinos-o-hijos-de-puta\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/09\/justicia-puta.png?fit=500%2C475&ssl=1","datePublished":"2019-09-29T20:19:00+00:00","dateModified":"2021-02-08T20:40:14+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/09\/29\/cretinos-o-hijos-de-puta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/09\/29\/cretinos-o-hijos-de-puta\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/09\/29\/cretinos-o-hijos-de-puta\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/09\/justicia-puta.png?fit=500%2C475&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/09\/justicia-puta.png?fit=500%2C475&ssl=1","width":500,"height":475},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/09\/29\/cretinos-o-hijos-de-puta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"\u00bfCretinos o hijos de puta?"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/09\/justicia-puta.png?fit=500%2C475&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1286,"url":"https:\/\/informatepy.com\/2021\/2019\/06\/24\/acusan-a-payo-de-liderar-turba-que-ataco-negocio-de-familia-urbieta-en-concepcion\/","url_meta":{"origin":1536,"position":0},"title":"Acusan a Payo de liderar turba que atac\u00f3 negocio de familia Urbieta en Concepci\u00f3n","date":"24 de junio de 2019","format":false,"excerpt":"\u201cHoy el senador Payo Cubas con una turba de v\u00e1ndalos destruy\u00f3 el negocio de mis padres ,impotente como la polic\u00eda les dejaba hacer lo que quer\u00edan a estos impresentables\u201d, lament\u00f3 el diputado Luis Urbieta, (ANR) diputado por Concepci\u00f3n. Los ataques son en protesta contra la gesti\u00f3n del intendente de Concepci\u00f3n,\u2026","rel":"","context":"En \u00abMunicipales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/payo-ataca-negocio-urbieta.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10685,"url":"https:\/\/informatepy.com\/2021\/2022\/03\/17\/cada-vez-mas-sola-acusan-a-kattya-gonzalez-de-usar-a-la-camara-de-diputados-para-su-proyecto-presidencial\/","url_meta":{"origin":1536,"position":1},"title":"Cada vez m\u00e1s sola: Acusan a Kattya Gonz\u00e1lez de usar a la C\u00e1mara de Diputados para su proyecto presidencial","date":"17 de marzo de 2022","format":false,"excerpt":"El diputado Luis Urbieta (ANR, A\u00f1etete) acus\u00f3 este jueves a su colega Kattya Gonz\u00e1lez de usar a la C\u00e1mara Baja para cuestiones pol\u00edticas y sus proyectos presidenciales para las elecciones generales del 2023.\u00a0 En una entrevista con el canal GEN, el legislador afirm\u00f3 que \u201cLa colega Kattya Gonz\u00e1lez present\u00f3 el\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/03\/kattya-apesadumbrada.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11472,"url":"https:\/\/informatepy.com\/2021\/2022\/05\/04\/ftc-desmiente-a-la-familia-denis-e-insiste-con-que-el-epp-esta-derrotado\/","url_meta":{"origin":1536,"position":2},"title":"FTC desmiente a la familia Denis e insiste con que el EPP est\u00e1 derrotado","date":"4 de mayo de 2022","format":false,"excerpt":"A pesar de que aun hoy siguen 3 ciudadanos paraguayos secuestrados, la Fuerza de Tarea Conjunta insiste en que el autodenominado Ej\u00e9rcito del pueblo paraguayo (EPP) est\u00e1 estrat\u00e9gicamente derrotado. Las hijas del ex vicepresidente \u00d3scar Denis, criticaron duramente al gobierno y a la FTC por presumir que hab\u00edan logrado derrotar\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/05\/Luis-Apesteguia.jpg?fit=600%2C441&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8802,"url":"https:\/\/informatepy.com\/2021\/2021\/12\/12\/tras-las-criticas-recibidas-obispos-piden-por-los-secuestrados\/","url_meta":{"origin":1536,"position":3},"title":"Tras las cr\u00edticas recibidas, obispos piden por los secuestrados","date":"12 de diciembre de 2021","format":false,"excerpt":"Luego de las fuertes criticas recibidas por haber ignorado el tema durante las \"Fiestas Marianas\", la Conferencia Episcopal Paraguaya (CEP) emiti\u00f3 un comunicado donde pidi\u00f3: \u201cbasta de violencia, basta de secuestro\u201d. Exhorto a todos los cristianos a realizar cadenas de oraci\u00f3n para pedir la liberaci\u00f3n de Peter Reimer, Oscar Denis,\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/conferencia-episcopal-paraguaya.jpeg?fit=696%2C474&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1886,"url":"https:\/\/informatepy.com\/2021\/2020\/04\/18\/cale-galaverna-y-el-fin-de-una-era-en-la-politica-paraguaya\/","url_meta":{"origin":1536,"position":4},"title":"Cal\u00e9 Galaverna, y el fin de una era en la pol\u00edtica paraguaya","date":"18 de abril de 2020","format":false,"excerpt":"Quienes seguimos paso a paso el debate y la posterior aprobaci\u00f3n del proyecto de ley del Senador Sergio Godoy donde se plantean topes salariales y el recorte de gastos superfluos en los entes del estado, tal vez, sin darnos cuenta, presenciamos los \u00faltimos estertores de la vieja pol\u00edtica. En un\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/calC3A9-galaverna.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13820,"url":"https:\/\/informatepy.com\/2021\/2022\/09\/09\/dos-anos-sin-oscar-denis\/","url_meta":{"origin":1536,"position":5},"title":"Dos a\u00f1os sin Oscar Denis","date":"9 de septiembre de 2022","format":false,"excerpt":"Este viernes se cumplen dos a\u00f1os del secuestro del ex vicepresidente de la Rep\u00fablica, Oscar Denis, ocurrido en el 2020. El hombre fue llevado de su estancia ubicada en el departamento de Concepci\u00f3n, presuntamente por criminales del EPP. Las hijas de Denis, conjuntamente con los familiares de los otros secuestrados,\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/09\/oscar-denis.jpg?fit=960%2C640&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=1536"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1536\/revisions"}],"predecessor-version":[{"id":2715,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1536\/revisions\/2715"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/1537"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=1536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=1536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=1536"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=1536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}