{"id":1503,"date":"2019-09-16T20:19:00","date_gmt":"2019-09-16T20:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=1503"},"modified":"2021-02-08T20:57:18","modified_gmt":"2021-02-08T20:57:18","slug":"la-improvisacion-como-forma-de-gobierno","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/09\/16\/la-improvisacion-como-forma-de-gobierno\/","title":{"rendered":"La improvisaci\u00f3n como forma de gobierno"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La improvisaci\u00f3n como forma de gobierno, hist\u00f3ricamente, acabo\ncon gobiernos de todos los signos y colores. El de Mario Abdo, seguramente no\nser\u00e1 a excepci\u00f3n, y afirmo esto, de acuerdo a mi comprensi\u00f3n sobre la \u00faltima \u201cgenialidad\u201d\nde este gobierno\u2026 intentar sacar a las fuerzas armadas a las calles de la\nRep\u00fablica para combatir al crimen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El estudio de iniciativas similares a esta, da como resultado\ninequ\u00edvoco el fracaso rotundo de la acci\u00f3n, no solo ante la no soluci\u00f3n del\nproblema, sino ante el agravamiento de un cuadro; porque adem\u00e1s de que estas \u201csoluciones\u201d\nterminan generando una mayor espiral de violencia suman un nuevo problema, la\nviolaci\u00f3n de los derechos humanos. Un caso emblem\u00e1tico y de constante estudio\nes el de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con esto que afirmo, no quiero decir que las FFAA no est\u00e1n\npreparadas, lo est\u00e1n, pero para otra cosa. Cuando se viven prolongados tiempos\nde paz, el ciudadano promedio tiende a perder la noci\u00f3n de para qu\u00e9 est\u00e1n las\nfuerzas armadas, est\u00e1n para la guerra, y esta, entre sus paradigmas y leyes,\nincluye, inevitablemente, la aniquilaci\u00f3n del enemigo. Mientras tanto, las\nfuerzas de seguridad, como brazo armado de la justicia, una justicia diferente\na la justicia de las guerras, tiene un paradigma distinto; una paradigma que,\nsalvo en casos extremos, est\u00e1 orientado a la neutralizaci\u00f3n del \u201cenemigo\u201d y no\nde su aniquilaci\u00f3n. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El crimen organizado, la mayor\u00eda de las veces est\u00e1\n\u00edntimamente relacionado con el tr\u00e1fico y el consumo de drogas, algo que\nconvierte lo que en apariencia es un problema de seguridad, en un problema\nsocial y de salud p\u00fablica, pero eso es harina de otro costal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comprometer a las fuerzas armadas en las cuestiones de\nseguridad dom\u00e9stica conlleva un mont\u00f3n de errores estrat\u00e9gicos, que van desde\nla desnaturalizaci\u00f3n de la misi\u00f3n para la cual fueron creadas y entrenadas,\nhasta la posibilidad de destruir las bases del consenso nacional desde donde se\nconstruyen las rep\u00fablicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algunos dicen que hay tres tipos de personas, \u201cLos Inteligentes\u201d que aprenden de sus experiencias; \u201cLos Sabios\u201d que aprenden de los errores ajenos y \u201cLos Torpes\u201d que no aprenden nunca. \u00bfEn qu\u00e9 grupo se encuentra el gobierno?, solo el tiempo nos lo dir\u00e1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ND<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La improvisaci\u00f3n como forma de gobierno, hist\u00f3ricamente, acabo con gobiernos de todos los signos y colores. El de Mario Abdo, seguramente no ser\u00e1 a excepci\u00f3n, y afirmo esto, de acuerdo a mi comprensi\u00f3n sobre la \u00faltima \u201cgenialidad\u201d de este gobierno\u2026 intentar sacar a las fuerzas armadas a las calles de la Rep\u00fablica para combatir al [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1099,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[248],"tags":[697,698,644,332],"ppma_author":[1039],"class_list":["post-1503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis","tag-ffaa","tag-ffss","tag-inseguridad","tag-mario-abdo"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La improvisaci\u00f3n como forma de gobierno - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/09\/16\/la-improvisacion-como-forma-de-gobierno\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La improvisaci\u00f3n como forma de gobierno - Informatepy\" \/>\n<meta property=\"og:description\" content=\"La improvisaci\u00f3n como forma de gobierno, hist\u00f3ricamente, acabo con gobiernos de todos los signos y colores. El de Mario Abdo, seguramente no ser\u00e1 a excepci\u00f3n, y afirmo esto, de acuerdo a mi comprensi\u00f3n sobre la \u00faltima \u201cgenialidad\u201d de este gobierno\u2026 intentar sacar a las fuerzas armadas a las calles de la Rep\u00fablica para combatir al [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/09\/16\/la-improvisacion-como-forma-de-gobierno\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-16T20:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-08T20:57:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/abdo-guiC3B1o-ojo.jpg?fit=964%2C573&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"964\" \/>\n\t<meta property=\"og:image:height\" content=\"573\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/09\\\/16\\\/la-improvisacion-como-forma-de-gobierno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/09\\\/16\\\/la-improvisacion-como-forma-de-gobierno\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"La improvisaci\u00f3n como forma de gobierno\",\"datePublished\":\"2019-09-16T20:19:00+00:00\",\"dateModified\":\"2021-02-08T20:57:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/09\\\/16\\\/la-improvisacion-como-forma-de-gobierno\\\/\"},\"wordCount\":398,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/09\\\/16\\\/la-improvisacion-como-forma-de-gobierno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/abdo-guiC3B1o-ojo.jpg?fit=964%2C573&ssl=1\",\"keywords\":[\"FFAA\",\"FFSS\",\"inseguridad\",\"mario abdo\"],\"articleSection\":[\"Analisis\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/09\\\/16\\\/la-improvisacion-como-forma-de-gobierno\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/09\\\/16\\\/la-improvisacion-como-forma-de-gobierno\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/09\\\/16\\\/la-improvisacion-como-forma-de-gobierno\\\/\",\"name\":\"La improvisaci\u00f3n como forma de gobierno - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/09\\\/16\\\/la-improvisacion-como-forma-de-gobierno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/09\\\/16\\\/la-improvisacion-como-forma-de-gobierno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/abdo-guiC3B1o-ojo.jpg?fit=964%2C573&ssl=1\",\"datePublished\":\"2019-09-16T20:19:00+00:00\",\"dateModified\":\"2021-02-08T20:57:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/09\\\/16\\\/la-improvisacion-como-forma-de-gobierno\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/09\\\/16\\\/la-improvisacion-como-forma-de-gobierno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/09\\\/16\\\/la-improvisacion-como-forma-de-gobierno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/abdo-guiC3B1o-ojo.jpg?fit=964%2C573&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/abdo-guiC3B1o-ojo.jpg?fit=964%2C573&ssl=1\",\"width\":964,\"height\":573,\"caption\":\"Foto ABC\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/09\\\/16\\\/la-improvisacion-como-forma-de-gobierno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La improvisaci\u00f3n como forma de gobierno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La improvisaci\u00f3n como forma de gobierno - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/09\/16\/la-improvisacion-como-forma-de-gobierno\/","og_locale":"es_ES","og_type":"article","og_title":"La improvisaci\u00f3n como forma de gobierno - Informatepy","og_description":"La improvisaci\u00f3n como forma de gobierno, hist\u00f3ricamente, acabo con gobiernos de todos los signos y colores. El de Mario Abdo, seguramente no ser\u00e1 a excepci\u00f3n, y afirmo esto, de acuerdo a mi comprensi\u00f3n sobre la \u00faltima \u201cgenialidad\u201d de este gobierno\u2026 intentar sacar a las fuerzas armadas a las calles de la Rep\u00fablica para combatir al [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2019\/09\/16\/la-improvisacion-como-forma-de-gobierno\/","og_site_name":"Informatepy","article_published_time":"2019-09-16T20:19:00+00:00","article_modified_time":"2021-02-08T20:57:18+00:00","og_image":[{"width":964,"height":573,"url":"https:\/\/i2.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/abdo-guiC3B1o-ojo.jpg?fit=964%2C573&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/09\/16\/la-improvisacion-como-forma-de-gobierno\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/09\/16\/la-improvisacion-como-forma-de-gobierno\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"La improvisaci\u00f3n como forma de gobierno","datePublished":"2019-09-16T20:19:00+00:00","dateModified":"2021-02-08T20:57:18+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/09\/16\/la-improvisacion-como-forma-de-gobierno\/"},"wordCount":398,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/09\/16\/la-improvisacion-como-forma-de-gobierno\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/abdo-guiC3B1o-ojo.jpg?fit=964%2C573&ssl=1","keywords":["FFAA","FFSS","inseguridad","mario abdo"],"articleSection":["Analisis"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/09\/16\/la-improvisacion-como-forma-de-gobierno\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/09\/16\/la-improvisacion-como-forma-de-gobierno\/","url":"https:\/\/informatepy.com\/2021\/2019\/09\/16\/la-improvisacion-como-forma-de-gobierno\/","name":"La improvisaci\u00f3n como forma de gobierno - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/09\/16\/la-improvisacion-como-forma-de-gobierno\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/09\/16\/la-improvisacion-como-forma-de-gobierno\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/abdo-guiC3B1o-ojo.jpg?fit=964%2C573&ssl=1","datePublished":"2019-09-16T20:19:00+00:00","dateModified":"2021-02-08T20:57:18+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/09\/16\/la-improvisacion-como-forma-de-gobierno\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/09\/16\/la-improvisacion-como-forma-de-gobierno\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/09\/16\/la-improvisacion-como-forma-de-gobierno\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/abdo-guiC3B1o-ojo.jpg?fit=964%2C573&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/abdo-guiC3B1o-ojo.jpg?fit=964%2C573&ssl=1","width":964,"height":573,"caption":"Foto ABC"},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/09\/16\/la-improvisacion-como-forma-de-gobierno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"La improvisaci\u00f3n como forma de gobierno"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/abdo-guiC3B1o-ojo.jpg?fit=964%2C573&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":3775,"url":"https:\/\/informatepy.com\/2021\/2021\/03\/03\/la-tormenta-politica-perfecta\/","url_meta":{"origin":1503,"position":0},"title":"La tormenta pol\u00edtica perfecta","date":"3 de marzo de 2021","format":false,"excerpt":"Dicen los marineros que una tormenta perfecta se produce cuando dos grandes tormentas, una fr\u00eda y una caliente, se encuentran y se potencian mutuamente multiplicando as\u00ed su capacidad destructiva. En nuestro pa\u00eds esas dos tormentas se encontraron, la tormenta fr\u00eda de la insensibilidad de un gobierno formado con la \u00fanica\u2026","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/tormenta-perfecta.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8853,"url":"https:\/\/informatepy.com\/2021\/2021\/12\/14\/mario-abdo-afirmo-que-hay-que-aprender-a-vivir-con-el-crimen-organizado\/","url_meta":{"origin":1503,"position":1},"title":"Mario Abdo afirm\u00f3 que hay que aprender a vivir con el crimen organizado","date":"14 de diciembre de 2021","format":false,"excerpt":"El presidente Mario Abdo Ben\u00edtez dijo a trav\u00e9s de su cuenta de Twitter que los paraguayos tenemos que aprender a vivir con el crimen organizado como lo hace todo el mundo. Asegur\u00f3 tambi\u00e9n que el cuestionado ministro del Interior, Arnaldo Giuzzio, continuar\u00e1 en el cargo. Abdo asegur\u00f3 que su gobierno\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/abdo-solo.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13203,"url":"https:\/\/informatepy.com\/2021\/2022\/08\/09\/obligan-a-renunciar-a-la-responsable-del-informe-de-amnistia-que-revelaba-que-las-ffaa-ucranianas-ponian-en-peligro-a-los-civiles\/","url_meta":{"origin":1503,"position":2},"title":"Obligan a renunciar a la responsable del informe de Amnist\u00eda que revelaba que las FFAA ucranianas pon\u00edan en peligro a los civiles","date":"9 de agosto de 2022","format":false,"excerpt":"La cultura de la cancelaci\u00f3n no se rinde. Esta vez fue el turno de la responsable de la ONG Amnist\u00eda Internacional (AI) en Ucrania, Oksana Pokalchuk, quien fue obligada a renunciar a su cargo tras un informe de AI que acusa a las fuerzas armadas ucranianas de poner en peligro\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/Oksana-Pokalchuk-Amnistia-internacional.jpg?fit=700%2C394&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10001,"url":"https:\/\/informatepy.com\/2021\/2022\/02\/06\/ffaa-canadienses-se-niegan-a-reprimir-a-los-camioneros-mientras-trudeau-sigue-refugiado\/","url_meta":{"origin":1503,"position":3},"title":"FFAA canadienses se niegan a reprimir a los camioneros mientras Trudeau sigue refugiado","date":"6 de febrero de 2022","format":false,"excerpt":"A pesar de que la polic\u00eda de Ottawa, Canad\u00e1, plante\u00f3 la posibilidad de una \u201cintervenci\u00f3n militar\u201d para despejar la dura resistencia de los camioneros que bloquean su centro, las Fuerzas Armadas canadienses comunicaron que no participar\u00e1n de la represi\u00f3n. Un portavoz del Ministro de Defensa le dijo al Wall Street\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/02\/parlamento-canadiense.jpg?fit=700%2C394&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3844,"url":"https:\/\/informatepy.com\/2021\/2021\/03\/06\/carlitos-rejala-este-es-el-gobierno-de-la-tibieza-de-la-traicion-al-pueblo\/","url_meta":{"origin":1503,"position":4},"title":"Carlitos Rejala: \u00abEste es el gobierno de la tibieza, de la traici\u00f3n al pueblo\u00bb","date":"6 de marzo de 2021","format":false,"excerpt":"Conversamos con el Diputado del partido Hagamos, Carlos Rejala y nos dio sus impresiones del critico momento que atraviesa nuestro pa\u00eds","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":11029,"url":"https:\/\/informatepy.com\/2021\/2022\/04\/07\/para-colyn-soroka-abdo-o-nicanor-serian-los-candidatos-a-la-junta-de-gobierno-por-el-oficialismo\/","url_meta":{"origin":1503,"position":5},"title":"Para Colyn Soroka, Abdo o Nicanor ser\u00edan los candidatos a la Junta de Gobierno por el oficialismo","date":"7 de abril de 2022","format":false,"excerpt":"El diputado colorado Colyn Soroka explic\u00f3 que si el presidente de la Rep\u00fablica, Mario Abdo Ben\u00edtez, decide no presentarse para la Junta de Gobierno del Partido Colorado por el oficialismo, el elegido ser\u00eda el director de Yacyret\u00e1, Nicanor Duarte Frutos. \u201cCandidaturas hay muchas, opciones hay pocas. Si el presidente de\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/04\/nicanor_marito.jpg?fit=760%2C420&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=1503"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1503\/revisions"}],"predecessor-version":[{"id":2743,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1503\/revisions\/2743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/1099"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=1503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=1503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=1503"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=1503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}