{"id":1459,"date":"2019-08-28T20:19:00","date_gmt":"2019-08-28T20:19:00","guid":{"rendered":"http:\/\/informatepy.com\/2021\/?p=1459"},"modified":"2021-02-08T21:18:10","modified_gmt":"2021-02-08T21:18:10","slug":"cerro-perjudica-a-cerro","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2019\/08\/28\/cerro-perjudica-a-cerro\/","title":{"rendered":"Cerro perjudica a Cerro"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Antes de que arranquen (y me gustar\u00eda que se los ahorraran) con los insultos, he de decirles que quien esto escribe es hincha del Club Cerro Porte\u00f1o. Dicho hecho, avancemos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy vivimos, gracias a un periodista, una situaci\u00f3n ins\u00f3lita que solo encuentra su arraigo en la retroalimentaci\u00f3n del hincha cerrista con eso de que los partidos de la Libertadores <em><strong>\u00abse gana dentro y fuera de la cancha\u00bb<\/strong><\/em>; disiento con ellos; los partidos se ganan, tambi\u00e9n, fuera de la cancha y, aunque suene a lo mismo&#8230; no lo es.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/donofrio.jpg?w=740&#038;ssl=1\" alt=\"\" class=\"wp-image-1853\" data-recalc-dims=\"1\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Apelando a un pseudo patriotismo, arengando con los famosos: <em><strong>\u00absi le pasa a un paraguayo afuera&#8230;.\u00bb, \u00abnos viven cagando\u00bb<\/strong><\/em>, y una larga lista de etc\u00e9teras que suenan m\u00e1s a triste letan\u00eda que a una realidad, puesto que los paraguayos somos bien tratados y, sobre todo, somos bien considerados en todos los pa\u00edses de la regi\u00f3n, al menos los paraguayos de bien.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy, luego de la presi\u00f3n ejercida a distintas autoridades del aeropuerto Silvio Pettirossi, un periodista partidario (Empleado del club Cerro Porte\u00f1o), \u00abalert\u00f3\u00bb a las autoridades del pa\u00eds sobre un supuesto pedido de captura existente para el jugador del Club River Plate, Nicol\u00e1s de la Cruz y, no contento con eso, inici\u00f3 una campa\u00f1a de presi\u00f3n a las autoridades de la justicia paraguaya para que el mismo sea trasladado al penal de Tacumb\u00fa, cosa que a todas luces es una exageraci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras esto suced\u00eda, mientras el empleado de Cerro Porte\u00f1o \u00abagitaba\u00bb en las redes sociales y se jactaba de su \u00abviveza\u00bb, su jefe, Ra\u00fal Zapag declaraba en un medio radial que: <em><strong>\u00abQuer\u00edamos darle la bienvenida a la gente de River y esto nos sorprendi\u00f3, nos ponemos a disposici\u00f3n de River\u00bb<\/strong><\/em>. O Zapag miente y est\u00e1 detr\u00e1s de estas acciones, o simplemente sus empleados hacen lo que quieren, lo que ser\u00eda a\u00fan m\u00e1s triste trat\u00e1ndose de un club de las dimensiones de Cerro Porte\u00f1o, implicar\u00eda que el club est\u00e1 a la deriva.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/zapag.jpg?w=740&#038;ssl=1\" alt=\"\" class=\"wp-image-1852\" data-recalc-dims=\"1\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el punto de vista deportivo, esta situaci\u00f3n perjudica claramente a Cerro, porque lo enemista (a\u00fan m\u00e1s) con la CONMEBOL y motiva a los jugadores de River, quienes de por si arrancan con ventaja. \u00bfSe habr\u00e1n preguntado, acaso, los organizadores de esta movida como queda parado Cerro ante el mundo si ma\u00f1ana queda eliminado? \u00bfHabr\u00e1n dimensionado la magnitud de su error? Siento que no, siento que est\u00e1 m\u00e1s preocupados por \u00abSU\u00bb hinchada que por el propio Cerro Porte\u00f1o; River no necesita de la motivaci\u00f3n adicional que le brindan los simpatizantes de Cerro, pero bueno, el tiempo es el mejor autor&#8230; ma\u00f1ana escribe un nuevo cap\u00edtulo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antes de que arranquen (y me gustar\u00eda que se los ahorraran) con los insultos, he de decirles que quien esto escribe es hincha del Club Cerro Porte\u00f1o. Dicho hecho, avancemos. Hoy vivimos, gracias a un periodista, una situaci\u00f3n ins\u00f3lita que solo encuentra su arraigo en la retroalimentaci\u00f3n del hincha cerrista con eso de que los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1460,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[183],"tags":[187,297,579,445],"ppma_author":[1039],"class_list":["post-1459","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-cerro-porteno","tag-conmebol","tag-river-plate","tag-zapag"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cerro perjudica a Cerro - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2019\/08\/28\/cerro-perjudica-a-cerro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cerro perjudica a Cerro - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Antes de que arranquen (y me gustar\u00eda que se los ahorraran) con los insultos, he de decirles que quien esto escribe es hincha del Club Cerro Porte\u00f1o. Dicho hecho, avancemos. Hoy vivimos, gracias a un periodista, una situaci\u00f3n ins\u00f3lita que solo encuentra su arraigo en la retroalimentaci\u00f3n del hincha cerrista con eso de que los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2019\/08\/28\/cerro-perjudica-a-cerro\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-28T20:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-08T21:18:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/de-la-cruz-donofrio-pipino.jpg?fit=760%2C420&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/08\\\/28\\\/cerro-perjudica-a-cerro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/08\\\/28\\\/cerro-perjudica-a-cerro\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"headline\":\"Cerro perjudica a Cerro\",\"datePublished\":\"2019-08-28T20:19:00+00:00\",\"dateModified\":\"2021-02-08T21:18:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/08\\\/28\\\/cerro-perjudica-a-cerro\\\/\"},\"wordCount\":469,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/08\\\/28\\\/cerro-perjudica-a-cerro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/de-la-cruz-donofrio-pipino.jpg?fit=760%2C420&ssl=1\",\"keywords\":[\"cerro porte\u00f1o\",\"conmebol\",\"river plate\",\"zapag\"],\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/08\\\/28\\\/cerro-perjudica-a-cerro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/08\\\/28\\\/cerro-perjudica-a-cerro\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/08\\\/28\\\/cerro-perjudica-a-cerro\\\/\",\"name\":\"Cerro perjudica a Cerro - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/08\\\/28\\\/cerro-perjudica-a-cerro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/08\\\/28\\\/cerro-perjudica-a-cerro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/de-la-cruz-donofrio-pipino.jpg?fit=760%2C420&ssl=1\",\"datePublished\":\"2019-08-28T20:19:00+00:00\",\"dateModified\":\"2021-02-08T21:18:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/08\\\/28\\\/cerro-perjudica-a-cerro\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/08\\\/28\\\/cerro-perjudica-a-cerro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/08\\\/28\\\/cerro-perjudica-a-cerro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/de-la-cruz-donofrio-pipino.jpg?fit=760%2C420&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/de-la-cruz-donofrio-pipino.jpg?fit=760%2C420&ssl=1\",\"width\":760,\"height\":420,\"caption\":\"El jugador ya est\u00e1 con sus compa\u00f1eros de equipo. Foto: Nelson Cuevas.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2019\\\/08\\\/28\\\/cerro-perjudica-a-cerro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cerro perjudica a Cerro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cerro perjudica a Cerro - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2019\/08\/28\/cerro-perjudica-a-cerro\/","og_locale":"es_ES","og_type":"article","og_title":"Cerro perjudica a Cerro - Informatepy","og_description":"Antes de que arranquen (y me gustar\u00eda que se los ahorraran) con los insultos, he de decirles que quien esto escribe es hincha del Club Cerro Porte\u00f1o. Dicho hecho, avancemos. Hoy vivimos, gracias a un periodista, una situaci\u00f3n ins\u00f3lita que solo encuentra su arraigo en la retroalimentaci\u00f3n del hincha cerrista con eso de que los [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2019\/08\/28\/cerro-perjudica-a-cerro\/","og_site_name":"Informatepy","article_published_time":"2019-08-28T20:19:00+00:00","article_modified_time":"2021-02-08T21:18:10+00:00","og_image":[{"width":760,"height":420,"url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/de-la-cruz-donofrio-pipino.jpg?fit=760%2C420&ssl=1","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2019\/08\/28\/cerro-perjudica-a-cerro\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2019\/08\/28\/cerro-perjudica-a-cerro\/"},"author":{"name":"admin","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"headline":"Cerro perjudica a Cerro","datePublished":"2019-08-28T20:19:00+00:00","dateModified":"2021-02-08T21:18:10+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/08\/28\/cerro-perjudica-a-cerro\/"},"wordCount":469,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/08\/28\/cerro-perjudica-a-cerro\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/de-la-cruz-donofrio-pipino.jpg?fit=760%2C420&ssl=1","keywords":["cerro porte\u00f1o","conmebol","river plate","zapag"],"articleSection":["Deportes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2019\/08\/28\/cerro-perjudica-a-cerro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2019\/08\/28\/cerro-perjudica-a-cerro\/","url":"https:\/\/informatepy.com\/2021\/2019\/08\/28\/cerro-perjudica-a-cerro\/","name":"Cerro perjudica a Cerro - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2019\/08\/28\/cerro-perjudica-a-cerro\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2019\/08\/28\/cerro-perjudica-a-cerro\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/de-la-cruz-donofrio-pipino.jpg?fit=760%2C420&ssl=1","datePublished":"2019-08-28T20:19:00+00:00","dateModified":"2021-02-08T21:18:10+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2019\/08\/28\/cerro-perjudica-a-cerro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2019\/08\/28\/cerro-perjudica-a-cerro\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2019\/08\/28\/cerro-perjudica-a-cerro\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/de-la-cruz-donofrio-pipino.jpg?fit=760%2C420&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/de-la-cruz-donofrio-pipino.jpg?fit=760%2C420&ssl=1","width":760,"height":420,"caption":"El jugador ya est\u00e1 con sus compa\u00f1eros de equipo. Foto: Nelson Cuevas."},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2019\/08\/28\/cerro-perjudica-a-cerro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Cerro perjudica a Cerro"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"],"url":"https:\/\/informatepy.com\/2021\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/de-la-cruz-donofrio-pipino.jpg?fit=760%2C420&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":1177,"url":"https:\/\/informatepy.com\/2021\/2019\/05\/21\/cerro-porteno-y-una-autocritica-que-se-demora\/","url_meta":{"origin":1459,"position":0},"title":"Cerro Porte\u00f1o y una autocr\u00edtica que se demora","date":"21 de mayo de 2019","format":false,"excerpt":"Barras, falta de logros deportivos, errores dirigenciales graves y una larga lista de etc\u00e9teras hacen que se f\u00e1cil realizar diagn\u00f3sticos sobre la realidad de un gran del futbol paraguayo como lo es Cerro Porte\u00f1o. De un tiempo a esta parte, uno de los grandes del futbol paraguayo no para de\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/cerristas.jpg?fit=712%2C678&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1171,"url":"https:\/\/informatepy.com\/2021\/2019\/05\/20\/jubero-ya-no-es-el-dt-de-cerro-porteno\/","url_meta":{"origin":1459,"position":1},"title":"Jubero ya no es el DT de Cerro Porte\u00f1o","date":"20 de mayo de 2019","format":false,"excerpt":"Fernando Jubero ya no es entrenador de Cerro Porte\u00f1o. Luego de que el Cicl\u00f3n haya cerrado su participaci\u00f3n en el torneo Apertura finalizando en la segunda posici\u00f3n con 43 puntos, 11 menos que el campe\u00f3n, Olimpia, la dirigencia anunci\u00f3 la salida del DT, quien hab\u00eda llegado a Barrio Obrero en\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/nani-zapag-jubero.jpeg?fit=730%2C486&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1277,"url":"https:\/\/informatepy.com\/2021\/2019\/06\/21\/sergio-diaz-vuelve-a-cerro-porteno\/","url_meta":{"origin":1459,"position":2},"title":"Sergio D\u00edaz vuelve a Cerro Porte\u00f1o","date":"21 de junio de 2019","format":false,"excerpt":"Cerro Porte\u00f1o concret\u00f3 el regreso de Sergio D\u00edaz a Barrio Obrero para reforzar el plantel que tendr\u00e1 como desaf\u00edo, en el segundo semestre del a\u00f1o, el torneo Clausura, la Copa Paraguay y la llave de octavos de final de la Libertadores ante San Lorenzo de Almagro. El Chico D\u00edaz se\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/06\/sergio-diaz-cerro-porteC3B1o.jpg?fit=631%2C547&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1358,"url":"https:\/\/informatepy.com\/2021\/2019\/07\/21\/el-sueno-termino\/","url_meta":{"origin":1459,"position":3},"title":"El sue\u00f1o termin\u00f3. Cerro Vicecampe\u00f3n de Futsal","date":"21 de julio de 2019","format":false,"excerpt":"El Cicl\u00f3n rem\u00f3 siempre contra la corriente en el partido decisivo disputado en el Polideportivo de San Lorenzo, en Buenos Aires (Argentina). El equipo de Barrio Obrero combati\u00f3 en desventaja desde los 8 minutos del primer tiempo cuando el rival marc\u00f3 el gol por intermedio de Darlan. No obstante, la\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/07\/gary-ayala-futsal.jpg?fit=730%2C499&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13625,"url":"https:\/\/informatepy.com\/2021\/2022\/08\/27\/futbol-cerro-porteno-se-durmio-sobre-el-final\/","url_meta":{"origin":1459,"position":4},"title":"Futbol: Cerro Porte\u00f1o se durmi\u00f3 sobre el final","date":"27 de agosto de 2022","format":false,"excerpt":"Foto APF La pesadilla azulgrana tiene un nuevo cap\u00edtulo desde esta noche, el cicl\u00f3n no pudo retener la m\u00ednima ventaja conseguida en el primer tiempo y el Rojo de Mallorqu\u00edn lo empat\u00f3 sobre el final. Al principio de la primera etapa del partido jugado en el este de nuestro pa\u00eds,\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/CERRO-JLM.jpg?fit=1200%2C801&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13835,"url":"https:\/\/informatepy.com\/2021\/2022\/09\/09\/el-ciclon-le-gano-el-recreativo-a-resistencia\/","url_meta":{"origin":1459,"position":5},"title":"El Cicl\u00f3n le gan\u00f3 el recreativo a Resistencia","date":"9 de septiembre de 2022","format":false,"excerpt":"Cerro Porte\u00f1o hizo de \u201cpelota jara\u201d en el barrio Sajonia, se adue\u00f1\u00f3 del partido y le gan\u00f3 a Resistencia sin complicaci\u00f3n alguna, casi en modo entrenamiento. El cicl\u00f3n no perdi\u00f3 tiempo y de entrada nomas sali\u00f3 a pasarle por encima a Resistencia y se puso arriba en el marcador a\u2026","rel":"","context":"En \u00abDeportes\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/09\/cerro-resistencia.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1039,"user_id":1,"is_guest":0,"slug":"admin","display_name":"admin","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","first_name":"","last_name":"","user_url":"http:\/\/informatepy.com\/2021","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=1459"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1459\/revisions"}],"predecessor-version":[{"id":2769,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/1459\/revisions\/2769"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/1460"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=1459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=1459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=1459"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=1459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}