{"id":14021,"date":"2022-09-22T08:30:00","date_gmt":"2022-09-22T11:30:00","guid":{"rendered":"https:\/\/informatepy.com\/2021\/?p=14021"},"modified":"2022-09-21T18:21:47","modified_gmt":"2022-09-21T21:21:47","slug":"entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2022\/09\/22\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\/","title":{"rendered":"Entrevista exclusiva con Ricardo L\u00f3pez Murphy: \u00abSigo creyendo que las ideas colectivistas han hecho un gran da\u00f1o\u00bb"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">Ayer en <strong>Enfoque 360<\/strong>, programa radial del <strong>Dr. Nahem Reyes<\/strong> en Radio 1000AM, se difundi\u00f3 la entrevista que \u00e9ste le hiciera al ExMinistro de Econom\u00eda de Argentina y Diputando Nacional por Republicanos Unidos, el Dr. Ricardo L\u00f3pez Murphy, quien fuera conferencista en un evento organizado el s\u00e1bado pasado por el Centro de Estudios Sociales juntamente con la Fundaci\u00f3n Naumann. Aqu\u00ed de seguidas la transcripci\u00f3n:<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><strong>\u00bfQu\u00e9 es el liberalismo y cu\u00e1l es la importancia de este movimiento filos\u00f3fico y pol\u00edtico hoy en d\u00eda para nuestros pa\u00edses y las democracias latinoamericanas?<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Yo dir\u00eda que la idea de la libertad, es el proyecto que respeta el proyecto del otro, convive y reconoce la diversidad, lo hace en un marco institucional, valoriza la iniciativa privada y sobre todo hace un gran \u00e9nfasis en el gobierno limitado, en no usar la violencia y en conservar el mayor espacio de libertad posible para la sociedad civil.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><strong>\u00bfEstamos observado una suerte de emergencia o versi\u00f3n 2.0 del socialismo del siglo XXI, sobre todo con la victoria los Fern\u00e1ndez en Argentina, Boric en Chile y ahora Petro en Colombia. Est\u00e1 en peligro la democracia y la libertad en las sociedades latinoamericanas del siglo XXI?<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">A ver, yo dir\u00eda la elecci\u00f3n que tuvimos en noviembre en Argentina revela una gran derrota del kirchnerismo, \u00f3sea, la verdad no los llevamos puesto esa elecci\u00f3n, yo creo que el Presidente Boric acaba de perder el plebiscito por la Constituci\u00f3n de una manera abrumadora. El \u00fanico caso que a m\u00ed me preocupa es el caso de Petro, pero bueno, &nbsp;es un caso que me cuesta entender bien porque Colombia est\u00e1 muy cercana a Venezuela y es dif\u00edcil querer repetir un modelo tan fracasado como el venezolano, como el cubano. Pero bueno, ese es el \u00fanico caso que yo reconozco un gran retroceso.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><strong>Aprovechando que Ud. en su conferencia dijo una frase que me result\u00f3 muy simp\u00e1tica, que \u201cel mercado se maneja por la mano invisible, a veces, una mano artr\u00edtica, pero que es preferible al dedo de Cristina\u201d, com\u00e9ntenos un poco, \u00bfqu\u00e9 significa?<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Yo creo que siempre, toda \u00e9sta construcci\u00f3n que son las ideas de la libertad, es una construcci\u00f3n provisoria, va mejor\u00e1ndose con la experiencia y los mercados funcionan tambi\u00e9n as\u00ed, no son construcciones perfectas, son fen\u00f3menos sociales surgidos de la interacci\u00f3n humana. Ahora, uno siempre tiene que comprar realidades, no una visi\u00f3n ut\u00f3pica y conceptual del socialismo y la sociedad libre, sino la experiencia pr\u00e1ctica y cuando uno compara, la mano invisible artr\u00edtica con el dedo de Cristina, uno sabe que nos ha ido muy mal, hemos retrocedido mucho, ha sido muy perjudicial para los argentinos ese gobierno. Entonces, yo digo, no nos hagan trampa, no nos comparen una tipolog\u00eda conceptual, una ut\u00f3pica con la realidad de la econom\u00eda de mercado, comparemos pelo a pelo, \u00bfqu\u00e9 quiere decir pelo a pelo? Los dos tipos de gobierno en ejercicio, y bueno, uno ve la experiencia del kirchnerismo ni se le ocurre repetirlo.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Entrevista exclusiva con el Dr. Ricardo L\u00f3pez Murphy\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/yJec6KDyc9Q?start=7&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><figcaption>Escuch\u00e1 la entrevista completa<\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><strong>Los cr\u00edticos o los progresistas se\u00f1ala que est\u00e1 desgastado este debate entre izquierda y derecha, \u00bfrealmente Ud. considera que es as\u00ed?<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">A ver, yo sigo creyendo que las ideas colectivistas han hecho un gran da\u00f1o, hayan sido \u00e9stas las nazzi-fascistas o las comunistas, a m\u00ed me parece que ese debate est\u00e1 en la naturaleza del ser humano, porque siempre hay alguno que se le ocurre que gobernar autoritariamente, es decir, que va a ser el d\u00e9spota ilustrado, y yo nunca cre\u00ed que los d\u00e9spotas sean ilustradas ni que nos vaya bien, por ese lado.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Yo no siento que haya un desgaste, yo siento que ese debate sigue tan vigoroso como antes, es verdad que no tiene el componente cuasi-religioso que ten\u00eda cuando estaba la Uni\u00f3n Sovi\u00e9tica, la Uni\u00f3n Sovi\u00e9tica ten\u00eda un componente misional, hoy digamos, Corea del Norte no puede misionar a nadie, Cuba no puede misionar a nadie, han perdido ese car\u00e1cter hist\u00f3rico que tuvieron de convertirse casi en una religi\u00f3n, acu\u00e9rdese Ud., yo cont\u00e9 la truhaner\u00eda del Premio Nobel Neruda cuando dec\u00eda que \u201cla paloma de la paz se apoyaba sobre el hombro de Stalin\u201d, un conocido criminal de 25 millones de personas asesinadas y le adjudicaban la paloma de la paz. Y digo bueno, ese tipo de debates hoy ser\u00eda inveros\u00edmil, hoy ya no se da, se da otro debate, seguramente importante que es \u00bfc\u00f3mo convivir en sociedades que por el cambio tecnol\u00f3gico se han vuelto muy heterog\u00e9neas?<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Yo contaba el caso de los programadores en Argentina, \u00f3sea, hay gente que vive instalada en la econom\u00eda mundial con un nivel de vida enorme y hay gente que vive en condiciones de mucha marginalidad e indigencia y obviamente eso genera un clima conflictivo, pero no creo que sean los t\u00e9rminos que el debate fue en el pasado, es decir, hoy nadie se animar\u00eda a ver un car\u00e1cter religioso ni a Putin, ni a Maduro, ni a Ortega, por favor.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><strong>Para ir cerrando, sobre un tema que quiz\u00e1s no estamos muy acostumbrados a hablar, es la bio-pol\u00edtica, estos desaf\u00edos de la alteraci\u00f3n del genoma humano e incluso se habla que a corto plazo vamos a tener embutidos dispositivos electr\u00f3nicos en nuestro cuerpo, \u00bfese es el nuevo desaf\u00edo de la discusi\u00f3n en las pr\u00f3ximas d\u00e9cadas?<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">En general, te digo (\u2026) en el 2003 me hab\u00eda comprometido en una Comisi\u00f3n Nacional de Bio\u00e9tica, porque estos debates est\u00e1n en la cuesti\u00f3n \u00bfhasta d\u00f3nde y cu\u00e1les son los l\u00edmites? Yo veo la parte positiva y la parte negativa, la parte positiva veo lo que se ha avanzado en las terapias contra las enfermedades, yo creo que ha habido una revoluci\u00f3n en las ciencias de la vida.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">La parte peligrosa es que tratemos de crear, digamos, un ejemplar que se parezca al humano en un laboratorio y eso me pondr\u00eda nervioso, eso reconozco que hay dilemas ah\u00ed, pero yo espero que teniendo en cuenta la dimensi\u00f3n \u00e9tica sepamos separar lo que son las mejores cient\u00edfica que cooperan en un desarrollo m\u00e1s l\u00f3gico y sano de la humanidad de lo que pudr\u00eda ser una malformaci\u00f3n de clonar seres humanos, todos esos problemas que claro, tienen una dimensi\u00f3n de conflicto y de dilemas.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Yo no se lo voy a negar, no es que los liberales hemos construido el fin de la historia, no es verdad, al rev\u00e9s, estamos frente a dilemas \u00e9ticos muy complejos y es verdad vamos a tener que enfrentarlos. Ahora, ese debate est\u00e1 frente a nosotros, ahora yo no me niego al progreso tecnol\u00f3gico y veo el formidable progreso en la lucha contra enfermedades, ah\u00ed ha habido un progreso extraordinario, creo que lo tenemos que celebrar.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><strong>Y nuestra \u00faltima pregunta en exclusiva para Enfoque 360 de Radio 1000 y de InformatePy, \u00bfDoctor Ricardo L\u00f3pez Murphy se va a lanzar en la arena pol\u00edtica argentina como candidato a la presidencia de la Rep\u00fablica de Argentina?<\/strong> <\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">M\u00e1s que lanzarme no voy a tener m\u00e1s remedio, porque la columna de las ideas de la libertad va a buscar su abanderado y v\u00e9alo desde el punto de vista econ\u00f3mico, \u00bfqui\u00e9n es la figura m\u00e1s conocida de esas ideas en la Argentina? Bueno, es Ricardo L\u00f3pez Murphy y eso hace mucho m\u00e1s econ\u00f3mico salir a defenderla, porque a m\u00ed no hay que hacerme conocer. Entonces, no es que lo estoy buscando con desesperaci\u00f3n, no tengo m\u00e1s remedio, forma de mis obligaciones ser el abanderado de las ideas de la libertad y voy a tratar de hacerlo con la mayor dignidad y ejemplaridad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ayer en Enfoque 360, programa radial del Dr. Nahem Reyes en Radio 1000AM, se difundi\u00f3 la entrevista que \u00e9ste le hiciera al ExMinistro de Econom\u00eda de Argentina y Diputando Nacional por Republicanos Unidos, el Dr. Ricardo L\u00f3pez Murphy, quien fuera conferencista en un evento organizado el s\u00e1bado pasado por el Centro de Estudios Sociales juntamente [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":14023,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[173],"tags":[1036],"ppma_author":[1051],"class_list":["post-14021","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","tag-destacada"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entrevista exclusiva con Ricardo L\u00f3pez Murphy: &quot;Sigo creyendo que las ideas colectivistas han hecho un gran da\u00f1o&quot; - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2022\/09\/22\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entrevista exclusiva con Ricardo L\u00f3pez Murphy: &quot;Sigo creyendo que las ideas colectivistas han hecho un gran da\u00f1o&quot; - Informatepy\" \/>\n<meta property=\"og:description\" content=\"Ayer en Enfoque 360, programa radial del Dr. Nahem Reyes en Radio 1000AM, se difundi\u00f3 la entrevista que \u00e9ste le hiciera al ExMinistro de Econom\u00eda de Argentina y Diputando Nacional por Republicanos Unidos, el Dr. Ricardo L\u00f3pez Murphy, quien fuera conferencista en un evento organizado el s\u00e1bado pasado por el Centro de Estudios Sociales juntamente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2022\/09\/22\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/InformatePyCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-22T11:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/09\/entrevista-lopez-murphy.jpg?fit=1280%2C854&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/InformatePy1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/09\\\/22\\\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/09\\\/22\\\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\"},\"headline\":\"Entrevista exclusiva con Ricardo L\u00f3pez Murphy: \u00abSigo creyendo que las ideas colectivistas han hecho un gran da\u00f1o\u00bb\",\"datePublished\":\"2022-09-22T11:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/09\\\/22\\\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\\\/\"},\"wordCount\":1365,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/09\\\/22\\\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/entrevista-lopez-murphy.jpg?fit=1280%2C854&ssl=1\",\"keywords\":[\"destacada\"],\"articleSection\":[\"Mundo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/09\\\/22\\\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/09\\\/22\\\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/09\\\/22\\\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\\\/\",\"name\":\"Entrevista exclusiva con Ricardo L\u00f3pez Murphy: \\\"Sigo creyendo que las ideas colectivistas han hecho un gran da\u00f1o\\\" - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/09\\\/22\\\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/09\\\/22\\\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/entrevista-lopez-murphy.jpg?fit=1280%2C854&ssl=1\",\"datePublished\":\"2022-09-22T11:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/09\\\/22\\\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/09\\\/22\\\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/09\\\/22\\\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/entrevista-lopez-murphy.jpg?fit=1280%2C854&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/entrevista-lopez-murphy.jpg?fit=1280%2C854&ssl=1\",\"width\":1280,\"height\":854},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/09\\\/22\\\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entrevista exclusiva con Ricardo L\u00f3pez Murphy: \u00abSigo creyendo que las ideas colectivistas han hecho un gran da\u00f1o\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/0c842f525f84ea74ef3b44370d11757b\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/informate-circulo.png?fit=96%2C96&ssl=1\",\"caption\":\"Redacci\u00f3n\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InformatePyCom\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/InformatePy1\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entrevista exclusiva con Ricardo L\u00f3pez Murphy: \"Sigo creyendo que las ideas colectivistas han hecho un gran da\u00f1o\" - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2022\/09\/22\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\/","og_locale":"es_ES","og_type":"article","og_title":"Entrevista exclusiva con Ricardo L\u00f3pez Murphy: \"Sigo creyendo que las ideas colectivistas han hecho un gran da\u00f1o\" - Informatepy","og_description":"Ayer en Enfoque 360, programa radial del Dr. Nahem Reyes en Radio 1000AM, se difundi\u00f3 la entrevista que \u00e9ste le hiciera al ExMinistro de Econom\u00eda de Argentina y Diputando Nacional por Republicanos Unidos, el Dr. Ricardo L\u00f3pez Murphy, quien fuera conferencista en un evento organizado el s\u00e1bado pasado por el Centro de Estudios Sociales juntamente [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2022\/09\/22\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\/","og_site_name":"Informatepy","article_author":"https:\/\/www.facebook.com\/InformatePyCom","article_published_time":"2022-09-22T11:30:00+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/09\/entrevista-lopez-murphy.jpg?fit=1280%2C854&ssl=1","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/InformatePy1","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2022\/09\/22\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2022\/09\/22\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b"},"headline":"Entrevista exclusiva con Ricardo L\u00f3pez Murphy: \u00abSigo creyendo que las ideas colectivistas han hecho un gran da\u00f1o\u00bb","datePublished":"2022-09-22T11:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/09\/22\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\/"},"wordCount":1365,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/09\/22\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/09\/entrevista-lopez-murphy.jpg?fit=1280%2C854&ssl=1","keywords":["destacada"],"articleSection":["Mundo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2022\/09\/22\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2022\/09\/22\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\/","url":"https:\/\/informatepy.com\/2021\/2022\/09\/22\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\/","name":"Entrevista exclusiva con Ricardo L\u00f3pez Murphy: \"Sigo creyendo que las ideas colectivistas han hecho un gran da\u00f1o\" - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/09\/22\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/09\/22\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/09\/entrevista-lopez-murphy.jpg?fit=1280%2C854&ssl=1","datePublished":"2022-09-22T11:30:00+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2022\/09\/22\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2022\/09\/22\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2022\/09\/22\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/09\/entrevista-lopez-murphy.jpg?fit=1280%2C854&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/09\/entrevista-lopez-murphy.jpg?fit=1280%2C854&ssl=1","width":1280,"height":854},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2022\/09\/22\/entrevista-exclusiva-con-ricardo-lopez-murphy-sigo-creyendo-que-las-ideas-colectivistas-han-hecho-un-gran-dano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Entrevista exclusiva con Ricardo L\u00f3pez Murphy: \u00abSigo creyendo que las ideas colectivistas han hecho un gran da\u00f1o\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/0c842f525f84ea74ef3b44370d11757b","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","caption":"Redacci\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/InformatePyCom","https:\/\/x.com\/https:\/\/twitter.com\/InformatePy1"],"url":"https:\/\/informatepy.com\/2021\/author\/redaccion\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/09\/entrevista-lopez-murphy.jpg?fit=1280%2C854&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":7098,"url":"https:\/\/informatepy.com\/2021\/2021\/09\/13\/llora-la-izquierda-excelente-eleccion-de-javier-milei\/","url_meta":{"origin":14021,"position":0},"title":"Llora la izquierda: excelente elecci\u00f3n de Javier Milei","date":"13 de septiembre de 2021","format":false,"excerpt":"El economista liberal se consolid\u00f3 como la tercera fuerza en la Ciudad de Buenos Aires","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/javier-milei.jpg?fit=679%2C446&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6526,"url":"https:\/\/informatepy.com\/2021\/2021\/08\/18\/el-fenomeno-javier-milei\/","url_meta":{"origin":14021,"position":1},"title":"El fen\u00f3meno Javier Milei","date":"18 de agosto de 2021","format":false,"excerpt":"La gran pregunta es hasta d\u00f3nde puede crecer el fen\u00f3meno Javier Milei. Cada tanto, las elecciones dan grandes sorpresas y \u00e9sta puede ser una de esas ocasiones.","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/08\/javier-milei.jpg?fit=679%2C446&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4065,"url":"https:\/\/informatepy.com\/2021\/2021\/03\/21\/entrevista-con-el-dr-salle-lorier-y-su-mirada-de-las-grandes-corporaciones\/","url_meta":{"origin":14021,"position":2},"title":"Entrevista con el Dr. Salle Lorier, su mirada de la pol\u00edtica y de las grandes corporaciones","date":"21 de marzo de 2021","format":"video","excerpt":"Gustavo Salle Lorier es un abogado y pol\u00edtico uruguayo, perteneciente al Partido Identidad Soberana. Cobr\u00f3 notoriedad p\u00fablica al haber realizado varias denuncias penales a integrantes de gobierno del Frente Amplio. En particular, denunci\u00f3 al entonces vicepresidente Ra\u00fal Fernando Sendic por \"usurpaci\u00f3n de t\u00edtulo\".","rel":"","context":"En \u00abVideos\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/gustavo-salle-lorier.jpg?fit=800%2C445&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13630,"url":"https:\/\/informatepy.com\/2021\/2022\/08\/27\/eduardo-bolsonaro-cruzo-a-santiago-cafiero-con-una-despiadada-burla\/","url_meta":{"origin":14021,"position":3},"title":"Eduardo Bolsonaro cruz\u00f3 a Santiago Cafiero con una despiadada burla","date":"27 de agosto de 2022","format":false,"excerpt":"El diputado brasile\u00f1o Eduardo Bolsonaro, hijo del presidente Jair Bolsonaro, se burl\u00f3 del canciller argentino, quien lo hab\u00eda llamado \"ignorante\".","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/08\/eduardo-bolsonaro.jpg?fit=1200%2C592&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4610,"url":"https:\/\/informatepy.com\/2021\/2021\/04\/23\/avanza-el-proyecto-que-regulara-matricula-de-abogados\/","url_meta":{"origin":14021,"position":4},"title":"Avanza el proyecto que regular\u00e1 matr\u00edcula de abogados","date":"23 de abril de 2021","format":false,"excerpt":"El ministro Alberto Mart\u00ednez Sim\u00f3n en una entrevista concedida a periodistas judiciales, dijo que el proyecto para otorgar la matr\u00edcula a los futuros abogados est\u00e1 avanzado en la redacci\u00f3n del proyecto, que contempla exigencias tendientes a entregar matr\u00edculas s\u00f3lo a aqu\u00e9llas personas que superen el proceso de selecci\u00f3n. \u00abEstamos viendo\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/alberto-martinez-simon-CSJ.jpg?fit=960%2C580&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1134,"url":"https:\/\/informatepy.com\/2021\/2019\/05\/10\/abdo-retira-el-proyecto-de-los-consejeros\/","url_meta":{"origin":14021,"position":5},"title":"Abdo retira el proyecto de los consejeros","date":"10 de mayo de 2019","format":false,"excerpt":"El Presidente Mario Abdo, por medio de una nota remitida a Silvio Ovelar, titular del Senado, retir\u00f3 el proyecto de ley, que fuera fuertemente cuestionado por diversos sectores debido al gasto p\u00fablico que generar\u00eda. Esta propuesta hab\u00eda sido presentada por el Ejecutivo el pasado 22 de abril en la C\u00e1mara\u2026","rel":"","context":"En \u00abNacionales\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/05\/mario-abdo-cansado.jpg?fit=1200%2C861&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1051,"user_id":4,"is_guest":0,"slug":"redaccion","display_name":"Redacci\u00f3n","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/informate-circulo.png?fit=96%2C96&ssl=1","first_name":"Redacci\u00f3n","last_name":"","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/14021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=14021"}],"version-history":[{"count":2,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/14021\/revisions"}],"predecessor-version":[{"id":14025,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/14021\/revisions\/14025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/14023"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=14021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=14021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=14021"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=14021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}