{"id":13934,"date":"2022-09-15T18:05:00","date_gmt":"2022-09-15T21:05:00","guid":{"rendered":"https:\/\/informatepy.com\/2021\/?p=13934"},"modified":"2022-09-15T18:51:54","modified_gmt":"2022-09-15T21:51:54","slug":"los-insumisos","status":"publish","type":"post","link":"https:\/\/informatepy.com\/2021\/2022\/09\/15\/los-insumisos\/","title":{"rendered":"Los insumisos"},"content":{"rendered":"\n<figure class=\"wp-block-pullquote\"><blockquote><p>El mundo no ser\u00e1 salvado, si lo es, por nadie m\u00e1s que los insumisos. <\/p><cite>Andr\u00e9 Gide<\/cite><\/blockquote><\/figure>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">O, dir\u00eda yo, a los ojos de Dios, lo \u00fanicos que se salvar\u00e1n ser\u00e1n los insumisos. Fundamento b\u00edblico tengo, el remanente fiel, en \u00e9l, como perlas que se suceden en el tiempo, est\u00e1 toda la historia de Israel y su tormentosa relaci\u00f3n con Jehov\u00e1. La gran diferencia es que los del resto fiel eran los obedientes y no los rebeldes hasta que vino el Mes\u00edas y cambi\u00f3 la historia. Entonces, la raz\u00f3n se dio vuelta y los obedientes comenzaron a ser perseguidos porque se volvieron insumisos, los que permanecieron en Cristo.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">\u00bfQuien no conoce la persecuci\u00f3n a los primeros cristianos por parte de los romanos y de los mismos jud\u00edos? El ejemplo m\u00e1s importante y claro fue el de Saulo de Tarso, romano y fariseo a la vez, quien, sin embargo, en plena faena para cazar a los seguidores del nazareno se convirti\u00f3 por el camino a Damasco de un golpe por asalto que le dio el Se\u00f1or mismo.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Ahora bien, \u00bfinsumisos a que y quienes? He ah\u00ed la cuesti\u00f3n, ser o no ser, como que de siempre;<br>al sistema de este mundo que maneja el mismo Diablo quien solo est\u00e1 para hurtar, matar y destruir. Un sistema disfrazado de buenas intenciones y organizaciones para enga\u00f1ar a la gente que no sabe lo que pasa y no sabe que no sabe a decir de Noam Chomsky. Y \u00faltimamente dopada de idiotez para que vayan como ovejas al matadero. <strong>\u00bfCual fue el dopaje? Los medios masivos de comunicaci\u00f3n. \u00bfY el matadero? La vacunaci\u00f3n.<\/strong> Y es cierto, nadie fue obligado, claro que terriblemente presionados as\u00ed como tambi\u00e9n lo fueron quienes permanecieron fieles a Cristo en tiempo de persecuci\u00f3n.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Entonces, si te vacunaste porque tuviste que viajar dijiste, o te exigieron en tu trabajo, fuiste, te dejaste poner el alcohol del anticristo y ahora vendr\u00e1 el pinchazo definitivo, la marca y doble fuiste. Jodete, morite, la vida pide lo suyo y se vuelve tr\u00e1gica en cualquier momento. Vos que eras tan buenita resultaste tan est\u00fapida. Chau.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">La institucionalidad es la trampa, la democracia, el Estado, el Gobierno, los Tratados, la pir\u00e1mide de Kelsen, ere erea. Preguntame si me calienta que digas que soy muy radical, \u00bfAcaso Jes\u00fas no lo fue? \u00bfEn qu\u00e9 crees vos? Falso cristiano, tibio y desgraciado.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Lo que est\u00e1 establecido, m\u00e1s conocido como el \u00abestablishment\u00bb es la trampa, no el establecimiento ni el estacionamiento. Lo defino, a mi coqueto entender, establishment: Poder paralelo al verdadero que viene de lo alto, establecido por hombres en contra natura, impuesto por los privilegiados para mantener sus privilegios. Es una mafia.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00abEl establishment m\u00e9dico es un poder m\u00e9dico paralelo, enfrentado al poder de curaci\u00f3n natural, innato en toda persona. Lo establece y lo impone la clase privilegiada para dominar y explotar a los pacientes, manteniendo as\u00ed sus privilegios. Es la mafia m\u00e9dica\u00bb. <\/p><cite>Ghislaine Lanctot<\/cite><\/blockquote><\/figure>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><strong><em>\u00abSolo quisiera que la gente reconociera las cosas como son de verdad. Quisiera que entendiera los impuestos como robo, los pol\u00edticos como ladrones y todo el aparato y burocracia del Estado como una estructura de protecci\u00f3n, una empresa similar a la Mafia, solo que mucho m\u00e1s grande y peligrosa. En resumen, quisiera que odiaran el Estado. Si todos creyeran e hicieran esto, entonces, como ha demostrado la Bo\u00e9tie, todo el poder del Estado se desvanecer\u00e1 casi instant\u00e1neamente\u00bb<\/em><\/strong>. Hans Hermann Hope<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">\u00bfComprendido?<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">\u00bfQuien es la Bo\u00e9tie?<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Un \u00e1ngel adolescente que escribi\u00f3 \u00abLa servidumbre voluntaria\u00bb all\u00e1 por el 1547, incre\u00edble. Un ensayo en el cual demuestra que el poder de los gobernantes y a\u00fan de los tiranos deviene de lo que dice el mismo t\u00edtulo; de los sumisos, que son mayor\u00eda en este mundo. Sumisos al poder terrenal pero insumisos al de Dios, lo que les hace desobedientes y est\u00fapidos. Escrito est\u00e1, el principio de la sabidur\u00eda es el temor a Dios, no a los hombres que gobiernan sobre otros. <strong><em>\u00abDice el necio en su coraz\u00f3n: No hay Dios\u00bb<\/em><\/strong>. Salmo 14<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Seg\u00fan el converso Saulo a Pablo, no hay excusas para no creer porque el Creador se manifiesta en lo creado, en la naturaleza misma, pero otro menos santo como Mark Twain, padre de la literatura norteamericana sentenci\u00f3: <em><strong>\u00abNunca hay suficiente evidencia para el idiota\u00bb.<\/strong><\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Y para que no queden dudas, repito lo de Kalil Gibr\u00e1n: <em><strong>\u00abCristo cur\u00f3 a los ciegos, a los lisiados, a los paral\u00edticos y a los leprosos. Pero a los idiotas no pudo curarlos\u00bb<\/strong><\/em>. De ah\u00ed que, este pa\u00eds de cretinos como dijo Cecilio Baez, es incurable. Cerremos entonces, el \u00faltimo que apague la luz, seamos brasile\u00f1os, m\u00e1s ahora que le tienen a Bolsonaro. Y hablando de, aqu\u00ed est\u00e1, es \u00e9l y su ballet haciendo historia para todo el mundo con las convocatorias m\u00e1s numerosas que se hayan visto, de proporciones b\u00edblicas. Gener\u00f3 un mar de girasoles y nosotros le tenemos a Marito, v\u00e1yanse a la puta paraguayitos, traigamos los restos del General para que descanse en el Pante\u00f3n de los H\u00e9roes y reconciliarnos con nuestra historia y alguna vez legitimar el poder, \u00a1generaci\u00f3n de v\u00edboras\u00a1 Aunque ya muri\u00f3 la culebra.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Los infiltrados para explotar desde adentro son los insumisos: Jair Mesias, Nayib Bukele, presidente de El Salvador, peque\u00f1o pa\u00eds del tama\u00f1o de Kaaguasu pero que el mundo entero escucha hablar de \u00e9l gracias al insumiso que lo gobierna, y ese nombre, del pa\u00eds digo, \u00bfpiensan que es casualidad? Como todas las muertes que se suceden luego de la campa\u00f1a de vacunaci\u00f3n masiva, \u00a1que casualidad! \u00a1Idiotas!<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Tambi\u00e9n est\u00e1 Victor Orban, \u00a1macho dijo la partera! otro gran insumiso, \u00bfquien no conoce el goulash? Oscar \u00abla bosta\u00bb Acosta no tiene\u00a0puta idea, como tantos otros. \u00a1Viva Hungr\u00eda carajo!<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Y a Dios gracias, y d\u00e9mosle muchas gracias por el nuevo Zar de Rusia Vladimir Putin \u00a1Nasdarovya! Que monte el oso ruso por el resto de su bendita vida carajo. Pate\u00f3 el tablero de los genocidas e impuso uno nuevo de ajedrez sobre el cual juega su partida y prepararse porque esta vez el general invierno visitar\u00e1 Europa y causar\u00e1 estragos, miremos y aplaudamos desde el palco, uni\u00f3n de degenerados hijos de puta, m\u00e9tanse el euro en el culo o qu\u00e9menlo para soportar el fr\u00edo que se les viene, pero claro, el calentamiento global los salvar\u00e1.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Finalmente, quiz\u00e1s el mayor intento de insumisi\u00f3n, el que quiso drenar el inmundo pantano de la Roma sobre el Potomac, el mejor presidente de la historia de USA, Donald J. Trump, por lo menos Tom Brady sigue jugando a\u00fan en la NFL.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Marito de mierda, morite maldito, deber\u00edas estar colgado en una de las plazas de Asunci\u00f3n por traidor a la patria. Sos el que entregas el Paraguay a las garras del anticristo, para acabar con \u00e9l, para que deje de ser, abyecto batracio de la ignorancia, sumiso asqueroso.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">\u00a1Viva Bolsonaro, Bukele, Orban, Trump y Putin! \u00a1Que vivan los insumisos carajo!\u00a0 \u00a1Que viva la libertad!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Feliz finde chiques<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mundo no ser\u00e1 salvado, si lo es, por nadie m\u00e1s que los insumisos. Andr\u00e9 Gide O, dir\u00eda yo, a los ojos de Dios, lo \u00fanicos que se salvar\u00e1n ser\u00e1n los insumisos. Fundamento b\u00edblico tengo, el remanente fiel, en \u00e9l, como perlas que se suceden en el tiempo, est\u00e1 toda la historia de Israel y [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":8523,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":false},"categories":[248],"tags":[1036],"ppma_author":[1088],"class_list":["post-13934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analisis","tag-destacada"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los insumisos - Informatepy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/informatepy.com\/2021\/2022\/09\/15\/los-insumisos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los insumisos - Informatepy\" \/>\n<meta property=\"og:description\" content=\"El mundo no ser\u00e1 salvado, si lo es, por nadie m\u00e1s que los insumisos. Andr\u00e9 Gide O, dir\u00eda yo, a los ojos de Dios, lo \u00fanicos que se salvar\u00e1n ser\u00e1n los insumisos. Fundamento b\u00edblico tengo, el remanente fiel, en \u00e9l, como perlas que se suceden en el tiempo, est\u00e1 toda la historia de Israel y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/informatepy.com\/2021\/2022\/09\/15\/los-insumisos\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatepy\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-15T21:05:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-15T21:51:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/raul-melamed-columnista.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1281\" \/>\n\t<meta property=\"og:image:height\" content=\"701\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ra\u00fal Melamed\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/raulmelamed\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ra\u00fal Melamed\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/09\\\/15\\\/los-insumisos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/09\\\/15\\\/los-insumisos\\\/\"},\"author\":{\"name\":\"Ra\u00fal Melamed\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/aac7b42a7411859e51d531e57d111a48\"},\"headline\":\"Los insumisos\",\"datePublished\":\"2022-09-15T21:05:00+00:00\",\"dateModified\":\"2022-09-15T21:51:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/09\\\/15\\\/los-insumisos\\\/\"},\"wordCount\":1219,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/09\\\/15\\\/los-insumisos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/raul-melamed-columnista.png?fit=1281%2C701&ssl=1\",\"keywords\":[\"destacada\"],\"articleSection\":[\"Analisis\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/09\\\/15\\\/los-insumisos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/09\\\/15\\\/los-insumisos\\\/\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/09\\\/15\\\/los-insumisos\\\/\",\"name\":\"Los insumisos - Informatepy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/09\\\/15\\\/los-insumisos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/09\\\/15\\\/los-insumisos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/raul-melamed-columnista.png?fit=1281%2C701&ssl=1\",\"datePublished\":\"2022-09-15T21:05:00+00:00\",\"dateModified\":\"2022-09-15T21:51:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/09\\\/15\\\/los-insumisos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/09\\\/15\\\/los-insumisos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/09\\\/15\\\/los-insumisos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/raul-melamed-columnista.png?fit=1281%2C701&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/raul-melamed-columnista.png?fit=1281%2C701&ssl=1\",\"width\":1281,\"height\":701},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/2022\\\/09\\\/15\\\/los-insumisos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los insumisos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/\",\"name\":\"Informatepy\",\"description\":\"La verdad, siempre!\",\"publisher\":{\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/edd302c981d6ba4596191719d1025a8a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/informatepy.com\\\/2021\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/#\\\/schema\\\/person\\\/aac7b42a7411859e51d531e57d111a48\",\"name\":\"Ra\u00fal Melamed\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Raul-Melamed.jpg?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Raul-Melamed.jpg?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/informatepy.com\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Raul-Melamed.jpg?fit=96%2C96&ssl=1\",\"caption\":\"Ra\u00fal Melamed\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/raulmelamed\"],\"url\":\"https:\\\/\\\/informatepy.com\\\/2021\\\/author\\\/raulmelamed\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los insumisos - Informatepy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/informatepy.com\/2021\/2022\/09\/15\/los-insumisos\/","og_locale":"es_ES","og_type":"article","og_title":"Los insumisos - Informatepy","og_description":"El mundo no ser\u00e1 salvado, si lo es, por nadie m\u00e1s que los insumisos. Andr\u00e9 Gide O, dir\u00eda yo, a los ojos de Dios, lo \u00fanicos que se salvar\u00e1n ser\u00e1n los insumisos. Fundamento b\u00edblico tengo, el remanente fiel, en \u00e9l, como perlas que se suceden en el tiempo, est\u00e1 toda la historia de Israel y [&hellip;]","og_url":"https:\/\/informatepy.com\/2021\/2022\/09\/15\/los-insumisos\/","og_site_name":"Informatepy","article_published_time":"2022-09-15T21:05:00+00:00","article_modified_time":"2022-09-15T21:51:54+00:00","og_image":[{"width":1281,"height":701,"url":"https:\/\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/raul-melamed-columnista.png","type":"image\/png"}],"author":"Ra\u00fal Melamed","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/raulmelamed","twitter_misc":{"Escrito por":"Ra\u00fal Melamed","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/informatepy.com\/2021\/2022\/09\/15\/los-insumisos\/#article","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/2022\/09\/15\/los-insumisos\/"},"author":{"name":"Ra\u00fal Melamed","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/aac7b42a7411859e51d531e57d111a48"},"headline":"Los insumisos","datePublished":"2022-09-15T21:05:00+00:00","dateModified":"2022-09-15T21:51:54+00:00","mainEntityOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/09\/15\/los-insumisos\/"},"wordCount":1219,"commentCount":0,"publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/09\/15\/los-insumisos\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/raul-melamed-columnista.png?fit=1281%2C701&ssl=1","keywords":["destacada"],"articleSection":["Analisis"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/informatepy.com\/2021\/2022\/09\/15\/los-insumisos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/informatepy.com\/2021\/2022\/09\/15\/los-insumisos\/","url":"https:\/\/informatepy.com\/2021\/2022\/09\/15\/los-insumisos\/","name":"Los insumisos - Informatepy","isPartOf":{"@id":"https:\/\/informatepy.com\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/informatepy.com\/2021\/2022\/09\/15\/los-insumisos\/#primaryimage"},"image":{"@id":"https:\/\/informatepy.com\/2021\/2022\/09\/15\/los-insumisos\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/raul-melamed-columnista.png?fit=1281%2C701&ssl=1","datePublished":"2022-09-15T21:05:00+00:00","dateModified":"2022-09-15T21:51:54+00:00","breadcrumb":{"@id":"https:\/\/informatepy.com\/2021\/2022\/09\/15\/los-insumisos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/informatepy.com\/2021\/2022\/09\/15\/los-insumisos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/informatepy.com\/2021\/2022\/09\/15\/los-insumisos\/#primaryimage","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/raul-melamed-columnista.png?fit=1281%2C701&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/raul-melamed-columnista.png?fit=1281%2C701&ssl=1","width":1281,"height":701},{"@type":"BreadcrumbList","@id":"https:\/\/informatepy.com\/2021\/2022\/09\/15\/los-insumisos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/informatepy.com\/2021\/"},{"@type":"ListItem","position":2,"name":"Los insumisos"}]},{"@type":"WebSite","@id":"https:\/\/informatepy.com\/2021\/#website","url":"https:\/\/informatepy.com\/2021\/","name":"Informatepy","description":"La verdad, siempre!","publisher":{"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/informatepy.com\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/edd302c981d6ba4596191719d1025a8a","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5310f602b6cbcfb86e030c4ccdbb78f6565a3b9bab6a74ab80fd3cb5428b65af?s=96&d=mm&r=g"},"sameAs":["http:\/\/informatepy.com\/2021"]},{"@type":"Person","@id":"https:\/\/informatepy.com\/2021\/#\/schema\/person\/aac7b42a7411859e51d531e57d111a48","name":"Ra\u00fal Melamed","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/Raul-Melamed.jpg?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/Raul-Melamed.jpg?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/Raul-Melamed.jpg?fit=96%2C96&ssl=1","caption":"Ra\u00fal Melamed"},"sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/raulmelamed"],"url":"https:\/\/informatepy.com\/2021\/author\/raulmelamed\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/11\/raul-melamed-columnista.png?fit=1281%2C701&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":4412,"url":"https:\/\/informatepy.com\/2021\/2021\/04\/09\/muneco-de-torta\/","url_meta":{"origin":13934,"position":0},"title":"Mu\u00f1eco de torta","date":"9 de abril de 2021","format":false,"excerpt":"Este tipo, el turquito, parece un mu\u00f1eco de torta puesto de adorno sobre el merengue. Claro, a su lado la mu\u00f1equita, su parejita, quien otrora sol\u00eda cacarear al pedo cual gallina turuleca hasta que se fu\u00e9 a Miami para hacerse lavandera con toda su parentela. Mientras, aqu\u00ed, el prescindente propon\u00eda\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/mborito.jpg?fit=1200%2C625&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8870,"url":"https:\/\/informatepy.com\/2021\/2021\/12\/16\/la-belleza-que-salvara-al-mundo\/","url_meta":{"origin":13934,"position":1},"title":"La belleza que salvar\u00e1 al mundo","date":"16 de diciembre de 2021","format":false,"excerpt":"A prop\u00f3sito del evento de Miss Universo que mantuvo en vilo a todo el pa\u00eds, aprovecho para filosofar un poco al respecto, pues todos los seres humanos pensamos sobre los m\u00e1s diversos temas, aunque cabe a\u00f1adir que no todos lo hacen bien, y ni siquiera habitualmente. De cualquier forma, apelo\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/12\/nadia-ferreira.jpeg?fit=1000%2C576&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4516,"url":"https:\/\/informatepy.com\/2021\/2021\/04\/16\/la-desnacionalizacion-del-remanente\/","url_meta":{"origin":13934,"position":2},"title":"La desnacionalizaci\u00f3n del remanente","date":"16 de abril de 2021","format":false,"excerpt":"Bueno, el t\u00edtulo lo dice todo, aunque es una propuesta revolucionaria y el terreno est\u00e1 abonado. Digo bien, terreno porque no es toda la tierra, solo una parte de ella en la cual cabe una minor\u00eda de gente pensante, consciente y digna. Que yo sepa nadie la ensay\u00f3 a\u00fan y\u2026","rel":"","context":"En \u00abAnalisis\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/04\/covidiotas.jpg?fit=1200%2C673&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11970,"url":"https:\/\/informatepy.com\/2021\/2022\/06\/05\/nigeria-terroristas-musulmanes-irrumpen-en-una-misa-de-pentecostes-y-asesinan-a-50-fieles\/","url_meta":{"origin":13934,"position":3},"title":"NIGERIA: Terroristas musulmanes irrumpen en una Misa de Pentecost\u00e9s y asesinan a 50 fieles","date":"5 de junio de 2022","format":false,"excerpt":"El ataque terrorista tuvo lugar durante la misa matutina en la iglesia de San Francisco en la localidad de Owo, situada en el suroeste del pa\u00eds. Los primeros reportes hablan de al menos 50 muertos. De acuerdo a declaraciones de testigos, los terroristas eran al menos 5 y, al ingresar\u2026","rel":"","context":"En \u00abMundo\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2022\/06\/ataque-iglesia-nigeria.webp?fit=820%2C508&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3756,"url":"https:\/\/informatepy.com\/2021\/2021\/03\/06\/vuelve-el-rock-y-la-cosa-nostra\/","url_meta":{"origin":13934,"position":4},"title":"Vuelve el Rock&#8230; y la \u201cCosa Nostra\u201d","date":"6 de marzo de 2021","format":false,"excerpt":"Ra\u00fal Melamed, el ex presentador televisivo y comunicador emp\u00edrico, como el mismo se autodefine, vuelve al ruedo.","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/raul-melamed.png?fit=1157%2C705&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3463,"url":"https:\/\/informatepy.com\/2021\/2021\/02\/20\/diputada-parece-que-olvido-limpiar-el-patio\/","url_meta":{"origin":13934,"position":5},"title":"Diputada, parece que olvid\u00f3 limpiar el patio","date":"20 de febrero de 2021","format":false,"excerpt":"Este viernes se reinici\u00f3 el juicio oral por la querella que le entablara la diputada Celeste Amarilla al exsenador V\u00edctor Bogado por, supuestamente, haber denigrado la memoria de su difunto esposo, el tambi\u00e9n pol\u00edtico Franklin Boccia, ex director de la Itaip\u00fa Binacional. Fiel a su estilo, la diputada mont\u00f3 un\u2026","rel":"","context":"En \u00abDestacados\u00bb","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/02\/celeste-amarilla-1.jpg?fit=958%2C652&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"authors":[{"term_id":1088,"user_id":6,"is_guest":0,"slug":"raulmelamed","display_name":"Ra\u00fal Melamed","avatar_url":"https:\/\/i0.wp.com\/informatepy.com\/2021\/wp-content\/uploads\/2021\/03\/Raul-Melamed.jpg?fit=96%2C96&ssl=1","first_name":"Ra\u00fal","last_name":"Melamed","user_url":"","description":""}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/13934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/comments?post=13934"}],"version-history":[{"count":1,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/13934\/revisions"}],"predecessor-version":[{"id":13935,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/posts\/13934\/revisions\/13935"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media\/8523"}],"wp:attachment":[{"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/media?parent=13934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/categories?post=13934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/tags?post=13934"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/informatepy.com\/2021\/wp-json\/wp\/v2\/ppma_author?post=13934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}